{"id":87896,"date":"2025-10-10T05:11:23","date_gmt":"2025-10-10T08:11:23","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/10\/por-que-a-hp-quer-que-o-trabalho-deixe-de-parecer-trabalho-2\/"},"modified":"2025-10-10T05:11:23","modified_gmt":"2025-10-10T08:11:23","slug":"por-que-a-hp-quer-que-o-trabalho-deixe-de-parecer-trabalho-2","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/10\/por-que-a-hp-quer-que-o-trabalho-deixe-de-parecer-trabalho-2\/","title":{"rendered":"Por Que a HP Quer Que o Trabalho Deixe de Parecer Trabalho"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<figure class=\"destaque wp-caption\">&#13;<br \/>\n\t\t<img data-recalc-dims=\"1\" width=\"678\" height=\"452\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2025\/10\/CarlosHP-768x512.jpg?resize=678%2C452&#038;ssl=1\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" decoding=\"async\" fetchpriority=\"high\"\/>\t\t&#13;<figcaption class=\"wp-caption-text\">Carlos F. Cort\u00e9s, presidente da HP no M\u00e9xico: uso da tecnologia a favor da experi\u00eancia do colaborador<\/figcaption>&#13;<br \/>\n\t<\/figure>\n<div class=\"accessibility\">\n<p>Acessibilidade<\/p>\n<p>&#13;<br \/>\n\t\t\t<button onclick=\"alterFont1()\" id=\"btn1\" class=\"btn\">L<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFont2()\" id=\"btn2\" class=\"btn\" style=\"font-family:Merriweather\">L<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFontSmallerSize()\" id=\"btn3\" class=\"btn\">A-<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFontBiggerSize()\" id=\"btn4\" class=\"btn\">A+<\/button>&#13;<br \/>\n\t\t\t<!--<button onclick='alterFontBolder()' id='btn5' class=\"btn\" >B<\/button>-->&#13;<br \/>\n\t\t\t<button onclick=\"alterBackground()\" id=\"btn6\" class=\"btn\">\u25d0<\/button>&#13;<br \/>\n\t\t\t<!--<button onclick='clean()' id='btn7' class=\"btn\" >Limpar<\/button>-->&#13;\n\t\t<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<\/p><\/div>\n<p>Criada em uma garagem na cidade de Palo Alto, na Calif\u00f3rnia, em 1939, a <strong>HP<\/strong>, acr\u00f4nimo dos sobrenomes dos amigos William \u201cBill\u201d <strong>Hewlett<\/strong> e David \u201cDave\u201d <strong>Packard<\/strong>, tornou-se sin\u00f4nimo de <b>inova\u00e7\u00e3o<\/b>, ou melhor, a garagem da HP ficou conhecida como \u201co ber\u00e7o do <strong>Vale do Sil\u00edcio<\/strong>\u201c.<\/p>\n<p>Quase 86 anos depois e avaliada em US$ 25 bilh\u00f5es, essa mesma empresa, que domina os mercados de PCs e solu\u00e7\u00f5es para impress\u00e3o, tem um novo desafio: comunicar a seus clientes seu novo foco em servi\u00e7os integrados e fomentar uma constru\u00e7\u00e3o de marca baseada nas experi\u00eancias proporcionadas aos colaboradores. Em outras palavras, a HP quer se posicionar como uma empresa de <strong>\u201cemployee experience design\u201d<\/strong>, o <strong>EXD<\/strong>.<\/p>\n<p><strong>Carlos F. Cort\u00e9s, Presidente da HP no M\u00e9xico<\/strong>, ao apresentar o \u00cdndice de Satisfa\u00e7\u00e3o do Trabalho, realizado globalmente pela empresa, destacou que apenas 20% dos trabalhadores mant\u00eam uma rela\u00e7\u00e3o saud\u00e1vel com o trabalho. A pesquisa ouviu 18,2 mil profissionais em 14 pa\u00edses, incluindo M\u00e9xico, Brasil e Argentina.<\/p>\n<p>\u201cNosso objetivo, neste novo contexto de trabalho e sociedade, \u00e9 ser uma grande facilitadora da satisfa\u00e7\u00e3o no trabalho e pessoal. A IA n\u00e3o est\u00e1 mais unicamente na nuvem: hoje ela est\u00e1 dentro do equipamento, e n\u00e3o requer conex\u00e3o para ser utilizada. Isso marca uma nova era para o trabalho h\u00edbrido\u201d, destacou, explicando que, antes de levar isso para os clientes, a empresa, que tem quase 60 mil funcion\u00e1rios, levou o conceito inicialmente dentro de casa.<\/p>\n<p>O presidente da HP usa como exemplo as aplica\u00e7\u00f5es que a empresa j\u00e1 faz como parceira global da escuderia Ferrari, na F\u00f3rmula 1. Aplicamos tecnologia, refinamos os dados e usamos isso como uma forma de melhorar ainda mais a experi\u00eancia dos pilotos e das equipes. Essa l\u00f3gica se aplica para qualquer empresa que temos como parceiros\u201d, refor\u00e7a.<\/p>\n<p>A HP aplica o design de experi\u00eancia do funcion\u00e1rio por meio de plataformas e servi\u00e7os focados nas necessidades dos funcion\u00e1rios. Dentre os exemplos est\u00e3o a plataforma de aprendizagem \u201cBrain Candy\u201d e a Workforce Experience Platform (WXP) para gest\u00e3o de TI. \u201cEssas iniciativas, que incorporam o feedback dos funcion\u00e1rios e usam o design thinking para aprimorar o ambiente de trabalho, visam aumentar a produtividade, o engajamento e a reten\u00e7\u00e3o, oferecendo solu\u00e7\u00f5es personalizadas e relevantes ao longo da jornada do funcion\u00e1rio\u201d, destaca <strong>Gabriel Romero, Gerente de Solu\u00e7\u00f5es da HP no M\u00e9xico<\/strong>.<\/p>\n<h3>O desafio narrativo da HP<\/h3>\n<p>Se, por um lado, existe a oportunidade de se reinventar como companhia e trazer mais valor agregado, h\u00e1 tamb\u00e9m o desafio de comunicar isso ao mercado. No caso espec\u00edfico da ideia de experi\u00eancia do colaborador, barreiras culturais precisam ser quebradas, como explica <strong>Armando Halbinger, CMO da HP para Norte Latam<\/strong>. \u201cO grande desafio das empresas hoje n\u00e3o \u00e9 apenas tecnol\u00f3gico, mas narrativo. \u00c9 mostrar, especialmente para l\u00edderes e colaboradores, que o trabalho pode, e deve, ser mais do que um conjunto de tarefas repetitivas. Como disse um CIO recentemente, o papel do l\u00edder moderno \u00e9 empreender dentro da pr\u00f3pria organiza\u00e7\u00e3o, transformando frustra\u00e7\u00f5es t\u00edpicas dos empregados, tarefas mon\u00f3tonas, processos lentos, burocracia em experi\u00eancias mais leves e criativas.\u201d<\/p>\n<p>Ainda de acordo com Armando, gra\u00e7as \u00e0 tecnologia e \u00e0 Intelig\u00eancia Artificial, aquilo que antes era chato pode se tornar divertido e inspirador. \u201cEsse conceito tamb\u00e9m pode se estender para outras \u00e1reas. Em nosso \u00faltimo an\u00fancio, por exemplo, mostramos como uma simples tarefa escolar de matem\u00e1tica pode ganhar vida com o uso de uma impressora: n\u00fameros se transformam em cores, imagens e hist\u00f3rias. O mesmo princ\u00edpio vale para o mundo corporativo \u2014 com as ferramentas certas, o trabalho pode ser um espa\u00e7o de aprendizado, descoberta e significado.\u201d<\/p>\n<aside>\n<h2>Leia tamb\u00e9m<\/h2>\n<\/aside>\n<aside>\n<h2>Escolhas do editor<\/h2>\n<\/aside>\n<div class=\"follow-us\">Siga o canal da <a href=\"https:\/\/whatsapp.com\/channel\/0029Va9gQKwBFLgM96cJnu0u\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" title=\"Grupo da Forbes no WhatsApp\">Forbes<\/a> no WhatsApp e receba as principais not\u00edcias de empreendedorismo, carreira, tecnologia, agro e lifestyle.<\/div>\n<\/p><\/div>\n<p><script data-debloat-delay=\"1\" type=\"text\/debloat-script\">\n\t\t\t\t(function(d, s, id){\n\t\t\t\t\tvar js, fjs = d.getElementsByTagName(s)[0];\n\t\t\t\t\tif (d.getElementById(id)) return;\n\t\t\t\t\tjs = d.createElement(s); js.id = id;\n\t\t\t\t\tjs.src = \"\/\/connect.facebook.net\/pt_BR\/sdk.js#xfbml=1&version=v2.9\";\n\t\t\t\t\tfjs.parentNode.insertBefore(js, fjs);\n\t\t\t\t}(document, 'script', 'facebook-jssdk'));\n\t\t\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/forbes.com.br\/carreira\/2025\/10\/por-que-a-hp-quer-que-o-trabalho-deixe-de-parecer-trabalho\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] &#13; &#13;Carlos F. Cort\u00e9s, presidente da HP no M\u00e9xico: uso da tecnologia a favor da experi\u00eancia do colaborador&#13; Acessibilidade &#13; L&#13; L&#13; A-&#13; A+&#13; &#13; \u25d0&#13; &#13; Criada em uma garagem na cidade de Palo Alto, na Calif\u00f3rnia, em 1939, a HP, acr\u00f4nimo dos sobrenomes dos amigos William \u201cBill\u201d Hewlett e David \u201cDave\u201d Packard, &#8230; <a title=\"Por Que a HP Quer Que o Trabalho Deixe de Parecer Trabalho\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/10\/por-que-a-hp-quer-que-o-trabalho-deixe-de-parecer-trabalho-2\/\" aria-label=\"Read more about Por Que a HP Quer Que o Trabalho Deixe de Parecer Trabalho\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":87897,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1964],"tags":[],"class_list":["post-87896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-e-sucesso-dicas-para-carreira"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/1760083884_CarlosHP-1200x675.jpg?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/1760083884_CarlosHP-1200x675.jpg?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/1760083884_CarlosHP-1200x675.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/1760083884_CarlosHP-1200x675.jpg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/1760083884_CarlosHP-1200x675.jpg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/1760083884_CarlosHP-1200x675.jpg?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/1760083884_CarlosHP-1200x675.jpg?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/1760083884_CarlosHP-1200x675.jpg?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] &#13; &#13;Carlos F. Cort\u00e9s, presidente da HP no M\u00e9xico: uso da tecnologia a favor da experi\u00eancia do colaborador&#13; Acessibilidade &#13; L&#13; L&#13; A-&#13; A+&#13; &#13; \u25d0&#13; &#13; Criada em uma garagem na cidade de Palo Alto, na Calif\u00f3rnia, em 1939, a HP, acr\u00f4nimo dos sobrenomes dos amigos William \u201cBill\u201d Hewlett e David \u201cDave\u201d Packard,&hellip;","jetpack-related-posts":[{"id":87887,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/09\/por-que-a-hp-quer-que-o-trabalho-deixe-de-parecer-trabalho\/","url_meta":{"origin":87896,"position":0},"title":"Por Que a HP Quer Que o Trabalho Deixe de Parecer Trabalho","author":"ismaelcolosi.com.br","date":"9 de October de 2025","format":false,"excerpt":"[ad_1] \r \r Carlos F. Cort\u00e9s, presidente da HP no M\u00e9xico: uso da tecnologia a favor da experi\u00eancia do colaborador\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r Criada em uma garagem na cidade de Palo Alto, na Calif\u00f3rnia, em 1939, a HP, acr\u00f4nimo dos sobrenomes dos amigos William\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/CarlosHP-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/CarlosHP-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/CarlosHP-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/CarlosHP-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/CarlosHP-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":86975,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/08\/08\/podcast-work-in-progress-joga-luz-sobre-o-futuro-do-trabalho\/","url_meta":{"origin":87896,"position":1},"title":"Podcast \u2018Work in Progress\u2019 joga luz sobre o futuro do trabalho","author":"ismaelcolosi.com.br","date":"8 de August de 2025","format":false,"excerpt":"[ad_1] Da reda\u00e7\u00e3oi Da reda\u00e7\u00e3o 08\/08\/2025 - 17:45 Em um mundo em que o trabalho muda mais r\u00e1pido do que as organiza\u00e7\u00f5es conseguem acompanhar, o novo podcast Work in Progress chega com a proposta de debater \u2014 com profundidade e praticidade \u2014 as principais tend\u00eancias que est\u00e3o moldando o presente\u2026","rel":"","context":"In &quot;Empregos - Classificados&quot;","block_context":{"text":"Empregos - Classificados","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/08\/podcast-work-in-progress.jpg?fit=960%2C540&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/08\/podcast-work-in-progress.jpg?fit=960%2C540&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/08\/podcast-work-in-progress.jpg?fit=960%2C540&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/08\/podcast-work-in-progress.jpg?fit=960%2C540&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":89301,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2026\/02\/26\/ia-acelera-demissoes-globais-e-pressiona-mercado-de-trabalho\/","url_meta":{"origin":87896,"position":2},"title":"IA Acelera Demiss\u00f5es Globais e Pressiona Mercado de Trabalho","author":"ismaelcolosi.com.br","date":"26 de February de 2026","format":false,"excerpt":"[ad_1] As preocupa\u00e7\u00f5es de investidores e economistas de que a intelig\u00eancia artificial possa transformar radicalmente setores estabelecidos est\u00e3o se intensificando. O Goldman Sachs alertou na ter\u00e7a-feira (23) que a ado\u00e7\u00e3o acelerada de IA pode elevar o desemprego nos Estados Unidos neste ano, com perdas de postos de trabalho j\u00e1 surgindo\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2026\/02\/demissao-ia-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2026\/02\/demissao-ia-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2026\/02\/demissao-ia-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2026\/02\/demissao-ia-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2026\/02\/demissao-ia-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":85089,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/05\/02\/mexico-vai-reduzir-jornada-de-trabalho-para-40-horas-semanais\/","url_meta":{"origin":87896,"position":3},"title":"M\u00e9xico vai reduzir jornada de trabalho para 40 horas semanais","author":"ismaelcolosi.com.br","date":"2 de May de 2025","format":false,"excerpt":"[ad_1] \r \r \r \r Atualmente, a carga hor\u00e1ria no pa\u00eds \u00e9 de 48 horas por semana \r \r \r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 O governo do M\u00e9xico vai reduzir gradualmente a jornada semanal padr\u00e3o para 40 horas, afirmou o ministro do Trabalho e\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-og-1030x438.webp?fit=1030%2C438&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-og-1030x438.webp?fit=1030%2C438&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-og-1030x438.webp?fit=1030%2C438&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-og-1030x438.webp?fit=1030%2C438&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":85783,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/05\/28\/agencia-da-onu-para-o-trabalho-reduz-previsao-de-empregos-globais-em-meio-a-desaceleracao-economica\/","url_meta":{"origin":87896,"position":4},"title":"Ag\u00eancia da ONU para o Trabalho Reduz Previs\u00e3o de Empregos Globais em Meio \u00c0 Desacelera\u00e7\u00e3o Econ\u00f4mica","author":"ismaelcolosi.com.br","date":"28 de May de 2025","format":false,"excerpt":"[ad_1] \r \r \r \r Cerca de 53 milh\u00f5es de empregos ser\u00e3o criados este ano, 7 milh\u00f5es a menos do que se pensava anteriormente, segundo a Organiza\u00e7\u00e3o Internacional do Trabalho \r \r \r \r Getty Images\r Segundo a Organiza\u00e7\u00e3o Internacional do Trabalho, milh\u00f5es de empregos em 71 pa\u00edses ligados ao\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/carreira-organizacao-internacional-do-trabalho-getty-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/carreira-organizacao-internacional-do-trabalho-getty-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/carreira-organizacao-internacional-do-trabalho-getty-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/carreira-organizacao-internacional-do-trabalho-getty-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/carreira-organizacao-internacional-do-trabalho-getty-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":59870,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/13\/por-que-milhoes-de-brasileiros-estao-pedindo-demissao\/","url_meta":{"origin":87896,"position":5},"title":"Por que milh\u00f5es de brasileiros est\u00e3o pedindo demiss\u00e3o?","author":"ismaelcolosi.com.br","date":"13 de August de 2024","format":false,"excerpt":"[ad_1] \u00a0 Acessibilidade L L A- A+ \u25d0 \u00a0 Al\u00e9m da insatisfa\u00e7\u00e3o com o sal\u00e1rio, a falta de reconhecimento, problemas com o chefe e quest\u00f5es \u00e9ticas do trabalho est\u00e3o entre as principais motiva\u00e7\u00f5es para os pedidos de demiss\u00e3o dos brasileiros, mostra uma pesquisa divulgada esta semana pelo MTE (Minist\u00e9rio do\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/carreira-demissao-mudanca-de-emprego-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/carreira-demissao-mudanca-de-emprego-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/carreira-demissao-mudanca-de-emprego-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/carreira-demissao-mudanca-de-emprego-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-mRG","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/87896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=87896"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/87896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/87897"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=87896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=87896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=87896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}