{"id":87892,"date":"2025-10-09T16:50:09","date_gmt":"2025-10-09T19:50:09","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/09\/nivel-de-ocupacao-e-menor-que-o-registrado-em-2010\/"},"modified":"2025-10-09T16:50:09","modified_gmt":"2025-10-09T19:50:09","slug":"nivel-de-ocupacao-e-menor-que-o-registrado-em-2010","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/09\/nivel-de-ocupacao-e-menor-que-o-registrado-em-2010\/","title":{"rendered":"N\u00edvel de Ocupa\u00e7\u00e3o \u00c9 Menor Que o Registrado em 2010"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<figure class=\"destaque wp-caption\">&#13;<br \/>\n\t\t<img data-recalc-dims=\"1\" width=\"678\" height=\"452\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2025\/10\/ocupacao-censo-2022-populacao-768x512.jpg?resize=678%2C452&#038;ssl=1\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"pessoas na rua\" decoding=\"async\" fetchpriority=\"high\"\/>\t\t<\/p>\n<p>T\u00e2nia R\u00eago\/Ag\u00eancia Brasil<\/p>\n<p>&#13;<figcaption class=\"wp-caption-text\">Nas duas edi\u00e7\u00f5es da pesquisa, a maioria dos trabalhadores recebia entre 1 e 5 sal\u00e1rios m\u00ednimos, propor\u00e7\u00e3o que subiu de 54% para 57%, entre 2010 e 2022<\/figcaption>&#13;<br \/>\n\t<\/figure>\n<div class=\"accessibility\">\n<p>Acessibilidade<\/p>\n<p>&#13;<br \/>\n\t\t\t<button onclick=\"alterFont1()\" id=\"btn1\" class=\"btn\">L<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFont2()\" id=\"btn2\" class=\"btn\" style=\"font-family:Merriweather\">L<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFontSmallerSize()\" id=\"btn3\" class=\"btn\">A-<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFontBiggerSize()\" id=\"btn4\" class=\"btn\">A+<\/button>&#13;<br \/>\n\t\t\t<!--<button onclick='alterFontBolder()' id='btn5' class=\"btn\" >B<\/button>-->&#13;<br \/>\n\t\t\t<button onclick=\"alterBackground()\" id=\"btn6\" class=\"btn\">\u25d0<\/button>&#13;<br \/>\n\t\t\t<!--<button onclick='clean()' id='btn7' class=\"btn\" >Limpar<\/button>-->&#13;\n\t\t<\/p>\n<\/p><\/div>\n<p>O n\u00edvel de ocupa\u00e7\u00e3o da popula\u00e7\u00e3o brasileira chegou a<strong> 53,3%<\/strong> em 2022, de acordo com os dados do Censo. Isso significa que pouco mais da metade das pessoas com 14 anos de idade ou mais estava trabalhando quando a pesquisa foi realizada. A propor\u00e7\u00e3o \u00e9 um pouco menor do que a verificada no Censo anterior, realizado em 2010, quando 55,5% das pessoas a partir desta idade estavam ocupadas.<\/p>\n<p>\u201cEm 2010, a economia estava mais aquecida. J\u00e1 em 2022, a gente estava saindo da pandemia. Tem um movimento de recupera\u00e7\u00e3o em 2022, mas ainda n\u00e3o estava plenamente recuperada a economia\u201d, explica o analista do IBGE Jo\u00e3o Hallack Neto.<\/p>\n<aside>\n<h2>Leia tamb\u00e9m<\/h2>\n<\/aside>\n<p>Os dados do Censo relativos a trabalho e rendimentos foram divulgados nesta quinta-feira (9) pelo Instituto Brasileiro de Geografia e Estat\u00edstica e se referem a respostas dadas por cerca de 10% da popula\u00e7\u00e3o, selecionada de forma aleat\u00f3ria para compor uma amostra, que respondeu um question\u00e1rio mais completo do que as quest\u00f5es b\u00e1sicas aplicadas a todas as pessoas.<\/p>\n<p>Eles mostram ainda que 11,1% dos adolescentes entre 14 e 17 anos j\u00e1 exerciam algum tipo de trabalho no momento da pesquisa. Na outra ponta, 14,9% das pessoas com 65 anos ou mais tamb\u00e9m trabalhavam.<\/p>\n<h2>Renda<\/h2>\n<p>Em contrapartida, os trabalhadores brasileiros recebiam, em 2022, R$ 2.851 por m\u00eas, em m\u00e9dia, mas 35,3% das pessoas tinha remunera\u00e7\u00e3o de, no m\u00e1ximo, 1 sal\u00e1rio m\u00ednimo, o que na \u00e9poca equivalia a R$1.212. Neste quesito, houve um ligeiro avan\u00e7o entre os anos, j\u00e1 que a propor\u00e7\u00e3o no Censo de 2010 foi 36,4%.<\/p>\n<p>Nas duas edi\u00e7\u00f5es da pesquisa, a maioria dos trabalhadores recebia entre 1 e 5 sal\u00e1rios m\u00ednimos, propor\u00e7\u00e3o que subiu de 54% para 57%, entre 2010 e 2022. Por outro lado, a parcela de pessoas com rendimentos provenientes do trabalho superiores a 5 sal\u00e1rios m\u00ednimos caiu, de 9,6% para 7,6%.<\/p>\n<p>Ainda de acordo com o Censo, o rendimento proveniente do trabalho era respons\u00e1vel por 75,5% da renda mensal domiciliar, enquanto fontes como aposentaria, pens\u00e3o, benef\u00edcios de programas sociais do governo e alugu\u00e9is correspondiam aos outros 24,5%.<\/p>\n<p>A rela\u00e7\u00e3o entre o n\u00edvel educacional e a remunera\u00e7\u00e3o tamb\u00e9m foi comprovada: trabalhadores com ensino superior completo recebiam, em m\u00e9dia, R$5.796, cerca de R$3.500 a mais do que quem tinha completado apenas o ensino m\u00e9dio, popula\u00e7\u00e3o com renda m\u00e9dia de R$2.291 mensais.<\/p>\n<h2>Trabalho<\/h2>\n<p>Algumas mudan\u00e7as no mercado de trabalho tamb\u00e9m apareceram na pesquisa. Em 2022, a popula\u00e7\u00e3o ocupada como empregados somou 69,2%, quase 5 pontos percentuais a menos do que em 2010. J\u00e1 os trabalhadores por conta pr\u00f3pria somavam 26,7%, um aumento de mais de 4 pontos na compara\u00e7\u00e3o com 2010, quando eles perfaziam 22,4%. Apesar da propor\u00e7\u00e3o de empregadores ser bem menor, tamb\u00e9m houve aumento entre os anos, de 2,1% para 3,3%<\/p>\n<p>Entre os empregados, a maioria atuava no setor privado com carteira assinada, em 2022: 56,3%. Em seguida, vem os trabalhadores sem carteira do setor privado, que somavam 18,5% e os militares e estatut\u00e1rios, 13,7%.<\/p>\n<h2>Regi\u00f5es<\/h2>\n<p>A pesquisa tamb\u00e9m identificou algumas diferen\u00e7as regionais. Quanto ao n\u00edvel de ocupa\u00e7\u00e3o, por exemplo, a m\u00e9dia brasileira de 53,3% foi superada nas regi\u00f5es Sudeste e Centro-Oeste e no Sul, onde foi verificada a maior propor\u00e7\u00e3o: 60,3%. J\u00e1 no Norte e Nordeste, menos da metade da popula\u00e7\u00e3o com mais de 14 anos estava ocupada no momento da pesquisa: 48,4% e 45,6%, respectivamente.<\/p>\n<p>Essa desigualdade tamb\u00e9m apareceu nos rendimentos obtidos com o trabalho. No Centro-Oeste, essa renda representava 80,6% do total de rendimentos declarados pelos domic\u00edlios, 12,8 pontos percentuais a mais do que a propor\u00e7\u00e3o de 67,9% verificada no Nordeste. Nas outras tr\u00eas regi\u00f5es, a rela\u00e7\u00e3o ficou na casa dos 76%. J\u00e1 o rendimento m\u00e9dio mensal de todos os trabalhos variou de R$ 2.015 no Nordeste, a R$ 3.292 no Centro-Oeste, ficando em R$ 2.238 na Regi\u00e3o Norte, R$ 3.154 na Regi\u00e3o Sudeste e R$ 3.190 no Sul.<\/p>\n<p>\u201cDo total de munic\u00edpios, 520 deles apresentaram rendimento nominal abaixo de um sal\u00e1rio m\u00ednimo, enquanto 19 deles possuem um indicador acima de quatro sal\u00e1rios m\u00ednimos. Ilustrando a desigualdade t\u00e3o grande que a gente tem disseminada pela hist\u00f3ria, os 10 munic\u00edpios com menores rendimentos situavam-se na Regi\u00e3o Nordeste. Por outro lado, 10 munic\u00edpios com maiores rendimentos m\u00e9dios estavam nas regi\u00f5es Sul e Sudeste\u201d, complementa o analista do IBGE Jo\u00e3o Hallack Neto.<\/p>\n<aside>\n<h2>Escolhas do editor<\/h2>\n<\/aside>\n<div class=\"follow-us\">Siga o canal da <a href=\"https:\/\/whatsapp.com\/channel\/0029Va9gQKwBFLgM96cJnu0u\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" title=\"Grupo da Forbes no WhatsApp\">Forbes<\/a> no WhatsApp e receba as principais not\u00edcias de empreendedorismo, carreira, tecnologia, agro e lifestyle.<\/div>\n<\/p><\/div>\n<p><script data-debloat-delay=\"1\" type=\"text\/debloat-script\">\n\t\t\t\t(function(d, s, id){\n\t\t\t\t\tvar js, fjs = d.getElementsByTagName(s)[0];\n\t\t\t\t\tif (d.getElementById(id)) return;\n\t\t\t\t\tjs = d.createElement(s); js.id = id;\n\t\t\t\t\tjs.src = \"\/\/connect.facebook.net\/pt_BR\/sdk.js#xfbml=1&version=v2.9\";\n\t\t\t\t\tfjs.parentNode.insertBefore(js, fjs);\n\t\t\t\t}(document, 'script', 'facebook-jssdk'));\n\t\t\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/forbes.com.br\/carreira\/2025\/10\/censo-2022-nivel-de-ocupacao-e-menor-que-o-registrado-em-2010\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] &#13; T\u00e2nia R\u00eago\/Ag\u00eancia Brasil &#13;Nas duas edi\u00e7\u00f5es da pesquisa, a maioria dos trabalhadores recebia entre 1 e 5 sal\u00e1rios m\u00ednimos, propor\u00e7\u00e3o que subiu de 54% para 57%, entre 2010 e 2022&#13; Acessibilidade &#13; L&#13; L&#13; A-&#13; A+&#13; &#13; \u25d0&#13; &#13; O n\u00edvel de ocupa\u00e7\u00e3o da popula\u00e7\u00e3o brasileira chegou a 53,3% em 2022, de acordo &#8230; <a title=\"N\u00edvel de Ocupa\u00e7\u00e3o \u00c9 Menor Que o Registrado em 2010\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/09\/nivel-de-ocupacao-e-menor-que-o-registrado-em-2010\/\" aria-label=\"Leia mais sobre N\u00edvel de Ocupa\u00e7\u00e3o \u00c9 Menor Que o Registrado em 2010\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":87893,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1964],"tags":[],"class_list":["post-87892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-e-sucesso-dicas-para-carreira"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/ocupacao-censo-2022-populacao-1200x675.jpg?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/ocupacao-censo-2022-populacao-1200x675.jpg?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/ocupacao-censo-2022-populacao-1200x675.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/ocupacao-censo-2022-populacao-1200x675.jpg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/ocupacao-censo-2022-populacao-1200x675.jpg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/ocupacao-censo-2022-populacao-1200x675.jpg?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/ocupacao-censo-2022-populacao-1200x675.jpg?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/ocupacao-censo-2022-populacao-1200x675.jpg?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] &#13; T\u00e2nia R\u00eago\/Ag\u00eancia Brasil &#13;Nas duas edi\u00e7\u00f5es da pesquisa, a maioria dos trabalhadores recebia entre 1 e 5 sal\u00e1rios m\u00ednimos, propor\u00e7\u00e3o que subiu de 54% para 57%, entre 2010 e 2022&#13; Acessibilidade &#13; L&#13; L&#13; A-&#13; A+&#13; &#13; \u25d0&#13; &#13; O n\u00edvel de ocupa\u00e7\u00e3o da popula\u00e7\u00e3o brasileira chegou a 53,3% em 2022, de acordo&hellip;","jetpack-related-posts":[{"id":51522,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/28\/linkedin-disponibiliza-75-cursos-gratuitos\/","url_meta":{"origin":87892,"position":0},"title":"LinkedIn disponibiliza 75 cursos gratuitos","author":"ismaelcolosi.com.br","date":"28 de Maio de 2024","format":false,"excerpt":"[ad_1] Em comemora\u00e7\u00e3o aos 75 milh\u00f5es de usu\u00e1rios no Brasil, o LinkedIn est\u00e1 disponibilizando 75 cursos gratuitos na plataforma. Acessibilidade L L A- A+ \u25d0 As aulas abrangem soft e hard skills e envolvem intelig\u00eancia artificial, desenvolvimento de carreira, ferramentas digitais, neg\u00f3cios, lideran\u00e7a e comunica\u00e7\u00e3o. Tamb\u00e9m h\u00e1 cursos voltados para\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreira-linkedin-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreira-linkedin-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreira-linkedin-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/carreira-linkedin-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":75034,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/04\/novonor-indica-novo-presidente-executivo-para-braskem\/","url_meta":{"origin":87892,"position":1},"title":"Novonor Indica Novo Presidente-Executivo para Braskem","author":"ismaelcolosi.com.br","date":"4 de Novembro de 2024","format":false,"excerpt":"[ad_1] Reprodu\u00e7\u00e3o\/LinkedInA nomea\u00e7\u00e3o de Roberto Ramos ser\u00e1 apresentada formalmente \u00e0 aprova\u00e7\u00e3o do conselho de administra\u00e7\u00e3o da Braskem Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r A Braskem anunciou nesta segunda-feira (4) que o acionista controlador do grupo, Novonor, indicou Roberto Paraiso Ramos para ocupar o lugar de Roberto Bischoff\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/carreira-Roberto-Paraiso-Ramos-braskem-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/carreira-Roberto-Paraiso-Ramos-braskem-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/carreira-Roberto-Paraiso-Ramos-braskem-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/carreira-Roberto-Paraiso-Ramos-braskem-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/carreira-Roberto-Paraiso-Ramos-braskem-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":75878,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/08\/ibge-diz-que-ribeirao-tem-menos-favelas-do-que-afirma-a-prefeitura\/","url_meta":{"origin":87892,"position":2},"title":"IBGE diz que Ribeir\u00e3o tem menos favelas do que afirma a prefeitura","author":"ismaelcolosi.com.br","date":"8 de Novembro de 2024","format":false,"excerpt":"[ad_1] Dados do Censo 2022 divulgados nesta sexta-feira,8 de novembro, pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) revelou uma discrep\u00e2ncia entre o n\u00famero de favelas existentes em Ribeir\u00e3o Preto, divulgado pela prefeitura e o mais recente levantamento feito pelo Instituto. Segundo dados do Plano Municipal de Sa\u00fade para o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/imagem-420.jpg?fit=700%2C450&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/imagem-420.jpg?fit=700%2C450&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/imagem-420.jpg?fit=700%2C450&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/imagem-420.jpg?fit=700%2C450&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":87889,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/09\/ibge-mostra-queda-no-numero-de-brasileiros-que-trabalham-de-casa\/","url_meta":{"origin":87892,"position":3},"title":"IBGE Mostra Queda no N\u00famero de Brasileiros Que Trabalham de Casa","author":"ismaelcolosi.com.br","date":"9 de Outubro de 2025","format":false,"excerpt":"[ad_1] \r Adamkaz\/Getty Images\r N\u00famero de pessoas que fazem home office caiu de 18 milh\u00f5es em 2010 para 14 milh\u00f5es em 2022\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r De acordo com dados do Censo divulgados nesta quinta-feira (9) pelo IBGE (Instituto Brasileiro de Geografia e Estat\u00edstica), 16,9%\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/carreira-home-office-trabalho-remoto-getty-images-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/carreira-home-office-trabalho-remoto-getty-images-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/carreira-home-office-trabalho-remoto-getty-images-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/carreira-home-office-trabalho-remoto-getty-images-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/carreira-home-office-trabalho-remoto-getty-images-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":31501,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/22\/top-10-estados-mais-populosos-do-brasil-censo-2022\/","url_meta":{"origin":87892,"position":4},"title":"Top 10 estados mais populosos do Brasil (Censo 2022)","author":"ismaelcolosi.com.br","date":"22 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Os estados mais populosos do Brasil dessa lista top 10, somam mais de 151 milh\u00f5es de habitantes. Os dados divulgados pelo IBGE, s\u00e3o do Censo 2022 disponbilizadas em junho de 2023, que somando todas as unidades federativas, a popula\u00e7\u00e3o brasileira est\u00e1 em 203.062.512 pessoas. Anteriormente a isso, no \u00faltimo\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/estados-mais-populosos-do-brasil.jpg?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/estados-mais-populosos-do-brasil.jpg?fit=1200%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/estados-mais-populosos-do-brasil.jpg?fit=1200%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/estados-mais-populosos-do-brasil.jpg?fit=1200%2C801&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/estados-mais-populosos-do-brasil.jpg?fit=1200%2C801&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":50919,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/21\/brasileiro-cofundador-do-instagram-e-novo-executivo-da-rival-da-openai\/","url_meta":{"origin":87892,"position":5},"title":"Brasileiro cofundador do Instagram \u00e9 novo executivo da rival da OpenAI","author":"ismaelcolosi.com.br","date":"21 de Maio de 2024","format":false,"excerpt":"[ad_1] Mike Krieger est\u00e1 na lista Under 30 de 2015 da Forbes USA Acessibilidade L L A- A+ \u25d0 Mike Krieger nasceu em S\u00e3o Paulo em 1986. Aos 18 anos, o jovem brasileiro foi cursar ci\u00eancias da computa\u00e7\u00e3o na Universidade de Stanford (Calif\u00f3rnia), onde conheceu Kevin Systrom. Juntos, em 2010,\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Mike-Krieger-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Mike-Krieger-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Mike-Krieger-1024x683.png?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Mike-Krieger-1024x683.png?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-mRC","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/87892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=87892"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/87892\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/87893"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=87892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=87892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=87892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}