{"id":87861,"date":"2025-10-08T05:20:10","date_gmt":"2025-10-08T08:20:10","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/08\/o-que-o-mundo-pode-aprender-com-o-brasil\/"},"modified":"2025-10-08T05:20:10","modified_gmt":"2025-10-08T08:20:10","slug":"o-que-o-mundo-pode-aprender-com-o-brasil","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/08\/o-que-o-mundo-pode-aprender-com-o-brasil\/","title":{"rendered":"o Que o Mundo Pode Aprender com o Brasil"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<figure class=\"destaque wp-caption\">&#13;<br \/>\n\t\t<img data-recalc-dims=\"1\" width=\"678\" height=\"452\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2025\/10\/Otimismo-768x512.png?resize=678%2C452&#038;ssl=1\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" decoding=\"async\" fetchpriority=\"high\"\/>\t\t&#13;<figcaption class=\"wp-caption-text\"\/>&#13;<br \/>\n\t<\/figure>\n<div class=\"accessibility\">\n<p>Acessibilidade<\/p>\n<p>&#13;<br \/>\n\t\t\t<button onclick=\"alterFont1()\" id=\"btn1\" class=\"btn\">L<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFont2()\" id=\"btn2\" class=\"btn\" style=\"font-family:Merriweather\">L<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFontSmallerSize()\" id=\"btn3\" class=\"btn\">A-<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFontBiggerSize()\" id=\"btn4\" class=\"btn\">A+<\/button>&#13;<br \/>\n\t\t\t<!--<button onclick='alterFontBolder()' id='btn5' class=\"btn\" >B<\/button>-->&#13;<br \/>\n\t\t\t<button onclick=\"alterBackground()\" id=\"btn6\" class=\"btn\">\u25d0<\/button>&#13;<br \/>\n\t\t\t<!--<button onclick='clean()' id='btn7' class=\"btn\" >Limpar<\/button>-->&#13;\n\t\t<\/p>\n<\/p><\/div>\n<p>Recentemente, lan\u00e7amos uma pesquisa global no <strong>LinkedIn<\/strong> para entender como diferentes pa\u00edses est\u00e3o encarando o impacto da <strong>Intelig\u00eancia Artificial no mundo do trabalho<\/strong>. O Brasil apareceu em destaque: somos os mais <strong>entusiasmados<\/strong>, confiantes e preparados para experimentar a tecnologia no dia a dia. Para alguns, isso pode soar previs\u00edvel. Afinal, n\u00e3o \u00e9 de hoje que o brasileiro \u00e9 visto como otimista por natureza.<\/p>\n<p>O Brasil costuma aparecer entre os pa\u00edses com maior n\u00famero de pessoas que se declaram <strong>felizes com a vida<\/strong>, mesmo em per\u00edodos de crise. Mais recentemente, o <strong>Relat\u00f3rio Mundial da Felicidade<\/strong> 2025, divulgado pela <strong>ONU<\/strong>, apontou que o Brasil subiu oito posi\u00e7\u00f5es no ranking global, alcan\u00e7ando a <strong>36\u00aa coloca\u00e7\u00e3o<\/strong> \u2013 o segundo pa\u00eds mais bem posicionado da Am\u00e9rica do Sul, atr\u00e1s apenas do Chile.<\/p>\n<aside>\n<h2>Leia tamb\u00e9m<\/h2>\n<\/aside>\n<p>Nos esportes, a confian\u00e7a no \u2018vai dar certo\u2019 \u00e9 quase um <strong>patrim\u00f4nio cultural<\/strong>, repetido a cada Copa do Mundo ou Olimp\u00edada. E at\u00e9 no mundo dos neg\u00f3cios esse tra\u00e7o se repete: levantamentos da <strong>PwC e Deloitte<\/strong> j\u00e1 apontaram que os executivos brasileiros s\u00e3o mais confiantes no <strong>crescimento de suas<\/strong> empresas do que seus pares internacionais.<\/p>\n<p>Mas o que significa essa confian\u00e7a? Parte dela est\u00e1 na <strong>sociabilidade, na criatividade e na resili\u00eancia<\/strong> que \u00e9 inerente \u00e0 nossa cultura, a nossa forma de ser e de encarar a vida. Quando falo com executivos de fora do Brasil, eles sempre destacam a \u2018<strong>energia brasileira<\/strong>\u2018, algo que \u00e9 admirado internacionalmente. Mas de onde que isso vem?<\/p>\n<p>O otimismo e a resili\u00eancia do brasileiro v\u00eam de uma combina\u00e7\u00e3o de <strong>fatores hist\u00f3ricos<\/strong>, incluindo o forte senso de comunidade, criatividade para enfrentar desafios, a capacidade de se adaptar e a esperan\u00e7a no futuro, mesmo em tempos dif\u00edceis. E temos tamb\u00e9m outro fator fundamental que nos caracteriza: a <strong>cultura empreendedora<\/strong>.<\/p>\n<p>No Brasil, existem hoje mais de <strong>47 milh\u00f5es de pessoas que empreendem<\/strong>, seja de maneira formal ou informal, e cerca de 18 mil startups, o que n\u00e3o \u00e9 apenas um reflexo da resili\u00eancia e do positivismo que o brasileiro tem para os neg\u00f3cios e para assumir que um empreendimento vai ter sucesso, \u00e9 a nossa forma de transformar otimismo em capacidade real de promover mudan\u00e7as.<\/p>\n<p>Por isso, \u00e9 ineg\u00e1vel que essa disposi\u00e7\u00e3o para acreditar no futuro tem valor. Num mundo em transi\u00e7\u00e3o acelerada, marcado por novas tecnologias, crises globais e transforma\u00e7\u00f5es no trabalho, a confian\u00e7a de que \u00e9 poss\u00edvel se adaptar e aprender pode se tornar uma <strong>vantagem competitiva<\/strong>. A pesquisa do LinkedIn refor\u00e7a isso ao mostrar que 83% dos brasileiros acreditam que a IA pode melhorar sua rotina de trabalho e 84% consideram divertido experimentar a tecnologia, quando a m\u00e9dia global \u00e9 de 62% e 63%, respectivamente.<\/p>\n<p>\u00c9 justamente esse esp\u00edrito que destaca o Brasil no cen\u00e1rio global e revela <strong>li\u00e7\u00f5es valiosas<\/strong> que outros pa\u00edses podem aprender conosco. E essa forma de encarar as situa\u00e7\u00f5es n\u00e3o deve ser confundida com ingenuidade \u2013 \u00e9, na verdade, a express\u00e3o de uma cultura que insiste em imaginar um futuro melhor, mesmo diante de cen\u00e1rios complexos.<\/p>\n<p>Projetar confian\u00e7a no futuro n\u00e3o \u00e9 apenas um tra\u00e7o cultural, \u00e9 um <strong>ativo estrat\u00e9gico<\/strong>. Acredito que esta \u00e9 uma das principais contribui\u00e7\u00f5es do Brasil em um mundo que busca respostas em meio \u00e0 incertezas: transformar esperan\u00e7a em movimento, e movimento em transforma\u00e7\u00e3o.<\/p>\n<aside>\n<h2>Escolhas do editor<\/h2>\n<\/aside>\n<p><em>*Milton Beck, Diretor Geral do LinkedIn para Am\u00e9rica Latina e \u00c1frica<\/em><\/p>\n<p><em>Os artigos assinados s\u00e3o de responsabilidade exclusiva dos autores e n\u00e3o refletem, necessariamente, a opini\u00e3o de Forbes Brasil e de seus editores.<\/em><\/p>\n<div class=\"follow-us\">Siga o canal da <a href=\"https:\/\/whatsapp.com\/channel\/0029Va9gQKwBFLgM96cJnu0u\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" title=\"Grupo da Forbes no WhatsApp\">Forbes<\/a> no WhatsApp e receba as principais not\u00edcias de empreendedorismo, carreira, tecnologia, agro e lifestyle.<\/div>\n<\/p><\/div>\n<p><script data-debloat-delay=\"1\" type=\"text\/debloat-script\">\n\t\t\t\t(function(d, s, id){\n\t\t\t\t\tvar js, fjs = d.getElementsByTagName(s)[0];\n\t\t\t\t\tif (d.getElementById(id)) return;\n\t\t\t\t\tjs = d.createElement(s); js.id = id;\n\t\t\t\t\tjs.src = \"\/\/connect.facebook.net\/pt_BR\/sdk.js#xfbml=1&version=v2.9\";\n\t\t\t\t\tfjs.parentNode.insertBefore(js, fjs);\n\t\t\t\t}(document, 'script', 'facebook-jssdk'));\n\t\t\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/forbes.com.br\/coluna\/2025\/10\/otimismo-como-vantagem-competitiva-o-que-o-mundo-pode-aprender-com-o-brasil\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] &#13; &#13;&#13; Acessibilidade &#13; L&#13; L&#13; A-&#13; A+&#13; &#13; \u25d0&#13; &#13; Recentemente, lan\u00e7amos uma pesquisa global no LinkedIn para entender como diferentes pa\u00edses est\u00e3o encarando o impacto da Intelig\u00eancia Artificial no mundo do trabalho. O Brasil apareceu em destaque: somos os mais entusiasmados, confiantes e preparados para experimentar a tecnologia no dia a dia. &#8230; <a title=\"o Que o Mundo Pode Aprender com o Brasil\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/08\/o-que-o-mundo-pode-aprender-com-o-brasil\/\" aria-label=\"Leia mais sobre o Que o Mundo Pode Aprender com o Brasil\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":87862,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1964],"tags":[],"class_list":["post-87861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-e-sucesso-dicas-para-carreira"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Otimismo-1200x675.png?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Otimismo-1200x675.png?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Otimismo-1200x675.png?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Otimismo-1200x675.png?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Otimismo-1200x675.png?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Otimismo-1200x675.png?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Otimismo-1200x675.png?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Otimismo-1200x675.png?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] &#13; &#13;&#13; Acessibilidade &#13; L&#13; L&#13; A-&#13; A+&#13; &#13; \u25d0&#13; &#13; Recentemente, lan\u00e7amos uma pesquisa global no LinkedIn para entender como diferentes pa\u00edses est\u00e3o encarando o impacto da Intelig\u00eancia Artificial no mundo do trabalho. O Brasil apareceu em destaque: somos os mais entusiasmados, confiantes e preparados para experimentar a tecnologia no dia a dia.&hellip;","jetpack-related-posts":[{"id":76947,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/19\/vagas-de-empregos-na-microset-tecnologia-para-trabalhar-em-ribeirao-preto-sp-18\/","url_meta":{"origin":87861,"position":0},"title":"Vagas de empregos na Microset Tecnologia  para trabalhar em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"19 de Novembro de 2024","format":false,"excerpt":"Assistente de Service Desk lRibeir\u00e3o Preto - SPEfetivo Auxiliar Administrativo Ribeir\u00e3o Preto - SPEfetivo Auxiliar T\u00e9cnico de RedesRibeir\u00e3o Preto - SPEfetivo Microset Tecnologia Assistente de Service Desk lRibeir\u00e3o Preto - SPEfetivo V\u00eddeos","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732047822_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732047822_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732047822_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732047822_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732047822_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":82676,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/02\/07\/vagas-de-empregos-na-microset-tecnologia-para-trabalhar-em-ribeirao-preto-sp-23\/","url_meta":{"origin":87861,"position":1},"title":"Vagas de empregos na Microset Tecnologia  para trabalhar em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"7 de Fevereiro de 2025","format":false,"excerpt":"Assistente de Service Desk l Ribeir\u00e3o Preto - SPEfetivo Auxiliar T\u00e9cnico de Redes Ribeir\u00e3o Preto - SPEfetivo Gerente de Neg\u00f3cios - Campinas e regi\u00e3o Ribeir\u00e3o Preto - SPPessoa jur\u00eddica Microset Tecnologia Assistente de Service Desk l Ribeir\u00e3o Preto - SPEfetivo V\u00eddeos","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":51227,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/24\/conselho-da-petrobras-aprova-magda-chambriard-como-ceo\/","url_meta":{"origin":87861,"position":2},"title":"Conselho da Petrobras aprova Magda Chambriard como CEO","author":"ismaelcolosi.com.br","date":"24 de Maio de 2024","format":false,"excerpt":"[ad_1] \u00a0 Acessibilidade L L A- A+ \u25d0 A Petrobras informou que seu conselho de administra\u00e7\u00e3o aprovou nesta sexta-feira (24) Magda Chambriard como nova presidente-executiva e conselheira da companhia. Segundo fato relevante, Chambriard tomou posse em ambos os cargos nesta sexta-feira e passou a integrar o conselho imediatamente, n\u00e3o sendo\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Money_Magda-Chambriard_AgenciaBrasil-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Money_Magda-Chambriard_AgenciaBrasil-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Money_Magda-Chambriard_AgenciaBrasil-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Money_Magda-Chambriard_AgenciaBrasil-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":28608,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/16\/tereos-abre-500-vagas-para-safra\/","url_meta":{"origin":87861,"position":3},"title":"Tereos abre 500 vagas para safra","author":"ismaelcolosi.com.br","date":"16 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A Tereos, uma das l\u00edderes mundiais na produ\u00e7\u00e3o de a\u00e7\u00facar, etanol e bionergia, est\u00e1 com mais de 500 vagas de emprego abertas para a safra 2024\/25. As oportunidades s\u00e3o para as seis unidades industriais do grupo, localizadas na regi\u00e3o noroeste do Estado de S\u00e3o Paulo, e em todas as\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Tereos-Divulgacao-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Tereos-Divulgacao-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Tereos-Divulgacao-scaled.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Tereos-Divulgacao-scaled.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":76394,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/12\/vivara-anuncia-novo-ceo\/","url_meta":{"origin":87861,"position":4},"title":"Vivara Anuncia Novo CEO","author":"ismaelcolosi.com.br","date":"12 de Novembro de 2024","format":false,"excerpt":"[ad_1] Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r A Vivara informou que seu conselho de administra\u00e7\u00e3o elegeu o atual diretor de opera\u00e7\u00f5es, Icaro Borrello, para o cargo de presidente-executivo da companhia, em reuni\u00e3o realizada nesta ter\u00e7a-feira (11), conforme comunicado ao mercado. A decis\u00e3o segue-se \u00e0 ren\u00fancia do CEO\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-og-1030x438.webp?fit=1030%2C438&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-og-1030x438.webp?fit=1030%2C438&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-og-1030x438.webp?fit=1030%2C438&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-og-1030x438.webp?fit=1030%2C438&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":55226,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/01\/conselheira-da-vale-vera-marie-inkster-renuncia-ao-cargo\/","url_meta":{"origin":87861,"position":5},"title":"Conselheira da Vale Vera Marie Inkster renuncia ao cargo","author":"ismaelcolosi.com.br","date":"1 de Julho de 2024","format":false,"excerpt":"[ad_1] A mineradora Vale informou ao mercado em nota que Vera Marie Inkster apresentou sua ren\u00fancia ao cargo de membro do conselho de administra\u00e7\u00e3o da companhia nesta segunda-feira. Acessibilidade L L A- A+ \u25d0 Diante disso, a companhia afirmou que o colegiado \u201cest\u00e1 trabalhando em sua recomposi\u00e7\u00e3o e que, em\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Totem-com-logo-da-Vale-Foto-Washington-Alves-Reuters-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Totem-com-logo-da-Vale-Foto-Washington-Alves-Reuters-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Totem-com-logo-da-Vale-Foto-Washington-Alves-Reuters-1024x683.png?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Totem-com-logo-da-Vale-Foto-Washington-Alves-Reuters-1024x683.png?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-mR7","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/87861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=87861"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/87861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/87862"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=87861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=87861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=87861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}