{"id":87857,"date":"2025-10-08T05:07:47","date_gmt":"2025-10-08T08:07:47","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/08\/para-alem-das-tendencias\/"},"modified":"2025-10-08T05:07:47","modified_gmt":"2025-10-08T08:07:47","slug":"para-alem-das-tendencias","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/08\/para-alem-das-tendencias\/","title":{"rendered":"Para Al\u00e9m das Tend\u00eancias"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<figure class=\"destaque wp-caption\">&#13;<br \/>\n\t\t<img data-recalc-dims=\"1\" width=\"678\" height=\"452\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2025\/10\/Tamanho-site-Tech-9-1024x683.png?resize=678%2C452&#038;ssl=1\" class=\"attachment-large size-large wp-post-image\" alt=\"\" decoding=\"async\" fetchpriority=\"high\"\/>\t\t<\/p>\n<p>Foto: Divulga\u00e7\u00e3o<\/p>\n<p>&#13;<figcaption class=\"wp-caption-text\">Poliana Abreu, diretora de conte\u00fado e marketing da HSM e da Singularity Brazil<\/figcaption>&#13;<br \/>\n\t<\/figure>\n<div class=\"accessibility\">\n<p>Acessibilidade<\/p>\n<p>&#13;<br \/>\n\t\t\t<button onclick=\"alterFont1()\" id=\"btn1\" class=\"btn\">L<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFont2()\" id=\"btn2\" class=\"btn\" style=\"font-family:Merriweather\">L<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFontSmallerSize()\" id=\"btn3\" class=\"btn\">A-<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFontBiggerSize()\" id=\"btn4\" class=\"btn\">A+<\/button>&#13;<br \/>\n\t\t\t<!--<button onclick='alterFontBolder()' id='btn5' class=\"btn\" >B<\/button>-->&#13;<br \/>\n\t\t\t<button onclick=\"alterBackground()\" id=\"btn6\" class=\"btn\">\u25d0<\/button>&#13;<br \/>\n\t\t\t<!--<button onclick='clean()' id='btn7' class=\"btn\" >Limpar<\/button>-->&#13;\n\t\t<\/p>\n<\/p><\/div>\n<p>Vivemos uma era em que todos parecem obcecados por tend\u00eancias. Seja no notici\u00e1rio, nos eventos, na mesa de reuni\u00e3o, nos relat\u00f3rios de consultoria ou nas redes sociais, a pergunta que ecoa \u00e9: \u201cO que vem por a\u00ed?\u201d. Essa curiosidade \u00e9 leg\u00edtima e necess\u00e1ria. Afinal, antecipar mudan\u00e7as pode ser a diferen\u00e7a entre a sobreviv\u00eancia ou a obsolesc\u00eancia de uma organiza\u00e7\u00e3o. Mas talvez a quest\u00e3o mais estrat\u00e9gica seja outra: Estamos dedicando energia suficiente ao que n\u00e3o muda ou ao que n\u00e3o deveria mudar?<\/p>\n<p><a href=\"https:\/\/subrazil.com\/\" target=\"_blank\" rel=\"noopener\">A gest\u00e3o contempor\u00e2nea precisa ser ambidestra<\/a>: olhar, por um lado, para as transforma\u00e7\u00f5es, como a intelig\u00eancia artificial e seus impactos, e, por outro, preservar valores e pr\u00e1ticas que sustentam a ess\u00eancia das empresas e da lideran\u00e7a. Em outras palavras, equilibrar inova\u00e7\u00e3o com perman\u00eancia.<\/p>\n<p>A IA vai transformar processos, acelerar an\u00e1lises, automatizar tarefas, redesenhar profiss\u00f5es e criar estrat\u00e9gias e neg\u00f3cios. Mas ela n\u00e3o mudar\u00e1, e nem deve mudar, a import\u00e2ncia da confian\u00e7a, do pensamento cr\u00edtico, da empatia, da \u00e9tica e da capacidade humana de construir sentido coletivo. M\u00e1quinas podem aprender padr\u00f5es, mas apenas humanos podem criar prop\u00f3sitos.<\/p>\n<p>Esse olhar ampliado exige repert\u00f3rio. L\u00edderes que s\u00f3 correm atr\u00e1s da novidade se tornam ref\u00e9ns de modismos, enquanto aqueles que ignoram as mudan\u00e7as ficam paralisados. A virtude est\u00e1 em cultivar os dois movimentos: expandir a vis\u00e3o sobre o que pode ser reinventado e proteger a base que sustenta culturas, rela\u00e7\u00f5es e legados.<\/p>\n<p>Organiza\u00e7\u00f5es longevas sabem disso. Elas inovam sem abrir m\u00e3o de princ\u00edpios s\u00f3lidos. Preservam o que d\u00e1 identidade, ao mesmo tempo que testam novas fronteiras. Assim, garantem coer\u00eancia para atravessar as ondas tecnol\u00f3gicas e sociais que continuar\u00e3o a nos desafiar.<\/p>\n<p>Portanto, para al\u00e9m das tend\u00eancias, o convite \u00e9 exercitar uma lideran\u00e7a capaz de navegar com ambidestria: atentos ao futuro que se anuncia, mas firmes na ess\u00eancia que deve permanecer. Afinal, no mundo acelerado pela IA, ser\u00e1 a clareza sobre o que n\u00e3o muda que dar\u00e1 sentido ao que muda.<\/p>\n<p><a href=\"https:\/\/subrazil.com\/\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-716152 size-large\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2025\/10\/Singularity-Ed-134.pdf-1-1024x350.png?resize=1024%2C350&#038;ssl=1\" alt=\"\" width=\"1024\" height=\"350\"\/><\/a><\/p>\n<p>\u00a0<\/p>\n<p><em>*<strong>BrandVoice<\/strong> \u00e9 de responsabilidade exclusiva dos autores e n\u00e3o reflete, necessariamente, a opini\u00e3o da FORBES Brasil e de seus editores.<\/em><\/p>\n<\/p><\/div>\n<p><script data-debloat-delay=\"1\" type=\"text\/debloat-script\">\n\t\t\t\t(function(d, s, id){\n\t\t\t\t\tvar js, fjs = d.getElementsByTagName(s)[0];\n\t\t\t\t\tif (d.getElementById(id)) return;\n\t\t\t\t\tjs = d.createElement(s); js.id = id;\n\t\t\t\t\tjs.src = \"\/\/connect.facebook.net\/pt_BR\/sdk.js#xfbml=1&version=v2.9\";\n\t\t\t\t\tfjs.parentNode.insertBefore(js, fjs);\n\t\t\t\t}(document, 'script', 'facebook-jssdk'));\n\t\t\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/forbes.com.br\/carreira\/2025\/10\/para-alem-das-tendencias\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] &#13; Foto: Divulga\u00e7\u00e3o &#13;Poliana Abreu, diretora de conte\u00fado e marketing da HSM e da Singularity Brazil&#13; Acessibilidade &#13; L&#13; L&#13; A-&#13; A+&#13; &#13; \u25d0&#13; &#13; Vivemos uma era em que todos parecem obcecados por tend\u00eancias. Seja no notici\u00e1rio, nos eventos, na mesa de reuni\u00e3o, nos relat\u00f3rios de consultoria ou nas redes sociais, a pergunta &#8230; <a title=\"Para Al\u00e9m das Tend\u00eancias\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/08\/para-alem-das-tendencias\/\" aria-label=\"Leia mais sobre Para Al\u00e9m das Tend\u00eancias\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":87858,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1964],"tags":[],"class_list":["post-87857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-e-sucesso-dicas-para-carreira"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Tamanho-site-Tech-9-1200x675.png?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Tamanho-site-Tech-9-1200x675.png?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Tamanho-site-Tech-9-1200x675.png?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Tamanho-site-Tech-9-1200x675.png?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Tamanho-site-Tech-9-1200x675.png?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Tamanho-site-Tech-9-1200x675.png?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Tamanho-site-Tech-9-1200x675.png?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Tamanho-site-Tech-9-1200x675.png?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] &#13; Foto: Divulga\u00e7\u00e3o &#13;Poliana Abreu, diretora de conte\u00fado e marketing da HSM e da Singularity Brazil&#13; Acessibilidade &#13; L&#13; L&#13; A-&#13; A+&#13; &#13; \u25d0&#13; &#13; Vivemos uma era em que todos parecem obcecados por tend\u00eancias. Seja no notici\u00e1rio, nos eventos, na mesa de reuni\u00e3o, nos relat\u00f3rios de consultoria ou nas redes sociais, a pergunta&hellip;","jetpack-related-posts":[{"id":76947,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/19\/vagas-de-empregos-na-microset-tecnologia-para-trabalhar-em-ribeirao-preto-sp-18\/","url_meta":{"origin":87857,"position":0},"title":"Vagas de empregos na Microset Tecnologia  para trabalhar em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"19 de Novembro de 2024","format":false,"excerpt":"Assistente de Service Desk lRibeir\u00e3o Preto - SPEfetivo Auxiliar Administrativo Ribeir\u00e3o Preto - SPEfetivo Auxiliar T\u00e9cnico de RedesRibeir\u00e3o Preto - SPEfetivo Microset Tecnologia Assistente de Service Desk lRibeir\u00e3o Preto - SPEfetivo V\u00eddeos","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732047822_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732047822_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732047822_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732047822_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732047822_2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":82676,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/02\/07\/vagas-de-empregos-na-microset-tecnologia-para-trabalhar-em-ribeirao-preto-sp-23\/","url_meta":{"origin":87857,"position":1},"title":"Vagas de empregos na Microset Tecnologia  para trabalhar em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"7 de Fevereiro de 2025","format":false,"excerpt":"Assistente de Service Desk l Ribeir\u00e3o Preto - SPEfetivo Auxiliar T\u00e9cnico de Redes Ribeir\u00e3o Preto - SPEfetivo Gerente de Neg\u00f3cios - Campinas e regi\u00e3o Ribeir\u00e3o Preto - SPPessoa jur\u00eddica Microset Tecnologia Assistente de Service Desk l Ribeir\u00e3o Preto - SPEfetivo V\u00eddeos","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":51227,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/24\/conselho-da-petrobras-aprova-magda-chambriard-como-ceo\/","url_meta":{"origin":87857,"position":2},"title":"Conselho da Petrobras aprova Magda Chambriard como CEO","author":"ismaelcolosi.com.br","date":"24 de Maio de 2024","format":false,"excerpt":"[ad_1] \u00a0 Acessibilidade L L A- A+ \u25d0 A Petrobras informou que seu conselho de administra\u00e7\u00e3o aprovou nesta sexta-feira (24) Magda Chambriard como nova presidente-executiva e conselheira da companhia. Segundo fato relevante, Chambriard tomou posse em ambos os cargos nesta sexta-feira e passou a integrar o conselho imediatamente, n\u00e3o sendo\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Money_Magda-Chambriard_AgenciaBrasil-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Money_Magda-Chambriard_AgenciaBrasil-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Money_Magda-Chambriard_AgenciaBrasil-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Money_Magda-Chambriard_AgenciaBrasil-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":28608,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/16\/tereos-abre-500-vagas-para-safra\/","url_meta":{"origin":87857,"position":3},"title":"Tereos abre 500 vagas para safra","author":"ismaelcolosi.com.br","date":"16 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A Tereos, uma das l\u00edderes mundiais na produ\u00e7\u00e3o de a\u00e7\u00facar, etanol e bionergia, est\u00e1 com mais de 500 vagas de emprego abertas para a safra 2024\/25. As oportunidades s\u00e3o para as seis unidades industriais do grupo, localizadas na regi\u00e3o noroeste do Estado de S\u00e3o Paulo, e em todas as\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Tereos-Divulgacao-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Tereos-Divulgacao-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Tereos-Divulgacao-scaled.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Tereos-Divulgacao-scaled.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":76394,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/12\/vivara-anuncia-novo-ceo\/","url_meta":{"origin":87857,"position":4},"title":"Vivara Anuncia Novo CEO","author":"ismaelcolosi.com.br","date":"12 de Novembro de 2024","format":false,"excerpt":"[ad_1] Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r A Vivara informou que seu conselho de administra\u00e7\u00e3o elegeu o atual diretor de opera\u00e7\u00f5es, Icaro Borrello, para o cargo de presidente-executivo da companhia, em reuni\u00e3o realizada nesta ter\u00e7a-feira (11), conforme comunicado ao mercado. A decis\u00e3o segue-se \u00e0 ren\u00fancia do CEO\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-og-1030x438.webp?fit=1030%2C438&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-og-1030x438.webp?fit=1030%2C438&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-og-1030x438.webp?fit=1030%2C438&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-og-1030x438.webp?fit=1030%2C438&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":55226,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/01\/conselheira-da-vale-vera-marie-inkster-renuncia-ao-cargo\/","url_meta":{"origin":87857,"position":5},"title":"Conselheira da Vale Vera Marie Inkster renuncia ao cargo","author":"ismaelcolosi.com.br","date":"1 de Julho de 2024","format":false,"excerpt":"[ad_1] A mineradora Vale informou ao mercado em nota que Vera Marie Inkster apresentou sua ren\u00fancia ao cargo de membro do conselho de administra\u00e7\u00e3o da companhia nesta segunda-feira. Acessibilidade L L A- A+ \u25d0 Diante disso, a companhia afirmou que o colegiado \u201cest\u00e1 trabalhando em sua recomposi\u00e7\u00e3o e que, em\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Totem-com-logo-da-Vale-Foto-Washington-Alves-Reuters-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Totem-com-logo-da-Vale-Foto-Washington-Alves-Reuters-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Totem-com-logo-da-Vale-Foto-Washington-Alves-Reuters-1024x683.png?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Totem-com-logo-da-Vale-Foto-Washington-Alves-Reuters-1024x683.png?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-mR3","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/87857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=87857"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/87857\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/87858"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=87857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=87857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=87857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}