{"id":87548,"date":"2025-09-17T14:38:41","date_gmt":"2025-09-17T17:38:41","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/09\/17\/nestle-inaugura-nova-era-com-saida-antecipada-de-presidente-do-conselho\/"},"modified":"2025-09-17T14:38:41","modified_gmt":"2025-09-17T17:38:41","slug":"nestle-inaugura-nova-era-com-saida-antecipada-de-presidente-do-conselho","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/09\/17\/nestle-inaugura-nova-era-com-saida-antecipada-de-presidente-do-conselho\/","title":{"rendered":"Nestl\u00e9 Inaugura Nova era com Sa\u00edda Antecipada de Presidente do Conselho"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<figure class=\"destaque wp-caption\">&#13;<br \/>\n\t\t<img data-recalc-dims=\"1\" width=\"678\" height=\"452\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2025\/09\/nestle-forbes-768x512.jpg?resize=678%2C452&#038;ssl=1\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"Logo da Nestl\u00e9 na sede da empresa, em Vevey, na Su\u00ed\u00e7a\" decoding=\"async\" fetchpriority=\"high\"\/>\t\t<\/p>\n<p>REUTERS\/Denis Balibouse<\/p>\n<p>&#13;<figcaption class=\"wp-caption-text\">Logo da Nestl\u00e9 na sede da empresa, em Vevey, na Su\u00ed\u00e7a<\/figcaption>&#13;<br \/>\n\t<\/figure>\n<div class=\"accessibility\">\n<p>Acessibilidade<\/p>\n<p>&#13;<br \/>\n\t\t\t<button onclick=\"alterFont1()\" id=\"btn1\" class=\"btn\">L<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFont2()\" id=\"btn2\" class=\"btn\" style=\"font-family:Merriweather\">L<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFontSmallerSize()\" id=\"btn3\" class=\"btn\">A-<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFontBiggerSize()\" id=\"btn4\" class=\"btn\">A+<\/button>&#13;<br \/>\n\t\t\t<!--<button onclick='alterFontBolder()' id='btn5' class=\"btn\" >B<\/button>-->&#13;<br \/>\n\t\t\t<button onclick=\"alterBackground()\" id=\"btn6\" class=\"btn\">\u25d0<\/button>&#13;<br \/>\n\t\t\t<!--<button onclick='clean()' id='btn7' class=\"btn\" >Limpar<\/button>-->&#13;\n\t\t<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<\/p><\/div>\n<p>O presidente do conselho de administra\u00e7\u00e3o da <strong>Nestl\u00e9<\/strong>, <strong>Paul Bulcke<\/strong>, deixar\u00e1 o cargo antes do planejado e passar\u00e1 o comando para o ex-chefe da Inditex Pablo Isla em 1\u00ba de outubro, acelerando a troca na gigante su\u00ed\u00e7a de alimentos ap\u00f3s um per\u00edodo sem precedentes de turbul\u00eancia administrativa.<\/p>\n<p>A decis\u00e3o ocorre semanas depois que Laurent Freixe foi demitido do cargo de presidente-executivo por conta de um relacionamento amoroso n\u00e3o revelado, e abre caminho para que o novo chefe, Philipp Navratil, e Isla assumam o comando total da empresa, que tem enfrentado dificuldades nos \u00faltimos anos.<\/p>\n<aside>\n<h2>Leia tamb\u00e9m<\/h2>\n<\/aside>\n<p>Analistas e acionistas levantaram d\u00favidas sobre a posi\u00e7\u00e3o de Bulcke ap\u00f3s as revela\u00e7\u00f5es sobre o relacionamento amoroso de Freixe com uma subordinada, o que levou \u00e0 sua demiss\u00e3o apenas um ano ap\u00f3s ter assumido o comando.<\/p>\n<p>\u201cOs investidores queriam um novo come\u00e7o, com um novo presidente-executivo e um novo presidente do conselho para escrever o pr\u00f3ximo cap\u00edtulo\u201d, disse Jean-Philippe Bertschy, analista do Bank Vontobel.<\/p>\n<p>Ele acrescentou que Bulcke esteve sob enorme press\u00e3o nas \u00faltimas semanas e meses para se afastar. A recente turbul\u00eancia em torno da Freixe foi provavelmente a gota d\u2019\u00e1gua.<\/p>\n<p>\u201cOs investidores da Nestl\u00e9 agora querem que a empresa cumpra suas metas, especialmente para acelerar o crescimento das vendas\u201d, disse ele. \u201cUma das principais prioridades do novo presidente ser\u00e1 reorganizar o conselho, que tamb\u00e9m deve assumir total responsabilidade pelo fraco desempenho dos \u00faltimos anos.\u201d<\/p>\n<p>A Nestl\u00e9 acrescentou que Isla e Navratil est\u00e3o comprometidos com uma estrat\u00e9gia de crescimento org\u00e2nico que \u201calavancar\u00e1 efici\u00eancias\u201d para investir no forte portf\u00f3lio e nas marcas da Nestl\u00e9, que v\u00e3o desde o chocolate KitKat at\u00e9 o Nescaf\u00e9.<\/p>\n<p>\u201cO MOMENTO CERTO PARA ME AFASTAR\u201d<\/p>\n<p>Em uma breve declara\u00e7\u00e3o, Bulcke disse que a empresa est\u00e1 bem posicionada para o futuro, \u00e0 medida que avan\u00e7a com a transi\u00e7\u00e3o que havia sido programada anteriormente para abril do pr\u00f3ximo ano.<\/p>\n<p>Bulcke era presidente do conselho desde 2017 e, antes disso, foi presidente-executivo de 2008 a 2016.<\/p>\n<p>\u201cEste \u00e9 o momento certo para eu me afastar e acelerar a transi\u00e7\u00e3o planejada\u201d, disse Bulcke, que assumir\u00e1 a fun\u00e7\u00e3o de presidente honor\u00e1rio, em um comunicado, acrescentando que a nova lideran\u00e7a trar\u00e1 uma \u201cnova perspectiva\u201d.<\/p>\n<p>Investidores e analistas disseram que Isla demonstrou forte lideran\u00e7a na Inditex, propriet\u00e1ria da Zara.<\/p>\n<p>A Nestl\u00e9 enfrenta um desafio severo, com investidores e analistas pedindo que ela reduza seu tamanho, \u00e0 medida que os rivais cortam custos e at\u00e9 mesmo se separam para melhorar seu desempenho.<\/p>\n<p>O crescimento das vendas estagnou, as a\u00e7\u00f5es da empresa perderam mais de 40% desde 2022 e os custos aumentaram. Os n\u00edveis de endividamento ultrapassaram os de rivais como a Unilever.<\/p>\n<p>A Nestl\u00e9 disse em junho que Bulcke deixaria o cargo no pr\u00f3ximo ano, uma medida que se seguiu \u00e0 crescente inquieta\u00e7\u00e3o dos investidores com rela\u00e7\u00e3o ao desempenho do pre\u00e7o das a\u00e7\u00f5es da empresa, quest\u00f5es de lideran\u00e7a e preocupa\u00e7\u00f5es de que seu modelo de governan\u00e7a corporativa estivesse desatualizado.<\/p>\n<p>O apoio dos acionistas em Bulcke tamb\u00e9m estava diminuindo.<\/p>\n<p>Em abril, ele foi reeleito com 84,8% de apoio dos acionistas, abaixo do n\u00edvel que os presidentes normalmente obt\u00eam na Su\u00ed\u00e7a. Em 2017, ele recebeu quase 96% de apoio.<\/p>\n<aside>\n<h2>Escolhas do editor<\/h2>\n<\/aside>\n<div class=\"follow-us\">Siga o canal da <a href=\"https:\/\/whatsapp.com\/channel\/0029VaAZk57JuyA9F4UwQc2I\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" title=\"Grupo da Forbes Money no WhatsApp\">Forbes Money<\/a> no WhatsApp e receba as principais not\u00edcias de economia e mercado financeiro.<\/div>\n<\/p><\/div>\n<p><script data-debloat-delay=\"1\" type=\"text\/debloat-script\">\n\t\t\t\t(function(d, s, id){\n\t\t\t\t\tvar js, fjs = d.getElementsByTagName(s)[0];\n\t\t\t\t\tif (d.getElementById(id)) return;\n\t\t\t\t\tjs = d.createElement(s); js.id = id;\n\t\t\t\t\tjs.src = \"\/\/connect.facebook.net\/pt_BR\/sdk.js#xfbml=1&version=v2.9\";\n\t\t\t\t\tfjs.parentNode.insertBefore(js, fjs);\n\t\t\t\t}(document, 'script', 'facebook-jssdk'));\n\t\t\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/forbes.com.br\/carreira\/2025\/09\/nestle-inaugura-nova-era-com-saida-antecipada-de-presidente-do-conselho\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] &#13; REUTERS\/Denis Balibouse &#13;Logo da Nestl\u00e9 na sede da empresa, em Vevey, na Su\u00ed\u00e7a&#13; Acessibilidade &#13; L&#13; L&#13; A-&#13; A+&#13; &#13; \u25d0&#13; &#13; O presidente do conselho de administra\u00e7\u00e3o da Nestl\u00e9, Paul Bulcke, deixar\u00e1 o cargo antes do planejado e passar\u00e1 o comando para o ex-chefe da Inditex Pablo Isla em 1\u00ba de outubro, &#8230; <a title=\"Nestl\u00e9 Inaugura Nova era com Sa\u00edda Antecipada de Presidente do Conselho\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/09\/17\/nestle-inaugura-nova-era-com-saida-antecipada-de-presidente-do-conselho\/\" aria-label=\"Read more about Nestl\u00e9 Inaugura Nova era com Sa\u00edda Antecipada de Presidente do Conselho\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":87549,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1964],"tags":[],"class_list":["post-87548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-e-sucesso-dicas-para-carreira"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/09\/nestle-forbes-1200x675.jpg?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/09\/nestle-forbes-1200x675.jpg?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/09\/nestle-forbes-1200x675.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/09\/nestle-forbes-1200x675.jpg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/09\/nestle-forbes-1200x675.jpg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/09\/nestle-forbes-1200x675.jpg?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/09\/nestle-forbes-1200x675.jpg?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/09\/nestle-forbes-1200x675.jpg?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] &#13; REUTERS\/Denis Balibouse &#13;Logo da Nestl\u00e9 na sede da empresa, em Vevey, na Su\u00ed\u00e7a&#13; Acessibilidade &#13; L&#13; L&#13; A-&#13; A+&#13; &#13; \u25d0&#13; &#13; O presidente do conselho de administra\u00e7\u00e3o da Nestl\u00e9, Paul Bulcke, deixar\u00e1 o cargo antes do planejado e passar\u00e1 o comando para o ex-chefe da Inditex Pablo Isla em 1\u00ba de outubro,&hellip;","jetpack-related-posts":[{"id":84031,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/03\/25\/nestle-brasil-anuncia-nova-vice-presidente-de-pessoas\/","url_meta":{"origin":87548,"position":0},"title":"Nestl\u00e9 Brasil Anuncia Nova Vice-presidente de Pessoas","author":"ismaelcolosi.com.br","date":"25 de March de 2025","format":false,"excerpt":"[ad_1] \r \r \r \r Com 16 anos de carreira na multinacional, Martha Uribe ficou conhecida por impulsionar iniciativas de diversidade e inclus\u00e3o \r \r \r \r Divulga\u00e7\u00e3o\r Antes de ingressar na Nestl\u00e9, Martha Uribe atuou em multinacionais como Unilever e American Express\r Acessibilidade \r L\r L\r A-\r A+\r \r\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/forbes-nestle-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/forbes-nestle-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/forbes-nestle-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/forbes-nestle-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/forbes-nestle-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":87316,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/09\/01\/nestle-demite-ceo-por-relacionamento-amoroso-com-subordinada\/","url_meta":{"origin":87548,"position":1},"title":"Nestl\u00e9 Demite CEO por Relacionamento Amoroso com Subordinada","author":"ismaelcolosi.com.br","date":"1 de September de 2025","format":false,"excerpt":"[ad_1] \r \r \r \r Companhia nomeou Philipp Navratil como sucessor de Laurent Freixe \r \r \r \r Reprodu\u00e7\u00e3o\/LinkedIn\r Laurent Freixe, um veterano da Nestl\u00e9, assumiu o cargo de presidente-executivo em setembro do ano passado\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r A Nestl\u00e9 demitiu seu presidente-executivo, Laurent\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/09\/carreira-laurent-freixe-nestle-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/09\/carreira-laurent-freixe-nestle-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/09\/carreira-laurent-freixe-nestle-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/09\/carreira-laurent-freixe-nestle-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/09\/carreira-laurent-freixe-nestle-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":87938,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/16\/nestle-vai-cortar-16-000-empregos-diz-ceo\/","url_meta":{"origin":87548,"position":2},"title":"Nestl\u00e9 Vai Cortar 16.000 Empregos, Diz CEO","author":"ismaelcolosi.com.br","date":"16 de October de 2025","format":false,"excerpt":"[ad_1] \r \r \r \r Maior empresa de alimentos embalados do mundo busca cortar custos e reconquistar a confian\u00e7a dos investidores \r \r \r \r Denis Balibouse\/Reuters\r Logo da Nestl\u00e9\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r A Nestl\u00e9 cortar\u00e1 16.000 empregos, disse o novo CEO Philipp Navratil\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/money-nestle-puravida-23mai22-DenisBalibouse-1200x675.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/money-nestle-puravida-23mai22-DenisBalibouse-1200x675.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/money-nestle-puravida-23mai22-DenisBalibouse-1200x675.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/money-nestle-puravida-23mai22-DenisBalibouse-1200x675.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/money-nestle-puravida-23mai22-DenisBalibouse-1200x675.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":61682,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/22\/ceo-da-nestle-mark-schneider-renuncia-ao-cargo\/","url_meta":{"origin":87548,"position":3},"title":"CEO da Nestl\u00e9, Mark Schneider, renuncia ao cargo","author":"ismaelcolosi.com.br","date":"22 de August de 2024","format":false,"excerpt":"[ad_1] Nestl\u00e9\/Divulga\u00e7\u00e3oSob a lideran\u00e7a de Mark Schneider, as a\u00e7\u00f5es da Nestl\u00e9 alcan\u00e7aram seu n\u00edvel mais alto em janeiro de 2022 Acessibilidade L L A- A+ \u25d0 O CEO global da Nestl\u00e9, Mark Schneider, renunciou ao cargo ap\u00f3s oito anos \u00e0 frente da maior empresa de alimentos embalados do mundo. Schneider\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/nestle-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/nestle-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/nestle-1024x683.png?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/nestle-1024x683.png?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":87941,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/17\/ela-comecou-como-estagiaria-e-vai-liderar-os-chocolates-da-nestle-brasil\/","url_meta":{"origin":87548,"position":4},"title":"Ela Come\u00e7ou Como Estagi\u00e1ria e Vai Liderar os Chocolates da Nestl\u00e9 Brasil","author":"ismaelcolosi.com.br","date":"17 de October de 2025","format":false,"excerpt":"[ad_1] \r Divulga\u00e7\u00e3o\r \u00c0 frente das marcas Nestl\u00e9 e Garoto, Paula Munhoz quer construir um legado de inova\u00e7\u00e3o\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r H\u00e1 mais de 15 anos na Nestl\u00e9, Paula Munhoz \u00e9 a nova diretora de marketing da divis\u00e3o de chocolates da companhia, \u00e0 frente\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Nestle-Brasil-anuncia-Paula-Munhoz-como-nova-Diretora-de-Marketing-de-Chocolates-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Nestle-Brasil-anuncia-Paula-Munhoz-como-nova-Diretora-de-Marketing-de-Chocolates-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Nestle-Brasil-anuncia-Paula-Munhoz-como-nova-Diretora-de-Marketing-de-Chocolates-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Nestle-Brasil-anuncia-Paula-Munhoz-como-nova-Diretora-de-Marketing-de-Chocolates-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/10\/Nestle-Brasil-anuncia-Paula-Munhoz-como-nova-Diretora-de-Marketing-de-Chocolates-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":79339,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/15\/vagas-de-empregos-na-nestle-purina-em-ribeirao-preto-sp\/","url_meta":{"origin":87548,"position":5},"title":"Vagas de empregos\u00a0na Nestle-Purina em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"15 de December de 2024","format":false,"excerpt":"Vagas de empregos\u00a0 na Nestle-Purina em Ribeir\u00e3o Preto-SP 10 cuiosidades sobre a empresa Nestle Origem Su\u00ed\u00e7a: A Nestl\u00e9 foi fundada em 1866, na Su\u00ed\u00e7a, por Henri Nestl\u00e9, inicialmente para produzir uma f\u00f3rmula infantil destinada a beb\u00eas que n\u00e3o podiam ser amamentados. Primeiro Produto: O primeiro produto da Nestl\u00e9 foi o\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/noticiasconcursos.com_.br-nestle-esta-contratando-profissionais-veja-cargos-locais-e-beneficios-nestle-.png?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/noticiasconcursos.com_.br-nestle-esta-contratando-profissionais-veja-cargos-locais-e-beneficios-nestle-.png?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/noticiasconcursos.com_.br-nestle-esta-contratando-profissionais-veja-cargos-locais-e-beneficios-nestle-.png?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/noticiasconcursos.com_.br-nestle-esta-contratando-profissionais-veja-cargos-locais-e-beneficios-nestle-.png?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/noticiasconcursos.com_.br-nestle-esta-contratando-profissionais-veja-cargos-locais-e-beneficios-nestle-.png?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-mM4","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/87548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=87548"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/87548\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/87549"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=87548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=87548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=87548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}