{"id":8544,"date":"2023-11-30T11:45:55","date_gmt":"2023-11-30T14:45:55","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/30\/quase-que-jesus-me-chama\/"},"modified":"2023-11-30T11:45:55","modified_gmt":"2023-11-30T14:45:55","slug":"quase-que-jesus-me-chama","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/30\/quase-que-jesus-me-chama\/","title":{"rendered":"&#8216;Quase que Jesus me chama&#8221;"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div itemprop=\"text\">\n<p>O jornalismo brasileiro entrega not\u00edcia em primeira m\u00e3o diante de alguns acontecimentos. As mat\u00e9rias feitas na rua no dia a dia mostram \u00e0s vezes uma dura e perigosa realidade que afeta a todos presentes no momento.<\/p>\n<p>Os jornalistas tamb\u00e9m podem acabar sendo v\u00edtimas de alguma situa\u00e7\u00e3o que esteja cobrindo mat\u00e9ria. O apresentador Datena foi uma dessas v\u00edtimas e revelou momentos dif\u00edceis que passou.<\/p>\n<p>Ele estava cobrindo mat\u00e9ria da enchente no litoral de S\u00e3o Paulo, em S\u00e3o Sebasti\u00e3o, quando foi infectado pela \u00e1gua que, segundo ele, tinha muita mat\u00e9ria org\u00e2nica.<\/p>\n<p><em>\u201cAquela \u00e1gua que desceu dos morros tinha muita mat\u00e9ria org\u00e2nica. Peguei essa infec\u00e7\u00e3o que quase que Jesus me chama\u201d<\/em> relatou ele com bom humor ao ocorrido.<\/p>\n<p>Ainda segundo ele, foram mais de tr\u00eas bact\u00e9rias que atingiram a regi\u00e3o do per\u00edneo. Datena chegou a passar por cirurgia e ainda n\u00e3o sabe se est\u00e1 totalmente curado.<\/p>\n<p>Ap\u00f3s as cirurgias, realizadas no Hospital S\u00edrio Liban\u00eas, o apresentador usou as redes sociais agradecendo aos m\u00e9dicos pelo atendimento prestado e deixou uma reflex\u00e3o de que nem todas as pessoas t\u00eam acesso a esse tipo de atendimento.<\/p>\n<p>Em conversa com a apresentadora C\u00e1tia Fonseca, ele falava sobre sua outra condi\u00e7\u00e3o de sa\u00fade. Ele \u00e9 diab\u00e9tico e contou como \u00e9 sua rotina de alimenta\u00e7\u00e3o. Por costume, ele contou que come praticamente sem a\u00e7\u00facar e sem sal na comida. O apresentador ainda fez um alerta aos comerciantes e fabricantes terem dispon\u00edveis mais produtos pensados na alimenta\u00e7\u00e3o do diab\u00e9tico.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/fnmais.com\/datena-relembra-momento-em-que-pegou-tres-bacterias-quase-que-jesus-me-chama\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O jornalismo brasileiro entrega not\u00edcia em primeira m\u00e3o diante de alguns acontecimentos. As mat\u00e9rias feitas na rua no dia a dia mostram \u00e0s vezes uma dura e perigosa realidade que afeta a todos presentes no momento. Os jornalistas tamb\u00e9m podem acabar sendo v\u00edtimas de alguma situa\u00e7\u00e3o que esteja cobrindo mat\u00e9ria. O apresentador Datena foi&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":8545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65689ecb8c3589753.jpg?fit=1200%2C628&ssl=1",1200,628,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65689ecb8c3589753.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65689ecb8c3589753.jpg?fit=300%2C157&ssl=1",300,157,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65689ecb8c3589753.jpg?fit=768%2C402&ssl=1",768,402,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65689ecb8c3589753.jpg?fit=1024%2C536&ssl=1",1024,536,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65689ecb8c3589753.jpg?fit=1200%2C628&ssl=1",1200,628,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65689ecb8c3589753.jpg?fit=1200%2C628&ssl=1",1200,628,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65689ecb8c3589753.jpg?resize=930%2C620&ssl=1",930,620,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O jornalismo brasileiro entrega not\u00edcia em primeira m\u00e3o diante de alguns acontecimentos. As mat\u00e9rias feitas na rua no dia a dia mostram \u00e0s vezes uma dura e perigosa realidade que afeta a todos presentes no momento. Os jornalistas tamb\u00e9m podem acabar sendo v\u00edtimas de alguma situa\u00e7\u00e3o que esteja cobrindo mat\u00e9ria. O apresentador Datena foi&hellip;&nbsp;","jetpack-related-posts":[{"id":66069,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/16\/datena-agride-marcal-com-uma-cadeira-apos-ser-provocado-em-debate-video\/","url_meta":{"origin":8544,"position":0},"title":"Datena agride Mar\u00e7al com uma cadeira ap\u00f3s ser provocado em debate; V\u00eddeo","author":"ismaelcolosi.com.br","date":"16 de Setembro de 2024","format":false,"excerpt":"[ad_1] O apresentador ribeir\u00e3o-pretano Jos\u00e9 Luiz Datena (PSDB) partiu para cima do influenciador Pablo Mar\u00e7al (PRTB) e o agrediu com uma cadeira ap\u00f3s ser chamado de \u201carreg\u00e3o\u201d durante o debate promovido pela TV Cultura com os candidatos \u00e0 Prefeitura de S\u00e3o Paulo, na noite deste domingo (15). V\u00cdDEO \u201cO Datena\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/datena_2024-09-16_02-57-15_jpg_2024-09-16_02-57-15.webp.webp?fit=1132%2C734&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/datena_2024-09-16_02-57-15_jpg_2024-09-16_02-57-15.webp.webp?fit=1132%2C734&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/datena_2024-09-16_02-57-15_jpg_2024-09-16_02-57-15.webp.webp?fit=1132%2C734&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/datena_2024-09-16_02-57-15_jpg_2024-09-16_02-57-15.webp.webp?fit=1132%2C734&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/datena_2024-09-16_02-57-15_jpg_2024-09-16_02-57-15.webp.webp?fit=1132%2C734&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":45723,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/05\/datena-migra-para-o-psdb\/","url_meta":{"origin":8544,"position":1},"title":"Datena migra para o PSDB","author":"ismaelcolosi.com.br","date":"5 de Abril de 2024","format":false,"excerpt":"[ad_1] 5 de abril de 2024 | 14:005 de abril de 2024 | 10:08 0 Menos de quatro meses depois de se filiar ao PSB, o apresentador e jornalista ribeir\u00e3o-pretano Jos\u00e9 Luiz Datena assinou, nesta quinta-feira, 4 de abril, a ficha de filia\u00e7\u00e3o ao PSDB. A troca de legenda permitir\u00e1\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4470,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/21\/menino-de-2-anos-morre-apos-ser-picado-por-animal-peconhento-em-acampamento-com-a-familia-em-sp\/","url_meta":{"origin":8544,"position":2},"title":"Menino de 2 anos morre ap\u00f3s ser picado por animal pe\u00e7onhento em acampamento com a fam\u00edlia em SP","author":"ismaelcolosi.com.br","date":"21 de Novembro de 2023","format":false,"excerpt":"[ad_1] Uma crian\u00e7a de apenas 2 anos acabou indo a \u00f3bito ap\u00f3s receber uma picada de uma cobra cascavel. O tr\u00e1gico epis\u00f3dio aconteceu. A v\u00edtima foi identificada como Gael Henry Jesus Ribeiro.O menino estava em um acampamento de pesca chamado Angico na companhia da fam\u00edlia. Em determinado momento, ele foi\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655cd70dbc0da5018.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655cd70dbc0da5018.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655cd70dbc0da5018.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655cd70dbc0da5018.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655cd70dbc0da5018.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":44073,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/25\/brasil-gasta-milhoes-em-saude-por-falta-de-saneamento\/","url_meta":{"origin":8544,"position":3},"title":"Brasil gasta milh\u00f5es em sa\u00fade por falta de saneamento","author":"ismaelcolosi.com.br","date":"25 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] O potencial desperdi\u00e7ado pelo Brasil ao n\u00e3o capitalizar recursos financeiros com o aproveitamento dos esgotos sanit\u00e1rios, recai sobre o sistema de sa\u00fade. O estado despende milh\u00f5es no tratamento de doen\u00e7as decorrentes da car\u00eancia de saneamento b\u00e1sico. A incid\u00eancia de interna\u00e7\u00f5es no Brasil por doen\u00e7as relacionadas \u00e0 \u00e1gua contaminada, devido\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/saneamento-basico-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/saneamento-basico-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/saneamento-basico-scaled.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/saneamento-basico-scaled.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":37848,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/18\/as-belezas-de-pedregulho\/","url_meta":{"origin":8544,"position":4},"title":"As belezas de Pedregulho\u00a0 &#8211; Jornal Tribuna Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"18 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 18 de fevereiro de 2024 | 15:0016 de fevereiro de 2024 | 17:47 0Pedregulho fica pouco mais de 130 km de Ribeir\u00e3o Preto. \u00c9 uma daquelas viagens que pode ser feita num fim de semana ou mesmo no chamado \u2018bate e volta\u2019 em um dia, para quem mora na\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1-3-scaled.jpg?fit=977%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1-3-scaled.jpg?fit=977%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1-3-scaled.jpg?fit=977%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1-3-scaled.jpg?fit=977%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":71716,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/17\/de-saida-reuniao-na-proxima-semana-pode-definir-futuro-de-nogueira-no-psdb\/","url_meta":{"origin":8544,"position":5},"title":"De sa\u00edda? Reuni\u00e3o na pr\u00f3xima semana pode definir futuro de Nogueira no PSDB","author":"ismaelcolosi.com.br","date":"17 de Outubro de 2024","format":false,"excerpt":"[ad_1] O presidente nacional do PSDB, Marconi Perillo, deve se reunir com Duarte Nogueira para discutir a manuten\u00e7\u00e3o do prefeito de Ribeir\u00e3o Preto na legenda. Nogueira \u00e9 o atual presidente da Federa\u00e7\u00e3o PSDB\/Cidadania no Estado de S\u00e3o Paulo. A informa\u00e7\u00e3o foi publicada pela coluna Painel, da Folha de S. Paulo,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/duarte-nogueira_2024-10-17_17-55-49_jpeg_2024-10-17_17-55-50.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/duarte-nogueira_2024-10-17_17-55-49_jpeg_2024-10-17_17-55-50.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/duarte-nogueira_2024-10-17_17-55-49_jpeg_2024-10-17_17-55-50.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/duarte-nogueira_2024-10-17_17-55-49_jpeg_2024-10-17_17-55-50.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/duarte-nogueira_2024-10-17_17-55-49_jpeg_2024-10-17_17-55-50.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-2dO","jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65689ecb8c3589753.jpg?fit=1200%2C628&ssl=1","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=8544"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8544\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/8545"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=8544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=8544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=8544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}