{"id":83753,"date":"2025-03-13T13:39:19","date_gmt":"2025-03-13T16:39:19","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/03\/13\/federacao-dos-petroleiros-convoca-greve-de-funcionarios-da-petrobras-em-defesa-do-home-office-e-outras-pautas\/"},"modified":"2025-03-13T13:39:19","modified_gmt":"2025-03-13T16:39:19","slug":"federacao-dos-petroleiros-convoca-greve-de-funcionarios-da-petrobras-em-defesa-do-home-office-e-outras-pautas","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/03\/13\/federacao-dos-petroleiros-convoca-greve-de-funcionarios-da-petrobras-em-defesa-do-home-office-e-outras-pautas\/","title":{"rendered":"Federa\u00e7\u00e3o dos Petroleiros convoca greve de funcion\u00e1rios da Petrobras em defesa do home office e outras pautas"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"\">\n<div class=\"content-infos\">\n<div class=\"texts\">\n<p class=\"author tooltip-comp\"> Da Reuters<span class=\"icon-i\">i<\/span><span class=\"tooltiptext\"> <span class=\"author\"><span>Da Reuters<\/span> <\/span><span class=\"desc\"\/> <\/span><\/p>\n<p>13\/03\/2025 &#8211; 13:37<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<\/div>\n<div id=\"share-modal\" class=\"share-modal\"> <button class=\"box-close btn-share\"> <img decoding=\"async\" src=\"https:\/\/istoedinheiro.com.br\/wp-content\/themes\/dinheiro-wp-theme\/assets\/img\/svg\/closeIcon.svg?x46096\" alt=\"Close icon\" class=\"close-btn\"\/> <\/button><\/div>\n<\/p><\/div>\n<p>O conselho deliberativo da <strong>Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP)<\/strong> decidiu convocar trabalhadores da <strong>Petrobras<\/strong> para uma <strong>greve<\/strong> de advert\u00eancia de 24 horas em 26 de mar\u00e7o, em defesa do teletrabalho e de outras melhorias das <strong>condi\u00e7\u00f5es de trabalho<\/strong>, segundo comunicado da FUP nesta quinta-feira, 13.<\/p>\n<p><strong>+ Entenda como pedir empr\u00e9stimo consignado pela Carteira de Trabalho Digital<\/strong><\/p>\n<p>A paralisa\u00e7\u00e3o ser\u00e1 submetida \u00e0 aprova\u00e7\u00e3o da categoria em assembleias at\u00e9 o dia 23, explicou a FUP, que representa 12 sindicatos de petroleiros pelo Brasil.<\/p>\n<p>Normalmente, a <strong>Petrobras<\/strong> conta com equipes de conting\u00eancia em <strong>movimentos grevistas<\/strong>, tornando-se muito dif\u00edcil que haja impactos em suas opera\u00e7\u00f5es, principalmente em paralisa\u00e7\u00f5es de curto prazo.<\/p>\n<p>A pauta de reivindica\u00e7\u00f5es da <strong>FUP<\/strong> inclui a <strong>defesa do teletrabalho<\/strong> com regramento negociado coletivamente.<\/p>\n<p>Atualmente, o regime de trabalho para as \u00e1reas administrativas e escrit\u00f3rios da Petrobras prev\u00ea dois dias presenciais, sendo que a empresa pretende ampliar para tr\u00eas dias a partir de 7 de abril, sem ter acordo com os sindicatos, segundo a FUP.<\/p>\n<p>\u201cNa ter\u00e7a-feira, 11, dirigentes da FUP e representantes da Petrobras estiveram reunidos na sede da empresa, no Rio, para tratar da negocia\u00e7\u00e3o sobre o teletrabalho. As partes n\u00e3o chegaram a um acordo\u201d, disse a FUP, em nota.<\/p>\n<p>Al\u00e9m desse tema, a greve de um dia tamb\u00e9m far\u00e1 oposi\u00e7\u00e3o \u00e0 redu\u00e7\u00e3o da <strong>remunera\u00e7\u00e3o vari\u00e1vel<\/strong> dos trabalhadores e defender\u00e1 a <strong>recomposi\u00e7\u00e3o dos efetivos<\/strong> e a garantia de seguran\u00e7a em todo o Sistema Petrobras, nas prestadoras de servi\u00e7o e durante o per\u00edodo de manuten\u00e7\u00e3o.<\/p>\n<p>A federa\u00e7\u00e3o prop\u00f4s ainda defender a entrada em opera\u00e7\u00e3o da F\u00e1brica de Fertilizantes Nitrogenados do Paran\u00e1 (Fafen-PR), o fim dos equacionamentos da Petros e a cria\u00e7\u00e3o de um plano de cargos e sal\u00e1rios \u201cjusto e ison\u00f4mico\u201d.<\/p>\n<div id=\"share-modal\" class=\"share-modal\"> <button class=\"box-close btn-share\"> <img decoding=\"async\" src=\"https:\/\/istoedinheiro.com.br\/wp-content\/themes\/dinheiro-wp-theme\/assets\/img\/svg\/closeIcon.svg?x46096\" alt=\"Close icon\" class=\"close-btn\"\/> <\/button><\/div>\n<\/p><\/div>\n<p><script>!function(f,b,e,v,n,t,s){if(f.fbq)return;n=f.fbq=function(){n.callMethod?n.callMethod.apply(n,arguments):n.queue.push(arguments)};if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0';n.queue=[];t=b.createElement(e);t.async=!0;t.src=v;s=b.getElementsByTagName(e)[0];s.parentNode.insertBefore(t,s)}(window,document,'script','<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/istoedinheiro.com.br\/fup-convoca-greve-petrobras-home-office-outras-pautas\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Da Reutersi Da Reuters 13\/03\/2025 &#8211; 13:37 O conselho deliberativo da Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) decidiu convocar trabalhadores da Petrobras para uma greve de advert\u00eancia de 24 horas em 26 de mar\u00e7o, em defesa do teletrabalho e de outras melhorias das condi\u00e7\u00f5es de trabalho, segundo comunicado da FUP nesta quinta-feira, 13. + Entenda &#8230; <a title=\"Federa\u00e7\u00e3o dos Petroleiros convoca greve de funcion\u00e1rios da Petrobras em defesa do home office e outras pautas\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/03\/13\/federacao-dos-petroleiros-convoca-greve-de-funcionarios-da-petrobras-em-defesa-do-home-office-e-outras-pautas\/\" aria-label=\"Read more about Federa\u00e7\u00e3o dos Petroleiros convoca greve de funcion\u00e1rios da Petrobras em defesa do home office e outras pautas\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":83754,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3598],"tags":[],"class_list":["post-83753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empregos-classificados-vagas-trabalho"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/petrobras-sede-no-rj-geraldo-falcao-agencia-petrobras-e1657403222827.jpg?fit=700%2C394&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/petrobras-sede-no-rj-geraldo-falcao-agencia-petrobras-e1657403222827.jpg?fit=700%2C394&ssl=1",700,394,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/petrobras-sede-no-rj-geraldo-falcao-agencia-petrobras-e1657403222827.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/petrobras-sede-no-rj-geraldo-falcao-agencia-petrobras-e1657403222827.jpg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/petrobras-sede-no-rj-geraldo-falcao-agencia-petrobras-e1657403222827.jpg?fit=700%2C394&ssl=1",700,394,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/petrobras-sede-no-rj-geraldo-falcao-agencia-petrobras-e1657403222827.jpg?fit=700%2C394&ssl=1",700,394,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/petrobras-sede-no-rj-geraldo-falcao-agencia-petrobras-e1657403222827.jpg?fit=700%2C394&ssl=1",700,394,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/petrobras-sede-no-rj-geraldo-falcao-agencia-petrobras-e1657403222827.jpg?fit=700%2C394&ssl=1",700,394,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Da Reutersi Da Reuters 13\/03\/2025 &#8211; 13:37 O conselho deliberativo da Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) decidiu convocar trabalhadores da Petrobras para uma greve de advert\u00eancia de 24 horas em 26 de mar\u00e7o, em defesa do teletrabalho e de outras melhorias das condi\u00e7\u00f5es de trabalho, segundo comunicado da FUP nesta quinta-feira, 13. + Entenda&hellip;","jetpack-related-posts":[{"id":85570,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/05\/22\/federacao-dos-petroleiros-convoca-greve-de-funcionarios-da-petrobras-em-defesa-do-home-office-e-outras-pautas-2\/","url_meta":{"origin":83753,"position":0},"title":"Federa\u00e7\u00e3o dos Petroleiros convoca greve de funcion\u00e1rios da Petrobras em defesa do home office e outras pautas","author":"ismaelcolosi.com.br","date":"22 de May de 2025","format":false,"excerpt":"[ad_1] O conselho deliberativo da Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) decidiu convocar trabalhadores da Petrobras para uma greve de advert\u00eancia de 24 horas em 26 de mar\u00e7o, em defesa do teletrabalho e de outras melhorias das condi\u00e7\u00f5es de trabalho, segundo comunicado da FUP nesta quinta-feira, 13. + Entenda como pedir\u2026","rel":"","context":"In &quot;Empregos - Classificados&quot;","block_context":{"text":"Empregos - Classificados","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":85562,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/05\/21\/funcionarios-da-petrobras-aprovam-greve-para-26-de-marco-em-defesa-do-trabalho-remoto-2\/","url_meta":{"origin":83753,"position":1},"title":"Funcion\u00e1rios da Petrobras aprovam greve para 26 de mar\u00e7o em defesa do trabalho remoto","author":"ismaelcolosi.com.br","date":"21 de May de 2025","format":false,"excerpt":"[ad_1] Os funcion\u00e1rios da Petrobras aprovaram em assembleias uma greve de advert\u00eancia de 24 horas em 26 de mar\u00e7o, em defesa do trabalho remoto e de outras reivindica\u00e7\u00f5es trabalhistas, segundo comunicado da Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) nesta segunda-feira, 24. + Trump anuncia tarifas de 25% para pa\u00edses que compram\u2026","rel":"","context":"In &quot;Empregos - Classificados&quot;","block_context":{"text":"Empregos - Classificados","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":83999,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/03\/24\/funcionarios-da-petrobras-aprovam-greve-para-26-de-marco-em-defesa-do-trabalho-remoto\/","url_meta":{"origin":83753,"position":2},"title":"Funcion\u00e1rios da Petrobras aprovam greve para 26 de mar\u00e7o em defesa do trabalho remoto","author":"ismaelcolosi.com.br","date":"24 de March de 2025","format":false,"excerpt":"[ad_1] Da Reutersi Da Reuters 24\/03\/2025 - 14:05 Os funcion\u00e1rios da Petrobras aprovaram em assembleias uma greve de advert\u00eancia de 24 horas em 26 de mar\u00e7o, em defesa do trabalho remoto e de outras reivindica\u00e7\u00f5es trabalhistas, segundo comunicado da Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) nesta segunda-feira, 24.+ Trump anuncia tarifas\u2026","rel":"","context":"In &quot;Empregos - Classificados&quot;","block_context":{"text":"Empregos - Classificados","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/1742836178_petrobras-sede-no-rj-geraldo-falcao-agencia-petrobras-e1657403222827.jpg?fit=700%2C394&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/1742836178_petrobras-sede-no-rj-geraldo-falcao-agencia-petrobras-e1657403222827.jpg?fit=700%2C394&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/1742836178_petrobras-sede-no-rj-geraldo-falcao-agencia-petrobras-e1657403222827.jpg?fit=700%2C394&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/03\/1742836178_petrobras-sede-no-rj-geraldo-falcao-agencia-petrobras-e1657403222827.jpg?fit=700%2C394&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":85796,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/05\/29\/petroleiros-suspendem-greve-e-devem-aceitar-proposta-de-trabalho-hibrido-por-2-anos\/","url_meta":{"origin":83753,"position":3},"title":"Petroleiros suspendem greve e devem aceitar proposta de trabalho h\u00edbrido por 2 anos","author":"ismaelcolosi.com.br","date":"29 de May de 2025","format":false,"excerpt":"[ad_1] Reutersi Reuters 28\/05\/2025 - 19:02 O Conselho Deliberativo da Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) suspendeu a greve dos trabalhadores da Petrobras, que estava prevista para 29 e 30 de maio, e decidiu indicar a aprova\u00e7\u00e3o de nova proposta apresentada pela empresa, informou a entidade em nota nesta quarta-feira, 28.+\u2026","rel":"","context":"In &quot;Empregos - Classificados&quot;","block_context":{"text":"Empregos - Classificados","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/e44f6143a4a2cd4f77388ddf47088531e7fc1818.jpg?fit=768%2C511&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/e44f6143a4a2cd4f77388ddf47088531e7fc1818.jpg?fit=768%2C511&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/e44f6143a4a2cd4f77388ddf47088531e7fc1818.jpg?fit=768%2C511&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/e44f6143a4a2cd4f77388ddf47088531e7fc1818.jpg?fit=768%2C511&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":85624,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/05\/22\/federacao-de-petroleiros-protesta-contra-ampliacao-do-trabalho-presencial-na-petrobras-para-3-dias-por-semana-2\/","url_meta":{"origin":83753,"position":4},"title":"Federa\u00e7\u00e3o de Petroleiros protesta contra amplia\u00e7\u00e3o do trabalho presencial na Petrobras para 3 dias por semana","author":"ismaelcolosi.com.br","date":"22 de May de 2025","format":false,"excerpt":"[ad_1] A Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) informou que a entidade e os seus sindicatos v\u00e3o realizar um ato nesta ter\u00e7a-feira, 14, em protesto contra a altera\u00e7\u00e3o das regras do trabalho remoto. A partir de abril, os trabalhadores ter\u00e3o que realizar o trabalho presencial por tr\u00eas dias, e n\u00e3o dois,\u2026","rel":"","context":"In &quot;Empregos - Classificados&quot;","block_context":{"text":"Empregos - Classificados","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":81618,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/01\/13\/federacao-de-petroleiros-protesta-contra-ampliacao-do-trabalho-presencial-na-petrobras-para-3-dias-por-semana\/","url_meta":{"origin":83753,"position":5},"title":"Federa\u00e7\u00e3o de Petroleiros protesta contra amplia\u00e7\u00e3o do trabalho presencial na Petrobras para 3 dias por semana","author":"ismaelcolosi.com.br","date":"13 de January de 2025","format":false,"excerpt":"[ad_1] Estad\u00e3o Conte\u00fadoi Estad\u00e3o Conte\u00fado 13\/01\/2025 - 16:32 A Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) informou que a entidade e os seus sindicatos v\u00e3o realizar um ato nesta ter\u00e7a-feira, 14, em protesto contra a altera\u00e7\u00e3o das regras do trabalho remoto. A partir de abril, os trabalhadores ter\u00e3o que realizar o trabalho\u2026","rel":"","context":"In &quot;Empregos - Classificados&quot;","block_context":{"text":"Empregos - Classificados","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/petrobras-sede-no-rj-geraldo-falcao-agencia-petrobras-e1657403222827.jpg?fit=700%2C394&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/petrobras-sede-no-rj-geraldo-falcao-agencia-petrobras-e1657403222827.jpg?fit=700%2C394&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/petrobras-sede-no-rj-geraldo-falcao-agencia-petrobras-e1657403222827.jpg?fit=700%2C394&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/petrobras-sede-no-rj-geraldo-falcao-agencia-petrobras-e1657403222827.jpg?fit=700%2C394&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-lMR","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/83753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=83753"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/83753\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/83754"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=83753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=83753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=83753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}