{"id":83253,"date":"2025-02-21T14:45:40","date_gmt":"2025-02-21T17:45:40","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/?p=83253"},"modified":"2025-02-21T14:45:40","modified_gmt":"2025-02-21T17:45:40","slug":"3-vagas-home-office-de-assistente-atendente-a-ate-engenheiro-machine-learning-faca-sua-inscricao-online","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/02\/21\/3-vagas-home-office-de-assistente-atendente-a-ate-engenheiro-machine-learning-faca-sua-inscricao-online\/","title":{"rendered":"3 Vagas Home Office, de Assistente Atendente a at\u00e9 Engenheiro Machine Learning. Fa\u00e7a sua inscri\u00e7\u00e3o online!"},"content":{"rendered":"<hr \/>\n<p><span style=\"font-size: 14pt;\"><strong>Vaga: Assistente de Atendimento &#8211; Customer Success<\/strong><\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Empresa: NEXDOM Healthtech<\/strong><br \/>\n<strong>Modelo de trabalho: Remoto<\/strong><br \/>\n<strong>Inscri\u00e7\u00f5es at\u00e9: 19 de maio de 2025<\/strong><\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Descri\u00e7\u00e3o da Vaga:<\/strong> Voc\u00ea estar\u00e1 atendendo proativamente os clientes, esclarecendo d\u00favidas sobre funcionalidades do sistema, acompanhando chamados e controlando o SLA dos clientes sob sua responsabilidade.<\/span><\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p><span style=\"font-size: 14pt;\"><strong>Requisitos:<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\">Experi\u00eancia em atendimento ao cliente e\/ou customer success<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Conhecimento em ferramentas tecnol\u00f3gicas (Office 365, CRM)<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Habilidade em an\u00e1lise de dados e condu\u00e7\u00e3o de projetos<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Comunica\u00e7\u00e3o escrita e verbal assertiva<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 14pt;\"><strong>Diferenciais:<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\">Conhecimento em Unimed<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Atua\u00e7\u00e3o em customer success<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 14pt;\"><strong>Benef\u00edcios:<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\">Plano de sa\u00fade e odontol\u00f3gico para voc\u00ea e dependentes (sem mensalidade)<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Vale alimenta\u00e7\u00e3o\/refei\u00e7\u00e3o<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Totalpass<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Conv\u00eanio com cl\u00ednica psicol\u00f3gica<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Seguro de vida<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Day off no m\u00eas do anivers\u00e1rio<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Bolsa de estudos<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Aux\u00edlio home office<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Vale transporte e estacionamento<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Flexibilidade de trabalho h\u00edbrido ou remoto<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Ambiente leve e descontra\u00eddo, cultura focada em inova\u00e7\u00e3o, excel\u00eancia, comprometimento e trabalho em equipe<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 14pt;\"><a href=\"https:\/\/vempranexdom.gupy.io\/jobs\/8671131\" target=\"_blank\" rel=\"noopener\">Candidatar-se<\/a><\/span><\/p>\n<hr \/>\n<h3><span style=\"font-size: 14pt;\">Vaga: Analista Melhoria da Jornada do Colaborador Junior &#8211; People Analytics<\/span><\/h3>\n<p><span style=\"font-size: 14pt;\"><strong>Empresa:<\/strong> Libbs Farmac\u00eautica<br \/>\n<strong>Modelo de trabalho:<\/strong> Remoto (tamb\u00e9m dispon\u00edvel para PcD)<br \/>\n<strong>Inscri\u00e7\u00f5es at\u00e9:<\/strong> 24 de mar\u00e7o de 2025<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Descri\u00e7\u00e3o da Vaga:<\/strong> Atuar com People Analytics para melhorar a jornada do colaborador, construindo dashboards e relat\u00f3rios no Power BI, realizando an\u00e1lises de dados e colaborando com diferentes \u00e1reas de RH para estruturar e analisar informa\u00e7\u00f5es relevantes.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Requisitos:<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\">Experi\u00eancia com Power BI<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Conhecimento em SQL ou Python<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Interesse por an\u00e1lise de dados aplicada a Recursos Humanos<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Capacidade anal\u00edtica e vontade de aprender sobre People Analytics<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 14pt;\"><strong>Diferenciais:<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\">Experi\u00eancia com ferramentas de People Analytics<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">No\u00e7\u00f5es de DataBricks<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Familiaridade com engajamento, cultura ou recrutamento e sele\u00e7\u00e3o<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Habilidade para traduzir dados em insights estrat\u00e9gicos para o RH<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 14pt;\"><strong>Benef\u00edcios:<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\">Vale refei\u00e7\u00e3o e alimenta\u00e7\u00e3o<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Medicamentos Libbs &#8211; 100%<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Conv\u00eanio Farm\u00e1cia \u2013 Vidalink<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">PPR (Programa de Participa\u00e7\u00e3o dos Lucros e Resultados)<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Estacionamento, vale transporte ou fretado (aplic\u00e1vel para turnos presenciais)<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Programa USE: subs\u00eddio para compra de equipamento de trabalho<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Benef\u00edcios flex\u00edveis (TotalPass, seguro de vida, previd\u00eancia privada, assist\u00eancia m\u00e9dica e odontol\u00f3gica, aux\u00edlio alimenta\u00e7\u00e3o)<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 14pt;\"><a href=\"https:\/\/vempralibbs.gupy.io\/jobs\/8661566\" target=\"_blank\" rel=\"noopener\">Candidatar-se<\/a><\/span><\/p>\n<hr \/>\n<h3><span style=\"font-size: 14pt;\">Vaga: Pessoa Engenheira de Machine Learning S\u00eanior<\/span><\/h3>\n<p><span style=\"font-size: 14pt;\"><strong>Empresa:<\/strong> Grupo OLX<br \/>\n<strong>Modelo de trabalho:<\/strong> Remoto (tamb\u00e9m dispon\u00edvel para PcD)<br \/>\n<strong>Inscri\u00e7\u00f5es at\u00e9:<\/strong> 20 de maio de 2025<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Descri\u00e7\u00e3o da Vaga:<\/strong> Nessa posi\u00e7\u00e3o, voc\u00ea far\u00e1 parte da Tribo de Big Data, atuando no time de Data Science e Machine Learning Operations (MLOps). Suas principais responsabilidades incluem construir e manter a plataforma que otimiza a jornada dos cientistas de dados, implementar novas tecnologias para novos casos de uso de machine learning e IA, e desenvolver novas features enquanto mant\u00e9m rastreabilidade e observabilidade do desenvolvimento.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Requisitos:<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\">Conhecimentos em Python e Java<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Conhecimento avan\u00e7ado em SQL<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Experi\u00eancia com Streaming de dados<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Conhecimentos em frameworks de Big Data (Hive, Trino e Spark)<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Experi\u00eancia com Docker, Kubernetes, EKS, Terraform<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Experi\u00eancia com Airflow<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Dom\u00ednio do desenvolvimento de software, preferencialmente em arquitetura de microsservi\u00e7os<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Experi\u00eancia em ambiente cloud AWS<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Capacidade de elaborar testes unit\u00e1rios e de integra\u00e7\u00e3o<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Experi\u00eancia com metodologias \u00e1geis e pr\u00e1ticas \u00e1geis (ex: TDD, Pair Programming, CI, CD)<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Conhecimento sobre observabilidade<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Conhecimento em Git\/Github<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 14pt;\"><strong>Benef\u00edcios:<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\">Remunera\u00e7\u00e3o compat\u00edvel com o mercado<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Plano de sa\u00fade e odontol\u00f3gico<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Previd\u00eancia privada<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Benef\u00edcios flex\u00edveis<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Aux\u00edlio alimenta\u00e7\u00e3o<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Aconselhamento financeiro<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Clube de vantagens<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Aux\u00edlio home office<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Aux\u00edlio mobilidade<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Aux\u00edlio crian\u00e7a<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Seguro de vida<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Licen\u00e7as estendidas<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Incentivo ao esporte, qualidade de vida e bem-estar<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Empr\u00e9stimo consignado com taxas reduzidas<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 14pt;\"><a href=\"https:\/\/vemsergrupoolx.gupy.io\/jobs\/8679042\" target=\"_blank\" rel=\"noopener\">Candidatar-se<\/a><\/span><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>Vaga: Assistente de Atendimento &#8211; Customer Success Empresa: NEXDOM Healthtech Modelo de trabalho: Remoto Inscri\u00e7\u00f5es at\u00e9: 19 de maio de 2025 Descri\u00e7\u00e3o da Vaga: Voc\u00ea estar\u00e1 atendendo proativamente os clientes, esclarecendo d\u00favidas sobre funcionalidades do sistema, acompanhando chamados e controlando o SLA dos clientes sob sua responsabilidade. Requisitos: Experi\u00eancia em atendimento ao cliente e\/ou customer &#8230; <a title=\"3 Vagas Home Office, de Assistente Atendente a at\u00e9 Engenheiro Machine Learning. Fa\u00e7a sua inscri\u00e7\u00e3o online!\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/02\/21\/3-vagas-home-office-de-assistente-atendente-a-ate-engenheiro-machine-learning-faca-sua-inscricao-online\/\" aria-label=\"Read more about 3 Vagas Home Office, de Assistente Atendente a at\u00e9 Engenheiro Machine Learning. Fa\u00e7a sua inscri\u00e7\u00e3o online!\">Read more<\/a><\/p>\n","protected":false},"author":5,"featured_media":83254,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-83253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/20230825072158736_picture-scaled.jpg?fit=2560%2C775&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/20230825072158736_picture-scaled.jpg?fit=2560%2C775&ssl=1",2560,775,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/20230825072158736_picture-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/20230825072158736_picture-scaled.jpg?fit=300%2C91&ssl=1",300,91,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/20230825072158736_picture-scaled.jpg?fit=768%2C233&ssl=1",768,233,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/20230825072158736_picture-scaled.jpg?fit=1024%2C310&ssl=1",1024,310,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/20230825072158736_picture-scaled.jpg?fit=1536%2C465&ssl=1",1536,465,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/20230825072158736_picture-scaled.jpg?fit=2048%2C620&ssl=1",2048,620,true]},"uagb_author_info":{"display_name":"Arthur Tijolo","author_link":"https:\/\/ismaelcolosi.com.br\/author\/autor-2024\/"},"uagb_comment_info":0,"uagb_excerpt":"Vaga: Assistente de Atendimento &#8211; Customer Success Empresa: NEXDOM Healthtech Modelo de trabalho: Remoto Inscri\u00e7\u00f5es at\u00e9: 19 de maio de 2025 Descri\u00e7\u00e3o da Vaga: Voc\u00ea estar\u00e1 atendendo proativamente os clientes, esclarecendo d\u00favidas sobre funcionalidades do sistema, acompanhando chamados e controlando o SLA dos clientes sob sua responsabilidade. Requisitos: Experi\u00eancia em atendimento ao cliente e\/ou customer&hellip;","jetpack-related-posts":[{"id":84536,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/04\/14\/confira-as-novas-vagas-de-emprego-para-trabalhar-de-casa-trabalho-home-office-com-salarios-de-1-500-ate-3-mil-clique-e-confira-agora-186\/","url_meta":{"origin":83253,"position":0},"title":"Confira as novas vagas de emprego para trabalhar de casa. Trabalho home office, com sal\u00e1rios de 1.500 at\u00e9 3 mil, clique e confira agora","author":"ismaelcolosi.com.br","date":"14 de April de 2025","format":false,"excerpt":"Home Office Trabalhe de Casa Ganhando 2 mil por m\u00eas no cargo de Assistente Administrativo na Benner 11 de abril de 202511 de abril de 2025 Capital Vagas Home Office Contabilizei abriu vaga HOME OFFICE com sal\u00e1rio de 2 mil para Assistente de Ativa\u00e7\u00e3o (Foco Atendimento) 11 de abril de\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"Ganhe at\u00e9 R$ 2500,00 por m\u00eas! ySense Brasil abre novas vagas para Pesquisadores Online com pagamentos em D\u00f3lares ou Euros; Veja como funciona","src":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":82242,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/01\/27\/confira-as-novas-vagas-de-emprego-para-trabalhar-de-casa-trabalho-home-office-com-salarios-de-1-500-ate-3-mil-clique-e-confira-agora-175\/","url_meta":{"origin":83253,"position":1},"title":"Confira as novas vagas de emprego para trabalhar de casa. Trabalho home office, com sal\u00e1rios de 1.500 at\u00e9 3 mil, clique e confira agora","author":"ismaelcolosi.com.br","date":"27 de January de 2025","format":false,"excerpt":"Home Office Home Office de N\u00edvel M\u00e9dio! Nexdom Healthtech 100% Remoto para Assistente de Atendimento Home Office Trabalhe de casa! Asaas abriu vagas 100% Home office para Assistente de Atendimento ao Cliente Home Office Que tal trabalhar sem sair de casa? Beep Sa\u00fade Abriu Vagas Home Office Para Assistente de\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"Ganhe at\u00e9 R$ 2500,00 por m\u00eas! ySense Brasil abre novas vagas para Pesquisadores Online com pagamentos em D\u00f3lares ou Euros; Veja como funciona","src":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":59328,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/07\/confira-as-novas-vagas-de-emprego-para-trabalhar-de-casa-trabalho-home-office-com-salarios-de-1-500-ate-3-mil-clique-e-confira-agora-33\/","url_meta":{"origin":83253,"position":2},"title":"Confira as novas vagas de emprego para trabalhar de casa. Trabalho home office, com sal\u00e1rios de 1.500 at\u00e9 3 mil, clique e confira agora","author":"ismaelcolosi.com.br","date":"7 de August de 2024","format":false,"excerpt":"Home Office N\u00e3o precisa de experi\u00eancia! Unimed abriu vaga Home Office com sal\u00e1rio de R$ 2.304,06 para Assistente de Cadastro e Regras Home Office Gran Cursos abre vagas HOME OFFICE para Assistente Administrativo e oferece at\u00e9 Kit de Equipamentos completo Home Office Grupo Botic\u00e1rio abre as portas do Mercado de\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"N\u00e3o precisa de experi\u00eancia! Unimed abriu vaga Home Office com sal\u00e1rio de R$ 2.304,06 para Assistente de Cadastro e Regras","src":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/UNIMED-761x492.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/UNIMED-761x492.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/UNIMED-761x492.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/UNIMED-761x492.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":83837,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/03\/17\/confira-as-novas-vagas-de-emprego-para-trabalhar-de-casa-trabalho-home-office-com-salarios-de-1-500-ate-3-mil-clique-e-confira-agora-182\/","url_meta":{"origin":83253,"position":3},"title":"Confira as novas vagas de emprego para trabalhar de casa. Trabalho home office, com sal\u00e1rios de 1.500 at\u00e9 3 mil, clique e confira agora","author":"ismaelcolosi.com.br","date":"17 de March de 2025","format":false,"excerpt":"Home Office Trabalhe sem sair de Casa! Unimed abriu vaga HOME OFFICE com Sal\u00e1rio de R$ 4.271,51 e Alimenta\u00e7\u00e3o de R$ 850,00 para Consultores Home Office Trabalhe de Casa! RankMyApp abriu vaga HOME OFFICE para Assistente de Atendimento e Opera\u00e7\u00f5es Home Office Wiser Educa\u00e7\u00e3o abre vagas HOME OFFICE para Atendimento\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"Ganhe at\u00e9 R$ 2500,00 por m\u00eas! ySense Brasil abre novas vagas para Pesquisadores Online com pagamentos em D\u00f3lares ou Euros; Veja como funciona","src":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":39722,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/27\/trabalhe-em-casa-stefanini-abre-vaga-home-office-para-auxiliar-juridico-salario-de-ate-1-5-mil-por-mes\/","url_meta":{"origin":83253,"position":4},"title":"Trabalhe em Casa: Stefanini abre vaga HOME OFFICE para Auxiliar Jur\u00eddico sal\u00e1rio de at\u00e9 1.5 MIL por m\u00eas","author":"ismaelcolosi.com.br","date":"27 de February de 2024","format":false,"excerpt":"Home Office Trabalhe em Casa: Stefanini abre vaga HOME OFFICE para Auxiliar Jur\u00eddico sal\u00e1rio de at\u00e9 1.5 MIL por m\u00eas Home Office Trabalhe de Casa: Banco NEON abre vaga HOME OFFICE com sal\u00e1rio de at\u00e9 4 MIL por m\u00eas para Analista de Capta\u00e7\u00e3o Home Office Home Office: Grupo Gran Cursos\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/STEFANINI-761x492.webp?fit=761%2C492&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/STEFANINI-761x492.webp?fit=761%2C492&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/STEFANINI-761x492.webp?fit=761%2C492&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/STEFANINI-761x492.webp?fit=761%2C492&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":82741,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/02\/10\/confira-as-novas-vagas-de-emprego-para-trabalhar-de-casa-trabalho-home-office-com-salarios-de-1-500-ate-3-mil-clique-e-confira-agora-177\/","url_meta":{"origin":83253,"position":5},"title":"Confira as novas vagas de emprego para trabalhar de casa. Trabalho home office, com sal\u00e1rios de 1.500 at\u00e9 3 mil, clique e confira agora","author":"ismaelcolosi.com.br","date":"10 de February de 2025","format":false,"excerpt":"Home Office Knewin abriu vaga Home Office somente pela amanh\u00e3 das 08h \u00e0s 14h para Suporte ao Cliente! Home Office Effecti abriu vaga HOME OFFICE para Atendimento ao Cliente oferecendo Sal\u00e1rio + Alimenta\u00e7\u00e3o de R$ 770,00 e Aux\u00edlio Home Office de R$ 230,00 Home Office Sicoob abriu vaga para Trabalhar\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"Ganhe at\u00e9 R$ 2500,00 por m\u00eas! ySense Brasil abre novas vagas para Pesquisadores Online com pagamentos em D\u00f3lares ou Euros; Veja como funciona","src":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-lEN","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/83253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=83253"}],"version-history":[{"count":1,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/83253\/revisions"}],"predecessor-version":[{"id":83255,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/83253\/revisions\/83255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/83254"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=83253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=83253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=83253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}