{"id":81792,"date":"2025-01-17T05:24:32","date_gmt":"2025-01-17T08:24:32","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/01\/17\/ny-exige-que-empresas-informem-demissoes-relacionadas-a-ia\/"},"modified":"2025-01-17T05:24:32","modified_gmt":"2025-01-17T08:24:32","slug":"ny-exige-que-empresas-informem-demissoes-relacionadas-a-ia","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/01\/17\/ny-exige-que-empresas-informem-demissoes-relacionadas-a-ia\/","title":{"rendered":"NY Exige Que Empresas Informem Demiss\u00f5es Relacionadas \u00e0 IA"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<figure class=\"destaque wp-caption\">&#13;<br \/>\n\t\t<img data-recalc-dims=\"1\" width=\"678\" height=\"452\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2025\/01\/demissoes-ia-forbes-768x512.jpg?resize=678%2C452&#038;ssl=1\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"demissoes ia forbes\" decoding=\"async\" fetchpriority=\"high\"\/>\t\t<\/p>\n<p>Getty Images<\/p>\n<p>&#13;<figcaption class=\"wp-caption-text\">Novidade reflete uma maior conscientiza\u00e7\u00e3o sobre o poder da IA para moldar as organiza\u00e7\u00f5es e a for\u00e7a de trabalho do futuro<\/figcaption>&#13;<br \/>\n\t<\/figure>\n<p>\u00a0<\/p>\n<div class=\"accessibility\">\n<p>Acessibilidade<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p>&#13;<br \/>\n\t\t\t<button onclick=\"alterFont1()\" id=\"btn1\" class=\"btn\">L<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFont2()\" id=\"btn2\" class=\"btn\" style=\"font-family:Merriweather\">L<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFontSmallerSize()\" id=\"btn3\" class=\"btn\">A-<\/button>&#13;<br \/>\n\t\t\t<button onclick=\"alterFontBiggerSize()\" id=\"btn4\" class=\"btn\">A+<\/button>&#13;<br \/>\n\t\t\t<!--<button onclick='alterFontBolder()' id='btn5' class=\"btn\" >B<\/button>-->&#13;<br \/>\n\t\t\t<button onclick=\"alterBackground()\" id=\"btn6\" class=\"btn\">\u25d0<\/button>&#13;<br \/>\n\t\t\t<!--<button onclick='clean()' id='btn7' class=\"btn\" >Limpar<\/button>-->&#13;\n\t\t<\/p>\n<\/p><\/div>\n<p>\u00a0<\/p>\n<p>O crescimento explosivo da intelig\u00eancia artificial no ambiente de trabalho est\u00e1 transformando ind\u00fastrias e gerando uma mistura de medo e entusiasmo entre profissionais e candidatos a emprego.<\/p>\n<p>Not\u00edcias sobre automa\u00e7\u00e3o em larga escala e consequentes demiss\u00f5es geram preocupa\u00e7\u00e3o em diferentes setores. Nesta semana, foi relatado que bancos globais podem cortar at\u00e9<strong> 200 mil empregos<\/strong> nos pr\u00f3ximos anos, e a <strong>Meta<\/strong> est\u00e1 reduzindo 5% da sua equipe, mirando em profissionais com baixo desempenho.<\/p>\n<p>Nos Estados Unidos, governos estaduais come\u00e7am a se atentar ao tema e a aumentar as prote\u00e7\u00f5es aos profissionais, al\u00e9m de exigir iniciativas de requalifica\u00e7\u00e3o das empresas.<\/p>\n<p>No relat\u00f3rio \u201cState of the State\u201d de 2025, a governadora de Nova York, Kathy Hochul, deu um passo significativo para abordar os potenciais impactos da IA na for\u00e7a de trabalho. Hochul ampliou a Lei de Notifica\u00e7\u00e3o de Ajuste e Requalifica\u00e7\u00e3o de Trabalhadores \u2013 na sigla em ingl\u00eas, WARN (Worker Adjustment and Retraining Notification Act) \u2013 para incluir perdas de empregos relacionadas \u00e0 IA.<\/p>\n<p>Sob essas novas regulamenta\u00e7\u00f5es, as empresas devem notificar o estado sobre demiss\u00f5es explicitamente ligadas \u00e0 ado\u00e7\u00e3o de intelig\u00eancia artificial.<\/p>\n<h2>O que muda<\/h2>\n<p>A legisla\u00e7\u00e3o exige que as empresas forne\u00e7am aviso pr\u00e9vio de demiss\u00f5es em massa para ajudar os profissionais a se requalificar ou encontrar novos empregos. Mais de uma d\u00fazia de estados americanos t\u00eam vers\u00f5es dessa lei, com per\u00edodos de aviso e exig\u00eancias que variam de acordo com o tamanho da companhia.<\/p>\n<p>Agora, Nova York ser\u00e1 o primeiro estado a incluir demiss\u00f5es relacionadas \u00e0 IA, estabelecendo um precedente para a responsabiliza\u00e7\u00e3o corporativa na transforma\u00e7\u00e3o digital.<\/p>\n<p>A novidade reflete uma maior conscientiza\u00e7\u00e3o sobre o poder da IA para moldar as organiza\u00e7\u00f5es e a for\u00e7a de trabalho do futuro. Tamb\u00e9m alerta os empregadores de que os efeitos sociais e trabalhistas da IA devem ser gerenciados de forma respons\u00e1vel. Isso pode incentivar as empresas a investir em programas de requalifica\u00e7\u00e3o ou redistribui\u00e7\u00e3o da for\u00e7a de trabalho, minimizando as redu\u00e7\u00f5es no quadro de funcion\u00e1rios.<\/p>\n<h2>O que as empresas podem fazer<\/h2>\n<h3>Investir em programas de requalifica\u00e7\u00e3o<\/h3>\n<p>As companhias podem ampliar iniciativas internas de treinamento para ajudar os funcion\u00e1rios a se adaptar a novas fun\u00e7\u00f5es que aproveitem as tecnologias de IA, em vez de competir com elas. Isso inclui a requalifica\u00e7\u00e3o de trabalhadores para fun\u00e7\u00f5es de alta demanda, como gerenciamento de sistemas de IA ou an\u00e1lise de dados.<\/p>\n<p>De acordo com o F\u00f3rum Econ\u00f4mico Mundial, as lacunas de habilidades s\u00e3o consideradas a maior barreira \u00e0 transforma\u00e7\u00e3o das empresas.<\/p>\n<p>Segundo o levantamento, 85% dos empregadores planejam priorizar a qualifica\u00e7\u00e3o de sua for\u00e7a de trabalho, sendo que 50% planejam a transi\u00e7\u00e3o de funcion\u00e1rios de fun\u00e7\u00f5es em decl\u00ednio para fun\u00e7\u00f5es em crescimento.<\/p>\n<p>No entanto, um relat\u00f3rio da The Conference, publicado na mesma semana, afirma que apenas 7% dos diretores de RH dizem estar implementando estrat\u00e9gias de requalifica\u00e7\u00e3o para fun\u00e7\u00f5es com alta probabilidade de terem pelo menos 25% das tarefas assumidas por IA.<\/p>\n<p>A governadora de Nova York determinar\u00e1 que o Escrit\u00f3rio de Servi\u00e7os de Tecnologia da Informa\u00e7\u00e3o implemente treinamentos de IA para os funcion\u00e1rios do estado. A capacita\u00e7\u00e3o vai oferecer educa\u00e7\u00e3o b\u00e1sica sobre como a IA pode ser usada de forma segura no local de trabalho para melhorar produtividade e efici\u00eancia.<\/p>\n<h3>Elaborar um planejamento estrat\u00e9gico para a for\u00e7a de trabalho<\/h3>\n<p>Os empregadores devem avaliar suas necessidades de for\u00e7a de trabalho, identificando oportunidades para qualificar funcion\u00e1rios atuais em vez de depender exclusivamente de contrata\u00e7\u00f5es externas para posi\u00e7\u00f5es relacionadas \u00e0 IA. Eles tamb\u00e9m devem considerar quais novos empregos ser\u00e3o criados pela transforma\u00e7\u00e3o com a intelig\u00eancia artificial e atualizar seus planos de recrutamento de acordo com isso.<\/p>\n<p>Segundo o relat\u00f3rio \u201cState of the New York City Economy\u201d da NYCEDC (New York City Economic Development Corporation), para cada emprego perdido para a IA em Nova York, de quatro a dez outras fun\u00e7\u00f5es podem ser ampliadas por ela. A consultoria McKinsey &amp; Company tamb\u00e9m prev\u00ea que a regi\u00e3o ter\u00e1 200 mil novos empregos l\u00edquidos at\u00e9 2030, relacionados a avan\u00e7os como a IA.<\/p>\n<h3>Tomar decis\u00f5es com transpar\u00eancia<\/h3>\n<p>Com os requisitos regulat\u00f3rios em vigor, as empresas devem comunicar abertamente as raz\u00f5es por tr\u00e1s das mudan\u00e7as impulsionadas pela IA e incluir os profissionais no processo de transi\u00e7\u00e3o. A comunica\u00e7\u00e3o clara constr\u00f3i confian\u00e7a e ajuda a aliviar preocupa\u00e7\u00f5es dos funcion\u00e1rios, esclarecendo os motivos para a ado\u00e7\u00e3o da IA e os resultados esperados. Ser transparente cria um ambiente de equipe em que os trabalhadores se sentem valorizados e informados, aumentando a probabilidade de que aceitem programas de requalifica\u00e7\u00e3o oferecidos pelos empregadores.<\/p>\n<h2>O que fazer para n\u00e3o perder seu emprego para a IA<\/h2>\n<p>Os profissionais devem focar em cinco estrat\u00e9gias para se posicionarem com sucesso no cen\u00e1rio em transforma\u00e7\u00e3o impulsionado pela IA:<\/p>\n<ul>\n<li><strong>1. Compreenda as tend\u00eancias:<\/strong> Antecipe como a IA ir\u00e1 ampliar ou substituir fun\u00e7\u00f5es em seu setor nos pr\u00f3ximos anos.<\/li>\n<li><strong>2. Invista em aprendizado cont\u00ednuo:<\/strong> Cursos online tornam o aprendizado acess\u00edvel para profissionais de qualquer idade e n\u00edvel atual de profici\u00eancia t\u00e9cnica.<\/li>\n<li><strong>3. Foque em habilidades socioemocionais:<\/strong> Desenvolve e mantenha habilidades socioemocionais, como lideran\u00e7a, curiosidade e pensamento cr\u00edtico, que continuar\u00e3o sendo indispens\u00e1veis mesmo com o avan\u00e7o da IA.<\/li>\n<li><strong>4. Aproveite ferramentas de IA:<\/strong> Familiarize-se com ferramentas baseadas em IA para mostrar aos empregadores que voc\u00ea pode se adaptar e prosperar em um ambiente de trabalho aprimorado pela tecnologia.<\/li>\n<li><strong>5. Construa redes e conex\u00f5es:<\/strong> Conecte-se a comunidades ligadas \u00e0 intelig\u00eancia artificial para descobrir oportunidades alinhadas \u00e0s suas habilidades e interesses.<\/li>\n<\/ul>\n<p><em>*Phil Kirschner \u00e9 colaborador da Forbes USA. Ele \u00e9 especialista no futuro do trabalho e na din\u00e2mica dos ambientes profissionais. J\u00e1 trabalhou como Expert S\u00eanior na McKinsey &amp; Company, foi l\u00edder de estrat\u00e9gia de ambiente de trabalho na WeWork, JLL e Credit Suisse.<\/em><\/p>\n<div class=\"follow-us\">Siga o canal da <a href=\"https:\/\/whatsapp.com\/channel\/0029Va9gQKwBFLgM96cJnu0u\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" title=\"Grupo da Forbes no WhatsApp\">Forbes<\/a> no WhatsApp e receba as principais not\u00edcias de empreendedorismo, carreira, tecnologia, agro e lifestyle.<\/div>\n<\/p><\/div>\n<p><script>\n\t\t\t\t(function(d, s, id){\n\t\t\t\t\tvar js, fjs = d.getElementsByTagName(s)[0];\n\t\t\t\t\tif (d.getElementById(id)) return;\n\t\t\t\t\tjs = d.createElement(s); js.id = id;\n\t\t\t\t\tjs.src = \"\/\/connect.facebook.net\/pt_BR\/sdk.js#xfbml=1&version=v2.9\";\n\t\t\t\t\tfjs.parentNode.insertBefore(js, fjs);\n\t\t\t\t}(document, 'script', 'facebook-jssdk'));\n\t\t\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/forbes.com.br\/carreira\/2025\/01\/nova-york-exige-que-empresas-comuniquem-demissoes-relacionadas-ao-uso-de-ia\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] &#13; Getty Images &#13;Novidade reflete uma maior conscientiza\u00e7\u00e3o sobre o poder da IA para moldar as organiza\u00e7\u00f5es e a for\u00e7a de trabalho do futuro&#13; \u00a0 Acessibilidade &#13; L&#13; L&#13; A-&#13; A+&#13; &#13; \u25d0&#13; &#13; \u00a0 O crescimento explosivo da intelig\u00eancia artificial no ambiente de trabalho est\u00e1 transformando ind\u00fastrias e gerando uma mistura de medo &#8230; <a title=\"NY Exige Que Empresas Informem Demiss\u00f5es Relacionadas \u00e0 IA\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/01\/17\/ny-exige-que-empresas-informem-demissoes-relacionadas-a-ia\/\" aria-label=\"Read more about NY Exige Que Empresas Informem Demiss\u00f5es Relacionadas \u00e0 IA\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":81793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1964],"tags":[],"class_list":["post-81792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-e-sucesso-dicas-para-carreira"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/demissoes-ia-forbes-1200x675.jpg?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/demissoes-ia-forbes-1200x675.jpg?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/demissoes-ia-forbes-1200x675.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/demissoes-ia-forbes-1200x675.jpg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/demissoes-ia-forbes-1200x675.jpg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/demissoes-ia-forbes-1200x675.jpg?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/demissoes-ia-forbes-1200x675.jpg?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/01\/demissoes-ia-forbes-1200x675.jpg?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] &#13; Getty Images &#13;Novidade reflete uma maior conscientiza\u00e7\u00e3o sobre o poder da IA para moldar as organiza\u00e7\u00f5es e a for\u00e7a de trabalho do futuro&#13; \u00a0 Acessibilidade &#13; L&#13; L&#13; A-&#13; A+&#13; &#13; \u25d0&#13; &#13; \u00a0 O crescimento explosivo da intelig\u00eancia artificial no ambiente de trabalho est\u00e1 transformando ind\u00fastrias e gerando uma mistura de medo&hellip;","jetpack-related-posts":[{"id":77385,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/25\/8-cursos-gratuitos-para-desenvolver-habilidades-em-ia\/","url_meta":{"origin":81792,"position":0},"title":"8 Cursos Gratuitos Para Desenvolver Habilidades em IA","author":"ismaelcolosi.com.br","date":"25 de November de 2024","format":false,"excerpt":"[ad_1] \u00a0 Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 Com as transforma\u00e7\u00f5es proporcionadas pela intelig\u00eancia artificial no mercado de trabalho, ter conhecimento das novas tecnologias n\u00e3o \u00e9 mais apenas um diferencial no curr\u00edculo, e sim a chave para conquistar posi\u00e7\u00f5es de destaque no mundo corporativo. Segundo o\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-habilidades-ia-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-habilidades-ia-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-habilidades-ia-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-habilidades-ia-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/forbes-habilidades-ia-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":84817,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/04\/25\/profissionais-podem-economizar-122-horas-por-ano-ao-adotar-ia\/","url_meta":{"origin":81792,"position":1},"title":"Profissionais Podem Economizar 122 Horas por Ano Ao Adotar IA","author":"ismaelcolosi.com.br","date":"25 de April de 2025","format":false,"excerpt":"[ad_1] \r Reuters\r Profissional em Londres\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 O Reino Unido poderia ganhar 400 bilh\u00f5es de libras (US$533 bilh\u00f5es) com o crescimento impulsionado pela intelig\u00eancia artificial se treinasse sua for\u00e7a de trabalho, disse o Google, depois que um projeto piloto no pa\u00eds\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-IA-carreira-trabalho-londres-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-IA-carreira-trabalho-londres-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-IA-carreira-trabalho-londres-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-IA-carreira-trabalho-londres-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-IA-carreira-trabalho-londres-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":67548,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/24\/cursos-gratuitos-para-aprender-sobre-ia-ciberseguranca-e-analise-de-dados\/","url_meta":{"origin":81792,"position":2},"title":"Cursos Gratuitos para Aprender sobre IA, Ciberseguran\u00e7a e An\u00e1lise de Dados","author":"ismaelcolosi.com.br","date":"24 de September de 2024","format":false,"excerpt":"[ad_1] A pesquisa CEO Study, realizada pela IBM, aponta que 35% da for\u00e7a de trabalho brasileira precisar\u00e1 ser requalificada nos pr\u00f3ximos tr\u00eas anos devido aos avan\u00e7os tecnol\u00f3gicos. O levantamento tamb\u00e9m mostra que 37% dos CEOs no Brasil planejam contratar colaboradores adicionais devido \u00e0 IA generativa. Acessibilidade L L A- A+\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/cursos-gratuitos-tecnologia-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/cursos-gratuitos-tecnologia-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/cursos-gratuitos-tecnologia-1024x683.png?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/cursos-gratuitos-tecnologia-1024x683.png?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":67801,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/25\/cursos-gratuitos-para-aprender-sobre-ia-ciberseguranca-e-analise-de-dados-2\/","url_meta":{"origin":81792,"position":3},"title":"Cursos Gratuitos para Aprender sobre IA, Ciberseguran\u00e7a e An\u00e1lise de Dados","author":"ismaelcolosi.com.br","date":"25 de September de 2024","format":false,"excerpt":"[ad_1] A pesquisa CEO Study, realizada pela IBM, aponta que 35% da for\u00e7a de trabalho brasileira precisar\u00e1 ser requalificada nos pr\u00f3ximos tr\u00eas anos devido aos avan\u00e7os tecnol\u00f3gicos. O levantamento tamb\u00e9m mostra que 37% dos CEOs no Brasil planejam contratar colaboradores adicionais devido \u00e0 IA generativa. Acessibilidade L L A- A+\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727285159_cursos-gratuitos-tecnologia-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727285159_cursos-gratuitos-tecnologia-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727285159_cursos-gratuitos-tecnologia-1024x683.png?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727285159_cursos-gratuitos-tecnologia-1024x683.png?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":53445,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/17\/6-cursos-gratuitos-de-ia-para-turbinar-sua-carreira-em-2024\/","url_meta":{"origin":81792,"position":4},"title":"6 cursos gratuitos de IA para turbinar sua carreira em 2024","author":"ismaelcolosi.com.br","date":"17 de June de 2024","format":false,"excerpt":"[ad_1] Empregadores est\u00e3o dispostos a pagar at\u00e9 47% a mais para funcion\u00e1rios com habilidades em IA, segundo um novo estudo da Amazon Web Services (AWS) com 3.297 empregados e 1.340 organiza\u00e7\u00f5es de diversos setores nos EUA. Acessibilidade L L A- A+ \u25d0 Siga a Forbes no WhatsApp e receba as\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Curso-de-IA-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Curso-de-IA-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Curso-de-IA-1024x683.png?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Curso-de-IA-1024x683.png?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":86074,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/06\/11\/microsoft-e-the-trust-for-the-americas-oferecem-capacitacao-gratuita-em-ia\/","url_meta":{"origin":81792,"position":5},"title":"Microsoft e The Trust for the Americas Oferecem Capacita\u00e7\u00e3o Gratuita em IA","author":"ismaelcolosi.com.br","date":"11 de June de 2025","format":false,"excerpt":"[ad_1] \r Canva\r \r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 \u00a0 Em parceria com a Microsoft e apoio da Avanade, a ONG The Trust for the Americas reuniu capacita\u00e7\u00f5es gratuitas em intelig\u00eancia artificial com foco em brasileiros de diferentes perfis. Entre as iniciativas englobadas pela AcademIA\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/06\/capacitacao-em-IA-1200x675.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/06\/capacitacao-em-IA-1200x675.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/06\/capacitacao-em-IA-1200x675.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/06\/capacitacao-em-IA-1200x675.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/06\/capacitacao-em-IA-1200x675.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-lhe","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/81792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=81792"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/81792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/81793"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=81792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=81792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=81792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}