{"id":80476,"date":"2024-12-26T14:10:55","date_gmt":"2024-12-26T17:10:55","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/?p=80476"},"modified":"2024-12-26T14:16:04","modified_gmt":"2024-12-26T17:16:04","slug":"recepcionista-hospitalar-ribeirao-preto-4","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/26\/recepcionista-hospitalar-ribeirao-preto-4\/","title":{"rendered":"Recepcionista Hospitalar (Ribeir\u00e3o Preto)"},"content":{"rendered":"<div class=\"sc-974f7df8-3 iLkwdn\">\n<div class=\"sc-ccd5d36-4 ebbPap\">\n<div class=\"sc-ccd5d36-3 fYFYcJ\">\n<div class=\"sc-ccd5d36-5 emNbUA\">\n<h1 id=\"h1\" class=\"sc-ccd5d36-6 gdqSpl\" tabindex=\"-1\">Recepcionista Hospitalar (Ribeir\u00e3o Preto)<\/h1>\n<div class=\"sc-974f7df8-6 hLeFJ\">\n<div class=\"sc-kbousE bXXrWG\" role=\"alert\" aria-hidden=\"true\">\n<div class=\"sc-sLsrZ eHZmyT\">\n<div class=\"sc-fifgRP ceImex\">Publicada em 09 de outubro de 2024<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"sc-ccd5d36-7 eFURNm\">\n<p class=\"sc-ccd5d36-11 dmmNfl\">Inscri\u00e7\u00f5es abertas at\u00e9 31 de janeiro de 2025<\/p>\n<\/div>\n<\/div>\n<div class=\"sc-ccd5d36-9 iatlme\">\n<div class=\"sc-ccd5d36-1 iIRwzz\">\n<hr class=\"sc-eeDRCY sc-ccd5d36-0 lgidzY hOWdNe\" aria-hidden=\"true\" \/>\n<\/div>\n<div class=\"sc-ccd5d36-8 hJyGMQ\">\n<p class=\"sc-ccd5d36-11 sc-ccd5d36-12 dmmNfl guFMyc\"><span class=\"sc-dfd42894-0 bzQMFp\">Local de trabalho: Ribeir\u00e3o Preto &#8211; SP<\/span><img decoding=\"async\" class=\"sc-ccd5d36-10 gOmRAz\" src=\"https:\/\/vfphospitalveterinario.gupy.io\/images\/place.svg\" alt=\"Efetivo\" aria-hidden=\"true\" \/><span aria-hidden=\"true\">Ribeir\u00e3o Preto &#8211; SP<\/span><\/p>\n<p class=\"sc-ccd5d36-11 sc-ccd5d36-12 dmmNfl guFMyc\"><span class=\"sc-dfd42894-0 bzQMFp\">Tipo de vaga: Efetivo<\/span><img decoding=\"async\" class=\"sc-ccd5d36-10 gOmRAz\" src=\"https:\/\/vfphospitalveterinario.gupy.io\/images\/work.svg\" alt=\"Modelo de trabalho \u00edcone\" aria-hidden=\"true\" \/><span aria-hidden=\"true\">Efetivo<\/span><\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p class=\"sc-ccd5d36-11 sc-ccd5d36-12 dmmNfl guFMyc\"><span class=\"sc-dfd42894-0 bzQMFp\">Modelo de trabalho: Presencial<\/span><img decoding=\"async\" class=\"sc-ccd5d36-10 gOmRAz\" src=\"https:\/\/vfphospitalveterinario.gupy.io\/images\/on-site.svg\" alt=\"Trabalho Presencial \u00edcone\" aria-hidden=\"true\" \/><span aria-hidden=\"true\">Presencial<\/span><\/p>\n<\/div>\n<hr class=\"sc-eeDRCY sc-ccd5d36-0 lgidzY hOWdNe\" aria-hidden=\"true\" \/>\n<\/div>\n<\/div>\n<\/div>\n<section>\n<div class=\"sc-add46fb1-1 rSSXJ\" data-testid=\"text-section\">\n<h2 class=\"sc-c87ac0d4-0 gDozGp\" data-testid=\"section-Descri\u00e7\u00e3o da vaga-title\">Descri\u00e7\u00e3o da vaga<\/h2>\n<div class=\"sc-add46fb1-3 fJDlzV\">\n<p>\ud83c\udfe5O Hospital VFP \u00e9 tido como refer\u00eancia na medicina veterin\u00e1ria intensiva no quesito qualidade e inova\u00e7\u00e3o no Brasil e, em 2024, novas unidades pr\u00f3prias e franqueadas ser\u00e3o inauguradas.<\/p>\n<p>\u267b Nosso hospital vive sob a cultura de aprendizagem, com valoriza\u00e7\u00e3o de stakeholders e com as melhores tecnologias do mercado para que a assist\u00eancia m\u00e9dica veterin\u00e1ria seja eficiente.<\/p>\n<p>Venha trabalhar conosco!<\/p>\n<\/div>\n<\/div>\n<div class=\"sc-add46fb1-1 rSSXJ\" data-testid=\"text-section\">\n<h2 class=\"sc-c87ac0d4-0 gDozGp\" data-testid=\"section-Responsabilidades e atribui\u00e7\u00f5es-title\">Responsabilidades e atribui\u00e7\u00f5es<\/h2>\n<div class=\"sc-add46fb1-3 fJDlzV\">\n<p class=\"ql-align-justify\">A recep\u00e7\u00e3o \u00e9 o primeiro contato do tutor com o ambiente hospitalar, ou seja, ser\u00e1 a primeira impress\u00e3o que ele ter\u00e1 da empresa. Portanto, um local aconchegante, limpo e organizado deve ser prezado em todos os momentos do dia. As principais responsabilidades e atribui\u00e7\u00f5es do cargo s\u00e3o:<\/p>\n<ul>\n<li class=\"ql-align-justify\">Atendimento presencial<\/li>\n<li class=\"ql-align-justify\">Atendimento telef\u00f4nico<\/li>\n<li class=\"ql-align-justify\">Atendimento via WhatsApp<\/li>\n<li class=\"ql-align-justify\">Confer\u00eancia e recebimento de despesas hospitalares<\/li>\n<li class=\"ql-align-justify\">Execu\u00e7\u00e3o do checklist de recep\u00e7\u00e3o<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"sc-add46fb1-1 rSSXJ\" data-testid=\"text-section\">\n<h2 class=\"sc-c87ac0d4-0 gDozGp\" data-testid=\"section-Requisitos e qualifica\u00e7\u00f5es-title\">Requisitos e qualifica\u00e7\u00f5es<\/h2>\n<div class=\"sc-add46fb1-3 fJDlzV\">\n<p class=\"ql-align-justify\">Os profissionais que atuam nesse setor devem ser emp\u00e1ticos e sol\u00edcitos, j\u00e1 que suas a\u00e7\u00f5es podem ser decisivas para o bem-estar do paciente e para a qualidade da assist\u00eancia m\u00e9dica veterin\u00e1ria. Todos os profissionais passam por treinamentos espec\u00edficos para estarem aptos a identificar um poss\u00edvel atendimento de urg\u00eancia ou emerg\u00eancia, ou seja, aquele paciente que n\u00e3o pode aguardar nem mesmo por um curto per\u00edodo na recep\u00e7\u00e3o, no entanto, precisamos de pessoas determinadas a exercerem a fun\u00e7\u00e3o com excel\u00eancia.<\/p>\n<\/div>\n<\/div>\n<div class=\"sc-add46fb1-1 rSSXJ\" data-testid=\"text-section\">\n<h2 class=\"sc-c87ac0d4-0 gDozGp\" data-testid=\"section-Informa\u00e7\u00f5es adicionais-title\">Informa\u00e7\u00f5es adicionais<\/h2>\n<div class=\"sc-add46fb1-3 fJDlzV\">\n<p>Os benef\u00edcios oferecidos pelo Hospital VFP s\u00e3o:<\/p>\n<ul>\n<li>Vale alimenta\u00e7\u00e3o<\/li>\n<li>Aux\u00edlio refei\u00e7\u00e3o<\/li>\n<li>Vale transporte<\/li>\n<li>Descontos nos servi\u00e7os e produtos<\/li>\n<li>Day Off de anivers\u00e1rio \ud83c\udf82\ud83e\udd73<\/li>\n<li>Gympass para facilitar acesso a diversas academias no Brasil<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"sc-add46fb1-1 rSSXJ\" data-testid=\"text-section\">\n<h2 class=\"sc-c87ac0d4-0 gDozGp\" data-testid=\"section-Etapas do processo-title\">Etapas do processo<\/h2>\n<ol class=\"sc-97f6c339-0 wTJDe\" data-testid=\"job-steps-list\">\n<li><span class=\"sc-dfd42894-0 bzQMFp\">Etapa 1: Cadastro<\/span><span class=\"counter\" aria-hidden=\"true\">1<\/span><span aria-hidden=\"true\">Cadastro<\/span><\/li>\n<li><span class=\"sc-dfd42894-0 bzQMFp\">Etapa 2: V\u00eddeo profissional<\/span><span class=\"counter\" aria-hidden=\"true\">2<\/span><span aria-hidden=\"true\">V\u00eddeo profissional<\/span><\/li>\n<li><span class=\"sc-dfd42894-0 bzQMFp\">Etapa 3: Entrevista<\/span><span class=\"counter\" aria-hidden=\"true\">3<\/span><span aria-hidden=\"true\">Entrevista<\/span><\/li>\n<li><span class=\"sc-dfd42894-0 bzQMFp\">Etapa 4: Envio de oferta<\/span><span class=\"counter\" aria-hidden=\"true\">4<\/span><span aria-hidden=\"true\">Envio de oferta<\/span><\/li>\n<li><span class=\"sc-dfd42894-0 bzQMFp\">Etapa 5: Contrata\u00e7\u00e3o<\/span><span class=\"counter\" aria-hidden=\"true\">5<\/span><span aria-hidden=\"true\">Contrata\u00e7\u00e3o<\/span><\/li>\n<\/ol>\n<\/div>\n<div class=\"sc-add46fb1-1 rSSXJ\" data-testid=\"text-section\">\n<h2 class=\"sc-c87ac0d4-0 gDozGp\" data-testid=\"section-Breve hist\u00f3rico do Hospital VFP-title\">Breve hist\u00f3rico do Hospital VFP<\/h2>\n<div class=\"sc-add46fb1-3 fJDlzV\">\n<p>O Hospital Veterin\u00e1rio VFP \u00e9 um hospital de apoio ao m\u00e9dico veterin\u00e1rio, foi inaugurado em julho do ano de 2020 com 5 colaboradores contratados apenas, al\u00e9m dos dois s\u00f3cios administradores. Em menos de dois anos, a empresa j\u00e1 contava com uma equipe de mais de 30 colaboradores. Em junho de 2023, a unidade matriz de Ribeir\u00e3o Preto passou de 40 colaboradores.<\/p>\n<p>\ud83c\udfe5 Atualmente, o Hospital Veterin\u00e1rio VFP de Ribeir\u00e3o Preto j\u00e1 passa de 60 pessoas na equipe e nossos principais diferenciais s\u00e3o:<\/p>\n<p>\u2705 Equipe certificada e especializada ao atendimento de pacientes graves<\/p>\n<p>\u2705 Equipamentos de alta tecnologia com o que tem mais de avan\u00e7ado na medicina<\/p>\n<p>\u2705 Comunica\u00e7\u00e3o eficiente com m\u00e9dicos veterin\u00e1rios parceiros atrav\u00e9s de sistema pr\u00f3prio de gest\u00e3o de encaminhamentos<\/p>\n<p>\u2705 Estrutura organizacional equiparada aos melhores hospitais do mundo<\/p>\n<p>\u2705 Auditorias e controle de qualidade de assist\u00eancia, limpeza e organiza\u00e7\u00e3o realizadas periodicamente<\/p>\n<p>\ud83d\ude80 O Hospital VFP \u00e9 tido como refer\u00eancia na medicina veterin\u00e1ria intensiva no quesito qualidade e inova\u00e7\u00e3o no Brasil e, em 2024, novas unidades pr\u00f3prias e franqueadas ser\u00e3o inauguradas em Araraquara, S\u00e3o Jos\u00e9 dos Campos, Uberl\u00e2ncia e Piracicaba.<\/p>\n<p>\u267b Nosso hospital vive sob a cultura de aprendizagem, com valoriza\u00e7\u00e3o de stakeholders e com as melhores tecnologias do mercado para que a assist\u00eancia m\u00e9dica veterin\u00e1ria seja eficiente.<\/p>\n<p>Venha trabalhar conosco! \ud83d\ude91 Fa\u00e7a sua inscri\u00e7\u00e3o<a href=\"https:\/\/vfphospitalveterinario.gupy.io\/job\/eyJqb2JJZCI6Nzk0MjI2OCwic291cmNlIjoiZ3VweV9wb3J0YWwifQ==?jobBoardSource=share_link\" target=\"_blank\" rel=\"noopener\"> clicando aqui<\/a>.<\/p>\n<\/div>\n<\/div>\n<\/section>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>Recepcionista Hospitalar (Ribeir\u00e3o Preto) Publicada em 09 de outubro de 2024 Inscri\u00e7\u00f5es abertas at\u00e9 31 de janeiro de 2025 Local de trabalho: Ribeir\u00e3o Preto &#8211; SPRibeir\u00e3o Preto &#8211; SP Tipo de vaga: EfetivoEfetivo Modelo de trabalho: PresencialPresencial Descri\u00e7\u00e3o da vaga \ud83c\udfe5O Hospital VFP \u00e9 tido como refer\u00eancia na medicina veterin\u00e1ria intensiva no quesito qualidade e &#8230; <a title=\"Recepcionista Hospitalar (Ribeir\u00e3o Preto)\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/26\/recepcionista-hospitalar-ribeirao-preto-4\/\" aria-label=\"Read more about Recepcionista Hospitalar (Ribeir\u00e3o Preto)\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":12630,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1,7],"tags":[],"class_list":["post-80476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-vagas-de-empregos-em-ribeirao-preto-regiao-brasil"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Recepcionista-1.webp.webp?fit=2560%2C1440&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Recepcionista-1.webp.webp?fit=2560%2C1440&ssl=1",2560,1440,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Recepcionista-1.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Recepcionista-1.webp.webp?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Recepcionista-1.webp.webp?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Recepcionista-1.webp.webp?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Recepcionista-1.webp.webp?fit=1536%2C864&ssl=1",1536,864,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Recepcionista-1.webp.webp?fit=2048%2C1152&ssl=1",2048,1152,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"Recepcionista Hospitalar (Ribeir\u00e3o Preto) Publicada em 09 de outubro de 2024 Inscri\u00e7\u00f5es abertas at\u00e9 31 de janeiro de 2025 Local de trabalho: Ribeir\u00e3o Preto &#8211; SPRibeir\u00e3o Preto &#8211; SP Tipo de vaga: EfetivoEfetivo Modelo de trabalho: PresencialPresencial Descri\u00e7\u00e3o da vaga \ud83c\udfe5O Hospital VFP \u00e9 tido como refer\u00eancia na medicina veterin\u00e1ria intensiva no quesito qualidade e&hellip;","jetpack-related-posts":[{"id":78613,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/06\/mais-de-10-vagas-de-emprego-de-recepcionista-em-ribeirao-preto-sp-38\/","url_meta":{"origin":80476,"position":0},"title":"Mais de 10 vagas de emprego de Recepcionista em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"6 de December de 2024","format":false,"excerpt":"Recep\u00e7\u00e3o - Ribeir\u00e3o Preto\/SP Studios | Recepcionista | Ribeir\u00e3o Preto (420062) Secret\u00e1ria Secret\u00e1ria - SP Recepcionista Hospitalar (Ribeir\u00e3o Preto) Pulmer- Recepcionista- Rib. Preto\/SP Recepcionista | Ribeir\u00e3o Preto - SP Recepcionista Recepcionista Recepcionista Recepcionista - SP Recepcionista Recepcionista de Academia","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/e8b9e5779e0bd80639e96387162e8114.jpg?fit=550%2C300&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/e8b9e5779e0bd80639e96387162e8114.jpg?fit=550%2C300&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/e8b9e5779e0bd80639e96387162e8114.jpg?fit=550%2C300&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":90050,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2026\/04\/27\/mais-de-10-vagas-de-emprego-de-recepcionista-em-ribeirao-preto-sp-48\/","url_meta":{"origin":80476,"position":1},"title":"Mais de 10 vagas de emprego de Recepcionista em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"27 de April de 2026","format":false,"excerpt":"Recepcionista Hospitalar (Ribeir\u00e3o Preto) Recepcionista de Agendamento Recepcionista - Unidade Ribeir\u00e3o Shopping Recepcionista Caixa - SP Recepcionista Gerente Secretaria Acad\u00eamica - Nepuga Ribeir\u00e3o Preto Recepcionista - Coco Bambu Ribeir\u00e3o Preto Recepcionista ASSISTENTE COMERCIAL\/RECEP\u00c7\u00c3O - RIBEIR\u00c3O PRETO Recepcionista Atendente","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2026\/04\/e8b9e5779e0bd80639e96387162e8114.jpg?fit=550%2C300&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2026\/04\/e8b9e5779e0bd80639e96387162e8114.jpg?fit=550%2C300&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2026\/04\/e8b9e5779e0bd80639e96387162e8114.jpg?fit=550%2C300&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":88051,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/10\/26\/mais-de-10-vagas-de-emprego-de-recepcionista-em-ribeirao-preto-sp-45\/","url_meta":{"origin":80476,"position":2},"title":"Mais de 10 vagas de emprego de Recepcionista em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"26 de October de 2025","format":false,"excerpt":"Recepcionista | Ribeir\u00e3o Preto | (Banco de Talentos) Recepcionista clinica de est\u00e9tica - Ribeir\u00e3o Preto Secret\u00e1ria Recepcionista Hospitalar (Ribeir\u00e3o Preto) Secret\u00e1ria Recepcionista - Agendamento Recepcionista RECEPCIONISTA | RIBEIR\u00c3O PRETO - SP Recepcionista area da saude Recepcionista Recepcionista Consultor(a) de Sa\u00fade.","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":89699,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2026\/03\/29\/mais-de-10-vagas-de-emprego-de-recepcionista-em-ribeirao-preto-sp-47\/","url_meta":{"origin":80476,"position":3},"title":"Mais de 10 vagas de emprego de Recepcionista em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"29 de March de 2026","format":false,"excerpt":"Recepcionista Hospitalar (Ribeir\u00e3o Preto) Recepcionista - Agendamento Recepcionista de Agendamento Recepcionista Recepcionista Recepcionista - Coco Bambu Ribeir\u00e3o Preto Recepcionista - SP Recepcionista Recepcionista Atendente EST\u00c1GIO DE RECEP\u00c7\u00c3O - RIBEIR\u00c3O PRETO Recepcionista Est\u00e1gio Administrativo - Secretariado - SP","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":75592,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/06\/mais-de-10-vagas-de-emprego-de-recepcionista-em-ribeirao-preto-sp-37\/","url_meta":{"origin":80476,"position":4},"title":"Mais de 10 vagas de emprego de Recepcionista em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"6 de November de 2024","format":false,"excerpt":"RECEPCIONISTA - BAJAJ Recepcionista Recepcionista Recepcionista Hospitalar (Ribeir\u00e3o Preto) Recepcionista Recepcionista Recepcionista Secret\u00e1ria Atendente de Recep\u00e7\u00e3o\/ Comercial - Ribeir\u00e3o Preto Recepcionista Recepcionista Recepcionista Recepcionista - SP","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":61901,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/23\/mais-de-10-vagas-de-emprego-de-recepcionista-em-ribeirao-preto-sp-33\/","url_meta":{"origin":80476,"position":5},"title":"Mais de 10 vagas de emprego de Recepcionista em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"23 de August de 2024","format":false,"excerpt":"RECEPCIONISTA HOSPITALAR RIBEIR\u00c3O PRETO - SP Efetivo Recepcionista Recepcionista Recepcionista de Loja - Petz Ribeir\u00e3o Preto Presidente Vargas Recepcionista - Ribeir\u00e3o Preto\/SP Recepcionista AME RP: Aux. de Atendim. RECEP\u00c7\u00c3O - 220h","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/e8b9e5779e0bd80639e96387162e8114.jpg?fit=550%2C300&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/e8b9e5779e0bd80639e96387162e8114.jpg?fit=550%2C300&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/e8b9e5779e0bd80639e96387162e8114.jpg?fit=550%2C300&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-kW0","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/80476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=80476"}],"version-history":[{"count":3,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/80476\/revisions"}],"predecessor-version":[{"id":80479,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/80476\/revisions\/80479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/12630"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=80476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=80476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=80476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}