{"id":8044,"date":"2023-11-29T11:13:03","date_gmt":"2023-11-29T14:13:03","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/29\/nao-estou-em-um-relacionamento\/"},"modified":"2023-11-29T11:13:03","modified_gmt":"2023-11-29T14:13:03","slug":"nao-estou-em-um-relacionamento","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/29\/nao-estou-em-um-relacionamento\/","title":{"rendered":"&#8216;N\u00e3o estou em um relacionamento&#8217;"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div itemprop=\"text\">\n<p>Parece que que algumas das separa\u00e7\u00f5es mais previstas foi confirmada. Alguns casais famosos j\u00e1 estavam dando sinais de que o relacionamento n\u00e3o ia bem e a confirma\u00e7\u00e3o veio.<\/p>\n<p>Bruna Biancardi usou as redes sociais para falar sobre o fim de seu relacionamento com o jogador de futebol Neymar Jr. Isso ap\u00f3s surgir um suposto novo caso do jogador com outra mulher, ela aproveitou para deixar claro seu status atual.<\/p>\n<p><em>\u201cEste \u00e9 um assunto particular, mas como diariamente me relacionam as not\u00edcias, suposi\u00e7\u00f5es, piadas, informo que n\u00e3o estou em um relacionamento\u201d<\/em> escreveu ela em seu Instagram.<\/p>\n<p>Ela, que est\u00e1 hospedada na mans\u00e3o do jogador com sua filha reafirmou sua posi\u00e7\u00e3o explicando que ela e Neymar Jr s\u00e3o os pais de Mavie e este \u00e9 o v\u00ednculo deles.<\/p>\n<p>Bruna e a filha resolveram passar uma temporada com a fam\u00edlia do jogador ap\u00f3s acontecer um assalto na casa em que seus pais estavam, em Cotia. A resid\u00eancia foi invadida por bandidos.<\/p>\n<p>Um dos participantes foi preso e identificado como morador do condom\u00ednio em que fica a resid\u00eancia. Sendo ele quem facilitou a entrada dos comparsas, j\u00e1 que estava a uma semana morando neste condom\u00ednio com a m\u00e3e e o padrasto.<\/p>\n<p>Na ocasi\u00e3o, os pais de Bruna foram amarrados enquanto eles roubavam pertences de valor da casa, como j\u00f3ias, bolsas de luxo e outros artigos caros. O preju\u00edzo chegou a ser estimado em R$ 600 mil levados por eles da casa.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/fnmais.com\/apos-suposto-novo-caso-neymar-bruna-biancardi-expoe-novo-status-nao-estou-em-relacionamento\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Parece que que algumas das separa\u00e7\u00f5es mais previstas foi confirmada. Alguns casais famosos j\u00e1 estavam dando sinais de que o relacionamento n\u00e3o ia bem e a confirma\u00e7\u00e3o veio. Bruna Biancardi usou as redes sociais para falar sobre o fim de seu relacionamento com o jogador de futebol Neymar Jr. Isso ap\u00f3s surgir um suposto&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":8045,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656738a7943009673.jpg?fit=1200%2C628&ssl=1",1200,628,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656738a7943009673.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656738a7943009673.jpg?fit=300%2C157&ssl=1",300,157,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656738a7943009673.jpg?fit=768%2C402&ssl=1",768,402,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656738a7943009673.jpg?fit=1024%2C536&ssl=1",1024,536,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656738a7943009673.jpg?fit=1200%2C628&ssl=1",1200,628,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656738a7943009673.jpg?fit=1200%2C628&ssl=1",1200,628,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656738a7943009673.jpg?resize=930%2C620&ssl=1",930,620,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Parece que que algumas das separa\u00e7\u00f5es mais previstas foi confirmada. Alguns casais famosos j\u00e1 estavam dando sinais de que o relacionamento n\u00e3o ia bem e a confirma\u00e7\u00e3o veio. Bruna Biancardi usou as redes sociais para falar sobre o fim de seu relacionamento com o jogador de futebol Neymar Jr. Isso ap\u00f3s surgir um suposto&hellip;&nbsp;","jetpack-related-posts":[{"id":23599,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/02\/neymar-jr-se-envolve-em-boato-de-que-seria-pai-pela-terceira-vez-detalhes-sao-expostos\/","url_meta":{"origin":8044,"position":0},"title":"Neymar Jr. se envolve em boato de que seria pai pela terceira vez; detalhes s\u00e3o expostos","author":"ismaelcolosi.com.br","date":"2 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Nesta ter\u00e7a-feira, dia 2 de janeiro, a internet ficou agitada com a not\u00edcia de que possivelmente o famoso jogador Neymar Jr ser\u00e1 pai pela terceira vez.Tudo aconteceu ap\u00f3s a influenciadora Jamile Lima ter causado alvoro\u00e7o ao deixar um coment\u00e1rio sugestivo em uma postagem sobre Mavie, a filha mais nova\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65944826e64816971.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65944826e64816971.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65944826e64816971.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65944826e64816971.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65944826e64816971.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":20741,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/26\/neymar-jr-e-bruna-biancardi-passam-noite-de-natal-juntos-e-registram\/","url_meta":{"origin":8044,"position":1},"title":"Neymar Jr e Bruna Biancardi passam noite de Natal juntos e registram","author":"ismaelcolosi.com.br","date":"26 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Natal tem um de\u00a0 seus sin\u00f4nimos reuni\u00e3o de fam\u00edlia. \u00c9 o momento em que qualquer tipo de desaven\u00e7a familiar \u00e9 deixada para tr\u00e1s para que todos se re\u00fanam \u00e0 mesa e comemorar.Um dos ex casais mais vigiados da internet, Bruna Biancardi e Neymar Jr est\u00e3o separados a mais de\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658ae2c480ee47919.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658ae2c480ee47919.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658ae2c480ee47919.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658ae2c480ee47919.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658ae2c480ee47919.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":17987,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/19\/bruna-biancardi-rebate-criticas-apos-relatar-noite-mal-dormida-com-mavie-parem-de-ser-amargas\/","url_meta":{"origin":8044,"position":2},"title":"Bruna Biancardi rebate cr\u00edticas ap\u00f3s relatar noite mal dormida com Mavie: &#8216;Parem de ser amargas&#8217;","author":"ismaelcolosi.com.br","date":"19 de Dezembro de 2023","format":false,"excerpt":"[ad_1] A mais nova herdeira do jogador Neymar Jr, fruto de seu relacionamento com a influenciadora digital Bruna Biancardi \u00e9 not\u00edcia sempre que aparece nas redes sociais dos pais.Dessa vez, a mam\u00e3e da rec\u00e9m nascida usou as redes sociais para falar da noite mal dormida ap\u00f3s a filha precisar acordar\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6581c7a5034ad2756.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6581c7a5034ad2756.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6581c7a5034ad2756.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6581c7a5034ad2756.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6581c7a5034ad2756.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":23693,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/02\/polemica-em-torno-de-boato-de-terceiro-filho-de-neymar-gera-repercussao\/","url_meta":{"origin":8044,"position":3},"title":"Pol\u00eamica em torno de boato de terceiro filho de Neymar gera repercuss\u00e3o","author":"ismaelcolosi.com.br","date":"2 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A vida pessoal do jogador Neymar Jr. n\u00e3o para de ser assunto nas redes sociais. Desta vez, come\u00e7ou a circular o boato de que o atleta, que atualmente joga pelo Al-Hilal, iria ser pai novamente.A not\u00edcia foi divulgada na manh\u00e3 desta ter\u00e7a-feira (02\/12), pelo colunista Leo Dias. De acordo\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659498a03c5504192.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659498a03c5504192.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659498a03c5504192.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659498a03c5504192.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659498a03c5504192.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":24985,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/05\/biancardi-desabafa-sobre-carater-e-detalhe-faz-fas-apontarem-indireta-para-neymar\/","url_meta":{"origin":8044,"position":4},"title":"Biancardi desabafa sobre car\u00e1ter e detalhe faz f\u00e3s apontarem indireta para Neymar","author":"ismaelcolosi.com.br","date":"5 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Bruna Biancardi voltou a desabafar nas redes sociais e chamar a aten\u00e7\u00e3o com o conte\u00fado publicado. A influenciadora postou um text\u00e3o sobre car\u00e1ter, o que muitos f\u00e3s entenderam como uma alfinetada em Neymar.\u201cCar\u00e1ter \u00e9 algo que est\u00e1 no cora\u00e7\u00e3o, nas veias, na pele, na alma. Car\u00e1ter corre no sangue.\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659852396bb975844.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659852396bb975844.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659852396bb975844.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659852396bb975844.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659852396bb975844.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":23528,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/02\/filho-de-neymar-sofre-acidente-e-imagens-sao-expostas-menino-tem-12-anos\/","url_meta":{"origin":8044,"position":5},"title":"Filho de Neymar sofre acidente e imagens s\u00e3o expostas; menino tem 12 anos","author":"ismaelcolosi.com.br","date":"2 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A \u00faltima semana do jogador Neymar Jr. foi de muita farr a edivers\u00e3o dentro de seu cruzeiro. O navio que levava o atleta transportava centenas de famosos e an\u00f4nimos, que pagaram valor astron\u00f4mico para ficar a bordo da embarca\u00e7\u00e3o.Recentemente, Neymar passou um susto com o filho, Davi Lucca, de\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659448d4e8ea36841.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659448d4e8ea36841.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659448d4e8ea36841.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659448d4e8ea36841.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659448d4e8ea36841.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-25K","jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656738a7943009673.jpg?fit=1200%2C628&ssl=1","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=8044"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8044\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/8045"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=8044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=8044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=8044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}