{"id":8038,"date":"2023-11-29T11:00:33","date_gmt":"2023-11-29T14:00:33","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/29\/ana-hickmann-tem-pedido-negado-pela-justica-apos-pedir-divorcio-pela-maria-da-penha-contra-marido\/"},"modified":"2023-11-29T11:00:33","modified_gmt":"2023-11-29T14:00:33","slug":"ana-hickmann-tem-pedido-negado-pela-justica-apos-pedir-divorcio-pela-maria-da-penha-contra-marido","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/29\/ana-hickmann-tem-pedido-negado-pela-justica-apos-pedir-divorcio-pela-maria-da-penha-contra-marido\/","title":{"rendered":"Ana Hickmann tem pedido negado pela justi\u00e7a ap\u00f3s pedir div\u00f3rcio pela Maria da Penha contra marido"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div itemprop=\"text\">\n<p>A apresentadora Ana Hickmann tem vivido dias dif\u00edceis nas \u00faltimas semanas. Isso porque a famosa, que tem 42 anos, foi agredida pelo marido, o empres\u00e1rio Alexandre Corr\u00eaa, com quem \u00e9 casada h\u00e1 15 anos.<\/p>\n<p>No total, Ana e Alexandre j\u00e1 estavam juntos h\u00e1 25 anos. Os dois s\u00e3o pais do pequeno Ale, de 9 anos, \u00fanico fruto do casamento. A briga entre os dois aconteceu no \u00faltimo dia 11 e gerou bastante repercuss\u00e3o na m\u00eddia.<\/p>\n<p>Em entrevista recente dada ao programa Domingo Especular, da Record, Ana Hickmann detalhou a agress\u00e3o de Alexandre. Ela disse, inclusive, que o empres\u00e1rio fechou a porta contra seu bra\u00e7o lhe causando uma les\u00e3o.<\/p>\n<p>Diante da situa\u00e7\u00e3o, Ana Hickmann pediu div\u00f3rcio atrav\u00e9s da lei Maria da Penha. Contudo, a apresentadora teve o pedido negado pelo juiz da 1\u00aa Vara Criminal e de Viol\u00eancia Dom\u00e9stica e Familiar de S\u00e3o Paulo.<\/p>\n<p>Segundo o que foi informado pelo advogado de Alexandre Correa, marido de Ana Hickmann, a partir da decis\u00e3o judicial, o processo de div\u00f3rcio litigioso vai tramitar pela Vara de Fam\u00edlia e n\u00e3o pela Vara de Viol\u00eancia Dom\u00e9stica, como era esperado pela apresentadora.<\/p>\n<p>Ana e Alexandre n\u00e3o se falam desde a briga, que aconteceu dentro da casa do casal, situada no munic\u00edpio de Itu, no interior de S\u00e3o Paulo. Alguns funcion\u00e1rios estavam no local quando o epis\u00f3dio ocorreu. Uma cozinheira prestou depoimento \u00e0 pol\u00edcia e informou que as discuss\u00f5es eram comuns na casa.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/fnmais.com\/ana-hickmann-tem-pedido-negado-pela-justica-apos-pedir-divorcio-pela-maria-penha-contra-marido\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A apresentadora Ana Hickmann tem vivido dias dif\u00edceis nas \u00faltimas semanas. Isso porque a famosa, que tem 42 anos, foi agredida pelo marido, o empres\u00e1rio Alexandre Corr\u00eaa, com quem \u00e9 casada h\u00e1 15 anos. No total, Ana e Alexandre j\u00e1 estavam juntos h\u00e1 25 anos. Os dois s\u00e3o pais do pequeno Ale, de 9&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":8039,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6567392438ac57662.jpg?fit=1200%2C628&ssl=1",1200,628,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6567392438ac57662.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6567392438ac57662.jpg?fit=300%2C157&ssl=1",300,157,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6567392438ac57662.jpg?fit=768%2C402&ssl=1",768,402,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6567392438ac57662.jpg?fit=1024%2C536&ssl=1",1024,536,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6567392438ac57662.jpg?fit=1200%2C628&ssl=1",1200,628,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6567392438ac57662.jpg?fit=1200%2C628&ssl=1",1200,628,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6567392438ac57662.jpg?resize=930%2C620&ssl=1",930,620,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A apresentadora Ana Hickmann tem vivido dias dif\u00edceis nas \u00faltimas semanas. Isso porque a famosa, que tem 42 anos, foi agredida pelo marido, o empres\u00e1rio Alexandre Corr\u00eaa, com quem \u00e9 casada h\u00e1 15 anos. No total, Ana e Alexandre j\u00e1 estavam juntos h\u00e1 25 anos. Os dois s\u00e3o pais do pequeno Ale, de 9&hellip;&nbsp;","jetpack-related-posts":[{"id":5916,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/24\/segundo-advogado-marido-de-ana-hickmann-entra-com-pedido-de-divorcio\/","url_meta":{"origin":8038,"position":0},"title":"Segundo advogado, Marido de Ana Hickmann entra com pedido de div\u00f3rcio","author":"ismaelcolosi.com.br","date":"24 de Novembro de 2023","format":false,"excerpt":"[ad_1] Ap\u00f3s o site \u201cNot\u00edcias da TV\u201d divulgaram que a apresentadora Ana Hickmann j\u00e1 estaria se referindo a Alexandre Correa como ex marido, parece que ele tomou provid\u00eancias com rela\u00e7\u00e3o a isso.Segundo o advogado Enio Martins Murad em entrevista ao G1, Alexandre teria entrado com pedido de div\u00f3rcio nesta sexta\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656103f437cd03875.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656103f437cd03875.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656103f437cd03875.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656103f437cd03875.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656103f437cd03875.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":9967,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/03\/alexandre-correa-desiste-de-acao-de-divorcio-contra-ana-hickmann-apos-receber-noticia-que-o-emocionou\/","url_meta":{"origin":8038,"position":1},"title":"Alexandre Correa desiste de a\u00e7\u00e3o de div\u00f3rcio contra Ana Hickmann ap\u00f3s receber not\u00edcia que o emocionou","author":"ismaelcolosi.com.br","date":"3 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Alexandre Correa decidiu retirar a a\u00e7\u00e3o de div\u00f3rcio que havia movido contra Ana Hickmann. Segundo informa\u00e7\u00f5es, o processo de separa\u00e7\u00e3o do casal prossegue, mas agora sob uma a\u00e7\u00e3o iniciada pela funcion\u00e1ria da Record.O advogado Enio Martins, representante de Alexandre Correa, em entrevista ao Estad\u00e3o, explicou que a desist\u00eancia ocorreu\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656c8d9fa0fe08046.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656c8d9fa0fe08046.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656c8d9fa0fe08046.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656c8d9fa0fe08046.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656c8d9fa0fe08046.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6794,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/26\/jurei-que-nenhum-homem-me-faria-isso\/","url_meta":{"origin":8038,"position":2},"title":"&#8216;Jurei que nenhum homem me faria isso&#8217;","author":"ismaelcolosi.com.br","date":"26 de Novembro de 2023","format":false,"excerpt":"[ad_1] Enfrentando um processo de div\u00f3rcio conturbado, ap\u00f3s ter denunciado o marido por viol\u00eancia dom\u00e9stica, Ana Hickmann quebrou o sil\u00eancio pela primeira vez. Em entrevista, a apresentadora falou abertamente sobre o caso.Ana foi casada por mais de 20 anos com Alexandre Correa, que desempenhava tamb\u00e9m papel de seu empres\u00e1rio. O\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6563ed8c550445587.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6563ed8c550445587.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6563ed8c550445587.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6563ed8c550445587.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6563ed8c550445587.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1571,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/13\/ana-hickmann-o-que-se-sabe-sobre-a-denuncia-contra-o-marido\/","url_meta":{"origin":8038,"position":3},"title":"Ana Hickmann: o que se sabe sobre a den\u00fancia contra o marido","author":"ismaelcolosi.com.br","date":"13 de Novembro de 2023","format":false,"excerpt":"[ad_1] A apresentadora e ex-modelo Ana Hickmann registrou um boletim de ocorr\u00eancia por viol\u00eancia dom\u00e9stica e les\u00e3o corporal contra o marido, o empres\u00e1rio Alexandre Correa, no \u00faltimo s\u00e1bado, 11. Em nota divulgada neste domingo, 12, Ana afirmou que teve um \u201cdesentendimento\u201d com o parceiro. Em outra nota, Correa negou a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/ana-scaled.jpg?fit=1000%2C552&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/ana-scaled.jpg?fit=1000%2C552&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/ana-scaled.jpg?fit=1000%2C552&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/ana-scaled.jpg?fit=1000%2C552&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":5930,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/24\/policia-arromba-apartamento-do-marido-de-ana-hickmann-e-motivo-sombrio-vem-a-tona\/","url_meta":{"origin":8038,"position":4},"title":"Policia arromba apartamento do marido de Ana Hickmann e motivo sombrio vem \u00e0 tona","author":"ismaelcolosi.com.br","date":"24 de Novembro de 2023","format":false,"excerpt":"[ad_1] Em mais uma situa\u00e7\u00e3o surpreendente, policiais arrombaram o apartamento de Alexandre Correa, marido da famosa apresentadora Ana Hickmann, no bairro da Pompeia, em S\u00e3o Paulo. A a\u00e7\u00e3o policial, aconteceu nesta sexta, 24 de novembro.Este incidente \u00e9 o mais recente em uma s\u00e9rie de eventos tumultuados para o casal. H\u00e1\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656109f4d70b16281.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656109f4d70b16281.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656109f4d70b16281.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656109f4d70b16281.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656109f4d70b16281.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7273,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/27\/alexandre-alega-estar-sendo-vitima-e-acusa-ana-hickmann-de-perseguicao-obsessiva\/","url_meta":{"origin":8038,"position":5},"title":"Alexandre alega estar sendo v\u00edtima e acusa Ana Hickmann de &#8216;persegui\u00e7\u00e3o obsessiva&#8217;","author":"ismaelcolosi.com.br","date":"27 de Novembro de 2023","format":false,"excerpt":"[ad_1] No \u00faltimo domingo (26\/11), uma reportagem especial sobre o caso Ana Hickmann deu o que falar. Em entrevista, a apresentadora fez fortes revela\u00e7\u00f5es e acusa\u00e7\u00f5es contra o empres\u00e1rio Alexandre Correa.Os dois viveram um relacionamento por cerca de 25 anos, mas o t\u00e9rmino da rela\u00e7\u00e3o tem sido conturbado. Os dois\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65652f87a3a619659.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65652f87a3a619659.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65652f87a3a619659.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65652f87a3a619659.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65652f87a3a619659.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-25E","jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6567392438ac57662.jpg?fit=1200%2C628&ssl=1","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=8038"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8038\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/8039"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=8038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=8038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=8038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}