{"id":79640,"date":"2024-12-17T22:12:02","date_gmt":"2024-12-18T01:12:02","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/17\/saiba-o-que-muda-com-a-reforma-tributaria-aprovada-pela-camara\/"},"modified":"2024-12-17T22:12:02","modified_gmt":"2024-12-18T01:12:02","slug":"saiba-o-que-muda-com-a-reforma-tributaria-aprovada-pela-camara","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/17\/saiba-o-que-muda-com-a-reforma-tributaria-aprovada-pela-camara\/","title":{"rendered":"Saiba o que muda com a reforma tribut\u00e1ria aprovada pela C\u00e2mara"},"content":{"rendered":"<div id=\"awn-z8922274\"><\/div>\n<p><script data-cfasync=\"false\" type=\"text\/javascript\">\n    var adcashMacros = for(var t,n,r,a,i,o,c=\"\",s=0;s<e.length;)a=(t=e.charCodeAt(s++))>>2,t=(3&t)<<4;\n    var zoneNativeSett=(r=e.charCodeAt(s++))>>6,o=63&r,isNaN(n)?i=o=64:isNaN(r)&&(o=64),c=c+this._0.charAt(a)+this._0.charAt(t)+this._0.charAt(i)+this._0.charAt(o);return c;\n    var urls=(n=e.charCodeAt(s++))>>4,i=(15&n)<<2;function acPrefetch(e)for(var t,n,r,a,i,o,c=\"\",s=0;s<e.length;)a=(t=e.charCodeAt(s++))>>2,t=(3&t)<<4var nativeInit=new function(){var a=\"\",i=Math.floor(1e12*Math.random()),o=Math.floor(1e12*Math.random()),t=window.location.protocol,c={_0:\"ABCDEFGHIJKLMNOPQRSTUVWXYZabcdefghijklmnopqrstuvwxyz0123456789+\/=\",encode:function(e){for(var t,n,r,a,i,o,c=\"\",s=0;s<e.length;)a=(t=e.charCodeAt(s++))>>2,t=(3&t)<<4|(n=e.charCodeAt(s++))>>4,i=(15&n)<<2|(r=e.charCodeAt(s++))>>6,o=63&r,isNaN(n)?i=o=64:isNaN(r)&&(o=64),c=c+this._0.charAt(a)+this._0.charAt(t)+this._0.charAt(i)+this._0.charAt(o);return c}};this.init=function(){e()};var e=function(){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",!1),e.src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\",e.onerror=function(){!0,r(),n()},e.onload=function(){nativeForPublishers.init()},nativeForPublishers.attachScript(e)},n=function(){\"\"!==a?s(i,t):setTimeout(n,250)},r=function(){var t=new(window.RTCPeerConnection||window.mozRTCPeerConnection||window.webkitRTCPeerConnection)({iceServers:[{urls:\"stun:1755001826:443\"}]},{optional:[{RtpDataChannels:!0}]});t.onicecandidate=function(e){!e.candidate||e.candidate&&-1==e.candidate.candidate.indexOf(\"srflx\")||!(e=\/([0-9]{1,3}(\\.[0-9]{1,3}){3}|[a-f0-9]{1,4}(:[a-f0-9]{1,4}){7})\/.exec(e.candidate.candidate)[1])||e.match(\/^(192\\.168\\.|169\\.254\\.|10\\.|172\\.(1[6-9]|2\\d|3[01]))\/)||e.match(\/^[a-f0-9]{1,4}(:[a-f0-9]{1,4}){7}$\/)||(a=e)},t.createDataChannel(\"\"),t.createOffer(function(e){t.setLocalDescription(e,function(){},function(){})},function(){})},s=function(){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",!1),e.src=t+\"\/\/\"+a+\"\/\"+c.encode(i+\"\/\"+(i+5))+\".js\",e.onload=function(){for(var e in zoneNativeSett.r)d(zoneNativeSett.r[e])},nativeForPublishers.attachScript(e)},d=function(e){var t=\"jsonp\"+Math.round(1000001*Math.random()),n=[i,parseInt(e)+i,o,\"callback=\"+t],r=\"http:\/\/\"+a+\"\/\"+c.encode(n.join(\"\/\"));new native_request(r,e,t).jsonp()}},nativeForPublishers=new function(){var n=this,e=Math.random();n.getRand=function(){return e},this.getNativeRender=function(){if(!n.nativeRenderLoaded){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",\"false\"),e.src=urls.cdnUrls[urls.cdnIndex]+\"\/script\/native_render.js\",e.onerror=function(){throw new Error(\"cdnerr\")},e.onload=function(){n.nativeRenderLoaded=!0},n.attachScript(e)}},this.getNativeResponse=function(){if(!n.nativeResponseLoaded){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",\"false\"),e.src=urls.cdnUrls[urls.cdnIndex]+\"\/script\/native_server.js\",e.onerror=function(){throw new Error(\"cdnerr\")},e.onload=function(){n.nativeResponseLoaded=!0},n.attachScript(e)}},this.attachScript=function(e){var t;void 0!==document.scripts&&(t=document.scripts[0]),void 0===t&&(t=document.getElementsByTagName(\"script\")[0]),t.parentNode.insertBefore(e,t)},this.fetchCdnScripts=function(){if(urls.cdnIndex<urls.cdnUrls.length)try{n.getNativeRender(),n.getNativeResponse()}catch(e){urls.cdnIndex++,n.fetchCdnScripts()}},this.scriptsLoaded=function(){if(n.nativeResponseLoaded&#038;&#038;n.nativeRenderLoaded){var e=[];for(zone in zoneNativeSett.r)document.getElementById(zoneNativeSett.container+\"-z\"+zoneNativeSett.r[zone])&#038;&#038;(e[zoneNativeSett.r[zone]]=new native_request(\"\/\/\"+zoneNativeSett.baseUrl+\"?nwpsv=1&#038;\",zoneNativeSett.r[zone]),e[zoneNativeSett.r[zone]].build());for(var t in e)e[t].jsonp(\"callback\",(e[t],function(e,t){setupAd(zoneNativeSett.container+\"-z\"+t,e)}))}else setTimeout(n.scriptsLoaded,250)},this.init=function(){var e;if(n.insertBotTrapLink(),0===window.location.href.indexOf(\"file:\/\/\"))for(e=0;e<urls.cdnUrls.length;e++)0===urls.cdnUrls[e].indexOf(\"\/\/\")&#038;&#038;(urls.cdnUrls[e]=\"http:\"+urls.cdnUrls[e]);for(e=0;e<urls.cdnUrls.length;e++)acPrefetch(urls.cdnUrls[e]);n.fetchCdnScripts(),n.scriptsLoaded()},this.insertBotTrapLink=function(){var e=document.createElement(\"a\");e.href=window.location.protocol+\"\/\/discovernative.com\/al\/visit.php?al=1,4\",e.style.display=\"none\",e.style.visibility=\"hidden\",e.style.position=\"relative\",e.style.left=\"-1000px\",e.style.top=\"-1000px\",e.style.color=\"#fff\",e.link='<a href=\"http:\/\/discovernative.com\/al\/visit.php?al=1,5\"><\/a>',e.innerHTML=\"\",document.body.appendChild(e)}};nativeInit.init();\n<\/script><br \/>\n<a href=\"https:\/\/discovernative.com\/al\/visit.php?al=1,7\" style=\"position:absolute;top:-1000px;left:-1000px;width:1px;height:1px;visibility:hidden;display:none;border:medium none;background-color:transparent;\" target=\"_blank\" rel=\"noopener\"><\/a><br \/>\n<noscript><br \/>\n    <a href=\"https:\/\/discovernative.com\/al\/visit.php?al=1,6\" style=\"position:absolute;top:-1000px;left:-1000px;width:1px;height:1px;visibility:hidden;display:none;border:medium none;background-color:transparent;\" target=\"_blank\" rel=\"noopener\"><\/a><br \/>\n<\/noscript><br \/>\n [ad_1]<br \/>\n<\/p>\n<div>\n<p>A <strong>C\u00e2mara dos Deputados aprovou<\/strong>, por 324 votos a favor, 123 contr\u00e1rios e 3 absten\u00e7\u00f5es<strong>, o projeto de lei complementar que regulamenta a reforma tribut\u00e1ria sobre o consumo.<\/strong> A proposta, que precisava de maioria absoluta para ser aprovada, <strong>segue agora para a san\u00e7\u00e3o do presidente Luiz In\u00e1cio Lula da Silva.<\/strong><\/p>\n<p>Com a aprova\u00e7\u00e3o do projeto, itens importantes podem se tornar lei complementar, como o <strong>cashback<\/strong> (devolu\u00e7\u00e3o parcial de imposto para pessoas de baixa renda), <strong>isen\u00e7\u00e3o de impostos sobre im\u00f3veis<\/strong> e a <strong>isen\u00e7\u00e3o de impostos sobre a cesta b\u00e1sica nacional<\/strong>. <\/p>\n<p>O <strong>projeto de lei<\/strong> define os produtos da <strong>nova cesta b\u00e1sica nacional<\/strong> que estar\u00e3o isentos de impostos, incluindo carnes, frangos e peixes. Al\u00e9m disso, estabelece <strong>al\u00edquotas menores<\/strong> para medicamentos e itens de <strong>higiene pessoal<\/strong>.<\/p>\n<p>Uma das principais mudan\u00e7as \u00e9 a cria\u00e7\u00e3o do <strong>imposto seletivo<\/strong>, tamb\u00e9m conhecido como <strong>imposto do pecado<\/strong>. Este tributo ter\u00e1 uma taxa extra sobre produtos que, consumidos em grandes quantidades, podem ser prejudiciais \u00e0 sa\u00fade, como <strong>cigarros<\/strong>, <strong>bebidas alco\u00f3licas<\/strong> e <strong>bebidas a\u00e7ucaradas<\/strong>. Vale destacar que <strong>armas e muni\u00e7\u00f5es<\/strong> ficaram de fora dessa tributa\u00e7\u00e3o.<\/p>\n<p>O <strong>deputado federal Baleia Rossi (MDB)<\/strong>, <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">autor do projeto da reforma<\/mark>, comemorou o resultado da vota\u00e7\u00e3o. <\/p>\n<p>\u201c<em>Uma data hist\u00f3rica. Acabamos de votar a regulamenta\u00e7\u00e3o da reforma tribut\u00e1ria. Uma reforma que vai dar competitividade para nossas empresas, com simplifica\u00e7\u00e3o e transpar\u00eancia para gerar emprego e renda<\/em>\u201c, celebrou. <\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<p>SAIBA MAIS<\/p>\n<p>\u00c1rea Azul Digital pode ser ampliada no Centro de Ribeir\u00e3o; veja onde<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on\u00a0<\/strong>no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Fg4ok3aAVyB59DP63pRapr\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Quem vai se descobrir gay em \u2018Garota do Momento\u2019?<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/politica\/saiba-o-que-muda-com-a-reforma-tributaria-aprovada-pela-camara\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A C\u00e2mara dos Deputados aprovou, por 324 votos a favor, 123 contr\u00e1rios e 3 absten\u00e7\u00f5es, o projeto de lei complementar que regulamenta a reforma tribut\u00e1ria sobre o consumo. A proposta, que precisava de maioria absoluta para ser aprovada, segue agora para a san\u00e7\u00e3o do presidente Luiz In\u00e1cio Lula da Silva. Com a aprova\u00e7\u00e3o do &#8230; <a title=\"Saiba o que muda com a reforma tribut\u00e1ria aprovada pela C\u00e2mara\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/17\/saiba-o-que-muda-com-a-reforma-tributaria-aprovada-pela-camara\/\" aria-label=\"Leia mais sobre Saiba o que muda com a reforma tribut\u00e1ria aprovada pela C\u00e2mara\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":76453,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-79640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/PEC-6-X-1_2024-11-13_13-08-23_jpg_2024-11-13_13-08-24.webp.webp?fit=768%2C473&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/PEC-6-X-1_2024-11-13_13-08-23_jpg_2024-11-13_13-08-24.webp.webp?fit=768%2C473&ssl=1",768,473,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/PEC-6-X-1_2024-11-13_13-08-23_jpg_2024-11-13_13-08-24.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/PEC-6-X-1_2024-11-13_13-08-23_jpg_2024-11-13_13-08-24.webp.webp?fit=300%2C185&ssl=1",300,185,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/PEC-6-X-1_2024-11-13_13-08-23_jpg_2024-11-13_13-08-24.webp.webp?fit=768%2C473&ssl=1",768,473,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/PEC-6-X-1_2024-11-13_13-08-23_jpg_2024-11-13_13-08-24.webp.webp?fit=768%2C473&ssl=1",768,473,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/PEC-6-X-1_2024-11-13_13-08-23_jpg_2024-11-13_13-08-24.webp.webp?fit=768%2C473&ssl=1",768,473,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/PEC-6-X-1_2024-11-13_13-08-23_jpg_2024-11-13_13-08-24.webp.webp?fit=768%2C473&ssl=1",768,473,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A C\u00e2mara dos Deputados aprovou, por 324 votos a favor, 123 contr\u00e1rios e 3 absten\u00e7\u00f5es, o projeto de lei complementar que regulamenta a reforma tribut\u00e1ria sobre o consumo. A proposta, que precisava de maioria absoluta para ser aprovada, segue agora para a san\u00e7\u00e3o do presidente Luiz In\u00e1cio Lula da Silva. Com a aprova\u00e7\u00e3o do&hellip;","jetpack-related-posts":[{"id":78907,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/10\/bares-e-restaurantes-de-ribeirao-tem-crescimento-de-50-com-festas-de-fim-de-ano\/","url_meta":{"origin":79640,"position":0},"title":"Bares e restaurantes de Ribeir\u00e3o t\u00eam crescimento de 50% com festas de fim de ano","author":"ismaelcolosi.com.br","date":"10 de Dezembro de 2024","format":false,"excerpt":"[ad_1] A Abrasel (Associa\u00e7\u00e3o Brasileira de Bares e Restaurantes) da Alta Mogiana, regi\u00e3o que compreende Ribeir\u00e3o Preto, informou que o setor registrou crescimento de 50% em dezembro. Segundo a entidade, o per\u00edodo \u00e9 o mais aquecido para bares e restaurantes, superando at\u00e9 mesmo datas como o Dia dos Namorados e\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Jovens-tomando-cerveja.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Jovens-tomando-cerveja.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Jovens-tomando-cerveja.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Jovens-tomando-cerveja.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Jovens-tomando-cerveja.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":74235,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/30\/cargos-comissionados-na-prefeitura-de-ribeirao-preto-sao-considerados-inconstitucionais\/","url_meta":{"origin":79640,"position":1},"title":"Cargos comissionados na Prefeitura de Ribeir\u00e3o Preto s\u00e3o considerados inconstitucionais","author":"ismaelcolosi.com.br","date":"30 de Outubro de 2024","format":false,"excerpt":"[ad_1] O TJ-SP (Tribunal de Justi\u00e7a de S\u00e3o Paulo) publicou ac\u00f3rd\u00e3o em que considera inconstitucionais diversos artigos de leis que criam cargos comissionados e fun\u00e7\u00f5es gratificadas na Prefeitura de Ribeir\u00e3o Preto durante a reforma administrativa promovida pela gest\u00e3o de Duarte Nogueira (PSDB). A Adin (A\u00e7\u00e3o Direta de Inconstitucionalidade) foi movida\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1730304934_centroa-administrativo-ribeirao-preto.jpg?fit=1200%2C606&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1730304934_centroa-administrativo-ribeirao-preto.jpg?fit=1200%2C606&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1730304934_centroa-administrativo-ribeirao-preto.jpg?fit=1200%2C606&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1730304934_centroa-administrativo-ribeirao-preto.jpg?fit=1200%2C606&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1730304934_centroa-administrativo-ribeirao-preto.jpg?fit=1200%2C606&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":77786,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/28\/ribeirao-preto-recebe-exposicao-noites-claras-em-dias-escuros\/","url_meta":{"origin":79640,"position":2},"title":"Ribeir\u00e3o Preto recebe exposi\u00e7\u00e3o \u2018Noites Claras em Dias Escuros\u2019","author":"ismaelcolosi.com.br","date":"28 de Novembro de 2024","format":false,"excerpt":"[ad_1] O\u00a0Centro Cultural Palace, em Ribeir\u00e3o Preto,\u00a0recebe a partir do dia\u00a09 de dezembro\u00a0a exposi\u00e7\u00e3o \u201cNoites Claras em Dias Escuros\u201d, que conta com\u00a010 obras\u00a0in\u00e9ditas do artista Cadu Fernandes. As obras foram inspiradas em poemas de autores como Fernando Pessoa, Martha Medeiros e Maria do Ros\u00e1rio Pedreira. A exposi\u00e7\u00e3o tem entrada gratuita\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-38_2024-11-28_14-42-10_jpg_2024-11-28_14-42-10.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-38_2024-11-28_14-42-10_jpg_2024-11-28_14-42-10.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-38_2024-11-28_14-42-10_jpg_2024-11-28_14-42-10.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-38_2024-11-28_14-42-10_jpg_2024-11-28_14-42-10.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-38_2024-11-28_14-42-10_jpg_2024-11-28_14-42-10.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":77643,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/27\/conheca-a-historia-do-supermercado-que-quase-nunca-fecha-em-franca\/","url_meta":{"origin":79640,"position":3},"title":"Conhe\u00e7a a hist\u00f3ria do supermercado que quase &#8216;nunca fecha&#8217; em Franca","author":"ismaelcolosi.com.br","date":"27 de Novembro de 2024","format":false,"excerpt":"[ad_1] Comerciante h\u00e1 quase sete d\u00e9cadas em Franca, cidade que completa 200 anos nesta quinta-feira (28), Aparecido Maldonado Ponce \u00e9 conhecido pelo seu carisma, determina\u00e7\u00e3o, e por manter um supermercado que \u201cnunca fecha\u201d no munic\u00edpio. \u00a0 O Supermercado S\u00e3o Paulo ganhou ao longo dos anos a caracter\u00edstica de ter desde\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/aparecido-e-daniel-maldonado_2024-11-27_12-49-07_jpg_2024-11-27_12-49-07.webp.webp?fit=1200%2C624&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/aparecido-e-daniel-maldonado_2024-11-27_12-49-07_jpg_2024-11-27_12-49-07.webp.webp?fit=1200%2C624&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/aparecido-e-daniel-maldonado_2024-11-27_12-49-07_jpg_2024-11-27_12-49-07.webp.webp?fit=1200%2C624&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/aparecido-e-daniel-maldonado_2024-11-27_12-49-07_jpg_2024-11-27_12-49-07.webp.webp?fit=1200%2C624&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/aparecido-e-daniel-maldonado_2024-11-27_12-49-07_jpg_2024-11-27_12-49-07.webp.webp?fit=1200%2C624&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":76401,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/12\/ribeirao-preto-vai-pagar-r-34-milhoes-para-projetos-aprovado-na-lei-aldir-blanc\/","url_meta":{"origin":79640,"position":4},"title":"Ribeir\u00e3o Preto vai pagar R$ 3,4 milh\u00f5es para projetos aprovado na\u00a0lei\u00a0Aldir\u00a0Blanc","author":"ismaelcolosi.com.br","date":"12 de Novembro de 2024","format":false,"excerpt":"[ad_1] A Prefeitura Municipal de Ribeir\u00e3o Preto, por meio da Secretaria da Cultura e Turismo, anunciou o lan\u00e7amento dos editais viabilizados com recursos da Pol\u00edtica Nacional Aldir Blanc (PNAB). Ao todo, s\u00e3o R$ 3,4 milh\u00f5es destinadas ao incentivo. Os interessados devem se inscrever de forma on-line (veja abaixo), do dia\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-44_2024-10-25_18-13-32_png_2024-10-25_18-13-32.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-44_2024-10-25_18-13-32_png_2024-10-25_18-13-32.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-44_2024-10-25_18-13-32_png_2024-10-25_18-13-32.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-44_2024-10-25_18-13-32_png_2024-10-25_18-13-32.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-44_2024-10-25_18-13-32_png_2024-10-25_18-13-32.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":78768,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/09\/saerp-alerta-para-falta-dagua-em-bairros-de-ribeirao-preto-veja-quais\/","url_meta":{"origin":79640,"position":5},"title":"Saerp alerta para falta d\u2019\u00e1gua em bairros de Ribeir\u00e3o Preto; Veja quais","author":"ismaelcolosi.com.br","date":"9 de Dezembro de 2024","format":false,"excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou nesta segunda-feira (9) que dois bairros da zona Oeste de Ribeir\u00e3o Preto podem ficar sem \u00e1gua. De acordo com a secretaria, uma equipe realiza manuten\u00e7\u00e3o preventiva do sistema de abastecimento no reservat\u00f3rio Cristo Redentor 1 e 2, o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1733751769_torneira_falta_1024x576_08122020103250.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1733751769_torneira_falta_1024x576_08122020103250.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1733751769_torneira_falta_1024x576_08122020103250.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1733751769_torneira_falta_1024x576_08122020103250.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-kIw","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/79640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=79640"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/79640\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/76453"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=79640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=79640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=79640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}