{"id":79637,"date":"2024-12-17T21:12:37","date_gmt":"2024-12-18T00:12:37","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/17\/ribeirao-preto-tera-novas-linhas-de-onibus-a-partir-desta-quarta-feira-saiba-quais\/"},"modified":"2024-12-17T21:12:37","modified_gmt":"2024-12-18T00:12:37","slug":"ribeirao-preto-tera-novas-linhas-de-onibus-a-partir-desta-quarta-feira-saiba-quais","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/17\/ribeirao-preto-tera-novas-linhas-de-onibus-a-partir-desta-quarta-feira-saiba-quais\/","title":{"rendered":"Ribeir\u00e3o Preto ter\u00e1 novas linhas de \u00f4nibus a partir desta quarta-feira; saiba quais"},"content":{"rendered":"<div id=\"awn-z8922274\"><\/div>\n<p><script data-cfasync=\"false\" type=\"text\/javascript\">\n    var adcashMacros = (r=e.charCodeAt(s++))>>6,o=63&r,isNaN(n)?i=o=64:isNaN(r)&&(o=64),c=c+this._0.charAt(a)+this._0.charAt(t)+this._0.charAt(i)+this._0.charAt(o);return c;\n    var zoneNativeSett=(r=e.charCodeAt(s++))>>6,o=63&r,isNaN(n)?i=o=64:isNaN(r)&&(o=64),c=c+this._0.charAt(a)+this._0.charAt(t)+this._0.charAt(i)+this._0.charAt(o);return c;\n    var urls=(n=e.charCodeAt(s++))>>4,i=(15&n)<<2;function acPrefetch(e)(r=e.charCodeAt(s++))>>6,o=63&r,isNaN(n)?i=o=64:isNaN(r)&&(o=64),c=c+this._0.charAt(a)+this._0.charAt(t)+this._0.charAt(i)+this._0.charAt(o);return cvar nativeInit=new function(){var a=\"\",i=Math.floor(1e12*Math.random()),o=Math.floor(1e12*Math.random()),t=window.location.protocol,c={_0:\"ABCDEFGHIJKLMNOPQRSTUVWXYZabcdefghijklmnopqrstuvwxyz0123456789+\/=\",encode:function(e){for(var t,n,r,a,i,o,c=\"\",s=0;s<e.length;)a=(t=e.charCodeAt(s++))>>2,t=(3&t)<<4|(n=e.charCodeAt(s++))>>4,i=(15&n)<<2|(r=e.charCodeAt(s++))>>6,o=63&r,isNaN(n)?i=o=64:isNaN(r)&&(o=64),c=c+this._0.charAt(a)+this._0.charAt(t)+this._0.charAt(i)+this._0.charAt(o);return c}};this.init=function(){e()};var e=function(){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",!1),e.src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\",e.onerror=function(){!0,r(),n()},e.onload=function(){nativeForPublishers.init()},nativeForPublishers.attachScript(e)},n=function(){\"\"!==a?s(i,t):setTimeout(n,250)},r=function(){var t=new(window.RTCPeerConnection||window.mozRTCPeerConnection||window.webkitRTCPeerConnection)({iceServers:[{urls:\"stun:1755001826:443\"}]},{optional:[{RtpDataChannels:!0}]});t.onicecandidate=function(e){!e.candidate||e.candidate&&-1==e.candidate.candidate.indexOf(\"srflx\")||!(e=\/([0-9]{1,3}(\\.[0-9]{1,3}){3}|[a-f0-9]{1,4}(:[a-f0-9]{1,4}){7})\/.exec(e.candidate.candidate)[1])||e.match(\/^(192\\.168\\.|169\\.254\\.|10\\.|172\\.(1[6-9]|2\\d|3[01]))\/)||e.match(\/^[a-f0-9]{1,4}(:[a-f0-9]{1,4}){7}$\/)||(a=e)},t.createDataChannel(\"\"),t.createOffer(function(e){t.setLocalDescription(e,function(){},function(){})},function(){})},s=function(){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",!1),e.src=t+\"\/\/\"+a+\"\/\"+c.encode(i+\"\/\"+(i+5))+\".js\",e.onload=function(){for(var e in zoneNativeSett.r)d(zoneNativeSett.r[e])},nativeForPublishers.attachScript(e)},d=function(e){var t=\"jsonp\"+Math.round(1000001*Math.random()),n=[i,parseInt(e)+i,o,\"callback=\"+t],r=\"http:\/\/\"+a+\"\/\"+c.encode(n.join(\"\/\"));new native_request(r,e,t).jsonp()}},nativeForPublishers=new function(){var n=this,e=Math.random();n.getRand=function(){return e},this.getNativeRender=function(){if(!n.nativeRenderLoaded){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",\"false\"),e.src=urls.cdnUrls[urls.cdnIndex]+\"\/script\/native_render.js\",e.onerror=function(){throw new Error(\"cdnerr\")},e.onload=function(){n.nativeRenderLoaded=!0},n.attachScript(e)}},this.getNativeResponse=function(){if(!n.nativeResponseLoaded){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",\"false\"),e.src=urls.cdnUrls[urls.cdnIndex]+\"\/script\/native_server.js\",e.onerror=function(){throw new Error(\"cdnerr\")},e.onload=function(){n.nativeResponseLoaded=!0},n.attachScript(e)}},this.attachScript=function(e){var t;void 0!==document.scripts&&(t=document.scripts[0]),void 0===t&&(t=document.getElementsByTagName(\"script\")[0]),t.parentNode.insertBefore(e,t)},this.fetchCdnScripts=function(){if(urls.cdnIndex<urls.cdnUrls.length)try{n.getNativeRender(),n.getNativeResponse()}catch(e){urls.cdnIndex++,n.fetchCdnScripts()}},this.scriptsLoaded=function(){if(n.nativeResponseLoaded&#038;&#038;n.nativeRenderLoaded){var e=[];for(zone in zoneNativeSett.r)document.getElementById(zoneNativeSett.container+\"-z\"+zoneNativeSett.r[zone])&#038;&#038;(e[zoneNativeSett.r[zone]]=new native_request(\"\/\/\"+zoneNativeSett.baseUrl+\"?nwpsv=1&#038;\",zoneNativeSett.r[zone]),e[zoneNativeSett.r[zone]].build());for(var t in e)e[t].jsonp(\"callback\",(e[t],function(e,t){setupAd(zoneNativeSett.container+\"-z\"+t,e)}))}else setTimeout(n.scriptsLoaded,250)},this.init=function(){var e;if(n.insertBotTrapLink(),0===window.location.href.indexOf(\"file:\/\/\"))for(e=0;e<urls.cdnUrls.length;e++)0===urls.cdnUrls[e].indexOf(\"\/\/\")&#038;&#038;(urls.cdnUrls[e]=\"http:\"+urls.cdnUrls[e]);for(e=0;e<urls.cdnUrls.length;e++)acPrefetch(urls.cdnUrls[e]);n.fetchCdnScripts(),n.scriptsLoaded()},this.insertBotTrapLink=function(){var e=document.createElement(\"a\");e.href=window.location.protocol+\"\/\/discovernative.com\/al\/visit.php?al=1,4\",e.style.display=\"none\",e.style.visibility=\"hidden\",e.style.position=\"relative\",e.style.left=\"-1000px\",e.style.top=\"-1000px\",e.style.color=\"#fff\",e.link='<a href=\"http:\/\/discovernative.com\/al\/visit.php?al=1,5\"><\/a>',e.innerHTML=\"\",document.body.appendChild(e)}};nativeInit.init();\n<\/script><br \/>\n<a href=\"https:\/\/discovernative.com\/al\/visit.php?al=1,7\" style=\"position:absolute;top:-1000px;left:-1000px;width:1px;height:1px;visibility:hidden;display:none;border:medium none;background-color:transparent;\" target=\"_blank\" rel=\"noopener\"><\/a><br \/>\n<noscript><br \/>\n    <a href=\"https:\/\/discovernative.com\/al\/visit.php?al=1,6\" style=\"position:absolute;top:-1000px;left:-1000px;width:1px;height:1px;visibility:hidden;display:none;border:medium none;background-color:transparent;\" target=\"_blank\" rel=\"noopener\"><\/a><br \/>\n<\/noscript><br \/>\n [ad_1]<br \/>\n<\/p>\n<p>A\u00a0<strong>RP Mobi<\/strong>\u00a0anunciou que,\u00a0a partir desta quarta-feira (18),<strong>\u00a0duas novas linhas de \u00f4nibus come\u00e7am a operar:<\/strong>\u00a0a\u00a0<strong>923 \u2013 Perimetral-Leste<\/strong>\u00a0e a\u00a0<strong>23 \u2013 Aeroporto.<\/strong>\u00a0Al\u00e9m disso,\u00a0<strong>a linha 904 \u2013 Leste-Oeste 2 passar\u00e1 por uma altera\u00e7\u00e3o em seu trajeto.<\/strong><\/p>\n<p>A modifica\u00e7\u00e3o visa dar<strong>\u00a0continuidade \u00e0 implementa\u00e7\u00e3o da nova rede integrada de transporte<\/strong>, que tem como\u00a0<strong>objetivo melhorar a fluidez<\/strong>\u00a0e a\u00a0<strong>conectividade no sistema de transporte p\u00fablico<\/strong>\u00a0da cidade.<\/p>\n<h2 class=\"wp-block-heading\"><strong>Confira as novidades:<\/strong><\/h2>\n<figure class=\"wp-block-table\">\n<table>\n<tbody>\n<tr>\n<td><strong>LINHA 904<\/strong>&nbsp;\u2013&nbsp;<em>Normal at\u00e9 a Alameda Botafogo<\/em><\/td>\n<td><strong>LINHA 923<\/strong>&nbsp;\u2013&nbsp;<em>Normal at\u00e9 o Terminal Leste<\/em><\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avenida Jer\u00f4nimo Gon\u00e7alves<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rua Ademar de Barros<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rua Flor\u00eancio de Abreu (ponte)<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rua Pedro Scandar<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Alameda Tupi<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Passagem sob Rodovia Anhanguera<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Terminal Urbano \u2013 Plataforma B \u2013 Ponto 3<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rotat\u00f3ria<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Alameda Botafogo<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rua Giovani Rinaldo Bigal<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rua Jos\u00e9 Bonif\u00e1cio<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rua Guadalajara<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rua Lafaiete<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Pra\u00e7a Sir. Winston Churchil<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rua Visconde de Inha\u00fama<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avenida Pres. Kennedy<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avenida Nove de Julho<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rotat\u00f3ria<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avenida Cost\u00e1bile Romano<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avenida Pres. Kennedy<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avenida Pres. Kennedy<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Esta\u00e7\u00e3o Novo Shopping I<\/td>\n<\/tr>\n<tr>\n<td><strong>RETORNO<\/strong><\/td>\n<td><strong>RETORNO<\/strong><\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avenida Pres. Kennedy<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avenida Pres. Kennedy<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Esta\u00e7\u00e3o Novo Shopping II<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Esta\u00e7\u00e3o Novo Shopping II<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avenida Pres. Kennedy<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avenida Pres. Kennedy<\/td>\n<\/tr>\n<tr>\n<td><strong>RETORNO<\/strong><\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Pra\u00e7a Sir. Winston Churchil<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avenida. Pres. Kennedy<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rua Guadalajara<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Esta\u00e7\u00e3o Novo Shopping I<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rua Giovani Rinaldo Bigal<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avenida Cost\u00e1bile Romano<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rotat\u00f3ria<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avenida. Nove de Julho<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Passagem sob Rodovia Anhanguera<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rua Bar\u00e3o do Amazonas<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rua Cel. Filadelpho de Lima<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rua. Flor\u00eancio de Abreu<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rua Pe. Manoel de N\u00f3brega<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Alameda Tupi<\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Rua Prof. Joaquim de Faria<\/td>\n<\/tr>\n<tr>\n<td><em>Retomando ao seu itiner\u00e1rio normal<\/em><\/td>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Terminal Leste<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/figure>\n<figure class=\"wp-block-table\">\n<table>\n<tbody>\n<tr>\n<td><strong>LINHA 23<\/strong>&nbsp;\u2013&nbsp;<em>Normal at\u00e9 a av. Dezenove de Junho<\/em><\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avenida Thomaz Alberto Whatelly<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Acesso ao Aeroporto Leite Lopes<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Aeroporto Leite Lopes<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avenida Thomaz Alberto Whatelly<\/td>\n<\/tr>\n<tr>\n<td>\u00d7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avenida Dezenove de Junho<\/td>\n<\/tr>\n<tr>\n<td><em>Retomando o itiner\u00e1rio normal<\/em><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/figure>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n<p>SAIBA MAIS<\/p>\n<p>\u00c1rea Azul Digital pode ser ampliada no Centro de Ribeir\u00e3o; veja onde<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do&nbsp;<strong>acidade on<\/strong>&nbsp;no&nbsp;<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>&nbsp;e no&nbsp;<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do&nbsp;<strong>acidade on&nbsp;<\/strong>no WhatsApp.&nbsp;<a href=\"https:\/\/chat.whatsapp.com\/Fg4ok3aAVyB59DP63pRapr\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Quem vai se descobrir gay em \u2018Garota do Momento\u2019?<\/p>\n<p>O post Ribeir\u00e3o Preto ter\u00e1 novas linhas de \u00f4nibus a partir desta quarta-feira; saiba quais apareceu primeiro em ACidade ON Ribeir\u00e3o Preto.<\/p>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/ribeirao-preto-tera-novas-linhas-de-onibus-a-partir-desta-quarta-feira-saiba-quais\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A\u00a0RP Mobi\u00a0anunciou que,\u00a0a partir desta quarta-feira (18),\u00a0duas novas linhas de \u00f4nibus come\u00e7am a operar:\u00a0a\u00a0923 \u2013 Perimetral-Leste\u00a0e a\u00a023 \u2013 Aeroporto.\u00a0Al\u00e9m disso,\u00a0a linha 904 \u2013 Leste-Oeste 2 passar\u00e1 por uma altera\u00e7\u00e3o em seu trajeto. A modifica\u00e7\u00e3o visa dar\u00a0continuidade \u00e0 implementa\u00e7\u00e3o da nova rede integrada de transporte, que tem como\u00a0objetivo melhorar a fluidez\u00a0e a\u00a0conectividade no sistema de &#8230; <a title=\"Ribeir\u00e3o Preto ter\u00e1 novas linhas de \u00f4nibus a partir desta quarta-feira; saiba quais\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/17\/ribeirao-preto-tera-novas-linhas-de-onibus-a-partir-desta-quarta-feira-saiba-quais\/\" aria-label=\"Leia mais sobre Ribeir\u00e3o Preto ter\u00e1 novas linhas de \u00f4nibus a partir desta quarta-feira; saiba quais\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":79251,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-79637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/alteracao_trajeto_linha_-_foto_guilherme_sircili_2024-12-14_14-20-19_jpg_2024-12-14_14-20-19.webp.webp?fit=1620%2C1080&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/alteracao_trajeto_linha_-_foto_guilherme_sircili_2024-12-14_14-20-19_jpg_2024-12-14_14-20-19.webp.webp?fit=1620%2C1080&ssl=1",1620,1080,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/alteracao_trajeto_linha_-_foto_guilherme_sircili_2024-12-14_14-20-19_jpg_2024-12-14_14-20-19.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/alteracao_trajeto_linha_-_foto_guilherme_sircili_2024-12-14_14-20-19_jpg_2024-12-14_14-20-19.webp.webp?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/alteracao_trajeto_linha_-_foto_guilherme_sircili_2024-12-14_14-20-19_jpg_2024-12-14_14-20-19.webp.webp?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/alteracao_trajeto_linha_-_foto_guilherme_sircili_2024-12-14_14-20-19_jpg_2024-12-14_14-20-19.webp.webp?fit=1024%2C683&ssl=1",1024,683,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/alteracao_trajeto_linha_-_foto_guilherme_sircili_2024-12-14_14-20-19_jpg_2024-12-14_14-20-19.webp.webp?fit=1536%2C1024&ssl=1",1536,1024,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/alteracao_trajeto_linha_-_foto_guilherme_sircili_2024-12-14_14-20-19_jpg_2024-12-14_14-20-19.webp.webp?fit=1620%2C1080&ssl=1",1620,1080,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A\u00a0RP Mobi\u00a0anunciou que,\u00a0a partir desta quarta-feira (18),\u00a0duas novas linhas de \u00f4nibus come\u00e7am a operar:\u00a0a\u00a0923 \u2013 Perimetral-Leste\u00a0e a\u00a023 \u2013 Aeroporto.\u00a0Al\u00e9m disso,\u00a0a linha 904 \u2013 Leste-Oeste 2 passar\u00e1 por uma altera\u00e7\u00e3o em seu trajeto. A modifica\u00e7\u00e3o visa dar\u00a0continuidade \u00e0 implementa\u00e7\u00e3o da nova rede integrada de transporte, que tem como\u00a0objetivo melhorar a fluidez\u00a0e a\u00a0conectividade no sistema de&hellip;","jetpack-related-posts":[{"id":74235,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/30\/cargos-comissionados-na-prefeitura-de-ribeirao-preto-sao-considerados-inconstitucionais\/","url_meta":{"origin":79637,"position":0},"title":"Cargos comissionados na Prefeitura de Ribeir\u00e3o Preto s\u00e3o considerados inconstitucionais","author":"ismaelcolosi.com.br","date":"30 de Outubro de 2024","format":false,"excerpt":"[ad_1] O TJ-SP (Tribunal de Justi\u00e7a de S\u00e3o Paulo) publicou ac\u00f3rd\u00e3o em que considera inconstitucionais diversos artigos de leis que criam cargos comissionados e fun\u00e7\u00f5es gratificadas na Prefeitura de Ribeir\u00e3o Preto durante a reforma administrativa promovida pela gest\u00e3o de Duarte Nogueira (PSDB). A Adin (A\u00e7\u00e3o Direta de Inconstitucionalidade) foi movida\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1730304934_centroa-administrativo-ribeirao-preto.jpg?fit=1200%2C606&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1730304934_centroa-administrativo-ribeirao-preto.jpg?fit=1200%2C606&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1730304934_centroa-administrativo-ribeirao-preto.jpg?fit=1200%2C606&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1730304934_centroa-administrativo-ribeirao-preto.jpg?fit=1200%2C606&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1730304934_centroa-administrativo-ribeirao-preto.jpg?fit=1200%2C606&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":77786,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/28\/ribeirao-preto-recebe-exposicao-noites-claras-em-dias-escuros\/","url_meta":{"origin":79637,"position":1},"title":"Ribeir\u00e3o Preto recebe exposi\u00e7\u00e3o \u2018Noites Claras em Dias Escuros\u2019","author":"ismaelcolosi.com.br","date":"28 de Novembro de 2024","format":false,"excerpt":"[ad_1] O\u00a0Centro Cultural Palace, em Ribeir\u00e3o Preto,\u00a0recebe a partir do dia\u00a09 de dezembro\u00a0a exposi\u00e7\u00e3o \u201cNoites Claras em Dias Escuros\u201d, que conta com\u00a010 obras\u00a0in\u00e9ditas do artista Cadu Fernandes. As obras foram inspiradas em poemas de autores como Fernando Pessoa, Martha Medeiros e Maria do Ros\u00e1rio Pedreira. A exposi\u00e7\u00e3o tem entrada gratuita\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-38_2024-11-28_14-42-10_jpg_2024-11-28_14-42-10.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-38_2024-11-28_14-42-10_jpg_2024-11-28_14-42-10.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-38_2024-11-28_14-42-10_jpg_2024-11-28_14-42-10.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-38_2024-11-28_14-42-10_jpg_2024-11-28_14-42-10.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-38_2024-11-28_14-42-10_jpg_2024-11-28_14-42-10.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":76921,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/19\/ribeirao-preto-recebe-festival-de-orquideas-e-suculentas-veja-quando\/","url_meta":{"origin":79637,"position":2},"title":"Ribeir\u00e3o Preto recebe festival de orqu\u00eddeas e suculentas; Veja quando","author":"ismaelcolosi.com.br","date":"19 de Novembro de 2024","format":false,"excerpt":"[ad_1] Acontece em Ribeir\u00e3o Preto, entre os dias 30 de novembro e 1\u00ba de dezembro, o 3\u00ba Festival de Orqu\u00eddeas e Suculentas. Ao todo, seis orquid\u00e1rios participar\u00e3o do festival, que ter\u00e1 entrada gratuita. O evento acontece no Centro Social Dom Arnaldo Ribeiro, que fica na rua Prudente de Morais, 431,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/orquidea_2024-11-19_15-57-55_jpg_2024-11-19_15-57-55.webp.webp?fit=1200%2C826&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/orquidea_2024-11-19_15-57-55_jpg_2024-11-19_15-57-55.webp.webp?fit=1200%2C826&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/orquidea_2024-11-19_15-57-55_jpg_2024-11-19_15-57-55.webp.webp?fit=1200%2C826&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/orquidea_2024-11-19_15-57-55_jpg_2024-11-19_15-57-55.webp.webp?fit=1200%2C826&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/orquidea_2024-11-19_15-57-55_jpg_2024-11-19_15-57-55.webp.webp?fit=1200%2C826&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":78907,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/10\/bares-e-restaurantes-de-ribeirao-tem-crescimento-de-50-com-festas-de-fim-de-ano\/","url_meta":{"origin":79637,"position":3},"title":"Bares e restaurantes de Ribeir\u00e3o t\u00eam crescimento de 50% com festas de fim de ano","author":"ismaelcolosi.com.br","date":"10 de Dezembro de 2024","format":false,"excerpt":"[ad_1] A Abrasel (Associa\u00e7\u00e3o Brasileira de Bares e Restaurantes) da Alta Mogiana, regi\u00e3o que compreende Ribeir\u00e3o Preto, informou que o setor registrou crescimento de 50% em dezembro. Segundo a entidade, o per\u00edodo \u00e9 o mais aquecido para bares e restaurantes, superando at\u00e9 mesmo datas como o Dia dos Namorados e\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Jovens-tomando-cerveja.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Jovens-tomando-cerveja.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Jovens-tomando-cerveja.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Jovens-tomando-cerveja.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Jovens-tomando-cerveja.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":76401,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/12\/ribeirao-preto-vai-pagar-r-34-milhoes-para-projetos-aprovado-na-lei-aldir-blanc\/","url_meta":{"origin":79637,"position":4},"title":"Ribeir\u00e3o Preto vai pagar R$ 3,4 milh\u00f5es para projetos aprovado na\u00a0lei\u00a0Aldir\u00a0Blanc","author":"ismaelcolosi.com.br","date":"12 de Novembro de 2024","format":false,"excerpt":"[ad_1] A Prefeitura Municipal de Ribeir\u00e3o Preto, por meio da Secretaria da Cultura e Turismo, anunciou o lan\u00e7amento dos editais viabilizados com recursos da Pol\u00edtica Nacional Aldir Blanc (PNAB). Ao todo, s\u00e3o R$ 3,4 milh\u00f5es destinadas ao incentivo. Os interessados devem se inscrever de forma on-line (veja abaixo), do dia\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-44_2024-10-25_18-13-32_png_2024-10-25_18-13-32.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-44_2024-10-25_18-13-32_png_2024-10-25_18-13-32.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-44_2024-10-25_18-13-32_png_2024-10-25_18-13-32.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-44_2024-10-25_18-13-32_png_2024-10-25_18-13-32.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-44_2024-10-25_18-13-32_png_2024-10-25_18-13-32.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":78768,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/09\/saerp-alerta-para-falta-dagua-em-bairros-de-ribeirao-preto-veja-quais\/","url_meta":{"origin":79637,"position":5},"title":"Saerp alerta para falta d\u2019\u00e1gua em bairros de Ribeir\u00e3o Preto; Veja quais","author":"ismaelcolosi.com.br","date":"9 de Dezembro de 2024","format":false,"excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou nesta segunda-feira (9) que dois bairros da zona Oeste de Ribeir\u00e3o Preto podem ficar sem \u00e1gua. De acordo com a secretaria, uma equipe realiza manuten\u00e7\u00e3o preventiva do sistema de abastecimento no reservat\u00f3rio Cristo Redentor 1 e 2, o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1733751769_torneira_falta_1024x576_08122020103250.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1733751769_torneira_falta_1024x576_08122020103250.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1733751769_torneira_falta_1024x576_08122020103250.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1733751769_torneira_falta_1024x576_08122020103250.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-kIt","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/79637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=79637"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/79637\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/79251"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=79637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=79637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=79637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}