{"id":77897,"date":"2024-11-29T12:21:46","date_gmt":"2024-11-29T15:21:46","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/29\/o-que-um-manager-faz-descubra-tudo-sobre-essa-funcao\/"},"modified":"2024-11-29T12:21:46","modified_gmt":"2024-11-29T15:21:46","slug":"o-que-um-manager-faz-descubra-tudo-sobre-essa-funcao","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/29\/o-que-um-manager-faz-descubra-tudo-sobre-essa-funcao\/","title":{"rendered":"O que um manager faz? Descubra tudo sobre essa fun\u00e7\u00e3o!"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<p>O ingl\u00eas est\u00e1 mais presente em nossa rotina do que pensamos.\u00a0Briefing, insight, networking, feedback\u00a0s\u00e3o alguns dos\u00a0termos corporativos em ingl\u00eas\u00a0que comprovam isso. Acontece que, com a globaliza\u00e7\u00e3o e o networking cada [&#8230;]<\/p>\n<p>O post O que um manager faz? Descubra tudo sobre essa fun\u00e7\u00e3o! apareceu primeiro em Carreira &amp; Sucesso.<\/p>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.catho.com.br\/carreira-sucesso\/o-que-um-manager-faz-descubra-tudo-sobre-essa-funcao\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O ingl\u00eas est\u00e1 mais presente em nossa rotina do que pensamos.\u00a0Briefing, insight, networking, feedback\u00a0s\u00e3o alguns dos\u00a0termos corporativos em ingl\u00eas\u00a0que comprovam isso. Acontece que, com a globaliza\u00e7\u00e3o e o networking cada [&#8230;] O post O que um manager faz? Descubra tudo sobre essa fun\u00e7\u00e3o! apareceu primeiro em Carreira &amp; Sucesso. [ad_2] Source link \ud83d\udce2 Aviso&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1964],"tags":[],"class_list":["post-77897","post","type-post","status-publish","format-standard","hentry","category-carreira-e-sucesso-dicas-para-carreira"],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"neve-blog":false},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O ingl\u00eas est\u00e1 mais presente em nossa rotina do que pensamos.\u00a0Briefing, insight, networking, feedback\u00a0s\u00e3o alguns dos\u00a0termos corporativos em ingl\u00eas\u00a0que comprovam isso. Acontece que, com a globaliza\u00e7\u00e3o e o networking cada [&#8230;] O post O que um manager faz? Descubra tudo sobre essa fun\u00e7\u00e3o! apareceu primeiro em Carreira &amp; Sucesso. [ad_2] Source link \ud83d\udce2 Aviso&hellip;&nbsp;","jetpack-related-posts":[{"id":13983,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/11\/confira-9-dicas-para-conseguir-emprego-sem-experiencia-em-2024\/","url_meta":{"origin":77897,"position":0},"title":"Confira 9 dicas para conseguir emprego sem experi\u00eancia em 2024","author":"ismaelcolosi.com.br","date":"11 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Procurar um emprego sem experi\u00eancia profissional pode ser um desafio, mas saiba que \u00e9 poss\u00edvel conquistar a t\u00e3o sonhada vaga de trabalho! Por isso, selecionamos nove dicas para voc\u00ea se preparar e ter um perfil profissional competitivo que o mercado espera. Se deseja saber mais sobre o assunto, confira\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/emprego-sem-experiencia.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/emprego-sem-experiencia.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/emprego-sem-experiencia.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/emprego-sem-experiencia.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/emprego-sem-experiencia.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":88290,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/11\/18\/tinder-ou-linkedin-profissionais-usam-apps-de-namoro-para-conseguir-emprego\/","url_meta":{"origin":77897,"position":1},"title":"Tinder ou LinkedIn? Profissionais Usam Apps de Namoro para Conseguir Emprego","author":"ismaelcolosi.com.br","date":"18 de Novembro de 2025","format":false,"excerpt":"[ad_1] \r d3sign\/Getty Images\r Quase metade dos profissionais que recorreram aos apps de namoro por motivos profissionais admitem estar desesperados\u00a0\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r Profissionais em busca de emprego est\u00e3o recorrendo a aplicativos de namoro para fazer conex\u00f5es e encontrar novas oportunidades de carreira, e\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/11\/apps-de-namoro-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/11\/apps-de-namoro-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/11\/apps-de-namoro-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/11\/apps-de-namoro-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/11\/apps-de-namoro-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":85708,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/05\/26\/seja-dona-da-sua-propria-carreira\/","url_meta":{"origin":77897,"position":2},"title":"\u201cSeja Dona da Sua Pr\u00f3pria Carreira\u201d","author":"ismaelcolosi.com.br","date":"26 de Maio de 2025","format":false,"excerpt":"[ad_1] \r Divulga\u00e7\u00e3o\r Nascida na Argentina, Marina Fernie morou quase 20 anos no Brasil, onde fez carreira em gigantes como Unilever e Danone\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 Marina Fernie, que assumiu como general manager da Danone em Portugal em abril deste ano, acredita que\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/danone-marina-fernie-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/danone-marina-fernie-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/danone-marina-fernie-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/danone-marina-fernie-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/danone-marina-fernie-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":84802,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/04\/25\/sem-dinheiro-comece-a-empreender-usando-o-chatgpt\/","url_meta":{"origin":77897,"position":3},"title":"Sem Dinheiro? Comece a Empreender Usando o ChatGPT","author":"ismaelcolosi.com.br","date":"25 de Abril de 2025","format":false,"excerpt":"[ad_1] \r Getty Images\r A IA pode te ajudar a empreender com estrat\u00e9gia, construir sua rede de contatos e conquistar os primeiros clientes\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 Para come\u00e7ar a empreender, voc\u00ea n\u00e3o precisa, necessariamente, ter muito dinheiro. Muitos neg\u00f3cios de sucesso come\u00e7aram com\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-computador-chatgpt-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-computador-chatgpt-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-computador-chatgpt-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-computador-chatgpt-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-computador-chatgpt-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":58281,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/30\/veja-os-empregos-mais-bem-pagos-de-2024\/","url_meta":{"origin":77897,"position":4},"title":"veja os empregos mais bem pagos de 2024","author":"ismaelcolosi.com.br","date":"30 de Julho de 2024","format":false,"excerpt":"[ad_1] \u00a0 Acessibilidade L L A- A+ \u25d0 H\u00e1 cada vez menos oportunidades remotas, segundo relat\u00f3rio do LinkedIn de agosto do ano passado, mas as vagas de regime h\u00edbrido t\u00eam aumentado. No entanto, apesar das pol\u00edticas de retorno ao escrit\u00f3rio, existem sinais positivos, especialmente em setores com empregos bem remunerados.\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/carreira-trabalho-remoto-1-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/carreira-trabalho-remoto-1-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/carreira-trabalho-remoto-1-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/carreira-trabalho-remoto-1-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":40999,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/06\/como-fazer-networking-em-grandes-eventos\/","url_meta":{"origin":77897,"position":5},"title":"Como fazer networking em grandes eventos","author":"ismaelcolosi.com.br","date":"6 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Travis P Ball\/Getty ImagesO SXSW come\u00e7a esta semana em Austin, no Texas, e deve atrair 345 mil pessoas, proporcionando diversas oportunidades de networking Fazer conex\u00f5es \u00e9 um dos pontos altos ao participar de grandes eventos e festivais de inova\u00e7\u00e3o, como o SXSW (South by Southwest), realizado em Austin, Texas,\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/carreira-sxsw-networking-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/carreira-sxsw-networking-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/carreira-sxsw-networking-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/carreira-sxsw-networking-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-kgp","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/77897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=77897"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/77897\/revisions"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=77897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=77897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=77897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}