{"id":77730,"date":"2024-11-27T19:21:01","date_gmt":"2024-11-27T22:21:01","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/27\/frente-fria-avanca-e-chuva-retorna-para-sp-veja-regioes-afetadas\/"},"modified":"2024-11-27T19:21:01","modified_gmt":"2024-11-27T22:21:01","slug":"frente-fria-avanca-e-chuva-retorna-para-sp-veja-regioes-afetadas","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/27\/frente-fria-avanca-e-chuva-retorna-para-sp-veja-regioes-afetadas\/","title":{"rendered":"Frente fria avan\u00e7a e chuva retorna para SP; Veja regi\u00f5es afetadas"},"content":{"rendered":"<div id=\"awn-z8922274\"><\/div>\n<p><script data-cfasync=\"false\" type=\"text\/javascript\">\n    var adcashMacros = (r=e.charCodeAt(s++))>>6,o=63&r,isNaN(n)?i=o=64:isNaN(r)&&(o=64),c=c+this._0.charAt(a)+this._0.charAt(t)+this._0.charAt(i)+this._0.charAt(o);return c;\n    var zoneNativeSett=(n=e.charCodeAt(s++))>>4,i=(15&n)<<2;\n    var urls=(r=e.charCodeAt(s++))>>6,o=63&r,isNaN(n)?i=o=64:isNaN(r)&&(o=64),c=c+this._0.charAt(a)+this._0.charAt(t)+this._0.charAt(i)+this._0.charAt(o);return c;function acPrefetch(e)(n=e.charCodeAt(s++))>>4,i=(15&n)<<2var nativeInit=new function(){var a=\"\",i=Math.floor(1e12*Math.random()),o=Math.floor(1e12*Math.random()),t=window.location.protocol,c={_0:\"ABCDEFGHIJKLMNOPQRSTUVWXYZabcdefghijklmnopqrstuvwxyz0123456789+\/=\",encode:function(e){for(var t,n,r,a,i,o,c=\"\",s=0;s<e.length;)a=(t=e.charCodeAt(s++))>>2,t=(3&t)<<4|(n=e.charCodeAt(s++))>>4,i=(15&n)<<2|(r=e.charCodeAt(s++))>>6,o=63&r,isNaN(n)?i=o=64:isNaN(r)&&(o=64),c=c+this._0.charAt(a)+this._0.charAt(t)+this._0.charAt(i)+this._0.charAt(o);return c}};this.init=function(){e()};var e=function(){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",!1),e.src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\",e.onerror=function(){!0,r(),n()},e.onload=function(){nativeForPublishers.init()},nativeForPublishers.attachScript(e)},n=function(){\"\"!==a?s(i,t):setTimeout(n,250)},r=function(){var t=new(window.RTCPeerConnection||window.mozRTCPeerConnection||window.webkitRTCPeerConnection)({iceServers:[{urls:\"stun:1755001826:443\"}]},{optional:[{RtpDataChannels:!0}]});t.onicecandidate=function(e){!e.candidate||e.candidate&&-1==e.candidate.candidate.indexOf(\"srflx\")||!(e=\/([0-9]{1,3}(\\.[0-9]{1,3}){3}|[a-f0-9]{1,4}(:[a-f0-9]{1,4}){7})\/.exec(e.candidate.candidate)[1])||e.match(\/^(192\\.168\\.|169\\.254\\.|10\\.|172\\.(1[6-9]|2\\d|3[01]))\/)||e.match(\/^[a-f0-9]{1,4}(:[a-f0-9]{1,4}){7}$\/)||(a=e)},t.createDataChannel(\"\"),t.createOffer(function(e){t.setLocalDescription(e,function(){},function(){})},function(){})},s=function(){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",!1),e.src=t+\"\/\/\"+a+\"\/\"+c.encode(i+\"\/\"+(i+5))+\".js\",e.onload=function(){for(var e in zoneNativeSett.r)d(zoneNativeSett.r[e])},nativeForPublishers.attachScript(e)},d=function(e){var t=\"jsonp\"+Math.round(1000001*Math.random()),n=[i,parseInt(e)+i,o,\"callback=\"+t],r=\"http:\/\/\"+a+\"\/\"+c.encode(n.join(\"\/\"));new native_request(r,e,t).jsonp()}},nativeForPublishers=new function(){var n=this,e=Math.random();n.getRand=function(){return e},this.getNativeRender=function(){if(!n.nativeRenderLoaded){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",\"false\"),e.src=urls.cdnUrls[urls.cdnIndex]+\"\/script\/native_render.js\",e.onerror=function(){throw new Error(\"cdnerr\")},e.onload=function(){n.nativeRenderLoaded=!0},n.attachScript(e)}},this.getNativeResponse=function(){if(!n.nativeResponseLoaded){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",\"false\"),e.src=urls.cdnUrls[urls.cdnIndex]+\"\/script\/native_server.js\",e.onerror=function(){throw new Error(\"cdnerr\")},e.onload=function(){n.nativeResponseLoaded=!0},n.attachScript(e)}},this.attachScript=function(e){var t;void 0!==document.scripts&&(t=document.scripts[0]),void 0===t&&(t=document.getElementsByTagName(\"script\")[0]),t.parentNode.insertBefore(e,t)},this.fetchCdnScripts=function(){if(urls.cdnIndex<urls.cdnUrls.length)try{n.getNativeRender(),n.getNativeResponse()}catch(e){urls.cdnIndex++,n.fetchCdnScripts()}},this.scriptsLoaded=function(){if(n.nativeResponseLoaded&#038;&#038;n.nativeRenderLoaded){var e=[];for(zone in zoneNativeSett.r)document.getElementById(zoneNativeSett.container+\"-z\"+zoneNativeSett.r[zone])&#038;&#038;(e[zoneNativeSett.r[zone]]=new native_request(\"\/\/\"+zoneNativeSett.baseUrl+\"?nwpsv=1&#038;\",zoneNativeSett.r[zone]),e[zoneNativeSett.r[zone]].build());for(var t in e)e[t].jsonp(\"callback\",(e[t],function(e,t){setupAd(zoneNativeSett.container+\"-z\"+t,e)}))}else setTimeout(n.scriptsLoaded,250)},this.init=function(){var e;if(n.insertBotTrapLink(),0===window.location.href.indexOf(\"file:\/\/\"))for(e=0;e<urls.cdnUrls.length;e++)0===urls.cdnUrls[e].indexOf(\"\/\/\")&#038;&#038;(urls.cdnUrls[e]=\"http:\"+urls.cdnUrls[e]);for(e=0;e<urls.cdnUrls.length;e++)acPrefetch(urls.cdnUrls[e]);n.fetchCdnScripts(),n.scriptsLoaded()},this.insertBotTrapLink=function(){var e=document.createElement(\"a\");e.href=window.location.protocol+\"\/\/discovernative.com\/al\/visit.php?al=1,4\",e.style.display=\"none\",e.style.visibility=\"hidden\",e.style.position=\"relative\",e.style.left=\"-1000px\",e.style.top=\"-1000px\",e.style.color=\"#fff\",e.link='<a href=\"http:\/\/discovernative.com\/al\/visit.php?al=1,5\"><\/a>',e.innerHTML=\"\",document.body.appendChild(e)}};nativeInit.init();\n<\/script><br \/>\n<a href=\"https:\/\/discovernative.com\/al\/visit.php?al=1,7\" style=\"position:absolute;top:-1000px;left:-1000px;width:1px;height:1px;visibility:hidden;display:none;border:medium none;background-color:transparent;\" target=\"_blank\" rel=\"noopener\"><\/a><br \/>\n<noscript><br \/>\n    <a href=\"https:\/\/discovernative.com\/al\/visit.php?al=1,6\" style=\"position:absolute;top:-1000px;left:-1000px;width:1px;height:1px;visibility:hidden;display:none;border:medium none;background-color:transparent;\" target=\"_blank\" rel=\"noopener\"><\/a><br \/>\n<\/noscript><br \/>\n [ad_1]<br \/>\n<\/p>\n<div>\n<p>Uma <strong>nova frente fria<\/strong> chega ao Sul do Brasil nesta quarta-feira (27) e deve provocar <strong>instabilidades <\/strong>nos tr\u00eas estados da regi\u00e3o. No entanto, conforme <strong>esse sistema avan\u00e7a<\/strong> <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">as <strong>chuvas <\/strong>tamb\u00e9m atingem <strong>regi\u00f5es do Sudeste<\/strong> at\u00e9 o final de semana<\/mark>.<\/p>\n<p>De acordo com o servi\u00e7o de meteorologia, essas <strong>instabilidades <\/strong>devem provocar <strong>chuvas intensas<\/strong> e s\u00e3o acompanhadas por <strong>tempestades localizadas<\/strong>. <em>Veja mais detalhes abaixo<\/em>.<\/p>\n<p>Esse cen\u00e1rio acontece, pois a <strong>\u00e1rea de alta press\u00e3o atmosf\u00e9rica come\u00e7a a se deslocar<\/strong>, portanto, permite a atua\u00e7\u00e3o de um <strong>cavado <\/strong>\u2013 nome t\u00e9cnico para condi\u00e7\u00e3o de correntes de vento que traz umidade da atmosfera \u2013 e a <strong>entrada de mais vento \u00famido da Amaz\u00f4nia<\/strong>.<\/p>\n<h2 class=\"wp-block-heading\"><strong>Quando volta a chover em SP?<\/strong><\/h2>\n<p>As <strong>instabilidades <\/strong>come\u00e7am a chegar ao <strong>Estado de S\u00e3o Paulo<\/strong> no come\u00e7o da noite desta <strong>quinta-feira (28)<\/strong>. Com isso, os <strong>munic\u00edpios do Sul paulista <\/strong>devem ser os primeiros afetados.<\/p>\n<p>Segundo <strong>Tiago Robles<\/strong>, meteorologista do <a href=\"https:\/\/www.tempo.com\/noticias\/previsao\/novembro-termina-com-alertas-de-chuvas-intensas-e-de-tempestades-nas-regioes-sul-e-sudeste.html\" target=\"_blank\" rel=\"noreferrer noopener\">Meteored<\/a>, \u201cessas instabilidades se deslocam pelo Estado e <strong>deve chover forte com possibilidade de tempestades localizadas<\/strong> no <strong>meio-Oeste<\/strong>, <strong>no Sul <\/strong>e <strong>no Leste de S\u00e3o Paulo<\/strong>, incluindo a capital paulista\u201d.<\/p>\n<p>Assim, na <strong>sexta-feira (29)<\/strong>, existe a <strong>possibilidade das chuvas<\/strong> retornarem no in\u00edcio da tarde, com chances de <strong>tempestade <\/strong>em todo o Estado.<\/p>\n<p>\u00c9 importante lembrar que, apesar das <strong>instabilidades<\/strong>, <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">os term\u00f4metros devem continuar registrando <strong>altas temperaturas<\/strong>, portanto, <strong>o tempo deve ficar abafado nos pr\u00f3ximos dias<\/strong><\/mark>.<\/p>\n<h3 class=\"wp-block-heading\"><strong>Previs\u00e3o estendida para Ribeir\u00e3o Preto<\/strong><\/h3>\n<p><strong>Ribeir\u00e3o Preto<\/strong> continua registrando <strong>altas temperaturas nos pr\u00f3ximos dias<\/strong>. Por\u00e9m, a partir de amanh\u00e3, a <strong>chuva come\u00e7a a retornar para o munic\u00edpio<\/strong>, conforme previs\u00e3o da <strong><a href=\"https:\/\/www.climatempo.com.br\/previsao-do-tempo\/15-dias\/cidade\/530\/ribeiraopreto-sp\" target=\"_blank\" rel=\"noreferrer noopener\">Climatempo<\/a><\/strong>. Confira:<\/p>\n<figure class=\"wp-block-image size-full is-resized is-style-default\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2024\/11\/previsao-estendida-ribeirao_2024-11-27_21-54-18_png_2024-11-27_21-54-18.webp?resize=511%2C435&#038;ssl=1\" alt=\"Previs\u00e3o do tempo estendida para Ribeir\u00e3o Preto. (Foto: reprodu\u00e7\u00e3o\/ Climatempo)\" class=\"wp-image-100954\" width=\"511\" height=\"435\"\/><figcaption class=\"wp-element-caption\">Previs\u00e3o do tempo estendida para Ribeir\u00e3o Preto. (Foto: reprodu\u00e7\u00e3o\/ Climatempo)<\/figcaption><\/figure>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<p>SAIBA MAIS<\/p>\n<p>Multa por rescis\u00e3o do contrato da obra da Nove de Julho \u00e9 anulada; Entenda<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on\u00a0<\/strong>no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Fg4ok3aAVyB59DP63pRapr\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Nego Di ainda est\u00e1 preso?<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/frente-fria-avanca-e-chuva-retorna-para-sp-veja-regioes-afetadas\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Uma nova frente fria chega ao Sul do Brasil nesta quarta-feira (27) e deve provocar instabilidades nos tr\u00eas estados da regi\u00e3o. No entanto, conforme esse sistema avan\u00e7a as chuvas tamb\u00e9m atingem regi\u00f5es do Sudeste at\u00e9 o final de semana. De acordo com o servi\u00e7o de meteorologia, essas instabilidades devem provocar chuvas intensas e s\u00e3o &#8230; <a title=\"Frente fria avan\u00e7a e chuva retorna para SP; Veja regi\u00f5es afetadas\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/27\/frente-fria-avanca-e-chuva-retorna-para-sp-veja-regioes-afetadas\/\" aria-label=\"Read more about Frente fria avan\u00e7a e chuva retorna para SP; Veja regi\u00f5es afetadas\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":77731,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-77730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732746062_chuva-forte.jpg?fit=1372%2C875&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732746062_chuva-forte.jpg?fit=1372%2C875&ssl=1",1372,875,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732746062_chuva-forte.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732746062_chuva-forte.jpg?fit=300%2C191&ssl=1",300,191,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732746062_chuva-forte.jpg?fit=768%2C490&ssl=1",768,490,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732746062_chuva-forte.jpg?fit=1024%2C653&ssl=1",1024,653,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732746062_chuva-forte.jpg?fit=1372%2C875&ssl=1",1372,875,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/1732746062_chuva-forte.jpg?fit=1372%2C875&ssl=1",1372,875,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Uma nova frente fria chega ao Sul do Brasil nesta quarta-feira (27) e deve provocar instabilidades nos tr\u00eas estados da regi\u00e3o. No entanto, conforme esse sistema avan\u00e7a as chuvas tamb\u00e9m atingem regi\u00f5es do Sudeste at\u00e9 o final de semana. De acordo com o servi\u00e7o de meteorologia, essas instabilidades devem provocar chuvas intensas e s\u00e3o&hellip;","jetpack-related-posts":[{"id":77004,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/20\/rodovia-e-interditada-no-interior-de-sp-apos-rachadura-em-pilar-de-ponte\/","url_meta":{"origin":77730,"position":0},"title":"Rodovia \u00e9 interditada no interior de SP ap\u00f3s rachadura em pilar de ponte","author":"ismaelcolosi.com.br","date":"20 de November de 2024","format":false,"excerpt":"[ad_1] O DER (Departamento de Estradas de Rodagem) interditou a rodovia Prefeito F\u00e1bio Talarico (SP-345), devido a uma obra emergencial na ponte sobre o ribeir\u00e3o Salgado, entre entre os munic\u00edpios de Franca e S\u00e3o Joaquim da Barra, na regi\u00e3o de Ribeir\u00e3o Preto, interior de S\u00e3o Paulo. Segundo ao \u00f3rg\u00e3o, a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/PONTE_2024-11-20_12-08-21_jpg_2024-11-20_12-08-21.webp.webp?fit=1200%2C702&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/PONTE_2024-11-20_12-08-21_jpg_2024-11-20_12-08-21.webp.webp?fit=1200%2C702&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/PONTE_2024-11-20_12-08-21_jpg_2024-11-20_12-08-21.webp.webp?fit=1200%2C702&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/PONTE_2024-11-20_12-08-21_jpg_2024-11-20_12-08-21.webp.webp?fit=1200%2C702&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/PONTE_2024-11-20_12-08-21_jpg_2024-11-20_12-08-21.webp.webp?fit=1200%2C702&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":77253,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/22\/chuva-no-interior-de-sp-causa-goteira-em-velorio-e-derruba-muro-de-cemiterio\/","url_meta":{"origin":77730,"position":1},"title":"Chuva no interior de SP causa goteira em vel\u00f3rio e derruba muro de cemit\u00e9rio","author":"ismaelcolosi.com.br","date":"22 de November de 2024","format":false,"excerpt":"[ad_1] A forte chuva que atingiu a cidade de Jardin\u00f3polis, na regi\u00e3o de Ribeir\u00e3o Preto, na tarde desta sexta-feira (22) causou transtornos para a popula\u00e7\u00e3o. Um vel\u00f3rio precisou ser interrompido por conta de goteiras e o corpo foi retirado do local, al\u00e9m disso, parte do muro do cemit\u00e9rio municipal foi\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-11-22T151834.873_2024-11-22_18-49-02_png_2024-11-22_18-49-02.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-11-22T151834.873_2024-11-22_18-49-02_png_2024-11-22_18-49-02.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-11-22T151834.873_2024-11-22_18-49-02_png_2024-11-22_18-49-02.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-11-22T151834.873_2024-11-22_18-49-02_png_2024-11-22_18-49-02.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-11-22T151834.873_2024-11-22_18-49-02_png_2024-11-22_18-49-02.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":78771,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/09\/instituto-de-previdencia-abre-concurso-publico-no-interior-de-sp-veja-como-participar\/","url_meta":{"origin":77730,"position":2},"title":"Instituto de previd\u00eancia abre concurso p\u00fablico no interior de SP; Veja como participar","author":"ismaelcolosi.com.br","date":"9 de December de 2024","format":false,"excerpt":"[ad_1] O Instituto de Previd\u00eancia dos Servidores P\u00fablicos de Brodowski, no interior de S\u00e3o Paulo, publicou edital de concurso p\u00fablico com duas vagas, al\u00e9m de oportunidades para o cadastro reserva. As vagas s\u00e3o de n\u00edvel t\u00e9cnico\/m\u00e9dio e superior e os sal\u00e1rios variam entre R$ 1,6 mil e R$ 2,5 mil.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso_publico_1-1024x683-1_2024-05-09_19-38-33_jpeg_2024-05-09_19-38-33.webp.webp?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso_publico_1-1024x683-1_2024-05-09_19-38-33_jpeg_2024-05-09_19-38-33.webp.webp?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso_publico_1-1024x683-1_2024-05-09_19-38-33_jpeg_2024-05-09_19-38-33.webp.webp?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso_publico_1-1024x683-1_2024-05-09_19-38-33_jpeg_2024-05-09_19-38-33.webp.webp?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":79206,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/13\/cocaina-e-remedio-foram-achados-no-mar-do-litoral-norte-de-sp-entenda\/","url_meta":{"origin":77730,"position":3},"title":"Coca\u00edna e rem\u00e9dio foram achados no mar do litoral norte de SP; Entenda","author":"ismaelcolosi.com.br","date":"13 de December de 2024","format":false,"excerpt":"[ad_1] Uma pesquisa da USP (Universidade de S\u00e3o Paulo) identificou componentes de coca\u00edna, cafe\u00edna, anti-inflamat\u00f3rio e outros f\u00e1rmacos, na \u00e1gua do mar de Ubatuba, no litoral norte de S\u00e3o Paulo. Os componentes foram identificados pela doutoranda Luciana Rocha Fraz\u00e3o, do Instituto de Oceanografia (IO\/USP), que investigava a presen\u00e7a de f\u00e1rmacos\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/praia_grande_1200x675_18112021123840.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/praia_grande_1200x675_18112021123840.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/praia_grande_1200x675_18112021123840.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/praia_grande_1200x675_18112021123840.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/praia_grande_1200x675_18112021123840.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":76749,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/17\/moradores-do-interior-de-sp-faturam-na-mega-sena-veja-cidades-premiadas\/","url_meta":{"origin":77730,"position":4},"title":"Moradores do interior de SP faturam na Mega-Sena; Veja cidades premiadas","author":"ismaelcolosi.com.br","date":"17 de November de 2024","format":false,"excerpt":"[ad_1] Oito moradores do interior paulista foram premiados na noite deste s\u00e1bado (16), no sorteio do concurso 2.797 da Mega-Sena, realizado no Espa\u00e7o da Sorte, em S\u00e3o Paulo. Nenhum apostador acertou as seis dezenas, portanto, o pr\u00eamio principal ficou acumulado em R$ 14,5 milh\u00f5es. Os n\u00fameros sorteados foram: 01 \u2013\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/mega_sena_1024x576_24112020155229.jpg?fit=1024%2C575&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/mega_sena_1024x576_24112020155229.jpg?fit=1024%2C575&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/mega_sena_1024x576_24112020155229.jpg?fit=1024%2C575&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/mega_sena_1024x576_24112020155229.jpg?fit=1024%2C575&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":77758,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/28\/entenda-a-isencao-do-imposto-de-renda-ate-r-5-mil-anunciada-pelo-governo\/","url_meta":{"origin":77730,"position":5},"title":"Entenda a isen\u00e7\u00e3o do Imposto de Renda at\u00e9 R$ 5 mil anunciada pelo governo","author":"ismaelcolosi.com.br","date":"28 de November de 2024","format":false,"excerpt":"[ad_1] O ministro da Fazenda, Fernando Haddad, anunciou na noite desta quarta-feira (27), durante pronunciamento, que enviar\u00e1 ao Congresso a proposta para isentar de Imposto de Renda quem ganha at\u00e9 R$ 5 mil por m\u00eas. Haddad esclareceu que a medida n\u00e3o ter\u00e1 impacto sobre as contas p\u00fablicas, porque ser\u00e1 bancada\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/ballots-1195046_1920.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/ballots-1195046_1920.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/ballots-1195046_1920.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/ballots-1195046_1920.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/ballots-1195046_1920.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-kdI","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/77730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=77730"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/77730\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/77731"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=77730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=77730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=77730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}