{"id":7542,"date":"2023-11-28T11:30:47","date_gmt":"2023-11-28T14:30:47","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/28\/tregua-entre-israel-e-hamas-chega-ao-quinto-dia-e-mais-refens-devem-ser-libertados-nesta-terca\/"},"modified":"2023-11-28T11:30:47","modified_gmt":"2023-11-28T14:30:47","slug":"tregua-entre-israel-e-hamas-chega-ao-quinto-dia-e-mais-refens-devem-ser-libertados-nesta-terca","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/28\/tregua-entre-israel-e-hamas-chega-ao-quinto-dia-e-mais-refens-devem-ser-libertados-nesta-terca\/","title":{"rendered":"Tr\u00e9gua entre Israel e Hamas chega ao quinto dia e mais ref\u00e9ns devem ser libertados nesta ter\u00e7a"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"Corpo\">Entrou em vigor nesta ter\u00e7a-feira, 28, a extens\u00e3o da tr\u00e9gua entre Israel e o grupo terrorista Hamas, depois que ambos os lados concordaram em prolongar o seu cessar-fogo por mais dois dias na segunda-feira, 27. Com a medida, mais ref\u00e9ns israelenses devem ser libertados em troca de palestinos que est\u00e3o nas pris\u00f5es israelenses at\u00e9 a quarta-feira, 29.<\/p>\n<p>O acordo para mais dois dias de cessar-fogo, anunciado pelo Catar, aumentou as esperan\u00e7as de novas prorroga\u00e7\u00f5es, que tamb\u00e9m permitiriam a entrada de mais ajuda humanit\u00e1ria na Faixa de Gaza, em meio a guerra que deslocou a popula\u00e7\u00e3o do enclave para o sul de Gaza.<\/p>\n<p>Onze ref\u00e9ns israelenses foram libertados pelo Hamas na segunda-feira, depois de mais de sete semanas em cativeiro no enclave palestino, no que seria o \u00faltimo dia do acordo de cessar-fogo entre Israel e o grupo terrorista, que havia sido negociado pelo Catar e Estados Unidos \u2013 e 33 prisioneiros palestinos foram libertados por Israel. Segundo o minist\u00e9rio da Sa\u00fade do pa\u00eds do Oriente M\u00e9dio, os 11 israelenses libertados tem boas condi\u00e7\u00f5es de sa\u00fade e j\u00e1 est\u00e3o reunidos com as suas fam\u00edlias<\/p>\n<p>Tel-Aviv afirmou que poderia estender o acordo em um dia para cada dez ref\u00e9ns adicionais libertados. Ap\u00f3s o an\u00fancio do Catar, o grupo terrorista Hamas confirmou que havia concordado em uma prorroga\u00e7\u00e3o de dois dias da tr\u00e9gua.<\/p>\n<p><b>Israel recebe lista de ref\u00e9ns que ser\u00e3o libertados<\/b><\/p>\n<p>Israel j\u00e1 recebeu a lista de ref\u00e9ns que deve sair de Gaza nesta ter\u00e7a-feira, segundo informa\u00e7\u00f5es do gabinete do primeiro-ministro de Israel, Binyamin Netanyahu. A lista est\u00e1 sendo revista e as fam\u00edlias dos ref\u00e9ns est\u00e3o sendo avisadas.<\/p>\n<p>O gabinete n\u00e3o especificou a quantidade de ref\u00e9ns que ser\u00e3o libertados. Dentre os ref\u00e9ns que podem sair nos pr\u00f3ximos dias est\u00e1 Kfir Bibas, de apenas 10 meses, que foi sequestrado junto com sua fam\u00edlia, que morava no Kibutz Nir Oz.<\/p>\n<p>Apesar da extens\u00e3o do acordo, Tel-Aviv segue afirmando que quer destruir as capacidades militares do Hamas e acabar com o seu dom\u00ednio da Faixa de Gaza, o que significaria uma continuidade na guerra no enclave palestino.<\/p>\n<p>Cinquenta e um ref\u00e9ns israelenses j\u00e1 foram libertados pelo grupo terrorista Hamas, al\u00e9m de 17 tailandeses, um filipino e um israelense-russo. 150 palestinos foram libertados das pris\u00f5es israelenses at\u00e9 o momento.<\/p>\n<p>\u00c9 poss\u00edvel que o Hamas ainda possua em cativeiro cerca de 175 ref\u00e9ns e poderia negociar mais uma extens\u00e3o do cessar-fogo para libertar mais pessoas que est\u00e3o em cativeiro. Contudo, muitos destes ref\u00e9ns s\u00e3o soldados das For\u00e7as de Defesa de Israel e o grupo terrorista poderia fazer mais exig\u00eancias para sua liberta\u00e7\u00e3o.<\/p>\n<p><b>Extens\u00e3o da tr\u00e9gua<\/b><\/p>\n<p>Segundo o jornal\u00a0<i>Times of Israel<\/i>, David Barnea, que \u00e9 chefe do Mossad, o servi\u00e7o de intelig\u00eancia de Israel, est\u00e1 em Doha, no Catar, para novas conversas com o governo do pa\u00eds do Oriente M\u00e9dio e o diretor da CIA, Bill Burns, sobre a possibilidade de mais uma extens\u00e3o no acordo de tr\u00e9gua. Esta \u00e9 a terceira viagem de Barnea ao Catar desde o in\u00edcio da guerra, e ele tamb\u00e9m recebeu funcion\u00e1rios do governo do Catar em Israel. Fonte: Associated Press.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/tregua-entre-israel-e-hamas-chega-ao-quinto-dia-e-mais-refens-devem-ser-libertados-nesta-terca\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Entrou em vigor nesta ter\u00e7a-feira, 28, a extens\u00e3o da tr\u00e9gua entre Israel e o grupo terrorista Hamas, depois que ambos os lados concordaram em prolongar o seu cessar-fogo por mais dois dias na segunda-feira, 27. Com a medida, mais ref\u00e9ns israelenses devem ser libertados em troca de palestinos que est\u00e3o nas pris\u00f5es israelenses at\u00e9 &#8230; <a title=\"Tr\u00e9gua entre Israel e Hamas chega ao quinto dia e mais ref\u00e9ns devem ser libertados nesta ter\u00e7a\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/28\/tregua-entre-israel-e-hamas-chega-ao-quinto-dia-e-mais-refens-devem-ser-libertados-nesta-terca\/\" aria-label=\"Leia mais sobre Tr\u00e9gua entre Israel e Hamas chega ao quinto dia e mais ref\u00e9ns devem ser libertados nesta ter\u00e7a\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":7543,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[531,977,142,389,974,973,978,276,207,975,976,845,168,972],"class_list":["post-7542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-chega","tag-devem","tag-dia","tag-entre","tag-hamas","tag-israel","tag-libertados","tag-mais","tag-nesta","tag-quinto","tag-refens","tag-ser","tag-terca","tag-tregua"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/familiagaza.jpg?fit=848%2C477&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/familiagaza.jpg?fit=848%2C477&ssl=1",848,477,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/familiagaza.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/familiagaza.jpg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/familiagaza.jpg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/familiagaza.jpg?fit=848%2C477&ssl=1",848,477,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/familiagaza.jpg?fit=848%2C477&ssl=1",848,477,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/familiagaza.jpg?fit=848%2C477&ssl=1",848,477,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Entrou em vigor nesta ter\u00e7a-feira, 28, a extens\u00e3o da tr\u00e9gua entre Israel e o grupo terrorista Hamas, depois que ambos os lados concordaram em prolongar o seu cessar-fogo por mais dois dias na segunda-feira, 27. Com a medida, mais ref\u00e9ns israelenses devem ser libertados em troca de palestinos que est\u00e3o nas pris\u00f5es israelenses at\u00e9&hellip;","jetpack-related-posts":[{"id":8996,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/01\/israel-retoma-combate-em-gaza\/","url_meta":{"origin":7542,"position":0},"title":"Israel retoma combate em Gaza","author":"ismaelcolosi.com.br","date":"1 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 1 de dezembro de 2023 | 10:301 de dezembro de 2023 | 9:38 0O ex\u00e9rcito de Israel retomou as opera\u00e7\u00f5es de combate na Faixa de Gaza minutos ap\u00f3s o cessar-fogo com o Hamas expirar, nesta sexta-feira, 1. Jerusal\u00e9m acusa o grupo palestino de n\u00e3o ter respeitado a tr\u00e9gua, que\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/israel.png?fit=627%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/israel.png?fit=627%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/israel.png?fit=627%2C400&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":16562,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/15\/quem-eram-os-refens-israelenses-que-tiveram-suas-vidas-tiradas-pelo-proprio-exercito-de-israel\/","url_meta":{"origin":7542,"position":1},"title":"Quem eram os ref\u00e9ns israelenses que tiveram suas vidas tiradas pelo pr\u00f3prio Ex\u00e9rcito de Israel","author":"ismaelcolosi.com.br","date":"15 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Nesta sexta-feira (15\/12), o ex\u00e9rcito do Estado de Israel confirmou ter sido respons\u00e1vel pela morte de tr\u00eas ref\u00e9ns tomados pelo Hamas. Segundo comunicado, as mortes foram um acidente.Segundo informa\u00e7\u00f5es da pr\u00f3pria For\u00e7as de Defesa de Israel, as tr\u00eas v\u00edtimas de \u201cfogo amigo\u201d eram cidad\u00e3os israelenses. Os restos mortais das\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657ce00eee7958658.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657ce00eee7958658.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657ce00eee7958658.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657ce00eee7958658.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657ce00eee7958658.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":13142,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/09\/voo-para-resgate-de-mais-brasileiros-em-gaza-decola-para-o-egito\/","url_meta":{"origin":7542,"position":2},"title":"Voo para resgate de mais brasileiros em Gaza decola para o Egito","author":"ismaelcolosi.com.br","date":"9 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 9 de dezembro de 2023 | 10:18 0O voo que aguardava no Rio de Janeiro\u00a0para resgatar mais brasileiros que est\u00e3o na Faixa de Gaza decolou no in\u00edcio da manh\u00e3 deste s\u00e1bado (9)\u00a0em dire\u00e7\u00e3o ao Egito, informou a For\u00e7a A\u00e9rea Brasileira (FAB). Este ser\u00e1 o 11\u00ba\u00a0voo de repatria\u00e7\u00e3o de brasileiros\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fab-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fab-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fab-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fab-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1525,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/13\/brasileiros-que-estavam-em-gaza-chegam-nesta-segunda-ao-brasil\/","url_meta":{"origin":7542,"position":3},"title":"Brasileiros que estavam em Gaza chegam nesta segunda ao Brasil","author":"ismaelcolosi.com.br","date":"13 de Novembro de 2023","format":false,"excerpt":"[ad_1] Os brasileiros e seus familiares palestinos que\u00a0deixaram a Faixa de Gaza\u00a0chegam nesta segunda-feira (13) ao Brasil. O governo federal j\u00e1 tem uma opera\u00e7\u00e3o de acolhimento pronta para o grupo, como atendimento m\u00e9dico e psicol\u00f3gico e regulariza\u00e7\u00e3o de documentos.\u00a0Eles\u00a0cruzaram a fronteira\u00a0com o Egito\u00a0pelo Portal de Rafah, no in\u00edcio da manh\u00e3\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/criancas-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/criancas-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/criancas-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/criancas-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1295,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/11\/manifestacao-em-ribeirao-preto-pede-cessar-fogo-em-gaza\/","url_meta":{"origin":7542,"position":4},"title":"Manifesta\u00e7\u00e3o em Ribeir\u00e3o Preto pede cessar-fogo em Gaza","author":"ismaelcolosi.com.br","date":"11 de Novembro de 2023","format":false,"excerpt":"[ad_1] Uma manifesta\u00e7\u00e3o, na manh\u00e3 deste s\u00e1bado (11), no Cal\u00e7ad\u00e3o de Ribeir\u00e3o Preto, pediu cessar-fogo na Faixa de Gaza. O grupo, levando v\u00e1rias bandeiras da Palestina, marchou pelo Centro da cidade (veja o v\u00eddeo logo baixo). Os manifestantes tamb\u00e9m gritam contra Israel por causa dos ataques em Gaza. Segundo o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-11-at-13.15.37.jpeg?fit=1200%2C693&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-11-at-13.15.37.jpeg?fit=1200%2C693&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-11-at-13.15.37.jpeg?fit=1200%2C693&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-11-at-13.15.37.jpeg?fit=1200%2C693&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-11-at-13.15.37.jpeg?fit=1200%2C693&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8952,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/01\/na-paz-e-na-guerra\/","url_meta":{"origin":7542,"position":5},"title":"Na paz e na guerra\u00a0","author":"ismaelcolosi.com.br","date":"1 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Luiz Paulo Tupynamb\u00e1 *\u00a0tupyweb@gmail.com\u00a0\u00a0Gaza\u00a0Felizmente a raz\u00e3o sobrepujou a convic\u00e7\u00e3o parva, que mistura interpreta\u00e7\u00e3o distorcida da religi\u00e3o com um patriotismo regado a interesses econ\u00f4micos e corporativos. Nesta guerra particularmente feroz entre duas pequenas na\u00e7\u00f5es, Israel e Hamas confirmaram pequenas tr\u00e9guas no combate para troca de ref\u00e9ns e prisioneiros, al\u00e9m de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/luizpaulotupynamba-1-scaled.jpg?fit=1000%2C625&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/luizpaulotupynamba-1-scaled.jpg?fit=1000%2C625&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/luizpaulotupynamba-1-scaled.jpg?fit=1000%2C625&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/luizpaulotupynamba-1-scaled.jpg?fit=1000%2C625&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-1XE","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7542"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7542\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/7543"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}