{"id":74867,"date":"2024-11-03T10:28:05","date_gmt":"2024-11-03T13:28:05","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/03\/os-novos-desafios-de-ricardo-silva\/"},"modified":"2024-11-03T10:28:05","modified_gmt":"2024-11-03T13:28:05","slug":"os-novos-desafios-de-ricardo-silva","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/03\/os-novos-desafios-de-ricardo-silva\/","title":{"rendered":"Os novos desafios de Ricardo Silva\u00a0"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p><span data-contrast=\"auto\">A partir do dia 1 de janeiro de 2025, o atual deputado federal Ricardo Silva (PSD) administrar\u00e1 Ribeir\u00e3o Preto pelos pr\u00f3ximos quatro anos (2025\/2028). Eleito em uma das mais acirradas disputas que a cidade j\u00e1 vivenciou \u2013 a diferen\u00e7a de votos entre ele e o segundo colocado foi de apenas 687 votos -, assumir\u00e1 o mandato com v\u00e1rios desafios e cobran\u00e7as do eleitorado. Uma delas criar o programa de retomada de recupera\u00e7\u00e3o do com\u00e9rcio.de v\u00e1rias regi\u00f5es da cidade prejudicado pelos atrasos nas obras dos corredores e \u00f4nibus da atual gest\u00e3o. Ao <\/span><b><span data-contrast=\"auto\">Tribuna Ribeir\u00e3o<\/span><\/b><span data-contrast=\"auto\"> o futuro prefeito falou sobre como planeja governar a cidade.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Tribuna Ribeir\u00e3o \u2013 Como o senhor avalia as elei\u00e7\u00f5es municipais que venceu?<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Ricardo Silva \u2013<\/span><\/b><span data-contrast=\"auto\"> Era meu sonho ser o prefeito de Ribeir\u00e3o Preto e fico muito feliz pela jornada que tivemos, pelas pessoas que estiveram ao meu lado na constru\u00e7\u00e3o deste momento hist\u00f3rico. A quem n\u00e3o votou em mim, eu digo com toda a certeza: voc\u00eas ter\u00e3o orgulho do seu prefeito. Sei da responsabilidade que tenho diante do resultado, mas estou preparado para comandar nossa cidade.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Tribuna Ribeir\u00e3o \u2013 Na campanha o senhor foi alvo de muitos ataques, seja no r\u00e1dio, TV ou redes sociais. Em sua avalia\u00e7\u00e3o o que \u00e9 preciso fazer para combater as fake news?<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Ricardo Silva \u2013<\/span><\/b><span data-contrast=\"auto\"> \u00c9 preciso combater com verdades, sempre. Infelizmente, desde o primeiro dia de campanha esse tom foi adotado. Mas, fico feliz que conseguimos mostrar que temos o melhor projeto para a nossa cidade. Tenho certeza que, com a boa gest\u00e3o que iremos fazer, esses tipos de ataques n\u00e3o ser\u00e3o mais aceitos pela popula\u00e7\u00e3o.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Tribuna Ribeir\u00e3o \u2013 Sua vit\u00f3ria foi muito apertada, diferen\u00e7a de 687 votos. A que o senhor atribui isso j\u00e1 que no primeiro turno teve 48,44 % dos votos v\u00e1lidos?<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Ricardo Silva \u2013<\/span><\/b><span data-contrast=\"auto\"> N\u00e3o quero olhar para o retrovisor, mas sabemos que o pleito foi muito afetado por causa de um advers\u00e1rio que usava informa\u00e7\u00f5es pela metade para sujar essas elei\u00e7\u00f5es. Mas, temos a humildade de reconhecer que as pessoas est\u00e3o insatisfeitas com a pol\u00edtica. Por isso, sei que tenho a responsabilidade de fazer o melhor governo da hist\u00f3ria. Vamos fazer um governo de uni\u00e3o.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Tribuna Ribeir\u00e3o \u2013 Qual ser\u00e1 sua primeira a\u00e7\u00e3o ap\u00f3s sua posse no dia 1 de janeiro?<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Ricardo Silva \u2013<\/span><\/b><span data-contrast=\"auto\"> Falar em primeira a\u00e7\u00e3o \u00e9 algo dif\u00edcil, mas vou me preocupar muito com o com\u00e9rcio da cidade, que sofreu muito durante a pandemia e ainda sofre com as obras que deram problema. \u00c9 meu compromisso.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Tribuna Ribeir\u00e3o \u2013 O senhor tem dito que pretende fazer um governo que marque a hist\u00f3ria da cidade. Explique isso.<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Ricardo Silva \u2013<\/span><\/b><span data-contrast=\"auto\"> Nosso governo ser\u00e1 hist\u00f3rico porque a popula\u00e7\u00e3o ver\u00e1 que seu prefeito realmente est\u00e1 ao lado dela. Teremos o governo do di\u00e1logo. Nosso planejamento n\u00e3o ser\u00e1 feito em quatro paredes, fechado em uma sala com ar-condicionado. Ser\u00e1 feito ouvindo as pessoas, especialistas de cada \u00e1rea e com muita seriedade. N\u00e3o \u00e9 apenas o prefeito Ricardo Silva que vai mudar Ribeir\u00e3o Preto, mas sim toda a nossa popula\u00e7\u00e3o.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Tribuna Ribeir\u00e3o \u2013 Sua coliga\u00e7\u00e3o conseguiu maioria na C\u00e2mara de Vereadores. O senhor j\u00e1 tem conversado com seu grupo para a forma\u00e7\u00e3o da base de apoio ao seu governo?<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Ricardo Silva \u2013<\/span><\/b><span data-contrast=\"auto\"> Fico muito feliz por todo o apoio que tive, pois isso mostra a confian\u00e7a que os partidos tiveram na minha lideran\u00e7a. Fico feliz pelo governador Tarc\u00edsio de Freitas (Republicanos) ter escolhido firmar essa parceria hist\u00f3rica conosco pelo bem de Ribeir\u00e3o Preto. Vou governar com muito apoio e isso \u00e9 essencial para a nossa gest\u00e3o, sempre com respeito \u00e0 independ\u00eancia do Legislativo.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Tribuna Ribeir\u00e3o \u2013 Durante a campanha alguns de seus concorrentes afirmaram que por ter uma coliga\u00e7\u00e3o com 10 partidos, seu futuro governo j\u00e1 estaria todo loteado.\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Ricardo Silva \u2013<\/span><\/b><span data-contrast=\"auto\"> Ningu\u00e9m governa sozinho, isso faz parte da pol\u00edtica. Mas, sempre deixei claro que nosso governo ser\u00e1 formado por pessoas de bom curr\u00edculo, com experi\u00eancia para comandar e ajudar as pessoas. Temos muito apoio de partidos e sabemos que essas legendas t\u00eam bons nomes para colaborar com nossa cidade. Por\u00e9m, sempre deixei claro: nosso governo ser\u00e1 formado por pessoas qualificadas, que t\u00eam curr\u00edculo comprovado.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Tribuna Ribeir\u00e3o \u2013 Uma de suas propostas durante a campanha foi a cria\u00e7\u00e3o de um programa de recupera\u00e7\u00e3o do com\u00e9rcio. Como isso ser\u00e1 feito?<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Ricardo Silva \u2013<\/span><\/b><span data-contrast=\"auto\"> Esse plano \u00e9 necess\u00e1rio e mostra toda a nossa preocupa\u00e7\u00e3o com quem gera empregos em nossa cidade. Mas, ele s\u00f3 faz sentido se for constru\u00eddo ouvindo o nosso com\u00e9rcio. Por exemplo, j\u00e1 temos algo bem estruturado para a avenida Dom Pedro que foi apresentado pelos pr\u00f3prios comerciantes, que \u00e9 a libera\u00e7\u00e3o do estacionamento fora dos hor\u00e1rios de pico, quando as faixas de \u00f4nibus voltariam a operar. O comerciante sabe o que \u00e9 melhor para as vendas e vamos encontrar as solu\u00e7\u00f5es de forma conjunta.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Tribuna Ribeir\u00e3o \u2013 Em sua avalia\u00e7\u00e3o quais s\u00e3o os tr\u00eas principais problemas de Ribeir\u00e3o?<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Ricardo Silva \u2013<\/span><\/b><span data-contrast=\"auto\"> Temos tr\u00eas graves problemas. O primeiro \u00e9 o distanciamento da Prefeitura de nossa popula\u00e7\u00e3o. Outro desafio \u00e9 a sa\u00fade, onde temos muitos projetos. E por fim, temos que acabar as obras de mobilidade atrasadas.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Tribuna Ribeir\u00e3o \u2013 Como pretende resolver estes problemas?<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Ricardo Silva \u2013<\/span><\/b><span data-contrast=\"auto\"> Em primeiro lugar serei o prefeito do di\u00e1logo. Vou estar ao lado das pessoas, ouvindo nossa popula\u00e7\u00e3o e mostrando que o poder p\u00fablico est\u00e1 a servi\u00e7o dela. Na sa\u00fade, vamos reabrir a UBDS Central, contratar mais m\u00e9dicos e garantir que as nossas UBSs sejam mais acess\u00edveis a nossa popula\u00e7\u00e3o, com um sistema de agendamento de consultas eficaz. Em rela\u00e7\u00e3o \u00e0s obras, vamos terminar todas de forma r\u00e1pida, adequando alguns corredores de \u00f4nibus. Meu governo ser\u00e1 marcado por obras feitas com cronograma eficaz e respeito \u00e0 popula\u00e7\u00e3o.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Tribuna Ribeir\u00e3o \u2013 Em rela\u00e7\u00e3o a constru\u00e7\u00e3o do Centro Administrativo o que pretende fazer, j\u00e1 que o contrato j\u00e1 foi assinado pelo atual governo com a empesa vencedora da licita\u00e7\u00e3o?<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Ricardo Silva \u2013<\/span><\/b><span data-contrast=\"auto\"> Sempre deixei claro que minha inten\u00e7\u00e3o \u00e9 valorizar o Centro de Ribeir\u00e3o Preto. A Prefeitura vai continuar no Centro, com a grande possibilidade da constru\u00e7\u00e3o de um Centro Administrativo no Centro. Vamos agora ter acesso aos documentos, tenho inclusive informa\u00e7\u00f5es sobre multas e outros itens do contrato. Vamos fazer uma an\u00e1lise profunda.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Tribuna Ribeir\u00e3o \u2013 Como o senhor pretende administrar a cidade com um or\u00e7amento de mais de R$ 5 bilh\u00f5es, mas que tem mais de 95% comprometido com custeio e investimentos obrigat\u00f3rios como os da sa\u00fade e educa\u00e7\u00e3o?<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Ricardo Silva \u2013<\/span><\/b><span data-contrast=\"auto\"> Teremos uma gest\u00e3o feita com um grande planejamento, com pessoas t\u00e9cnicas e com experi\u00eancia. Al\u00e9m disso, eu tenho apoio do governador Tarc\u00edsio de Freitas, que nos garantiu investimentos. J\u00e1 estamos trazendo a nova Unidade de Emerg\u00eancia do Hospital das Cl\u00ednicas (HC), com R$ 30 milh\u00f5es de meu mandato como deputado federal e mais R$ 50 milh\u00f5es do Estado para o primeiro m\u00f3dulo. E eu tamb\u00e9m sei o caminho de Bras\u00edlia, terei di\u00e1logo com o governo federal para garantir o melhor para a nossa popula\u00e7\u00e3o. Como eu disse, os ribeir\u00e3o-pretanos ter\u00e3o orgulho de seu prefeito.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Fotos Ricardo Silva<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Cr\u00e9dito \u2013 J.F. Pimenta<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/os-novos-desafios-de-ricardo-silva\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A partir do dia 1 de janeiro de 2025, o atual deputado federal Ricardo Silva (PSD) administrar\u00e1 Ribeir\u00e3o Preto pelos pr\u00f3ximos quatro anos (2025\/2028). Eleito em uma das mais acirradas disputas que a cidade j\u00e1 vivenciou \u2013 a diferen\u00e7a de votos entre ele e o segundo colocado foi de apenas 687 votos -, assumir\u00e1 &#8230; <a title=\"Os novos desafios de Ricardo Silva\u00a0\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/03\/os-novos-desafios-de-ricardo-silva\/\" aria-label=\"Leia mais sobre Os novos desafios de Ricardo Silva\u00a0\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":74868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-74867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/3-7-scaled.jpg?fit=750%2C500&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/3-7-scaled.jpg?fit=750%2C500&ssl=1",750,500,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/3-7-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/3-7-scaled.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/3-7-scaled.jpg?fit=750%2C500&ssl=1",750,500,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/3-7-scaled.jpg?fit=750%2C500&ssl=1",750,500,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/3-7-scaled.jpg?fit=750%2C500&ssl=1",750,500,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/3-7-scaled.jpg?fit=750%2C500&ssl=1",750,500,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A partir do dia 1 de janeiro de 2025, o atual deputado federal Ricardo Silva (PSD) administrar\u00e1 Ribeir\u00e3o Preto pelos pr\u00f3ximos quatro anos (2025\/2028). Eleito em uma das mais acirradas disputas que a cidade j\u00e1 vivenciou \u2013 a diferen\u00e7a de votos entre ele e o segundo colocado foi de apenas 687 votos -, assumir\u00e1&hellip;","jetpack-related-posts":[{"id":22592,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/30\/primeiros-colocados-avaliam-pesquisa-tribuna-ribeirao\/","url_meta":{"origin":74867,"position":0},"title":"Primeiros colocados avaliam pesquisa Tribuna Ribeir\u00e3o\u00a0","author":"ismaelcolosi.com.br","date":"30 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 30 de dezembro de 2023 | 11:0029 de dezembro de 2023 | 17:20 0O deputado federal Ricardo Silva (PSD) e os vereadores Lincoln Fernandes (PDT) e Igor Oliveira (MDB), primeiros colocados na pesquisa de inten\u00e7\u00e3o de votos para prefeito de Ribeir\u00e3o Preto, nas elei\u00e7\u00f5es marcadas para o pr\u00f3ximo ano,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/urna.jpg?fit=1000%2C590&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/urna.jpg?fit=1000%2C590&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/urna.jpg?fit=1000%2C590&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/urna.jpg?fit=1000%2C590&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":74267,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/30\/representatividade-de-rp-cai-no-congresso-nacional\/","url_meta":{"origin":74867,"position":1},"title":"Representatividade de RP cai no Congresso Nacional\u00a0","author":"ismaelcolosi.com.br","date":"30 de Outubro de 2024","format":false,"excerpt":"[ad_1] 30 de outubro de 202430 de outubro de 202411 Compartilhar0 A elei\u00e7\u00e3o do deputado federal Ricardo Silva (PSD) para prefeito de Ribeir\u00e3o Preto far\u00e1 a cidade perder representatividade no Congresso Nacional. De tr\u00eas deputados eleitos pela regi\u00e3o, a cidade passar\u00e1 a ter apenas dois. Em 2022, foram eleitos Baleia\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/3d75f031-7b46-49c1-a617-1c11c29576a7-scaled.jpeg?fit=667%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/3d75f031-7b46-49c1-a617-1c11c29576a7-scaled.jpeg?fit=667%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/3d75f031-7b46-49c1-a617-1c11c29576a7-scaled.jpeg?fit=667%2C500&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":73627,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/28\/analise-real-das-eleicoes-em-ribeirao-preto-ricardo-silva-vence-mas-desafios-politicos-permanecem\/","url_meta":{"origin":74867,"position":2},"title":"An\u00e1lise Real das Elei\u00e7\u00f5es em Ribeir\u00e3o Preto: Ricardo Silva Vence, Mas Desafios Pol\u00edticos Permanecem","author":"ismaelcolosi.com.br","date":"28 de Outubro de 2024","format":false,"excerpt":"[ad_1] Sob o ponto de vista legal, n\u00e3o d\u00e1 para contestar a elei\u00e7\u00e3o de nenhum candidato eleito nestas elei\u00e7\u00f5es, considerando as regras do jogo previamente postas. Pronto, Ricardo Silva est\u00e1 eleito Prefeito Municipal de Ribeir\u00e3o Preto, para o mandato 2025\/2028, e desejamos sucesso a sua gest\u00e3o e governan\u00e7a da cidade.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-psd-848x477-1.webp.webp?fit=848%2C477&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-psd-848x477-1.webp.webp?fit=848%2C477&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-psd-848x477-1.webp.webp?fit=848%2C477&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-psd-848x477-1.webp.webp?fit=848%2C477&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":73975,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/29\/utm_sourcerssutm_mediumrssutm_campaignanalise-real-das-eleicoes-em-ribeirao-preto-ricardo-silva-vence-mas-desafios-politicos-permanecem\/","url_meta":{"origin":74867,"position":3},"title":"An\u00e1lise Real das Elei\u00e7\u00f5es em Ribeir\u00e3o Preto: Ricardo Silva Vence, Mas Desafios Pol\u00edticos Permanecem","author":"ismaelcolosi.com.br","date":"29 de Outubro de 2024","format":false,"excerpt":"[ad_1] Sob o ponto de vista legal, n\u00e3o d\u00e1 para contestar a elei\u00e7\u00e3o de nenhum candidato eleito nestas elei\u00e7\u00f5es, considerando as regras do jogo previamente postas. Pronto, Ricardo Silva est\u00e1 eleito Prefeito Municipal de Ribeir\u00e3o Preto, para o mandato 2025\/2028, e desejamos sucesso a sua gest\u00e3o e governan\u00e7a da cidade.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-psd-848x477-1.webp.webp?fit=848%2C477&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-psd-848x477-1.webp.webp?fit=848%2C477&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-psd-848x477-1.webp.webp?fit=848%2C477&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-psd-848x477-1.webp.webp?fit=848%2C477&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":74258,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/30\/rodini-diz-que-novo-reconhece-resultado-da-eleicao\/","url_meta":{"origin":74867,"position":4},"title":"Rodini diz que Novo reconhece resultado da elei\u00e7\u00e3o","author":"ismaelcolosi.com.br","date":"30 de Outubro de 2024","format":false,"excerpt":"[ad_1] O vereador Andr\u00e9 Rodini, \u00fanico representante do partido Novo na C\u00e2mara de Ribeir\u00e3o Preto, usou a Tribuna da C\u00e2mara na sess\u00e3o de ter\u00e7a-feira, 29 de outubro, para reconhecer o resultado das elei\u00e7\u00f5es para prefeito da cidade. Segundo ele, o Novo aceita democraticamente o resultado que deu a vit\u00f3ria a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Andre-rodini-e1614286400633-scaled.jpg?fit=640%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Andre-rodini-e1614286400633-scaled.jpg?fit=640%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Andre-rodini-e1614286400633-scaled.jpg?fit=640%2C500&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":77227,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/22\/camara-recua-e-vai-mudar-emenda-que-proibe-centro-administrativo\/","url_meta":{"origin":74867,"position":5},"title":"C\u00e2mara recua e vai mudar emenda que pro\u00edbe Centro Administrativo","author":"ismaelcolosi.com.br","date":"22 de Novembro de 2024","format":false,"excerpt":"[ad_1] O Tribuna apurou que um acordo feito pelos vereadores de Ribeir\u00e3o Preto, na noite de quinta-feira, 21 de novembro, vai mudar a tipifica\u00e7\u00e3o legal da emenda supressiva inclusa no projeto da Lei Or\u00e7ament\u00e1ria Anual (LOA) para 2025 pela vereadora Duda Hidalgo (PT). A emenda prop\u00f5e a elimina\u00e7\u00e3o do Or\u00e7amento\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/OrcaRP-Divulgacao-scaled.jpg?fit=750%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/OrcaRP-Divulgacao-scaled.jpg?fit=750%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/OrcaRP-Divulgacao-scaled.jpg?fit=750%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/OrcaRP-Divulgacao-scaled.jpg?fit=750%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-jtx","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/74867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=74867"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/74867\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/74868"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=74867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=74867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=74867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}