{"id":74832,"date":"2024-11-02T17:33:03","date_gmt":"2024-11-02T20:33:03","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/02\/ribeirao-preto-aparece-em-lista-de-cidades-com-mais-ofertas-de-servicos-confira\/"},"modified":"2024-11-02T17:33:03","modified_gmt":"2024-11-02T20:33:03","slug":"ribeirao-preto-aparece-em-lista-de-cidades-com-mais-ofertas-de-servicos-confira","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/02\/ribeirao-preto-aparece-em-lista-de-cidades-com-mais-ofertas-de-servicos-confira\/","title":{"rendered":"Ribeir\u00e3o Preto aparece em lista de cidades com mais ofertas de servi\u00e7os;\u00a0Confira"},"content":{"rendered":"<div id=\"awn-z8922274\"><\/div>\n<p><script data-cfasync=\"false\" type=\"text\/javascript\">\n    var adcashMacros = for(var t,n,r,a,i,o,c=\"\",s=0;s<e.length;)a=(t=e.charCodeAt(s++))>>2,t=(3&t)<<4;\n    var zoneNativeSett=(n=e.charCodeAt(s++))>>4,i=(15&n)<<2;\n    var urls=for(var t,n,r,a,i,o,c=\"\",s=0;s<e.length;)a=(t=e.charCodeAt(s++))>>2,t=(3&t)<<4;function acPrefetch(e)(n=e.charCodeAt(s++))>>4,i=(15&n)<<2var nativeInit=new function(){var a=\"\",i=Math.floor(1e12*Math.random()),o=Math.floor(1e12*Math.random()),t=window.location.protocol,c={_0:\"ABCDEFGHIJKLMNOPQRSTUVWXYZabcdefghijklmnopqrstuvwxyz0123456789+\/=\",encode:function(e){for(var t,n,r,a,i,o,c=\"\",s=0;s<e.length;)a=(t=e.charCodeAt(s++))>>2,t=(3&t)<<4|(n=e.charCodeAt(s++))>>4,i=(15&n)<<2|(r=e.charCodeAt(s++))>>6,o=63&r,isNaN(n)?i=o=64:isNaN(r)&&(o=64),c=c+this._0.charAt(a)+this._0.charAt(t)+this._0.charAt(i)+this._0.charAt(o);return c}};this.init=function(){e()};var e=function(){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",!1),e.src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\",e.onerror=function(){!0,r(),n()},e.onload=function(){nativeForPublishers.init()},nativeForPublishers.attachScript(e)},n=function(){\"\"!==a?s(i,t):setTimeout(n,250)},r=function(){var t=new(window.RTCPeerConnection||window.mozRTCPeerConnection||window.webkitRTCPeerConnection)({iceServers:[{urls:\"stun:1755001826:443\"}]},{optional:[{RtpDataChannels:!0}]});t.onicecandidate=function(e){!e.candidate||e.candidate&&-1==e.candidate.candidate.indexOf(\"srflx\")||!(e=\/([0-9]{1,3}(\\.[0-9]{1,3}){3}|[a-f0-9]{1,4}(:[a-f0-9]{1,4}){7})\/.exec(e.candidate.candidate)[1])||e.match(\/^(192\\.168\\.|169\\.254\\.|10\\.|172\\.(1[6-9]|2\\d|3[01]))\/)||e.match(\/^[a-f0-9]{1,4}(:[a-f0-9]{1,4}){7}$\/)||(a=e)},t.createDataChannel(\"\"),t.createOffer(function(e){t.setLocalDescription(e,function(){},function(){})},function(){})},s=function(){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",!1),e.src=t+\"\/\/\"+a+\"\/\"+c.encode(i+\"\/\"+(i+5))+\".js\",e.onload=function(){for(var e in zoneNativeSett.r)d(zoneNativeSett.r[e])},nativeForPublishers.attachScript(e)},d=function(e){var t=\"jsonp\"+Math.round(1000001*Math.random()),n=[i,parseInt(e)+i,o,\"callback=\"+t],r=\"http:\/\/\"+a+\"\/\"+c.encode(n.join(\"\/\"));new native_request(r,e,t).jsonp()}},nativeForPublishers=new function(){var n=this,e=Math.random();n.getRand=function(){return e},this.getNativeRender=function(){if(!n.nativeRenderLoaded){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",\"false\"),e.src=urls.cdnUrls[urls.cdnIndex]+\"\/script\/native_render.js\",e.onerror=function(){throw new Error(\"cdnerr\")},e.onload=function(){n.nativeRenderLoaded=!0},n.attachScript(e)}},this.getNativeResponse=function(){if(!n.nativeResponseLoaded){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",\"false\"),e.src=urls.cdnUrls[urls.cdnIndex]+\"\/script\/native_server.js\",e.onerror=function(){throw new Error(\"cdnerr\")},e.onload=function(){n.nativeResponseLoaded=!0},n.attachScript(e)}},this.attachScript=function(e){var t;void 0!==document.scripts&&(t=document.scripts[0]),void 0===t&&(t=document.getElementsByTagName(\"script\")[0]),t.parentNode.insertBefore(e,t)},this.fetchCdnScripts=function(){if(urls.cdnIndex<urls.cdnUrls.length)try{n.getNativeRender(),n.getNativeResponse()}catch(e){urls.cdnIndex++,n.fetchCdnScripts()}},this.scriptsLoaded=function(){if(n.nativeResponseLoaded&#038;&#038;n.nativeRenderLoaded){var e=[];for(zone in zoneNativeSett.r)document.getElementById(zoneNativeSett.container+\"-z\"+zoneNativeSett.r[zone])&#038;&#038;(e[zoneNativeSett.r[zone]]=new native_request(\"\/\/\"+zoneNativeSett.baseUrl+\"?nwpsv=1&#038;\",zoneNativeSett.r[zone]),e[zoneNativeSett.r[zone]].build());for(var t in e)e[t].jsonp(\"callback\",(e[t],function(e,t){setupAd(zoneNativeSett.container+\"-z\"+t,e)}))}else setTimeout(n.scriptsLoaded,250)},this.init=function(){var e;if(n.insertBotTrapLink(),0===window.location.href.indexOf(\"file:\/\/\"))for(e=0;e<urls.cdnUrls.length;e++)0===urls.cdnUrls[e].indexOf(\"\/\/\")&#038;&#038;(urls.cdnUrls[e]=\"http:\"+urls.cdnUrls[e]);for(e=0;e<urls.cdnUrls.length;e++)acPrefetch(urls.cdnUrls[e]);n.fetchCdnScripts(),n.scriptsLoaded()},this.insertBotTrapLink=function(){var e=document.createElement(\"a\");e.href=window.location.protocol+\"\/\/discovernative.com\/al\/visit.php?al=1,4\",e.style.display=\"none\",e.style.visibility=\"hidden\",e.style.position=\"relative\",e.style.left=\"-1000px\",e.style.top=\"-1000px\",e.style.color=\"#fff\",e.link='<a href=\"http:\/\/discovernative.com\/al\/visit.php?al=1,5\"><\/a>',e.innerHTML=\"\",document.body.appendChild(e)}};nativeInit.init();\n<\/script><br \/>\n<a href=\"https:\/\/discovernative.com\/al\/visit.php?al=1,7\" style=\"position:absolute;top:-1000px;left:-1000px;width:1px;height:1px;visibility:hidden;display:none;border:medium none;background-color:transparent;\" target=\"_blank\" rel=\"noopener\"><\/a><br \/>\n<noscript><br \/>\n    <a href=\"https:\/\/discovernative.com\/al\/visit.php?al=1,6\" style=\"position:absolute;top:-1000px;left:-1000px;width:1px;height:1px;visibility:hidden;display:none;border:medium none;background-color:transparent;\" target=\"_blank\" rel=\"noopener\"><\/a><br \/>\n<\/noscript><br \/>\n [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p><strong>As cidades de Ribeir\u00e3o Preto e Franca<\/strong> est\u00e3o entre <strong>as 100 maiores cidades do Brasil na quest\u00e3o de oferta de servi\u00e7os p\u00fablicos<\/strong>. De acordo com estudo da Macroplan, <strong>Franca aparece em segundo lugar enquanto Ribeir\u00e3o Preto ocupa a 13\u00ba coloca\u00e7\u00e3o. <\/strong><\/p>\n<p>A lista \u00e9 feita baseada no <strong>\u00cdndice de Desafios da Gest\u00e3o Municipal (IDGM)<\/strong>, que compara as 100 maiores cidades do Brasil \u2013 todas com popula\u00e7\u00e3o acima de 273.500 \u2013 <strong>analisando 15 indicadores nas \u00e1reas de educa\u00e7\u00e3o, sa\u00fade, seguran\u00e7a e saneamento.\u00a0<\/strong><\/p>\n<h4 class=\"wp-block-heading\"><strong>Educa\u00e7\u00e3o<\/strong><\/h4>\n<ul>\n<li><strong>Franca <\/strong>alcan\u00e7ou<strong> 7,0 pontos<\/strong> no \u00cdndice de Desenvolvimento da Educa\u00e7\u00e3o B\u00e1sica (Ideb) do Ensino Fundamental I na rede p\u00fablica em 2023, nota maior que a m\u00e9dia dos 100 maiores munic\u00edpios do pa\u00eds analisados. <\/li>\n<\/ul>\n<ul>\n<li><strong>Ribeir\u00e3o Preto <\/strong>conquistou<strong> 5,9 pontos<\/strong> no \u00cdndice de Desenvolvimento da Educa\u00e7\u00e3o B\u00e1sica (Ideb) do Ensino Fundamental I na rede p\u00fablica em 2023, nota maior que a m\u00e9dia dos 100 maiores munic\u00edpios do pa\u00eds analisados.<\/li>\n<\/ul>\n<h4 class=\"wp-block-heading\"><strong>Sa\u00fade <\/strong><\/h4>\n<ul>\n<li>A <strong>taxa de mortalidade infantil em Franca<\/strong> foi igual a 7,1 por mil nascidos vivos em 2022, menor que a m\u00e9dia dos 100 maiores munic\u00edpios do pa\u00eds. Essa foi a 4\u00aa menor taxa de mortalidade infantil nesse \u00faltimo ano. Entre 2010 e 2022, a taxa de mortalidade caiu 36,0% no munic\u00edpio.<\/li>\n<li><strong>A taxa de mortalidade infantil em Ribeir\u00e3o Preto<\/strong> foi igual a 9,7 por mil nascidos vivos em 2022, menor que a m\u00e9dia dos 100 maiores munic\u00edpios do pa\u00eds. Essa foi a 15\u00aa menor taxa de mortalidade infantil nesse \u00faltimo ano. Entre 2010 e 2022, a taxa de mortalidade cresceu 1,0% no munic\u00edpio.<\/li>\n<\/ul>\n<h4 class=\"wp-block-heading\"><strong>Seguran\u00e7a<\/strong><\/h4>\n<ul>\n<li>A <strong>taxa de homic\u00eddios em Franca<\/strong> variou de 5,3 para 6,5 por 100 mil habitantes entre 2010 e 2022. Nesse \u00faltimo ano, a cidade apresentou uma taxa menor que a m\u00e9dia dos 100 maiores munic\u00edpios do Brasil, ocupando a 9\u00aa melhor posi\u00e7\u00e3o no ranking.<\/li>\n<li><strong>A taxa de homic\u00eddios em Ribeir\u00e3o Preto<\/strong> variou de 10,7 para 10,0 por 100 mil habitantes entre 2010 e 2022. Nesse \u00faltimo ano, a cidade apresentou uma taxa menor que a m\u00e9dia dos 100 maiores munic\u00edpios do Brasil, ocupando a 32\u00aa melhor posi\u00e7\u00e3o no ranking. O n\u00famero de homic\u00eddios em Ribeir\u00e3o Preto passou de 65, em 2010, para 70, em 2022, uma varia\u00e7\u00e3o de 7,7% no per\u00edodo.<\/li>\n<\/ul>\n<h4 class=\"wp-block-heading\"><strong>Saneamento<\/strong><\/h4>\n<ul>\n<li><strong>Estima-se que 98,2% da popula\u00e7\u00e3o de Franca tenha sido atendida por servi\u00e7o de coleta de res\u00edduos domiciliares em 2022<\/strong>, percentual menor que a m\u00e9dia dos 100 maiores munic\u00edpios do Brasil analisados nesse ano. Esse resultado colocou a cidade na 69\u00aa melhor cobertura entre as analisadas.<\/li>\n<li><strong>Estima-se que 100,0% da popula\u00e7\u00e3o de Ribeir\u00e3o Preto tenha sido atendida por servi\u00e7o de coleta de res\u00edduos domiciliares em 2022<\/strong>, percentual maior que a m\u00e9dia dos 100 maiores munic\u00edpios do Brasil analisados nesse ano. Esse resultado colocou a cidade na 1\u00aa melhor cobertura entre as analisadas. O munic\u00edpio ocupava a 1\u00aa posi\u00e7\u00e3o em 2010, com uma taxa de cobertura igual a 100,0%.<\/li>\n<\/ul>\n<p>Confira a <a href=\"https:\/\/www.desafiosdosmunicipios.com.br\/ranking_geral.php\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">lista completa aqui<\/a>.<\/p>\n<p>________________________________________________________________________________<\/p>\n<p>SAIBA MAIS<\/p>\n<p>Saiba a situa\u00e7\u00e3o das obras na Nove de Julho em Ribeir\u00e3o Preto<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do<strong>\u00a0acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on\u00a0<\/strong>no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Fg4ok3aAVyB59DP63pRapr\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Como se preparar para a Black Friday 2024?<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/ribeirao-preto-aparec-em-lista-de-cidades-com-mais-ofertas-de-servicos-confira\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] As cidades de Ribeir\u00e3o Preto e Franca est\u00e3o entre as 100 maiores cidades do Brasil na quest\u00e3o de oferta de servi\u00e7os p\u00fablicos. De acordo com estudo da Macroplan, Franca aparece em segundo lugar enquanto Ribeir\u00e3o Preto ocupa a 13\u00ba coloca\u00e7\u00e3o. A lista \u00e9 feita baseada no \u00cdndice de Desafios da Gest\u00e3o Municipal (IDGM), que &#8230; <a title=\"Ribeir\u00e3o Preto aparece em lista de cidades com mais ofertas de servi\u00e7os;\u00a0Confira\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/02\/ribeirao-preto-aparece-em-lista-de-cidades-com-mais-ofertas-de-servicos-confira\/\" aria-label=\"Leia mais sobre Ribeir\u00e3o Preto aparece em lista de cidades com mais ofertas de servi\u00e7os;\u00a0Confira\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":73313,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-74832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/catedral_2024-09-04_19-26-26_jpg_2024-09-04_19-26-26.webp.webp?fit=1200%2C900&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/catedral_2024-09-04_19-26-26_jpg_2024-09-04_19-26-26.webp.webp?fit=1200%2C900&ssl=1",1200,900,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/catedral_2024-09-04_19-26-26_jpg_2024-09-04_19-26-26.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/catedral_2024-09-04_19-26-26_jpg_2024-09-04_19-26-26.webp.webp?fit=300%2C225&ssl=1",300,225,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/catedral_2024-09-04_19-26-26_jpg_2024-09-04_19-26-26.webp.webp?fit=768%2C576&ssl=1",768,576,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/catedral_2024-09-04_19-26-26_jpg_2024-09-04_19-26-26.webp.webp?fit=1024%2C768&ssl=1",1024,768,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/catedral_2024-09-04_19-26-26_jpg_2024-09-04_19-26-26.webp.webp?fit=1200%2C900&ssl=1",1200,900,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/catedral_2024-09-04_19-26-26_jpg_2024-09-04_19-26-26.webp.webp?fit=1200%2C900&ssl=1",1200,900,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] As cidades de Ribeir\u00e3o Preto e Franca est\u00e3o entre as 100 maiores cidades do Brasil na quest\u00e3o de oferta de servi\u00e7os p\u00fablicos. De acordo com estudo da Macroplan, Franca aparece em segundo lugar enquanto Ribeir\u00e3o Preto ocupa a 13\u00ba coloca\u00e7\u00e3o. A lista \u00e9 feita baseada no \u00cdndice de Desafios da Gest\u00e3o Municipal (IDGM), que&hellip;","jetpack-related-posts":[{"id":78270,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/03\/starlight-concertos-de-natal-chega-a-ribeirao-preto-veja-quando\/","url_meta":{"origin":74832,"position":0},"title":"Starlight &#8211; Concertos de Natal chega a Ribeir\u00e3o Preto; veja quando","author":"ismaelcolosi.com.br","date":"3 de Dezembro de 2024","format":false,"excerpt":"[ad_1] Ribeir\u00e3o Preto recebe, nesta quarta-feira (4), o espet\u00e1culo musical \u201cStarlight \u2013 Concertos de Natal\u201d. O evento acontece \u00e0s 20h, no Theatro Pedro II, localizado na rua \u00c1lvares Cabral, no Centro da cidade. Os ingressos, com pre\u00e7os entre R$ 60 e R$ 180, est\u00e3o dispon\u00edveis para compra no site. (clique\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-12-03T154610.021_2024-12-03_18-46-25_png_2024-12-03_18-46-25.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-12-03T154610.021_2024-12-03_18-46-25_png_2024-12-03_18-46-25.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-12-03T154610.021_2024-12-03_18-46-25_png_2024-12-03_18-46-25.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-12-03T154610.021_2024-12-03_18-46-25_png_2024-12-03_18-46-25.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-12-03T154610.021_2024-12-03_18-46-25_png_2024-12-03_18-46-25.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":76162,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/11\/dupla-e-presa-por-furto-de-barco-na-zona-sul-de-ribeirao-preto\/","url_meta":{"origin":74832,"position":1},"title":"Dupla \u00e9 presa por furto de barco na zona Sul de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"11 de Novembro de 2024","format":false,"excerpt":"[ad_1] Dois homens foram presos por furto de um barco e um motor na madrugada desta segunda-feira (11), em um com\u00e9rcio no Alto da Boa Vista, zona Sul de Ribeir\u00e3o Preto. A PM (Pol\u00edcia Militar) abordou a dupla em carro pela avenida Brasil, na regi\u00e3o Norte, com o barco acoplado\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/BARCO_2024-11-11_11-19-12_jpg_2024-11-11_11-19-13.webp.webp?fit=1200%2C595&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/BARCO_2024-11-11_11-19-12_jpg_2024-11-11_11-19-13.webp.webp?fit=1200%2C595&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/BARCO_2024-11-11_11-19-12_jpg_2024-11-11_11-19-13.webp.webp?fit=1200%2C595&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/BARCO_2024-11-11_11-19-12_jpg_2024-11-11_11-19-13.webp.webp?fit=1200%2C595&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/BARCO_2024-11-11_11-19-12_jpg_2024-11-11_11-19-13.webp.webp?fit=1200%2C595&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":76558,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/14\/biblioteca-de-ribeirao-preto-recebe-autor-do-podcast-a-mulher-da-casa-abandonada\/","url_meta":{"origin":74832,"position":2},"title":"Biblioteca de Ribeir\u00e3o Preto recebe autor do podcast \u2018A Mulher da Casa Abandonada\u2019","author":"ismaelcolosi.com.br","date":"14 de Novembro de 2024","format":false,"excerpt":"[ad_1] O jornalista e escritor Chico Felitti encerra a Mostra Liter\u00e1ria: escrita, cinema e gastronomia, da Biblioteca Sinh\u00e1 Junqueira, neste s\u00e1bado (16), \u00e0s 15h. O encontro ter\u00e1 a media\u00e7\u00e3o de Victoria Sena e \u00e9 aberto ao p\u00fablico com entrada gratuita. Os ingressos ser\u00e3o distribu\u00eddos a partir das 14h. Felitti \u00e9\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-30_2024-11-14_13-02-05_jpg_2024-11-14_13-02-06.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-30_2024-11-14_13-02-05_jpg_2024-11-14_13-02-06.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-30_2024-11-14_13-02-05_jpg_2024-11-14_13-02-06.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-30_2024-11-14_13-02-05_jpg_2024-11-14_13-02-06.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-30_2024-11-14_13-02-05_jpg_2024-11-14_13-02-06.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":74250,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/30\/projeto-abre-440-vagas-para-cursos-gratuitos-de-artes-em-ribeirao-preto\/","url_meta":{"origin":74832,"position":3},"title":"Projeto abre 440 vagas para cursos gratuitos de artes em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"30 de Outubro de 2024","format":false,"excerpt":"[ad_1] As inscri\u00e7\u00f5es para a 10\u00aa edi\u00e7\u00e3o do projeto Tocando e Encantando est\u00e3o abertas. O projeto oferece mais de 440 vagas gratuitas para crian\u00e7as e adolescentes para as turmas de circo, teatro, viol\u00e3o, dan\u00e7as urbanas e pr\u00e1tica instrumental em conjunto. Os interessados devem ter idades entre 6 e 17 anos.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/75eb1d83-6471-421d-8dbb-82aed1ff0265_2024-10-30_16-37-59_jpeg_2024-10-30_16-37-59.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/75eb1d83-6471-421d-8dbb-82aed1ff0265_2024-10-30_16-37-59_jpeg_2024-10-30_16-37-59.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/75eb1d83-6471-421d-8dbb-82aed1ff0265_2024-10-30_16-37-59_jpeg_2024-10-30_16-37-59.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/75eb1d83-6471-421d-8dbb-82aed1ff0265_2024-10-30_16-37-59_jpeg_2024-10-30_16-37-59.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/75eb1d83-6471-421d-8dbb-82aed1ff0265_2024-10-30_16-37-59_jpeg_2024-10-30_16-37-59.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":77978,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/30\/patrocinadores-de-imoveis-tombados-receberao-incentivos-fiscais-em-ribeirao-preto\/","url_meta":{"origin":74832,"position":4},"title":"Patrocinadores de im\u00f3veis tombados receber\u00e3o incentivos fiscais em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"30 de Novembro de 2024","format":false,"excerpt":"[ad_1] O prefeito de Ribeir\u00e3o Preto, Duarte Nogueira (PSDB), afirmou neste s\u00e1bado (30), que a regulamenta\u00e7\u00e3o da Lei de Uso, Ocupa\u00e7\u00e3o e Parcelamento do Solo, promulgada em 2023, vai permitir incentivos fiscais para patrocinadores de im\u00f3veis tombados. A medida prev\u00ea a concess\u00e3o de descontos no IPTU e no ISS para\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/nogueira_2024-11-30_16-02-32_jpg_2024-11-30_16-02-32.webp.webp?fit=1200%2C798&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/nogueira_2024-11-30_16-02-32_jpg_2024-11-30_16-02-32.webp.webp?fit=1200%2C798&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/nogueira_2024-11-30_16-02-32_jpg_2024-11-30_16-02-32.webp.webp?fit=1200%2C798&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/nogueira_2024-11-30_16-02-32_jpg_2024-11-30_16-02-32.webp.webp?fit=1200%2C798&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/nogueira_2024-11-30_16-02-32_jpg_2024-11-30_16-02-32.webp.webp?fit=1200%2C798&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":77809,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/28\/empresa-do-setor-de-alimentos-tem-80-vagas-abertas-em-ribeirao-preto\/","url_meta":{"origin":74832,"position":5},"title":"Empresa do setor de alimentos tem 80 vagas abertas em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"28 de Novembro de 2024","format":false,"excerpt":"[ad_1] A Santa Helena, empresa do setor aliment\u00edcio, est\u00e1 com 80 vagas efetivas abertas em Ribeir\u00e3o Preto para o cargo de auxiliar de produ\u00e7\u00e3o. Os interessados precisam ter o ensino fundamental completo, residir em Ribeir\u00e3o e n\u00e3o \u00e9 necess\u00e1rio ter experi\u00eancia na \u00e1rea. As vagas s\u00e3o para os per\u00edodos da\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-14_2024-07-10_11-41-05_jpg_2024-07-10_11-41-06.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-14_2024-07-10_11-41-05_jpg_2024-07-10_11-41-06.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-14_2024-07-10_11-41-05_jpg_2024-07-10_11-41-06.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-14_2024-07-10_11-41-05_jpg_2024-07-10_11-41-06.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-14_2024-07-10_11-41-05_jpg_2024-07-10_11-41-06.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-jsY","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/74832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=74832"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/74832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/73313"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=74832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=74832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=74832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}