{"id":73094,"date":"2024-10-24T17:26:04","date_gmt":"2024-10-24T20:26:04","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/24\/chuva-derruba-estrutura-de-rodeio-na-regiao-de-ribeirao-preto-veja-video\/"},"modified":"2024-10-24T17:26:04","modified_gmt":"2024-10-24T20:26:04","slug":"chuva-derruba-estrutura-de-rodeio-na-regiao-de-ribeirao-preto-veja-video","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/24\/chuva-derruba-estrutura-de-rodeio-na-regiao-de-ribeirao-preto-veja-video\/","title":{"rendered":"Chuva derruba estrutura de rodeio na regi\u00e3o de Ribeir\u00e3o Preto; Veja v\u00eddeo"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>A abertura do <strong>rodeio de Cruz das Posses<\/strong>, distrito de <strong>Sert\u00e3ozinho<\/strong>, cidade na <strong>regi\u00e3o de Ribeir\u00e3o Preto<\/strong>, foi suspensa devido \u00e0s <strong>fortes chuvas<\/strong> que atingiram a regi\u00e3o, na tarde desta quinta-feira (24).<\/p>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">Por conta do <strong>temporal<\/strong>, a estrutura da festa foi totalmente comprometida \u2013 veja o v\u00eddeo abaixo.<\/mark> Apesar do susto, ningu\u00e9m ficou ferido. <strong>Ainda n\u00e3o foi divulgada uma nova data para realiza\u00e7\u00e3o do evento.<\/strong><\/p>\n<p>A<strong> Prefeitura de Sert\u00e3ozinho<\/strong> informou que equipes do <strong>Corpo de Bombeiros<\/strong> e da <strong>Defesa Civil <\/strong>foram acionadas e est\u00e3o fazendo a avalia\u00e7\u00e3o do local.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Alerta de tempestade<\/strong><\/h4>\n<p>O <strong>Instituto Nacional de Meteorologia (Inmet)<\/strong> emitiu, nesta quinta-feira (24), um novo <strong>alerta de grande perigo de tempestade<\/strong>, <strong>ventos intensos<\/strong> e <strong>queda de granizo<\/strong> para o <strong>interior de S\u00e3o Paulo.<\/strong><\/p>\n<p>De acordo com \u00f3rg\u00e3o, existe possibilidade de<strong> chuva entre 50 a 100 mil\u00edmetros por dia<\/strong> e <strong>ventos intensos que podem variar entre 60 a 100 quil\u00f4metros por hora<\/strong> \u2013 clique aqui e confira os locais afetados.<\/p>\n<blockquote class=\"tiktok-embed\" cite=\"https:\/\/www.tiktok.com\/@acidadeon\/video\/7429433399535734021\" data-video-id=\"7429433399535734021\" style=\"max-width: 605px;min-width: 325px;\">\n<section> <a target=\"_blank\" title=\"@acidadeon\" href=\"https:\/\/www.tiktok.com\/@acidadeon?refer=embed\" rel=\"noopener\">@acidadeon<\/a> \ud83d\ude28 A abertura do rodeio de Cruz das Posses, distrito de Sert\u00e3ozinho, cidade na regi\u00e3o de Ribeir\u00e3o Preto, foi suspensa devido \u00e0s fortes chuvas que atingiram a regi\u00e3o, na tarde desta quinta-feira. \u203c\ufe0f Por conta do temporal, a estrutura da festa foi totalmente comprometida. Apesar do susto, ningu\u00e9m ficou ferido.  \u27a1\ufe0f A Prefeitura de Sert\u00e3ozinho informou que equipes do Corpo de Bombeiros e da Defesa Civil foram acionadas e est\u00e3o fazendo a avalia\u00e7\u00e3o do local. \ud83c\udfa5 Reprodu\u00e7\u00e3o\/ redes sociais <a title=\"acidadeon\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/acidadeon?refer=embed\" rel=\"noopener\">#acidadeon<\/a> <a title=\"fiqueon\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/fiqueon?refer=embed\" rel=\"noopener\">#fiqueon<\/a> <a title=\"sert\u00e3ozinho\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/sert%C3%A3ozinho?refer=embed\" rel=\"noopener\">#sert\u00e3ozinho<\/a> <a title=\"cruzdasposses\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/cruzdasposses?refer=embed\" rel=\"noopener\">#cruzdasposses<\/a> <a target=\"_blank\" title=\"\u266c som original - acidade on\" href=\"https:\/\/www.tiktok.com\/music\/som-original-7429433419866655493?refer=embed\" rel=\"noopener\">\u266c som original \u2013 acidade on<\/a> <\/section>\n<\/blockquote>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<p>SAIBA MAIS<\/p>\n<p>Fam\u00edlia de Ribeir\u00e3o doa \u00f3rg\u00e3os de crian\u00e7a v\u00edtima de afogamento em parque aqu\u00e1tico<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on\u00a0<\/strong>no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Fg4ok3aAVyB59DP63pRapr\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Quando ser\u00e1 o show de Kylie Minogue no Brasil?<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><script async src=\"\/\/www.tiktok.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/chuva-derruba-estrutura-de-rodeio-na-regiao-de-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A abertura do rodeio de Cruz das Posses, distrito de Sert\u00e3ozinho, cidade na regi\u00e3o de Ribeir\u00e3o Preto, foi suspensa devido \u00e0s fortes chuvas que atingiram a regi\u00e3o, na tarde desta quinta-feira (24). Por conta do temporal, a estrutura da festa foi totalmente comprometida \u2013 veja o v\u00eddeo abaixo. Apesar do susto, ningu\u00e9m ficou ferido. &#8230; <a title=\"Chuva derruba estrutura de rodeio na regi\u00e3o de Ribeir\u00e3o Preto; Veja v\u00eddeo\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/24\/chuva-derruba-estrutura-de-rodeio-na-regiao-de-ribeirao-preto-veja-video\/\" aria-label=\"Read more about Chuva derruba estrutura de rodeio na regi\u00e3o de Ribeir\u00e3o Preto; Veja v\u00eddeo\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":73095,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-73094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-24-at-16.31.56_2024-10-24_19-56-31_jpeg_2024-10-24_19-56-32.webp.webp?fit=1600%2C900&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-24-at-16.31.56_2024-10-24_19-56-31_jpeg_2024-10-24_19-56-32.webp.webp?fit=1600%2C900&ssl=1",1600,900,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-24-at-16.31.56_2024-10-24_19-56-31_jpeg_2024-10-24_19-56-32.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-24-at-16.31.56_2024-10-24_19-56-31_jpeg_2024-10-24_19-56-32.webp.webp?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-24-at-16.31.56_2024-10-24_19-56-31_jpeg_2024-10-24_19-56-32.webp.webp?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-24-at-16.31.56_2024-10-24_19-56-31_jpeg_2024-10-24_19-56-32.webp.webp?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-24-at-16.31.56_2024-10-24_19-56-31_jpeg_2024-10-24_19-56-32.webp.webp?fit=1536%2C864&ssl=1",1536,864,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-24-at-16.31.56_2024-10-24_19-56-31_jpeg_2024-10-24_19-56-32.webp.webp?fit=1600%2C900&ssl=1",1600,900,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A abertura do rodeio de Cruz das Posses, distrito de Sert\u00e3ozinho, cidade na regi\u00e3o de Ribeir\u00e3o Preto, foi suspensa devido \u00e0s fortes chuvas que atingiram a regi\u00e3o, na tarde desta quinta-feira (24). Por conta do temporal, a estrutura da festa foi totalmente comprometida \u2013 veja o v\u00eddeo abaixo. Apesar do susto, ningu\u00e9m ficou ferido.&hellip;","jetpack-related-posts":[{"id":73298,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/25\/rodeio-na-regiao-de-ribeirao-preto-e-suspenso-apos-desabamento-de-estrutura\/","url_meta":{"origin":73094,"position":0},"title":"Rodeio na regi\u00e3o de Ribeir\u00e3o Preto \u00e9 suspenso ap\u00f3s desabamento de estrutura","author":"ismaelcolosi.com.br","date":"25 de October de 2024","format":false,"excerpt":"[ad_1] A Prefeitura de Sert\u00e3ozinho informou nesta sexta-feira (25) que o Cruz das Posses Rodeio Fest 2024 foi suspenso ap\u00f3s parte da estrutura ter desabado na tarde da \u00faltima quinta-feira (24) durante o temporal. Segundo a prefeitura, as fortes chuvas e ventos que atingiram a regi\u00e3o, comprometeram a estrutura do\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-24-at-16.31.56_2024-10-24_19-56-31_jpeg_2024-10-24_19-56-32.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-24-at-16.31.56_2024-10-24_19-56-31_jpeg_2024-10-24_19-56-32.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-24-at-16.31.56_2024-10-24_19-56-31_jpeg_2024-10-24_19-56-32.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-24-at-16.31.56_2024-10-24_19-56-31_jpeg_2024-10-24_19-56-32.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-24-at-16.31.56_2024-10-24_19-56-31_jpeg_2024-10-24_19-56-32.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":73427,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/26\/rodeio-na-regiao-de-ribeirao-preto-divulga-nova-data-confira\/","url_meta":{"origin":73094,"position":1},"title":"Rodeio na regi\u00e3o de Ribeir\u00e3o Preto divulga nova data; Confira","author":"ismaelcolosi.com.br","date":"26 de October de 2024","format":false,"excerpt":"[ad_1] O Cruz das Posses Rodeio Fest, que acontece em Cruz das Posses, distrito de Sert\u00e3ozinho, na regi\u00e3o de Ribeir\u00e3o Preto tem nova data confirmada. As atividades foram suspensas na tarde de quinta-feira (24) por conta do temporal. Em nota, a Prefeitura de Sert\u00e3ozinho informou que agora o evento deve\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/m1_princ_clip_20230526164120oDOT7RU8xH_2024-10-26_16-44-59_jpg_2024-10-26_16-44-59.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/m1_princ_clip_20230526164120oDOT7RU8xH_2024-10-26_16-44-59_jpg_2024-10-26_16-44-59.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/m1_princ_clip_20230526164120oDOT7RU8xH_2024-10-26_16-44-59_jpg_2024-10-26_16-44-59.webp.webp?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/m1_princ_clip_20230526164120oDOT7RU8xH_2024-10-26_16-44-59_jpg_2024-10-26_16-44-59.webp.webp?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/m1_princ_clip_20230526164120oDOT7RU8xH_2024-10-26_16-44-59_jpg_2024-10-26_16-44-59.webp.webp?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":71711,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/17\/lauana-prado-e-a-atracao-desta-quinta-feira-em-rodeio-na-regiao-de-ribeirao\/","url_meta":{"origin":73094,"position":2},"title":"Lauana Prado \u00e9 a atra\u00e7\u00e3o desta quinta-feira em rodeio na regi\u00e3o de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"17 de October de 2024","format":false,"excerpt":"[ad_1] Nesta quinta-feira (17), Lauana Prado sobe ao palco do est\u00e1dio Bela Vista, em Cravinhos, na regi\u00e3o de Ribeir\u00e3o Preto, para agitar a primeira noite do Cravinhos Rodeio Show. A cantora sertaneja, que se tornou a artista mais ouvida do pa\u00eds no primeiro semestre de 2024 e foi indicada pela\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-21_2024-10-17_17-55-09_png_2024-10-17_17-55-10.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-21_2024-10-17_17-55-09_png_2024-10-17_17-55-10.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-21_2024-10-17_17-55-09_png_2024-10-17_17-55-10.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-21_2024-10-17_17-55-09_png_2024-10-17_17-55-10.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-21_2024-10-17_17-55-09_png_2024-10-17_17-55-10.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":55641,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/04\/ana-castela-abre-programacao-musical-em-rodeio-na-regiao-de-ribeirao-preto\/","url_meta":{"origin":73094,"position":3},"title":"Ana Castela abre programa\u00e7\u00e3o musical em rodeio na regi\u00e3o de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"4 de July de 2024","format":false,"excerpt":"[ad_1] A cantora sertaneja, Ana Castela, abre a programa\u00e7\u00e3o musical do \u201cOrl\u00e2ndia Rodeo Music\u201d, que come\u00e7a nesta quinta-feira (4). O evento segue at\u00e9 o dia 8 de julho, v\u00e9spera de feriado. Conhecida como a \u201cBoiadeira\u201d, a cantora se apresenta no Recinto do Rodeio, que fica na avenida S com a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-04-at-11.57.01-1_2024-07-04_15-47-30_jpeg_2024-07-04_15-47-30.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-04-at-11.57.01-1_2024-07-04_15-47-30_jpeg_2024-07-04_15-47-30.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-04-at-11.57.01-1_2024-07-04_15-47-30_jpeg_2024-07-04_15-47-30.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-04-at-11.57.01-1_2024-07-04_15-47-30_jpeg_2024-07-04_15-47-30.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-04-at-11.57.01-1_2024-07-04_15-47-30_jpeg_2024-07-04_15-47-30.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":71240,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/15\/lauana-prado-e-gustavo-mioto-veja-atracoes-de-rodeio-na-regiao-de-ribeirao-preto\/","url_meta":{"origin":73094,"position":4},"title":"Lauana Prado e Gustavo Mioto: Veja atra\u00e7\u00f5es de rodeio na regi\u00e3o de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"15 de October de 2024","format":false,"excerpt":"[ad_1] Lauana Prado, Gustavo Mioto e outras atra\u00e7\u00f5es sobem ao palco do est\u00e1dio Bela Vista, em Cravinhos, na regi\u00e3o de Ribeir\u00e3o Preto, para agitar o Cravinhos Rodeio Show, que come\u00e7a nesta quinta-feira (17). Al\u00e9m de shows durante tr\u00eas noites, o Cravinhos Rodeio Show ter\u00e1 disputas de montarias pela Liga Nacional\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-21_2024-10-15_16-29-10_jpg_2024-10-15_16-29-10.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-21_2024-10-15_16-29-10_jpg_2024-10-15_16-29-10.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-21_2024-10-15_16-29-10_jpg_2024-10-15_16-29-10.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-21_2024-10-15_16-29-10_jpg_2024-10-15_16-29-10.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-21_2024-10-15_16-29-10_jpg_2024-10-15_16-29-10.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":56044,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/08\/lauana-prado-cancela-show-em-rodeio-na-regiao-de-ribeirao-preto-saiba-o-motivo\/","url_meta":{"origin":73094,"position":5},"title":"Lauana Prado cancela show em rodeio na regi\u00e3o de Ribeir\u00e3o Preto; Saiba o motivo","author":"ismaelcolosi.com.br","date":"8 de July de 2024","format":false,"excerpt":"[ad_1] A cantora Lauana Prado cancelou o show que faria em Orl\u00e2ndia, na regi\u00e3o de Ribeir\u00e3o Preto, na noite desta segunda-feira (8). O motivo foi uma gastroenterite, de acordo um v\u00eddeo postado em uma rede social oficial da cantora, em que ela aparece explicando sobre o ocorrido. No v\u00eddeo, Lauana\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-75.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-75.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-75.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-75.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-75.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-j0W","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/73094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=73094"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/73094\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/73095"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=73094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=73094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=73094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}