{"id":72280,"date":"2024-10-21T07:56:53","date_gmt":"2024-10-21T10:56:53","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/21\/confira-a-agenda-dos-candidatos-a-prefeitura-de-ribeirao-preto-nesta-segunda-21-2\/"},"modified":"2024-10-21T07:56:53","modified_gmt":"2024-10-21T10:56:53","slug":"confira-a-agenda-dos-candidatos-a-prefeitura-de-ribeirao-preto-nesta-segunda-21-2","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/21\/confira-a-agenda-dos-candidatos-a-prefeitura-de-ribeirao-preto-nesta-segunda-21-2\/","title":{"rendered":"Confira a agenda dos candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto nesta segunda (21)"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p><strong>Os candidatos \u00e0\u00a0Prefeitura de Ribeir\u00e3o Preto\u00a0divulgaram suas agendas de campanha\u00a0para esta segunda-feira (21).<\/strong><\/p>\n<p>O per\u00edodo de propaganda eleitoral no segundo turno come\u00e7ou no dia 7 de outubro, portanto,\u00a0<mark><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">candidatos podem apresentar \u00e0s eleitoras e aos eleitores suas ideias e propostas.<\/mark><\/mark><\/p>\n<p>A publicidade das candidaturas pode ser feita na internet, na rua, na imprensa escrita, em casas, ve\u00edculos e outros bens particulares.<\/p>\n<p>O hor\u00e1rio eleitoral gratuito no r\u00e1dio e na TV voltou a ser transmitido no dia 11 de outubro e vai at\u00e9 dia 25 de outubro \u2013\u00a0clique aqui e veja o que pode e n\u00e3o pode durante o per\u00edodo de propaganda eleitoral.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Veja a agenda dos candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto<\/strong>: <\/h4>\n<p><strong>Ricardo Silva (PSD)<\/strong><\/p>\n<ul>\n<li>Per\u00edodo da manh\u00e3: Sabatina com alunos de col\u00e9gio de Ribeir\u00e3o Preto; Sabatina em emissora de TV; Visita a comerciantes do Centro<\/li>\n<\/ul>\n<ul>\n<li>Per\u00edodo da tarde: Visita a comerciantes da zona Norte<\/li>\n<\/ul>\n<ul>\n<li>Per\u00edodo da noite: Sabatina em emissora de TV; Reuni\u00e3o com apoiadores no comit\u00ea eleitoral<\/li>\n<\/ul>\n<p><strong>Marco Aur\u00e9lio (Novo)<\/strong><\/p>\n<p>Per\u00edodo da manh\u00e3: Grava\u00e7\u00e3o de conte\u00fados para TV e internet; Visita a empreendedores na zona Norte<\/p>\n<p>Per\u00edodo da tarde: Reuni\u00e3o com empres\u00e1rios locais; Encontro com moradores na zona Norte<\/p>\n<p>Per\u00edodo da noite: Sabatina no Sincovarp (Sindicato do Com\u00e9rcio Varejista de Ribeir\u00e3o Preto)<\/p>\n<p>SAIBA MAIS<\/p>\n<p>Lula sofre acidente dom\u00e9stico e tem ferimento na cabe\u00e7a<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do acidade on no WhatsApp. Para entrar no grupo, basta\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Dtv9mxhy6V5BJBotM2OQ5k\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Qual \u00e9 a previs\u00e3o do tempo para S\u00e3o Paulo na pr\u00f3xima semana?<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/politica\/eleicoes\/confira-a-agenda-dos-candidatos-a-prefeitura-de-ribeirao-preto-nesta-segunda-21\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Os candidatos \u00e0\u00a0Prefeitura de Ribeir\u00e3o Preto\u00a0divulgaram suas agendas de campanha\u00a0para esta segunda-feira (21). O per\u00edodo de propaganda eleitoral no segundo turno come\u00e7ou no dia 7 de outubro, portanto,\u00a0candidatos podem apresentar \u00e0s eleitoras e aos eleitores suas ideias e propostas. A publicidade das candidaturas pode ser feita na internet, na rua, na imprensa escrita, em &#8230; <a title=\"Confira a agenda dos candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto nesta segunda (21)\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/21\/confira-a-agenda-dos-candidatos-a-prefeitura-de-ribeirao-preto-nesta-segunda-21-2\/\" aria-label=\"Leia mais sobre Confira a agenda dos candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto nesta segunda (21)\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":69582,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-72280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Os candidatos \u00e0\u00a0Prefeitura de Ribeir\u00e3o Preto\u00a0divulgaram suas agendas de campanha\u00a0para esta segunda-feira (21). O per\u00edodo de propaganda eleitoral no segundo turno come\u00e7ou no dia 7 de outubro, portanto,\u00a0candidatos podem apresentar \u00e0s eleitoras e aos eleitores suas ideias e propostas. A publicidade das candidaturas pode ser feita na internet, na rua, na imprensa escrita, em&hellip;","jetpack-related-posts":[{"id":72217,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/20\/confira-a-agenda-dos-candidatos-a-prefeitura-de-ribeirao-preto-nesta-segunda-21\/","url_meta":{"origin":72280,"position":0},"title":"Confira a agenda dos candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto nesta segunda (21)","author":"ismaelcolosi.com.br","date":"20 de Outubro de 2024","format":false,"excerpt":"[ad_1] Os candidatos \u00e0\u00a0Prefeitura de Ribeir\u00e3o Preto\u00a0divulgaram suas agendas de campanha\u00a0para esta segunda-feira (21). O per\u00edodo de propaganda eleitoral no segundo turno come\u00e7ou no dia 7 de outubro, portanto,\u00a0candidatos podem apresentar \u00e0s eleitoras e aos eleitores suas ideias e propostas. A publicidade das candidaturas pode ser feita na internet, na\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":73144,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/24\/confira-a-agenda-dos-candidatos-a-prefeitura-de-ribeirao-preto-nesta-sexta-25\/","url_meta":{"origin":72280,"position":1},"title":"Confira a agenda dos candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto nesta sexta (25)","author":"ismaelcolosi.com.br","date":"24 de Outubro de 2024","format":false,"excerpt":"[ad_1] Os candidatos \u00e0\u00a0Prefeitura de Ribeir\u00e3o Preto\u00a0divulgaram suas agendas de campanha\u00a0para esta sexta-feira (25). O per\u00edodo de propaganda eleitoral no segundo turno come\u00e7ou no dia 7 de outubro, portanto,\u00a0candidatos podem apresentar \u00e0s eleitoras e aos eleitores suas ideias e propostas. A publicidade das candidaturas pode ser feita na internet, na\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio-entrevista_2024-10-12_22-13-15_jpeg_2024-10-12_22-13-15.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio-entrevista_2024-10-12_22-13-15_jpeg_2024-10-12_22-13-15.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio-entrevista_2024-10-12_22-13-15_jpeg_2024-10-12_22-13-15.webp.webp?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio-entrevista_2024-10-12_22-13-15_jpeg_2024-10-12_22-13-15.webp.webp?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio-entrevista_2024-10-12_22-13-15_jpeg_2024-10-12_22-13-15.webp.webp?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":70851,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/13\/confira-a-agenda-dos-candidatos-a-prefeitura-de-ribeirao-preto-nesta-segunda-feira-14\/","url_meta":{"origin":72280,"position":2},"title":"Confira a agenda dos candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto nesta segunda-feira (14)","author":"ismaelcolosi.com.br","date":"13 de Outubro de 2024","format":false,"excerpt":"[ad_1] Os candidatos \u00e0\u00a0Prefeitura de Ribeir\u00e3o Preto\u00a0divulgaram suas agendas de campanha para esta segunda-feira (14). O per\u00edodo de propaganda eleitoral, para o segundo turno, come\u00e7ou no dia 7 de outubro, portanto,\u00a0candidatos podem apresentar \u00e0s eleitoras e aos eleitores suas ideias e propostas. A publicidade das candidaturas pode ser feita na\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1728855605_ribeirao-preto-prefeitura.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1728855605_ribeirao-preto-prefeitura.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1728855605_ribeirao-preto-prefeitura.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1728855605_ribeirao-preto-prefeitura.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1728855605_ribeirao-preto-prefeitura.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":72119,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/19\/confira-a-agenda-dos-candidatos-a-prefeitura-de-ribeirao-preto-neste-domingo-20\/","url_meta":{"origin":72280,"position":3},"title":"Confira a agenda dos candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto neste domingo (20)","author":"ismaelcolosi.com.br","date":"19 de Outubro de 2024","format":false,"excerpt":"[ad_1] Os candidatos \u00e0\u00a0Prefeitura de Ribeir\u00e3o Preto\u00a0divulgaram suas agendas de campanha para este domingo (20). O per\u00edodo de propaganda eleitoral, para o segundo turno, come\u00e7ou no dia 7 de outubro, portanto,\u00a0candidatos podem apresentar \u00e0s eleitoras e aos eleitores suas ideias e propostas. A publicidade das candidaturas pode ser feita na\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio-entrevista_2024-10-12_22-13-15_jpeg_2024-10-12_22-13-15.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio-entrevista_2024-10-12_22-13-15_jpeg_2024-10-12_22-13-15.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio-entrevista_2024-10-12_22-13-15_jpeg_2024-10-12_22-13-15.webp.webp?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio-entrevista_2024-10-12_22-13-15_jpeg_2024-10-12_22-13-15.webp.webp?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio-entrevista_2024-10-12_22-13-15_jpeg_2024-10-12_22-13-15.webp.webp?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":72122,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/19\/confira-a-agenda-dos-candidatos-a-prefeitura-de-ribeirao-preto-neste-domingo-20-2\/","url_meta":{"origin":72280,"position":4},"title":"Confira a agenda dos candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto neste domingo (20)","author":"ismaelcolosi.com.br","date":"19 de Outubro de 2024","format":false,"excerpt":"[ad_1] Os candidatos \u00e0\u00a0Prefeitura de Ribeir\u00e3o Preto\u00a0divulgaram suas agendas de campanha para este domingo (20). O per\u00edodo de propaganda eleitoral, para o segundo turno, come\u00e7ou no dia 7 de outubro, portanto,\u00a0candidatos podem apresentar \u00e0s eleitoras e aos eleitores suas ideias e propostas. A publicidade das candidaturas pode ser feita na\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio-entrevista_2024-10-12_22-13-15_jpeg_2024-10-12_22-13-15.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio-entrevista_2024-10-12_22-13-15_jpeg_2024-10-12_22-13-15.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio-entrevista_2024-10-12_22-13-15_jpeg_2024-10-12_22-13-15.webp.webp?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio-entrevista_2024-10-12_22-13-15_jpeg_2024-10-12_22-13-15.webp.webp?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio-entrevista_2024-10-12_22-13-15_jpeg_2024-10-12_22-13-15.webp.webp?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":70698,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/11\/confira-a-agenda-dos-candidatos-a-prefeitura-de-ribeirao-preto-neste-sabado-12\/","url_meta":{"origin":72280,"position":5},"title":"Confira a agenda dos candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto neste s\u00e1bado (12)","author":"ismaelcolosi.com.br","date":"11 de Outubro de 2024","format":false,"excerpt":"[ad_1] Os candidatos \u00e0\u00a0Prefeitura de Ribeir\u00e3o Preto\u00a0divulgaram suas agendas de campanha para\u00a0este s\u00e1bado (12) O per\u00edodo de propaganda eleitoral, para o segundo turno, come\u00e7ou no dia 7 de outubro, portanto, candidatos podem apresentar \u00e0s eleitoras e aos eleitores suas ideias e propostas. A publicidade das candidaturas pode ser feita na\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-95_2024-10-06_22-19-13_png_2024-10-06_22-19-13.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-iNO","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/72280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=72280"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/72280\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/69582"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=72280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=72280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=72280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}