{"id":72189,"date":"2024-10-20T14:25:34","date_gmt":"2024-10-20T17:25:34","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/20\/lula-sofre-acidente-domestico-e-tem-ferimento-na-cabeca\/"},"modified":"2024-10-20T14:25:34","modified_gmt":"2024-10-20T17:25:34","slug":"lula-sofre-acidente-domestico-e-tem-ferimento-na-cabeca","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/20\/lula-sofre-acidente-domestico-e-tem-ferimento-na-cabeca\/","title":{"rendered":"Lula sofre acidente dom\u00e9stico e tem ferimento na cabe\u00e7a"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p><strong>O presidente Luiz In\u00e1cio Lula da Silva (PT) sofreu um acidente dom\u00e9stico neste s\u00e1bado (19), em Bras\u00edlia.<\/strong> Ele teve um corte na nuca, segundo boletim m\u00e9dico divulgado pelo no Hospital S\u00edrio-Liban\u00eas.<\/p>\n<p>Os m\u00e9dicos avaliaram que o caso n\u00e3o \u00e9 grave. Por\u00e9m, por precau\u00e7\u00e3o, a viagem que o presidente faria \u00e0 R\u00fassia na tarde deste domingo (20) foi cancelada. <\/p>\n<p>Lula dever\u00e1 participar da C\u00fapula do Brics nesta semana por videoconfer\u00eancia.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Leia o boletim m\u00e9dico sobre o acidente com Lula:<\/strong><\/h4>\n<p>\u201cO Presidente Luiz In\u00e1cio Lula da Silva deu entrada no Hospital S\u00edrio-Liban\u00eas \u2013 unidade Bras\u00edlia, em 19\/10\/2024, ap\u00f3s acidente dom\u00e9stico, com ferimento corto-contuso em regi\u00e3o occipital. Ap\u00f3s avalia\u00e7\u00e3o da equipe m\u00e9dica, foi orientado evitar viagem a\u00e9rea de longa dist\u00e2ncia, podendo exercer suas demais atividades. Permanece sob acompanhamento de equipe m\u00e9dica, aos cuidados do Prof. Dr Roberto Kalil Filho e Dra Ana Helena Germoglio\u201d<\/p>\n<p>O boletim \u00e9 assinado pelos diretores do hospital Rafael Gadia e Luiza Dib.<\/p>\n<p><!-- CONTENT END 3 -->\n<\/div>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/politica\/lula-sofre-acidente-domestico-e-tem-ferimento-na-cabeca\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O presidente Luiz In\u00e1cio Lula da Silva (PT) sofreu um acidente dom\u00e9stico neste s\u00e1bado (19), em Bras\u00edlia. Ele teve um corte na nuca, segundo boletim m\u00e9dico divulgado pelo no Hospital S\u00edrio-Liban\u00eas. Os m\u00e9dicos avaliaram que o caso n\u00e3o \u00e9 grave. Por\u00e9m, por precau\u00e7\u00e3o, a viagem que o presidente faria \u00e0 R\u00fassia na tarde deste &#8230; <a title=\"Lula sofre acidente dom\u00e9stico e tem ferimento na cabe\u00e7a\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/20\/lula-sofre-acidente-domestico-e-tem-ferimento-na-cabeca\/\" aria-label=\"Leia mais sobre Lula sofre acidente dom\u00e9stico e tem ferimento na cabe\u00e7a\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":41969,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-72189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__lula.webp.webp?fit=2048%2C1365&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__lula.webp.webp?fit=2048%2C1365&ssl=1",2048,1365,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__lula.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__lula.webp.webp?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__lula.webp.webp?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__lula.webp.webp?fit=1024%2C683&ssl=1",1024,683,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__lula.webp.webp?fit=1536%2C1024&ssl=1",1536,1024,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__lula.webp.webp?fit=2048%2C1365&ssl=1",2048,1365,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O presidente Luiz In\u00e1cio Lula da Silva (PT) sofreu um acidente dom\u00e9stico neste s\u00e1bado (19), em Bras\u00edlia. Ele teve um corte na nuca, segundo boletim m\u00e9dico divulgado pelo no Hospital S\u00edrio-Liban\u00eas. Os m\u00e9dicos avaliaram que o caso n\u00e3o \u00e9 grave. Por\u00e9m, por precau\u00e7\u00e3o, a viagem que o presidente faria \u00e0 R\u00fassia na tarde deste&hellip;","jetpack-related-posts":[{"id":28320,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/15\/lula-passa-por-exames-de-rotina-em-hospital-de-sao-paulo\/","url_meta":{"origin":72189,"position":0},"title":"Lula passa por exames de rotina em hospital de S\u00e3o Paulo \u2013 Folha de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"15 de Janeiro de 2024","format":false,"excerpt":"[ad_1] O presidente da Rep\u00fablica, Luiz In\u00e1cio Lula da Silva, passou por exames de rotina no Hospital S\u00edrio-Liban\u00eas, em S\u00e3o Paulo. Segundo boletim m\u00e9dico divulgado na tarde deste s\u00e1bado (13), os exames n\u00e3o mostraram altera\u00e7\u00f5es em seu quadro de sa\u00fade. Lula estava\u00a0acompanhado pelo doutor\u00a0Roberto Kalil Filho, m\u00e9dico pessoal do presidente,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":59582,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/09\/lula-e-tarcisio-lamentam-queda-de-aviao-no-interior-de-sp\/","url_meta":{"origin":72189,"position":1},"title":"Lula e Tarc\u00edsio lamentam queda de avi\u00e3o no interior de SP","author":"ismaelcolosi.com.br","date":"9 de Agosto de 2024","format":false,"excerpt":"[ad_1] O presidente Luiz In\u00e1cio Lula da Silva pediu um minuto de sil\u00eancio para as v\u00edtimas da queda do avi\u00e3o com 58 passageiros e quatro tripulantes em Vinhedo, operado pela Voepass, com sede em Ribeir\u00e3o Preto, nesta sexta-feira (9). Queria que todos se colocassem de p\u00e9 para que a gente\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":59598,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/09\/lula-e-tarcisio-lamentam-queda-de-aviao-no-interior-de-sp-2\/","url_meta":{"origin":72189,"position":2},"title":"Lula e Tarc\u00edsio lamentam queda de avi\u00e3o no interior de SP","author":"ismaelcolosi.com.br","date":"9 de Agosto de 2024","format":false,"excerpt":"[ad_1] O presidente Luiz In\u00e1cio Lula da Silva pediu um minuto de sil\u00eancio para as v\u00edtimas da queda do avi\u00e3o com 58 passageiros e quatro tripulantes em Vinhedo, operado pela Voepass, com sede em Ribeir\u00e3o Preto, nesta sexta-feira (9). Queria que todos se colocassem de p\u00e9 para que a gente\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":37579,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/16\/lula-critica-corte-de-verba-humanitaria\/","url_meta":{"origin":72189,"position":3},"title":"Lula critica corte de verba humanit\u00e1ria","author":"ismaelcolosi.com.br","date":"16 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 16 de fevereiro de 2024 | 17:0016 de fevereiro de 2024 | 8:46 0O presidente Luiz In\u00e1cio Lula da Silva classificou nesta quinta-feira, 15 de fevereiro, como \u201cdesumanidade\u201d e \u201ccovardia\u201d contra o povo palestino, a decis\u00e3o de \u201cpa\u00edses ricos\u201d, entre eles os Estados Unidos, de cortar as contribui\u00e7\u00f5es milion\u00e1rias\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Lula-Ricardo-Stuckert-PR-1-scaled.jpg?fit=1000%2C623&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Lula-Ricardo-Stuckert-PR-1-scaled.jpg?fit=1000%2C623&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Lula-Ricardo-Stuckert-PR-1-scaled.jpg?fit=1000%2C623&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Lula-Ricardo-Stuckert-PR-1-scaled.jpg?fit=1000%2C623&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":15550,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/13\/obito-do-filho-flavio-dino-ministro-da-justica-volta-a-tona-e-gera-comocao\/","url_meta":{"origin":72189,"position":4},"title":"\u00d3bito do filho Fl\u00e1vio Dino, \u2018Ministro da Justi\u00e7a\u2019, volta \u00e0 tona e gera como\u00e7\u00e3o","author":"ismaelcolosi.com.br","date":"13 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Nomeado para o Supremo Tribunal Federal (STF) pelo presidente Luiz In\u00e1cio Lula da Silva, o ministro da Justi\u00e7a, Fl\u00e1vio Dino, passou por uma sabatina na Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ) do Senado Federal nesta quarta-feira (13).Posteriormente, seu nome ser\u00e1 submetido ao plen\u00e1rio, necessitando da aprova\u00e7\u00e3o de pelo menos\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657a45381cb917467.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657a45381cb917467.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657a45381cb917467.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657a45381cb917467.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657a45381cb917467.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":35251,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/05\/acaba-de-chegar-triste-noticia-sobre-aviao-do-presidente-lula-e-e-confirmado-a-aeronave-ver-mais\/","url_meta":{"origin":72189,"position":5},"title":"Acaba de chegar TRISTE NOT\u00cdCIA sobre avi\u00e3o do presidente Lula e \u00c9 CONFIRMADO: &#8220;A aeronave&#8230;Ver mais","author":"ismaelcolosi.com.br","date":"5 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] O avi\u00e3o do atual presidente Luiz In\u00e1cio Lula da Silva sofreu problemas em sua decolagem, algo que preocupou grande parte dos seus apoiadores e admiradores. A aeronave que estava fazendo o transporte do presidente acabou interrompendo a decolagem em Congonhas, aeroporto localizado em S\u00e3o Paulo. Na ocasi\u00e3o o avi\u00e3o\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Apresentacao-sem-titulo-3.png?fit=960%2C540&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Apresentacao-sem-titulo-3.png?fit=960%2C540&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Apresentacao-sem-titulo-3.png?fit=960%2C540&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Apresentacao-sem-titulo-3.png?fit=960%2C540&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-iMl","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/72189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=72189"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/72189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/41969"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=72189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=72189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=72189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}