{"id":7132,"date":"2023-11-27T16:07:52","date_gmt":"2023-11-27T19:07:52","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/27\/quem-sao-as-3-vitimas-que-perderam-suas-vidas-em-grave-acidente-envolvendo-2-onibus-em-mg\/"},"modified":"2023-11-27T16:07:52","modified_gmt":"2023-11-27T19:07:52","slug":"quem-sao-as-3-vitimas-que-perderam-suas-vidas-em-grave-acidente-envolvendo-2-onibus-em-mg","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/27\/quem-sao-as-3-vitimas-que-perderam-suas-vidas-em-grave-acidente-envolvendo-2-onibus-em-mg\/","title":{"rendered":"Quem s\u00e3o as 3 v\u00edtimas que perderam suas vidas em grave acidente envolvendo 2 \u00f4nibus em MG"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div itemprop=\"text\">\n<p>Neste \u00faltimo s\u00e1bado, dia 25 de novembro, aconteceu um grave acidente na rodovia Fern\u00e3o Dias, tirando a vida de tr\u00eas pessoas que foram identificadas recentemente. A colis\u00e3o envolveu dois \u00f4nibus, em S\u00e3o Sebasti\u00e3o da Bela Vista, em Minas Gerais.<\/p>\n<p>A ocorr\u00eancia deixou mais de trinta feridos, sendo que quatro ficaram em estado grave. Neste artigo, ser\u00e1 exposto mais detalhes sobre quem eram as v\u00edtimas, como os seus nomes e suas idades.<\/p>\n<p><b>Ananda Miranda Gon\u00e7alves<\/b><\/p>\n<p>Ela era natural de S\u00e3o Paulo e estudou na UNICAMP (Universidade de Campinas). Ela trabalhava como enfermeira, na regi\u00e3o de Belo Horizonte, em Minas Gerais.<\/p>\n<p>O hospital em que a profissional de sa\u00fade atuava divulgou uma nota, lamentando a situa\u00e7\u00e3o e solidarizando com os seus amigos e familiares.<\/p>\n<p><b>Barbara Barros Pires<\/b><\/p>\n<p>Ela tinha 37 anos e era natural de Belo Horizonte. Barbara morava na Su\u00e9cia e trabalhava na prefeitura de Gutemburgo. Ela estava no Brasil para visitar uma sobrinha que teria acabado de nascer.<\/p>\n<p><b>Francisco Jos\u00e9 Pastorelo Pereira<\/b><\/p>\n<p>Ele tinha 43 anos de idade e era natural de Valinhos, em S\u00e3o Paulo. Ele atuava como professor e dava aulas na regi\u00e3o de Vinhedo, no interior de S\u00e3o Paulo. Seu sepultamento ir\u00e1 ocorrer na tarde desta segunda-feira, dia 27 de novembro.<\/p>\n<p>Um dos \u00f4nibus tinha sa\u00eddo de Belo Horizonte e tinha como destino S\u00e3o Paulo. O outro, iria deixar passageiros em Campinas e depois seguiria viagem para Sorocaba, tamb\u00e9m no interior. As causas do acidente continuam a ser investigadas.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/fnmais.com\/quem-sao-3-vitimas-que-perderam-suas-vidas-em-grave-acidente-envolvendo-2-onibus-em-mg\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Neste \u00faltimo s\u00e1bado, dia 25 de novembro, aconteceu um grave acidente na rodovia Fern\u00e3o Dias, tirando a vida de tr\u00eas pessoas que foram identificadas recentemente. A colis\u00e3o envolveu dois \u00f4nibus, em S\u00e3o Sebasti\u00e3o da Bela Vista, em Minas Gerais. A ocorr\u00eancia deixou mais de trinta feridos, sendo que quatro ficaram em estado grave. Neste &#8230; <a title=\"Quem s\u00e3o as 3 v\u00edtimas que perderam suas vidas em grave acidente envolvendo 2 \u00f4nibus em MG\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/27\/quem-sao-as-3-vitimas-que-perderam-suas-vidas-em-grave-acidente-envolvendo-2-onibus-em-mg\/\" aria-label=\"Leia mais sobre Quem s\u00e3o as 3 v\u00edtimas que perderam suas vidas em grave acidente envolvendo 2 \u00f4nibus em MG\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":7133,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d3d562a1d3653.jpg?fit=1200%2C628&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d3d562a1d3653.jpg?fit=1200%2C628&ssl=1",1200,628,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d3d562a1d3653.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d3d562a1d3653.jpg?fit=300%2C157&ssl=1",300,157,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d3d562a1d3653.jpg?fit=768%2C402&ssl=1",768,402,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d3d562a1d3653.jpg?fit=1024%2C536&ssl=1",1024,536,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d3d562a1d3653.jpg?fit=1200%2C628&ssl=1",1200,628,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d3d562a1d3653.jpg?fit=1200%2C628&ssl=1",1200,628,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Neste \u00faltimo s\u00e1bado, dia 25 de novembro, aconteceu um grave acidente na rodovia Fern\u00e3o Dias, tirando a vida de tr\u00eas pessoas que foram identificadas recentemente. A colis\u00e3o envolveu dois \u00f4nibus, em S\u00e3o Sebasti\u00e3o da Bela Vista, em Minas Gerais. A ocorr\u00eancia deixou mais de trinta feridos, sendo que quatro ficaram em estado grave. Neste&hellip;","jetpack-related-posts":[{"id":7589,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/28\/quem-sao-as-vitimas-de-grave-acidente-na-fernao-dias-que-causou-6-falecimentos-eram-da-mesma-familia-e-outros-iam-para-consulta\/","url_meta":{"origin":7132,"position":0},"title":"Quem s\u00e3o as v\u00edtimas de grave acidente na Fern\u00e3o Dias que causou 6 falecimentos; eram da mesma fam\u00edlia e outros iam para consulta","author":"ismaelcolosi.com.br","date":"28 de Novembro de 2023","format":false,"excerpt":"[ad_1] Nesta segunda-feira, dia 27 de novembro, um tr\u00e1gico acidente aconteceu em uma rodovia e tirou a vida de seis pessoas. A situa\u00e7\u00e3o ocorreu na rodovia Fern\u00e3o Dias, na regi\u00e3o de Minas Gerais, em Belo Horizonte. Segundo o que foi informado, quatro v\u00edtimas eram da mesma fam\u00edlia.O local \u00e9 pr\u00f3ximo\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656613f0c75073881.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656613f0c75073881.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656613f0c75073881.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656613f0c75073881.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656613f0c75073881.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6353,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/25\/dois-onibus-com-69-pessoas-sofrem-acidente-em-mg-e-obito-ja-foi-confirmado\/","url_meta":{"origin":7132,"position":1},"title":"Dois \u00f4nibus com 69 pessoas sofrem acidente em MG e \u00f3bito j\u00e1 foi confirmado","author":"ismaelcolosi.com.br","date":"25 de Novembro de 2023","format":false,"excerpt":"[ad_1] Um grave acidente interditou a pista da Rodovia Fern\u00e3o Dias neste fim de semana. Dois \u00f4nibus colidiram com dezenas de pessoas a bordo. Antes do encerramento desta mat\u00e9ria, j\u00e1 havia sido confirmado o primeiro \u00f3bito.O acidente ocorreu na madrugada deste s\u00e1bado (25) nas proximidades do munic\u00edpio de S\u00e3o Sebasti\u00e3o\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65623672280347745.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65623672280347745.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65623672280347745.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65623672280347745.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65623672280347745.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":18982,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/21\/colisao-entre-onibus-e-carreta-deixa-veiculos-destruidos-e-diversas-vitimas\/","url_meta":{"origin":7132,"position":2},"title":"Colis\u00e3o entre \u00f4nibus e carreta deixa ve\u00edculos destru\u00eddos e diversas v\u00edtimas","author":"ismaelcolosi.com.br","date":"21 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Na madrugada desta quinta-feira (21), a rodovia BR-116, foi cen\u00e1rio de uma verdadeira trag\u00e9dia. Um grave acidente envolvendo um \u00f4nibus e uma carreta deixou os ve\u00edculos destru\u00eddos, al\u00e9m de v\u00e1rias v\u00edtimas.O acidente aconteceu na altura do munic\u00edpio de Muria\u00e9, localizado no interior do estado de Minas Gerais. De acordo\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6584672946d0c1005.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6584672946d0c1005.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6584672946d0c1005.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6584672946d0c1005.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6584672946d0c1005.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15910,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/14\/grave-acidente-entre-onibus-e-caminhao-deixa-vitimas-fatais-na-br-050\/","url_meta":{"origin":7132,"position":3},"title":"Grave acidente entre \u00f4nibus e caminh\u00e3o deixa v\u00edtimas fatais na BR-050","author":"ismaelcolosi.com.br","date":"14 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Na madrugada desta quinta-feira (14), um grave acidente envolvendo um \u00f4nibus e um caminh\u00e3o deixou v\u00edtimas fatais na rodovia BR-050. O caso aconteceu na altura do munic\u00edpio de Uberaba, localizado no Tri\u00e2ngulo Mineiro.De acordo com as primeiras informa\u00e7\u00f5es repassadas pela Pol\u00edcia Rodovi\u00e1ria Federal (PRF), o \u00f4nibus levava cerca de\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657b48a2ee9c83763.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657b48a2ee9c83763.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657b48a2ee9c83763.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657b48a2ee9c83763.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657b48a2ee9c83763.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7142,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/27\/tragedia-na-br-381-acidente-envolvendo-11-veiculos-deixa-pelo-menos-3-vitimas-fatais-e-numero-feridos-ainda-e-desconhecido\/","url_meta":{"origin":7132,"position":4},"title":"Trag\u00e9dia na BR-381: Acidente envolvendo 11 ve\u00edculos deixa pelo menos 3 v\u00edtimas fatais e n\u00famero feridos ainda \u00e9 desconhecido","author":"ismaelcolosi.com.br","date":"27 de Novembro de 2023","format":false,"excerpt":"[ad_1] Um acidente grave envolvendo 11 ve\u00edculos resultou em pelo menos tr\u00eas \u00f3bitos no final da manh\u00e3 desta segunda-feira (27) no quil\u00f4metro 517 da Rodovia Fern\u00e3o Dias, BR-381, pr\u00f3ximo a Igarap\u00e9, na regi\u00e3o metropolitana de Belo Horizonte.Segundo informa\u00e7\u00f5es da Arteris, a concession\u00e1ria respons\u00e1vel pelo trecho, a colis\u00e3o inclui oito autom\u00f3veis\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d2d1357673855.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d2d1357673855.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d2d1357673855.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d2d1357673855.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d2d1357673855.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":27498,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/12\/sc-acidente-envolvendo-dois-carro-e-onibus-deixa-vitima-fatal-feridos-e-cenario-de-destruicao\/","url_meta":{"origin":7132,"position":5},"title":"SC: Acidente envolvendo dois carro e \u00f4nibus deixa v\u00edtima fatal, feridos e cen\u00e1rio de destrui\u00e7\u00e3o","author":"ismaelcolosi.com.br","date":"12 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Na manh\u00e3 desta sexta-feira (12), um grave acidente envolvendo um \u00f4nibus e uma caminhonete, teve como cen\u00e1rio a rodovia BR-116.A colis\u00e3o violenta entre o ve\u00edculo e o \u00f4nibus que levava funcion\u00e1rios de uma empresa denominada Klabin, ocorreu por volta das 07h24, no km 227 da BR-116, no trecho que\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a1663626d9c2126.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a1663626d9c2126.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a1663626d9c2126.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a1663626d9c2126.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a1663626d9c2126.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-1R2","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7132"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/7133"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}