{"id":7130,"date":"2023-11-27T16:05:34","date_gmt":"2023-11-27T19:05:34","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/27\/concurso-publico-da-camara-de-cafelandia-oferece-oportunidade-para-nivel-fundamental-completo\/"},"modified":"2023-11-27T16:05:34","modified_gmt":"2023-11-27T19:05:34","slug":"concurso-publico-da-camara-de-cafelandia-oferece-oportunidade-para-nivel-fundamental-completo","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/27\/concurso-publico-da-camara-de-cafelandia-oferece-oportunidade-para-nivel-fundamental-completo\/","title":{"rendered":"Concurso P\u00fablico da C\u00e2mara de Cafel\u00e2ndia oferece oportunidade para n\u00edvel fundamental completo"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"attachment_2314352\">\n<div class=\"d-flex justify-content-center\" data-attachment-id=\"2314352\">\n<div class=\"position-relative d-inline-block\"><img data-recalc-dims=\"1\" data-portal-copyright=\"IStock\" decoding=\"async\" fetchpriority=\"high\" class=\"size-medium wp-image-2314352\" src=\"https:\/\/i0.wp.com\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-184929692-450x300.jpg?resize=450%2C300&#038;ssl=1\" alt=\"Concurso P\u00fablico da C\u00e2mara de Cafel\u00e2ndia\" width=\"450\" height=\"300\" srcset=\"https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-184929692-450x300.jpg 450w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-184929692-910x607.jpg 910w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-184929692-768x512.jpg 768w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-184929692.jpg 1254w\" sizes=\"(max-width: 450px) 100vw, 450px\"\/><\/p>\n<p>Cr\u00e9ditos: IStock<\/p>\n<\/div>\n<\/div>\n<p><span class=\"post-imagem__legenda\">Concurso P\u00fablico da C\u00e2mara de Cafel\u00e2ndia<\/span><\/p>\n<\/div>\n<p>A C\u00e2mara Municipal de Vereadores de Cafel\u00e2ndia, no estado de\u00a0S\u00e3o Paulo, anuncia edital de n\u00ba 001\/2023 para <a href=\"https:\/\/catracalivre.com.br\/educacao\/prefeitura-de-brejo-santo-abre-concurso-publico-com-salario-de-ate-r-63-mil\/\" target=\"_blank\" rel=\"noopener\">concurso<\/a> p\u00fablico, que visa o preenchimento de uma vaga imediata. O concurso oferta oportunidade para profissional com n\u00edvel fundamental completo.<\/p>\n<p>O <a href=\"https:\/\/catracalivre.com.br\/educacao\/concurso-publico-do-hcpa-oferece-cargos-de-niveis-fundamental-e-medio\/\" target=\"_blank\" rel=\"noopener\">concurso<\/a> p\u00fablico abre vaga para o cargo de\u00a0Agente de Servi\u00e7os Gerais. Aquele que for contratado ter\u00e1 direito a remunera\u00e7\u00e3o no valor de\u00a0R$ 2.634,05\u00a0para trabalhar em jornadas de 30 horas por semana.<\/p>\n<p>Realizar pequenos reparos e outros servi\u00e7os de limpeza e conserva\u00e7\u00e3o necess\u00e1rios.<\/p>\n<p>As inscri\u00e7\u00f5es devem ser realizadas atrav\u00e9s do <a href=\"https:\/\/portal.glconsultoria.com.br\/edital\/ver\/165\" target=\"_blank\" rel=\"noopener\">site<\/a> oficial das 13h de 27 de novembro at\u00e9 as 13h de 22 de dezembro de 2023. A taxa de inscri\u00e7\u00e3o tem o valor de\u00a0R$ 30,00.<\/p>\n<p>D\u00favidas e outras informa\u00e7\u00f5es devem ser direcionadas para a o endere\u00e7o de e-mail\u00a0contato@glconsultoria.com.br.<\/p>\n<p><script>\n\t\t! function(f, b, e, v, n, t, s) {\n\t\t\tif (f.fbq) return;\n\t\t\tn = f.fbq = function() {\n\t\t\t\tn.callMethod ?\n\t\t\t\t\tn.callMethod.apply(n, arguments) : n.queue.push(arguments)\n\t\t\t};\n\t\t\tif (!f._fbq) f._fbq = n;\n\t\t\tn.push = n;\n\t\t\tn.loaded = !0;\n\t\t\tn.version = '2.0';\n\t\t\tn.queue = [];\n\t\t\tt = b.createElement(e);\n\t\t\tt.async = !0;\n\t\t\tt.src = v;\n\t\t\ts = b.getElementsByTagName(e)[0];\n\t\t\ts.parentNode.insertBefore(t, s)\n\t\t}(window, document, 'script',\n\t\t\t'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n\t\tfbq('init', '338315473262380');\n\t\tfbq('track', 'PageView');\n\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/catracalivre.com.br\/educacao\/concurso-publico-da-camara-de-cafelandia-oferece-oportunidade-para-nivel-fundamental-completo\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Cr\u00e9ditos: IStock Concurso P\u00fablico da C\u00e2mara de Cafel\u00e2ndia A C\u00e2mara Municipal de Vereadores de Cafel\u00e2ndia, no estado de\u00a0S\u00e3o Paulo, anuncia edital de n\u00ba 001\/2023 para concurso p\u00fablico, que visa o preenchimento de uma vaga imediata. O concurso oferta oportunidade para profissional com n\u00edvel fundamental completo. O concurso p\u00fablico abre vaga para o cargo de\u00a0Agente &#8230; <a title=\"Concurso P\u00fablico da C\u00e2mara de Cafel\u00e2ndia oferece oportunidade para n\u00edvel fundamental completo\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/27\/concurso-publico-da-camara-de-cafelandia-oferece-oportunidade-para-nivel-fundamental-completo\/\" aria-label=\"Leia mais sobre Concurso P\u00fablico da C\u00e2mara de Cafel\u00e2ndia oferece oportunidade para n\u00edvel fundamental completo\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":7131,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-7130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-184929692.jpg?fit=1200%2C638&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-184929692.jpg?fit=1200%2C638&ssl=1",1200,638,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-184929692.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-184929692.jpg?fit=300%2C160&ssl=1",300,160,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-184929692.jpg?fit=768%2C408&ssl=1",768,408,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-184929692.jpg?fit=1024%2C544&ssl=1",1024,544,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-184929692.jpg?fit=1200%2C638&ssl=1",1200,638,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-184929692.jpg?fit=1200%2C638&ssl=1",1200,638,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Cr\u00e9ditos: IStock Concurso P\u00fablico da C\u00e2mara de Cafel\u00e2ndia A C\u00e2mara Municipal de Vereadores de Cafel\u00e2ndia, no estado de\u00a0S\u00e3o Paulo, anuncia edital de n\u00ba 001\/2023 para concurso p\u00fablico, que visa o preenchimento de uma vaga imediata. O concurso oferta oportunidade para profissional com n\u00edvel fundamental completo. O concurso p\u00fablico abre vaga para o cargo de\u00a0Agente&hellip;","jetpack-related-posts":[{"id":75111,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/04\/camara-vai-licitar-r-17-milhao-para-publicidade\/","url_meta":{"origin":7130,"position":0},"title":"C\u00e2mara vai licitar R$ 1,7 milh\u00e3o para publicidade","author":"ismaelcolosi.com.br","date":"4 de Novembro de 2024","format":false,"excerpt":"[ad_1] 4 de novembro de 20244 de novembro de 202411 Compartilhar0 A C\u00e2mara de Vereadores de Ribeir\u00e3o Preto vai abrir licita\u00e7\u00e3o para a contrata\u00e7\u00e3o de uma ag\u00eancia de publicidade. O valor do contrato ser\u00e1 de R$ 1,7 milh\u00e3o por um per\u00edodo de 12 meses e o edital dever\u00e1 ser publicado\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/2-FACHADA-Camara-Municipal-4-1-scaled-1.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/2-FACHADA-Camara-Municipal-4-1-scaled-1.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/2-FACHADA-Camara-Municipal-4-1-scaled-1.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/2-FACHADA-Camara-Municipal-4-1-scaled-1.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31712,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/23\/conselho-de-politica-criminal-recomenda-uso-de-cameras-corporais\/","url_meta":{"origin":7130,"position":1},"title":"Conselho de pol\u00edtica criminal recomenda uso de c\u00e2meras corporais","author":"ismaelcolosi.com.br","date":"23 de Janeiro de 2024","format":false,"excerpt":"[ad_1] 22 de janeiro de 2024 | 13:0022 de janeiro de 2024 | 10:29 0O Conselho Nacional de Pol\u00edtica Criminal e Penitenci\u00e1ria da Secretaria Nacional de Pol\u00edticas Penais recomendou o uso de c\u00e2meras corporais nas atividades dos agentes de seguran\u00e7a p\u00fablica e de seguran\u00e7a e vigil\u00e2ncia privada. A recomenda\u00e7\u00e3o est\u00e1\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/cameras-scaled.jpg?fit=1000%2C562&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/cameras-scaled.jpg?fit=1000%2C562&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/cameras-scaled.jpg?fit=1000%2C562&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/cameras-scaled.jpg?fit=1000%2C562&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":18349,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/20\/concurso-publico-da-camara-de-araguapaz-go-tem-salario-de-ate-r-35-mil\/","url_meta":{"origin":7130,"position":2},"title":"Concurso p\u00fablico da C\u00e2mara de Araguapaz (GO) tem sal\u00e1rio de at\u00e9 R$ 3,5 mil","author":"ismaelcolosi.com.br","date":"20 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Cr\u00e9ditos: IStockConcurso p\u00fablico da C\u00e2mara de AraguapazA C\u00e2mara de Araguapaz,\u00a0no estado de\u00a0Goi\u00e1s, anuncia o edital de n\u00ba 001\/2023\u00a0para concurso p\u00fablico, que visa o provimento de quatro vagas imediatas, al\u00e9m de formar cadastro reserva em outras 12 oportunidades. Os cargos s\u00e3o destinados a profissionais com grau de escolaridade m\u00e9dio e\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-495391766-1.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-495391766-1.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-495391766-1.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-495391766-1.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-495391766-1.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":12528,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/08\/concurso-publico-da-camara-de-itumirim-mg-tem-edital-publicado\/","url_meta":{"origin":7130,"position":3},"title":"Concurso p\u00fablico da C\u00e2mara de Itumirim (MG) tem edital publicado","author":"ismaelcolosi.com.br","date":"8 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Cr\u00e9ditos: IStockConcurso P\u00fablico da C\u00e2mara de ItumirimA\u00a0C\u00e2mara de Itumirim, no estado de\u00a0Minas Gerais, anuncia edital de n\u00ba 001\/2023 para concurso p\u00fablico, que visa o preenchimento de tr\u00eas vagas imediatas. As oportunidades s\u00e3o destinadas a profissionais com grau de escolaridade superior, fundamental e m\u00e9dio. A contrata\u00e7\u00e3o ser\u00e1 realizada sob o\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-535847793.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-535847793.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-535847793.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-535847793.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-535847793.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":11479,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/06\/concurso-publico-da-camara-de-cachoeirinha-oferece-salario-de-ate-r-6-mil\/","url_meta":{"origin":7130,"position":4},"title":"Concurso P\u00fablico da C\u00e2mara de Cachoeirinha oferece sal\u00e1rio de at\u00e9 R$ 6 mil","author":"ismaelcolosi.com.br","date":"6 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Cr\u00e9ditos: IStockConcurso P\u00fablico da C\u00e2mara de CachoeirinhaA C\u00e2mara de Cachoeirinha, no estado do\u00a0Rio Grande do Sul, anuncia edital de n\u00ba 01\/1023 para concurso p\u00fablico. Ao todo s\u00e3o duas oportunidades para contrata\u00e7\u00f5es imediatas, mais forma\u00e7\u00e3o de cadastro reserva (CR).O concurso p\u00fablico oferece remunera\u00e7\u00f5es que variam de R$ 3.516,77 at\u00e9\u00a0R$ 6.070,13\u00a0por\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1423281288.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1423281288.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1423281288.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1423281288.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1423281288.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15207,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/13\/concurso-publico-da-camara-de-machadinho-doeste-ro-tem-edital-e-inscricao\/","url_meta":{"origin":7130,"position":5},"title":"Concurso p\u00fablico da C\u00e2mara de Machadinho D\u2019Oeste (RO) tem edital e inscri\u00e7\u00e3o","author":"ismaelcolosi.com.br","date":"13 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Cr\u00e9ditos: IStockConcurso P\u00fablico da C\u00e2mara de Machadinho D\u2019Oeste A C\u00e2mara de Machadinho D\u2019Oeste, no estado de\u00a0Rond\u00f4nia, anuncia edital de n\u00ba 01\/2023 para concurso p\u00fablico, que oferta\u00a022 vagas\u00a0imediatas para diferentes \u00e1reas de atua\u00e7\u00e3o. O concurso p\u00fablico prev\u00ea que as jornadas podem oscilar\u00a0de 20 a 40 horas\u00a0semanais, a depender da vaga\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1218586447.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1218586447.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1218586447.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1218586447.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1218586447.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-1R0","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7130"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7130\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/7131"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}