{"id":70908,"date":"2024-10-14T06:44:04","date_gmt":"2024-10-14T09:44:04","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/14\/2-sinais-de-que-seu-chefe-esta-te-manipulando\/"},"modified":"2024-10-14T06:44:04","modified_gmt":"2024-10-14T09:44:04","slug":"2-sinais-de-que-seu-chefe-esta-te-manipulando","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/14\/2-sinais-de-que-seu-chefe-esta-te-manipulando\/","title":{"rendered":"2 Sinais de que Seu Chefe Est\u00e1 Te Manipulando"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>\u00a0<\/p>\n<div class=\"accessibility\">\n<p>Acessibilidade<\/p>\n<p>\n<button onclick=\"alterFont1()\" id=\"btn1\" class=\"btn\">L<\/button><br \/>\n<button onclick=\"alterFont2()\" id=\"btn2\" class=\"btn\" style=\"font-family: Merriweather\">L<\/button><br \/>\n<button onclick=\"alterFontSmallerSize()\" id=\"btn3\" class=\"btn\">A-<\/button><br \/>\n<button onclick=\"alterFontBiggerSize()\" id=\"btn4\" class=\"btn\">A+<\/button><\/p>\n<p><button onclick=\"alterBackground()\" id=\"btn6\" class=\"btn\">\u25d0<\/button><\/p>\n<\/div>\n<p>\u00a0<\/p>\n<p>Imagine um profissional promissor come\u00e7ando um novo emprego, sentindo que realmente pertence ao lugar. Seu novo chefe elogia o trabalho, diz que ele tem grande potencial e at\u00e9 compartilha \u201csegredos internos\u201d da empresa, ganhando sua confian\u00e7a. Mas, com o tempo, as coisas mudam.<\/p>\n<p>Em p\u00fablico, o chefe questiona suas decis\u00f5es quando algo d\u00e1 errado, enquanto oferece apoio em particular. Quando confrontado, o chefe nega tudo, dizendo: \u201cEu nunca disse isso, disse? Foi tudo voc\u00ea!\u201d A forma sutil com que o chefe narra os acontecimentos faz o funcion\u00e1rio sentir que ele \u00e9 o culpado. Exteriormente, ele parece bem, mas por dentro, se sente um impostor, perdendo a autoconfian\u00e7a e questionando sua compet\u00eancia.<\/p>\n<h2>Leia tamb\u00e9m<\/h2>\n<div id=\"attachment_634915\" class=\"wp-caption alignnone style=\" max-width:=\"\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-634915 size-medium\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/09\/saude-gaslighting-768x512.jpg?resize=678%2C452&#038;ssl=1\" alt=\"Gaslighting \" width=\"678\" height=\"452\"\/><\/p>\n<p>Getty Images<\/p>\n<p class=\"wp-caption-text\">Al\u00e9m do ambiente profissional, gaslighting pode ocorrer em diversos tipos de rela\u00e7\u00f5es \u2014 rom\u00e2nticas, sociais e at\u00e9 pol\u00edticas<\/p>\n<\/div>\n<p>Se voc\u00ea se identifica com essa situa\u00e7\u00e3o, \u00e9 prov\u00e1vel que tenha sido v\u00edtima de <strong>gaslighting<\/strong> no ambiente de trabalho. O termo se refere a um tipo de manipula\u00e7\u00e3o, especialmente em rela\u00e7\u00f5es amorosas, e acontece quando uma pessoa ou grupo de pessoas (por exemplo, um supervisor, colega ou equipe) faz outra pessoa duvidar da pr\u00f3pria realidade, compet\u00eancia ou desempenho, sutil ou abertamente. Esse comportamento pode fazer parte de uma cultura t\u00f3xica no trabalho e \u00e9 frequentemente usado para controlar algu\u00e9m.<\/p>\n<p>O gaslighting \u00e9 uma forma trai\u00e7oeira de abuso que pode afetar profundamente a sa\u00fade mental e o desempenho no trabalho. Aqui est\u00e3o dois sinais para ficar atento.<\/p>\n<h2>1. Seu chefe ignora sua vers\u00e3o dos fatos?<\/h2>\n<p>O gaslighting \u00e9 uma t\u00e1tica usada para sabotar a credibilidade das pessoas, especialmente das mulheres, fazendo com que duvidem de seus pr\u00f3prios relatos, de acordo com um estudo de 2019 publicado no The Monist, o mais antigo jornal acad\u00eamico de filosofia de Oxford.<\/p>\n<p>Esse tipo de gaslighting vai al\u00e9m de um simples desacordo e tem como objetivo acabar com a confian\u00e7a dessa pessoa em rela\u00e7\u00e3o \u00e0s suas pr\u00f3prias percep\u00e7\u00f5es e experi\u00eancias.<\/p>\n<p>Ele consiste em duas t\u00e1ticas principais:<\/p>\n<ul>\n<li><strong>Desviar<\/strong>: O manipulador evita ou ignora qualquer evid\u00eancia que apoie a vers\u00e3o da outra pessoa, fazendo com que suas alega\u00e7\u00f5es pare\u00e7am inv\u00e1lidas.<\/li>\n<li><strong>Transferir a culpa<\/strong>: O manipulador culpa a pessoa, sugerindo que o problema est\u00e1 em seu pensamento ou personalidade, insinuando que ela \u00e9 pouco confi\u00e1vel ou problem\u00e1tica.<\/li>\n<\/ul>\n<p>Um usu\u00e1rio do Reddit compartilhou uma experi\u00eancia de ter conversas e tomar decis\u00f5es com seu chefe, que depois negava ter conhecimento dessas conversas quando as decis\u00f5es se mostravam erradas. Outro usu\u00e1rio falou sobre a preocupa\u00e7\u00e3o de ser criticado por n\u00e3o fazer algo r\u00e1pido ou bem o suficiente, mas depois ser acusado de estar apressado ou impaciente quando tentava corrigir algo.<\/p>\n<p>Essa constante mudan\u00e7a de expectativas e cr\u00edticas cria uma situa\u00e7\u00e3o em que o funcion\u00e1rio nunca consegue fazer algo certo, ficando em um estado constante de culpa e d\u00favida. Manter uma documenta\u00e7\u00e3o escrita de conversas e reuni\u00f5es importantes \u00e9 essencial para se proteger desse tipo de manipula\u00e7\u00e3o.<\/p>\n<p>Outra t\u00e9cnica simples para desviar do gaslighting \u00e9 evitar intera\u00e7\u00f5es individuais com seu chefe sempre que poss\u00edvel. Tenha sempre um colega de confian\u00e7a com voc\u00ea para testemunhar esses encontros. Isso garantir\u00e1 que sua vers\u00e3o dos fatos nunca seja distorcida por uma situa\u00e7\u00e3o de uma palavra contra a outra. Se a arma do manipulador \u00e9 o isolamento, manter-se unido \u00e0 sua equipe contra esse comportamento deve ser sua primeira linha de defesa.<\/p>\n<h2>2. Seu chefe abala sua confian\u00e7a?<\/h2>\n<p>O gaslighting no ambiente de trabalho envolve comportamentos prejudiciais por parte de l\u00edderes (ou at\u00e9 de colegas), como a banaliza\u00e7\u00e3o, a desvaloriza\u00e7\u00e3o das preocupa\u00e7\u00f5es dos funcion\u00e1rios e a cria\u00e7\u00e3o de um ambiente de afli\u00e7\u00e3o emocional, de acordo com um estudo de 2023 publicado na revista acad\u00eamica Frontiers in Psychology.<\/p>\n<p>O gaslighting abala a confian\u00e7a dos funcion\u00e1rios, leva ao esgotamento emocional e est\u00e1 associado \u00e0 redu\u00e7\u00e3o da satisfa\u00e7\u00e3o no trabalho.<\/p>\n<p>Uma usu\u00e1ria do Reddit explicou que chegou a culpar seu p\u00f3s-parto por sua aparente falta de desempenho em um cargo que ocupava com sucesso h\u00e1 mais de dois anos. Descobriu que estava sendo responsabilizada injustamente por tarefas que n\u00e3o eram de sua responsabilidade. O gaslighting fez com que sua posi\u00e7\u00e3o atual parecesse o ponto mais baixo de uma carreira at\u00e9 ent\u00e3o brilhante.<\/p>\n<p>Esse \u00e9 um exemplo cl\u00e1ssico de como o gaslighting pode levar as pessoas a duvidar de suas habilidades, mesmo quando elas t\u00eam um hist\u00f3rico de bom desempenho. Voc\u00ea pode come\u00e7ar a sentir como se seus sucessos fossem apenas sorte, e cada dia se torna uma batalha mental para provar seu valor.<\/p>\n<p>Quando voc\u00ea \u00e9 exposto a uma lideran\u00e7a manipuladora por tempo suficiente, pode lentamente esquecer como \u00e9 e como deveria ser um l\u00edder competente. Por isso, \u00e9 importante manter contato com mentores e colegas de empregos anteriores, tanto no \u00e2mbito profissional quanto pessoal.<\/p>\n<p>At\u00e9 mesmo uma conversa simples com eles pode lembrar voc\u00ea n\u00e3o s\u00f3 do papel que um chefe deve desempenhar no ambiente de trabalho, mas tamb\u00e9m das conquistas e habilidades que voc\u00ea desenvolveu ao longo de sua carreira.<\/p>\n<p>A gest\u00e3o ou lideran\u00e7a manipuladora no trabalho constantemente muda expectativas, altera regras ou insinua sutilmente que voc\u00ea n\u00e3o est\u00e1 fazendo o suficiente. O efeito a longo prazo dessa manipula\u00e7\u00e3o pode ser devastador para a sa\u00fade mental e a carreira. Buscar valida\u00e7\u00e3o e apoio externo de colegas, mentores de confian\u00e7a e profissionais pode ajudar a quebrar esse ciclo.<\/p>\n<ul>\n<li>\n<h4>Siga a <a href=\"https:\/\/whatsapp.com\/channel\/0029Va9gQKwBFLgM96cJnu0u&gt;\" target=\"_blank\" rel=\"noopener\">Forbes<\/a> no WhatsApp e receba as principais not\u00edcias sobre neg\u00f3cios, carreira, tecnologia e estilo de vida<\/h4>\n<\/li>\n<\/ul>\n<p><em>*Mark Travers \u00e9 colaborador da Forbes USA. Ele \u00e9 um psic\u00f3logo americano formado pela Cornell University e pela University of Colorado em Boulder.\u00a0<\/em><\/p>\n<h2>Escolhas do editor<\/h2>\n<\/div>\n<p><script type=\"rocketlazyloadscript\">\n\t\t\t\t(function(d, s, id){\n\t\t\t\t\tvar js, fjs = d.getElementsByTagName(s)[0];\n\t\t\t\t\tif (d.getElementById(id)) return;\n\t\t\t\t\tjs = d.createElement(s); js.id = id;\n\t\t\t\t\tjs.src = \"\/\/connect.facebook.net\/pt_BR\/sdk.js#xfbml=1&version=v2.9\";\n\t\t\t\t\tfjs.parentNode.insertBefore(js, fjs);\n\t\t\t\t}(document, 'script', 'facebook-jssdk'));\n\t\t\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/forbes.com.br\/carreira\/2024\/10\/2-sinais-de-que-seu-chefe-esta-fazendo-gaslighting-com-voce\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] \u00a0 Acessibilidade L L A- A+ \u25d0 \u00a0 Imagine um profissional promissor come\u00e7ando um novo emprego, sentindo que realmente pertence ao lugar. Seu novo chefe elogia o trabalho, diz que ele tem grande potencial e at\u00e9 compartilha \u201csegredos internos\u201d da empresa, ganhando sua confian\u00e7a. Mas, com o tempo, as coisas mudam. Em p\u00fablico, o &#8230; <a title=\"2 Sinais de que Seu Chefe Est\u00e1 Te Manipulando\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/14\/2-sinais-de-que-seu-chefe-esta-te-manipulando\/\" aria-label=\"Leia mais sobre 2 Sinais de que Seu Chefe Est\u00e1 Te Manipulando\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":70909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1964],"tags":[],"class_list":["post-70908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-e-sucesso-dicas-para-carreira"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/saude-gaslighting-1024x683.jpg?fit=1024%2C683&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/saude-gaslighting-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/saude-gaslighting-1024x683.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/saude-gaslighting-1024x683.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/saude-gaslighting-1024x683.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/saude-gaslighting-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/saude-gaslighting-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/saude-gaslighting-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] \u00a0 Acessibilidade L L A- A+ \u25d0 \u00a0 Imagine um profissional promissor come\u00e7ando um novo emprego, sentindo que realmente pertence ao lugar. Seu novo chefe elogia o trabalho, diz que ele tem grande potencial e at\u00e9 compartilha \u201csegredos internos\u201d da empresa, ganhando sua confian\u00e7a. Mas, com o tempo, as coisas mudam. Em p\u00fablico, o&hellip;","jetpack-related-posts":[{"id":85103,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/05\/03\/como-saber-se-voce-sofre-gaslighting\/","url_meta":{"origin":70908,"position":0},"title":"Como Saber se Voc\u00ea Sofre Gaslighting","author":"ismaelcolosi.com.br","date":"3 de Maio de 2025","format":false,"excerpt":"[ad_1] \r Getty Images\r Al\u00e9m do ambiente profissional, gaslighting pode ocorrer em diversos tipos de rela\u00e7\u00f5es \u2014 rom\u00e2nticas, sociais e at\u00e9 pol\u00edticas\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 \u201cGaslighting\u201d \u00e9 mais do que uma palavra da moda. Especialistas em sa\u00fade mental afirmam que se trata de\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/forbes-Gaslighting-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/forbes-Gaslighting-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/forbes-Gaslighting-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/forbes-Gaslighting-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/forbes-Gaslighting-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":85107,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/05\/03\/como-saber-se-voce-sofre-gaslighting-2\/","url_meta":{"origin":70908,"position":1},"title":"Como Saber se Voc\u00ea Sofre Gaslighting","author":"ismaelcolosi.com.br","date":"3 de Maio de 2025","format":false,"excerpt":"[ad_1] \r Getty Images\r Al\u00e9m do ambiente profissional, gaslighting pode ocorrer em diversos tipos de rela\u00e7\u00f5es \u2014 rom\u00e2nticas, sociais e at\u00e9 pol\u00edticas\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 \u201cGaslighting\u201d \u00e9 mais do que uma palavra da moda. Especialistas em sa\u00fade mental afirmam que se trata de\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/1746289299_forbes-Gaslighting-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/1746289299_forbes-Gaslighting-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/1746289299_forbes-Gaslighting-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/1746289299_forbes-Gaslighting-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/1746289299_forbes-Gaslighting-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":86484,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/07\/03\/como-comunicar-ao-seu-chefe-que-voce-tem-tdah\/","url_meta":{"origin":70908,"position":2},"title":"Como Comunicar Ao Seu Chefe Que Voc\u00ea Tem TDAH","author":"ismaelcolosi.com.br","date":"3 de Julho de 2025","format":false,"excerpt":"[ad_1] \r Getty Images\r O TDAH \u00e9 uma condi\u00e7\u00e3o comportamental que dificulta manter o foco em tarefas e rotinas do dia a dia\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 O TDAH (Transtorno de D\u00e9ficit de Aten\u00e7\u00e3o e Hiperatividade) atinge de 5% a 8% da popula\u00e7\u00e3o mundial,\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/forbes-como-contar-ao-chefe-que-voce-tem-TDAH-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/forbes-como-contar-ao-chefe-que-voce-tem-TDAH-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/forbes-como-contar-ao-chefe-que-voce-tem-TDAH-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/forbes-como-contar-ao-chefe-que-voce-tem-TDAH-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/forbes-como-contar-ao-chefe-que-voce-tem-TDAH-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":52226,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/05\/por-que-profissionais-da-geracao-z-nao-querem-ser-chefes\/","url_meta":{"origin":70908,"position":3},"title":"Por que profissionais da gera\u00e7\u00e3o Z n\u00e3o querem ser chefes?","author":"ismaelcolosi.com.br","date":"5 de Junho de 2024","format":false,"excerpt":"[ad_1] \u00a0 Acessibilidade L L A- A+ \u25d0 Ser promovido e crescer na empresa pode ser uma das principais m\u00e9tricas de sucesso profissional \u2013 mas n\u00e3o para a gera\u00e7\u00e3o Z. Pesquisas recentes mostram que os mais jovens n\u00e3o t\u00eam ambi\u00e7\u00e3o de chegar ao topo, seja por falta de preparo, de\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/carreira-gera____o-z-trabalho-remoto-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/carreira-gera____o-z-trabalho-remoto-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/carreira-gera____o-z-trabalho-remoto-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/carreira-gera____o-z-trabalho-remoto-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":70488,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/11\/chefes-demitem-profissionais-da-gen-z-meses-apos-contratacao\/","url_meta":{"origin":70908,"position":4},"title":"Chefes Demitem Profissionais da Gen Z Meses ap\u00f3s Contrata\u00e7\u00e3o","author":"ismaelcolosi.com.br","date":"11 de Outubro de 2024","format":false,"excerpt":"[ad_1] \u00a0 Acessibilidade L L A- A+ \u25d0 \u00a0 Com a chegada da gera\u00e7\u00e3o Z ao mercado de trabalho, muitas empresas e l\u00edderes t\u00eam enfrentado dificuldades em receber os novos talentos. \u00c9 a gera\u00e7\u00e3o mais dif\u00edcil de liderar, segundo uma pesquisa da Resume Genius, plataforma de cria\u00e7\u00e3o de curr\u00edculos. E\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/carreira-geracao-Z-tecnologia-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/carreira-geracao-Z-tecnologia-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/carreira-geracao-Z-tecnologia-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/carreira-geracao-Z-tecnologia-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":60246,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/15\/um-chefe-ruim-e-suficiente-para-se-demitir-linkedin-indica-que-sim\/","url_meta":{"origin":70908,"position":5},"title":"Um chefe ruim \u00e9 suficiente para se demitir? LinkedIn indica que sim","author":"ismaelcolosi.com.br","date":"15 de Agosto de 2024","format":false,"excerpt":"[ad_1] \u00a0 Acessibilidade L L A- A+ \u25d0 \u00a0 A lideran\u00e7a direta pode ser o principal motivador para se manter em um emprego ou buscar novas oportunidades. Uma pesquisa recente do LinkedIn mostra que quase sete em cada dez profissionais nos Estados Unidos pediriam demiss\u00e3o para fugir de um chefe\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/carreira-chefe-trabalho-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/carreira-chefe-trabalho-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/carreira-chefe-trabalho-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/carreira-chefe-trabalho-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-irG","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=70908"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70908\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/70909"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=70908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=70908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=70908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}