{"id":70739,"date":"2024-10-12T11:38:14","date_gmt":"2024-10-12T14:38:14","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/12\/morre-em-sao-paulo-o-humorista-ary-toledo-aos-87-anos\/"},"modified":"2024-10-12T11:38:14","modified_gmt":"2024-10-12T14:38:14","slug":"morre-em-sao-paulo-o-humorista-ary-toledo-aos-87-anos","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/12\/morre-em-sao-paulo-o-humorista-ary-toledo-aos-87-anos\/","title":{"rendered":"Morre em S\u00e3o Paulo o humorista Ary Toledo, aos 87 anos"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>Morreu neste s\u00e1bado (12), aos 87 anos, o humorista <strong>Ary Toledo<\/strong>. Ele estava internado no <strong>Hospital S\u00edrio-Liban\u00eas<\/strong>, em S\u00e3o Paulo. Ele nasceu em Martin\u00f3polis, no interior paulista.<\/p>\n<p>A informa\u00e7\u00e3o foi confirmada pela fam\u00edlia de Ary Toledo no perfil oficial do humorista. Contudo, as casas da morte n\u00e3o foram divulgadas.<\/p>\n<p>\u201cCom profundo pesar, anunciamos o falecimento de Ary Christoni de Toledo, um humorista brilhante que iluminou nossas vidas com seu talento e risadas. Que sua mem\u00f3ria continue a trazer sorrisos a todos n\u00f3s\u2026 Sentiremos a sua falta Mestre\u201d, informa o comunicado.<\/p>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">O vel\u00f3rio de Ary Toledo ser\u00e1 na avenida Goi\u00e1s, 459, em S\u00e3o Caetano do Sul<\/mark>, na regi\u00e3o do ABC Paulista. A cerim\u00f4nia come\u00e7a \u00e0s 14h, deste s\u00e1bado. J\u00e1 a crema\u00e7\u00e3o ser\u00e1 acontece \u00e0s 19h.<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/morre-em-sao-paulo-o-humorista-ary-toledo-aos-87-anos\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Morreu neste s\u00e1bado (12), aos 87 anos, o humorista Ary Toledo. Ele estava internado no Hospital S\u00edrio-Liban\u00eas, em S\u00e3o Paulo. Ele nasceu em Martin\u00f3polis, no interior paulista. A informa\u00e7\u00e3o foi confirmada pela fam\u00edlia de Ary Toledo no perfil oficial do humorista. Contudo, as casas da morte n\u00e3o foram divulgadas. \u201cCom profundo pesar, anunciamos o &#8230; <a title=\"Morre em S\u00e3o Paulo o humorista Ary Toledo, aos 87 anos\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/12\/morre-em-sao-paulo-o-humorista-ary-toledo-aos-87-anos\/\" aria-label=\"Leia mais sobre Morre em S\u00e3o Paulo o humorista Ary Toledo, aos 87 anos\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":70740,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-70739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ary-toledo_2024-10-12_14-21-56_jpg_2024-10-12_14-21-56.webp.webp?fit=834%2C659&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ary-toledo_2024-10-12_14-21-56_jpg_2024-10-12_14-21-56.webp.webp?fit=834%2C659&ssl=1",834,659,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ary-toledo_2024-10-12_14-21-56_jpg_2024-10-12_14-21-56.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ary-toledo_2024-10-12_14-21-56_jpg_2024-10-12_14-21-56.webp.webp?fit=300%2C237&ssl=1",300,237,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ary-toledo_2024-10-12_14-21-56_jpg_2024-10-12_14-21-56.webp.webp?fit=768%2C607&ssl=1",768,607,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ary-toledo_2024-10-12_14-21-56_jpg_2024-10-12_14-21-56.webp.webp?fit=834%2C659&ssl=1",834,659,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ary-toledo_2024-10-12_14-21-56_jpg_2024-10-12_14-21-56.webp.webp?fit=834%2C659&ssl=1",834,659,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ary-toledo_2024-10-12_14-21-56_jpg_2024-10-12_14-21-56.webp.webp?fit=834%2C659&ssl=1",834,659,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Morreu neste s\u00e1bado (12), aos 87 anos, o humorista Ary Toledo. Ele estava internado no Hospital S\u00edrio-Liban\u00eas, em S\u00e3o Paulo. Ele nasceu em Martin\u00f3polis, no interior paulista. A informa\u00e7\u00e3o foi confirmada pela fam\u00edlia de Ary Toledo no perfil oficial do humorista. Contudo, as casas da morte n\u00e3o foram divulgadas. \u201cCom profundo pesar, anunciamos o&hellip;","jetpack-related-posts":[{"id":70814,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/13\/vai-chover-nos-proximos-dias-veja-previsao-para-ribeirao-preto\/","url_meta":{"origin":70739,"position":0},"title":"Vai chover nos pr\u00f3ximos dias? Veja previs\u00e3o para Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"13 de Outubro de 2024","format":false,"excerpt":"[ad_1] As temperaturas voltam a subir neste domingo (13), ap\u00f3s a passagem de uma frente fria que provocou chuva e leve queda nos term\u00f4metros em todo o Estado de S\u00e3o Paulo. Em Ribeir\u00e3o Preto, por exemplo, a temperatura m\u00e1xima pode chegar aos 33\u00baC. O dia ser\u00e1 de sol com muitas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/praca_xv_1200x675_20092021155111.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/praca_xv_1200x675_20092021155111.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/praca_xv_1200x675_20092021155111.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/praca_xv_1200x675_20092021155111.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/praca_xv_1200x675_20092021155111.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":29058,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/17\/nasce-1o-filho-do-cantor-joao-gomes-com-ary-mirelle-fotos-sao-divulgadas-e-fas-se-encantam-ele-e-lindo\/","url_meta":{"origin":70739,"position":1},"title":"Nasce 1\u00ba filho do cantor Jo\u00e3o Gomes com Ary Mirelle, fotos s\u00e3o divulgadas e f\u00e3s se encantam: &#8216;Ele \u00e9 lindo&#8217;","author":"ismaelcolosi.com.br","date":"17 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Na noite da \u00faltima ter\u00e7a-feira (16\/01), veio ao mundo o primeiro filho do cantor de forr\u00f3 Jo\u00e3o Gomes cm a namorada, Ary Mirelle. O casal n\u00e3o hesitou em vir \u00e0s redes sociais compartilhar a chegada do mais novo membro da fam\u00edlia.Em seu perfil oficial do Instagram, onde conta com\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a7e113e18297990.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a7e113e18297990.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a7e113e18297990.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a7e113e18297990.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a7e113e18297990.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":29791,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/19\/joao-gomes-se-despede-do-filho-recem-nascido-e-deixa-fas-comovidos-meu-coracao\/","url_meta":{"origin":70739,"position":2},"title":"Jo\u00e3o Gomes se despede do filho rec\u00e9m-nascido e deixa f\u00e3s comovidos: &#8216;Meu cora\u00e7\u00e3o&#8217;","author":"ismaelcolosi.com.br","date":"19 de Janeiro de 2024","format":false,"excerpt":"[ad_1] O cantor Jo\u00e3o Gomes deixou seus f\u00e3s comovidos nesta semana ao se despedir do pequeno Jorge, seu filho com a influenciadora digital Ary Mirelle.\u00c9 que o famoso teve que se ausentar do lado da fam\u00edlia porque tinha compromissos profissionais marcados, o que o deixou de cora\u00e7\u00e3o partido.Em sua conta\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65aa8c808dee38149.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65aa8c808dee38149.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65aa8c808dee38149.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65aa8c808dee38149.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65aa8c808dee38149.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14606,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/12\/a-voz-de-alaide-costa-em-rp\/","url_meta":{"origin":70739,"position":3},"title":"A voz de Ala\u00edde Costa em RP","author":"ismaelcolosi.com.br","date":"12 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Conhecida como a \u201cDiva da Can\u00e7\u00e3o\u201d, a cantora Ala\u00edde Costa e o cantor e compositor Eduardo Santhana estar\u00e3o no Teatro Municipal de Ribeir\u00e3o Preto, nesta quarta-feira, 13 de dezembro, \u00e0s 20 horas, com o show \u201cCan\u00e7\u00f5es de Amores Paulistas\u201d, com entrada gratuita. \u00a0\u00a0O show tem patroc\u00ednio da Secretaria de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/alaide-scaled.jpg?fit=968%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/alaide-scaled.jpg?fit=968%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/alaide-scaled.jpg?fit=968%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/alaide-scaled.jpg?fit=968%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":76199,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/11\/dezoito-agencias-do-interior-paulista-conquistam-trofeus-no-24o-premio-recall-de-criacao-publicitaria\/","url_meta":{"origin":70739,"position":4},"title":"Dezoito ag\u00eancias do interior paulista conquistam trof\u00e9us no 24\u00ba Pr\u00eamio Recall de Cria\u00e7\u00e3o Publicit\u00e1ria","author":"ismaelcolosi.com.br","date":"11 de Novembro de 2024","format":false,"excerpt":"[ad_1] Divulga\u00e7\u00e3o dos vencedores ocorreu na \u00faltima sexta-feira, em cerim\u00f4nia realizada em S\u00e3o Paulo; tr\u00eas ag\u00eancias de Ribeir\u00e3o est\u00e3o entre as premiadas As ag\u00eancias vencedoras do 24\u00ba Pr\u00eamio Recall de Cria\u00e7\u00e3o Publicit\u00e1ria foram conhecidas na \u00faltima sexta-feira (8\/11), em cerim\u00f4nia realizada na Mans\u00e3o Arya, no bairro da Lapa, em S\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Premio_Recall_2024_trofeus_Foto-Lucas-Frois-scaled.jpg?fit=749%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Premio_Recall_2024_trofeus_Foto-Lucas-Frois-scaled.jpg?fit=749%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Premio_Recall_2024_trofeus_Foto-Lucas-Frois-scaled.jpg?fit=749%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Premio_Recall_2024_trofeus_Foto-Lucas-Frois-scaled.jpg?fit=749%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1395,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/12\/bandolinista-e-violonista-de-sp-e-convidado-especial-do-choro-na-esquina\/","url_meta":{"origin":70739,"position":5},"title":"Bandolinista e violonista de SP \u00e9 convidado especial do Choro na esquina\u00a0","author":"ismaelcolosi.com.br","date":"12 de Novembro de 2023","format":false,"excerpt":"[ad_1] 12 de novembro de 2023 | 16:0012 de novembro de 2023 | 11:32 0No pr\u00f3ximo domingo, dia 19, v\u00e9spera de feriado, a Cia. Minaz promove mais uma edi\u00e7\u00e3o da s\u00e9rie \u201cChoro na Esquina\u201d, no Teatro Minaz.\u00a0\u00a0Nesta edi\u00e7\u00e3o, o bandolinista e violonista Lu\u00eds Passos, de S\u00e3o Paulo, ser\u00e1 o convidado.\u00a0A\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/choro-scaled.jpeg?fit=968%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/choro-scaled.jpeg?fit=968%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/choro-scaled.jpeg?fit=968%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/choro-scaled.jpeg?fit=968%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-ioX","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=70739"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70739\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/70740"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=70739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=70739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=70739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}