{"id":70606,"date":"2024-10-11T15:15:33","date_gmt":"2024-10-11T18:15:33","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/11\/fumaca-toxica-se-espalha-apos-explosao-e-evacua-bairro-em-sertaozinho\/"},"modified":"2024-10-11T15:15:33","modified_gmt":"2024-10-11T18:15:33","slug":"fumaca-toxica-se-espalha-apos-explosao-e-evacua-bairro-em-sertaozinho","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/11\/fumaca-toxica-se-espalha-apos-explosao-e-evacua-bairro-em-sertaozinho\/","title":{"rendered":"Fuma\u00e7a t\u00f3xica se espalha ap\u00f3s explos\u00e3o e evacua bairro em Sert\u00e3ozinho"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<p>Um caminh\u00e3o carregado com produtos qu\u00edmicos explodiu, no in\u00edcio da tarde desta sexta-feira (11), em<strong>\u00a0Sert\u00e3ozinho<\/strong>, na regi\u00e3o de\u00a0<strong>Ribeir\u00e3o Preto<\/strong>. O fogo se alastrou e atingiu uma ind\u00fastria qu\u00edmica. A fuma\u00e7a considerada altamente t\u00f3xica se espalhou e o bairro precisou ser evacuado. <\/p>\n<p>A <strong>Prefeitura de Sert\u00e3ozinho informou<\/strong>, em nota, <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">que a Defesa Civil j\u00e1 est\u00e1 no local e a \u00e1rea foi isolada para garantir a seguran\u00e7a da popula\u00e7\u00e3o.<\/mark>  <\/p>\n<p>A <strong><a href=\"https:\/\/cetesb.sp.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Companhia Ambiental do Estado de S\u00e3o Paulo (Cetesb)<\/a><\/strong> j\u00e1 foi acionada, <strong>visto que o \u00f3rg\u00e3o \u00e9 respons\u00e1vel por disponibilizar o agente neutralizador do produto qu\u00edmico envolvido na explos\u00e3o. <\/strong><\/p>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">As v\u00edtimas est\u00e3o sendo atendidas pelas equipes de emerg\u00eancia, mas n\u00e3o se sabe o n\u00famero e nem o estado de sa\u00fade delas. <\/mark><\/p>\n<p><strong>Parte do produto qu\u00edmico \u00e9 reagente a \u00e1gua<\/strong>, <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">o que dificulta o trabalho do Corpo de Bombeiros. <\/mark><\/p>\n<h4 class=\"wp-block-heading\"><strong>Veja v\u00eddeo: <\/strong><\/h4>\n<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/DA_e_xup9cV\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\"background:#FFF;border:0;border-radius:3px;margin: 1px;max-width:540px;min-width:326px;padding:0;width:99.375%;width:-webkit-calc(100% - 2px);width:calc(100% - 2px)\">\n<div style=\"padding:16px\"> <a href=\"https:\/\/www.instagram.com\/reel\/DA_e_xup9cV\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\"background:#FFFFFF;line-height:0;padding:0 0;text-align:center;text-decoration:none;width:100%\" target=\"_blank\" rel=\"noopener\"> <\/p>\n<div style=\"flex-direction: row;align-items: center\">\n<div style=\"background-color: #F4F4F4;border-radius: 50%;flex-grow: 0;height: 40px;margin-right: 14px;width: 40px\"><\/div>\n<div style=\"flex-direction: column;flex-grow: 1;justify-content: center\">\n<div style=\"background-color: #F4F4F4;border-radius: 4px;flex-grow: 0;height: 14px;margin-bottom: 6px;width: 100px\"><\/div>\n<div style=\"background-color: #F4F4F4;border-radius: 4px;flex-grow: 0;height: 14px;width: 60px\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0\"><\/div>\n<div style=\"height:50px;margin:0 auto 12px;width:50px\"><\/div>\n<div style=\"padding-top: 8px\">\n<div style=\"color:#3897f0;font-family:Arial,sans-serif;font-size:14px;font-style:normal;font-weight:550;line-height:18px\">Ver essa foto no Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0\"><\/div>\n<div style=\"flex-direction: row;margin-bottom: 14px;align-items: center\">\n<div>\n<div style=\"background-color: #F4F4F4;border-radius: 50%;height: 12.5px;width: 12.5px\"><\/div>\n<div style=\"background-color: #F4F4F4;height: 12.5px;width: 12.5px;flex-grow: 0;margin-right: 14px;margin-left: 2px\"><\/div>\n<div style=\"background-color: #F4F4F4;border-radius: 50%;height: 12.5px;width: 12.5px\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px\">\n<div style=\"background-color: #F4F4F4;border-radius: 50%;flex-grow: 0;height: 20px;width: 20px\"><\/div>\n<div style=\"width: 0;height: 0;border-top: 2px solid transparent;border-left: 6px solid #f4f4f4;border-bottom: 2px solid transparent\"><\/div>\n<\/div>\n<div style=\"margin-left: auto\">\n<div style=\"width: 0px;border-top: 8px solid #F4F4F4;border-right: 8px solid transparent\"><\/div>\n<div style=\"background-color: #F4F4F4;flex-grow: 0;height: 12px;width: 16px\"><\/div>\n<div style=\"width: 0;height: 0;border-top: 8px solid #F4F4F4;border-left: 8px solid transparent\"><\/div>\n<\/div>\n<\/div>\n<div style=\"flex-direction: column;flex-grow: 1;justify-content: center;margin-bottom: 24px\">\n<div style=\"background-color: #F4F4F4;border-radius: 4px;flex-grow: 0;height: 14px;margin-bottom: 6px;width: 224px\"><\/div>\n<div style=\"background-color: #F4F4F4;border-radius: 4px;flex-grow: 0;height: 14px;width: 144px\"><\/div>\n<\/div>\n<p><\/a><\/p>\n<p style=\"color:#c9c8cd;font-family:Arial,sans-serif;font-size:14px;line-height:17px;margin-bottom:0;margin-top:8px;overflow:hidden;padding:8px 0 7px;text-align:center\"><a href=\"https:\/\/www.instagram.com\/reel\/DA_e_xup9cV\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\"color:#c9c8cd;font-family:Arial,sans-serif;font-size:14px;font-style:normal;font-weight:normal;line-height:17px;text-decoration:none\" target=\"_blank\" rel=\"noopener\">Uma publica\u00e7\u00e3o compartilhada por acidade on Ribeir\u00e3o (@acidadeonribeirao)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p>SAIBA MAIS<br \/>Caminh\u00e3o com produtos qu\u00edmicos explode em Sert\u00e3ozinho; Veja v\u00eddeo<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do <strong>acidade on <\/strong>no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Instagram <\/a>e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do <strong>acidade on <\/strong>no WhatsApp. <a href=\"https:\/\/chat.whatsapp.com\/Fg4ok3aAVyB59DP63pRapr\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Balinhas saud\u00e1veis de fruta; aprenda receita<\/p>\n<p>O post Fuma\u00e7a t\u00f3xica se espalha ap\u00f3s explos\u00e3o e evacua bairro em Sert\u00e3ozinho apareceu primeiro em ACidade ON Ribeir\u00e3o Preto.<\/p>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/exlosao-atingcaminhao-com-produtos-toxicos-e-deixa-feridos-em-sertaozinho\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Um caminh\u00e3o carregado com produtos qu\u00edmicos explodiu, no in\u00edcio da tarde desta sexta-feira (11), em\u00a0Sert\u00e3ozinho, na regi\u00e3o de\u00a0Ribeir\u00e3o Preto. O fogo se alastrou e atingiu uma ind\u00fastria qu\u00edmica. A fuma\u00e7a considerada altamente t\u00f3xica se espalhou e o bairro precisou ser evacuado. A Prefeitura de Sert\u00e3ozinho informou, em nota, que a Defesa Civil j\u00e1 est\u00e1 &#8230; <a title=\"Fuma\u00e7a t\u00f3xica se espalha ap\u00f3s explos\u00e3o e evacua bairro em Sert\u00e3ozinho\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/11\/fumaca-toxica-se-espalha-apos-explosao-e-evacua-bairro-em-sertaozinho\/\" aria-label=\"Leia mais sobre Fuma\u00e7a t\u00f3xica se espalha ap\u00f3s explos\u00e3o e evacua bairro em Sert\u00e3ozinho\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":70607,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-70606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=1506%2C851&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=1506%2C851&ssl=1",1506,851,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=300%2C170&ssl=1",300,170,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=768%2C434&ssl=1",768,434,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=1024%2C579&ssl=1",1024,579,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=1506%2C851&ssl=1",1506,851,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_17-37-36_png_2024-10-11_17-37-37.webp.webp?fit=1506%2C851&ssl=1",1506,851,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Um caminh\u00e3o carregado com produtos qu\u00edmicos explodiu, no in\u00edcio da tarde desta sexta-feira (11), em\u00a0Sert\u00e3ozinho, na regi\u00e3o de\u00a0Ribeir\u00e3o Preto. O fogo se alastrou e atingiu uma ind\u00fastria qu\u00edmica. A fuma\u00e7a considerada altamente t\u00f3xica se espalhou e o bairro precisou ser evacuado. A Prefeitura de Sert\u00e3ozinho informou, em nota, que a Defesa Civil j\u00e1 est\u00e1&hellip;","jetpack-related-posts":[{"id":70620,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/11\/trinta-pessoas-sao-socorridas-apos-incendio-em-industria-quimica-de-sertaozinho\/","url_meta":{"origin":70606,"position":0},"title":"Trinta pessoas s\u00e3o socorridas ap\u00f3s inc\u00eandio em ind\u00fastria qu\u00edmica de Sert\u00e3ozinho","author":"ismaelcolosi.com.br","date":"11 de Outubro de 2024","format":false,"excerpt":"[ad_1] A Secretaria de Sa\u00fade de Sert\u00e3ozinho confirmou trinta v\u00edtimas da explos\u00e3o que atinge uma ind\u00fastria qu\u00edmica, na tarde desta sexta-feira (11), no munic\u00edpio. Em nota, o departamento informou que quatro desses casos s\u00e3o considerados graves. As v\u00edtimas foram estabilizadas e, assim que poss\u00edvel, ser\u00e3o encaminhadas para hospitais de maior\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-11-at-15.37.58_2024-10-11_18-45-56_jpeg_2024-10-11_18-45-57-scaled.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-11-at-15.37.58_2024-10-11_18-45-56_jpeg_2024-10-11_18-45-57-scaled.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-11-at-15.37.58_2024-10-11_18-45-56_jpeg_2024-10-11_18-45-57-scaled.webp.webp?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-11-at-15.37.58_2024-10-11_18-45-56_jpeg_2024-10-11_18-45-57-scaled.webp.webp?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-11-at-15.37.58_2024-10-11_18-45-56_jpeg_2024-10-11_18-45-57-scaled.webp.webp?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":70613,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/11\/interior-de-sp-tem-novo-alerta-de-tempestade-veja-os-locais-afetados\/","url_meta":{"origin":70606,"position":1},"title":"Interior de SP tem novo alerta de tempestade; Veja os locais afetados","author":"ismaelcolosi.com.br","date":"11 de Outubro de 2024","format":false,"excerpt":"[ad_1] O Inmet (Instituto Nacional de Meteorologia) publicou um novo alerta de perigo para tempestade para o interior de S\u00e3o Paulo nesta sexta-feira (11). O aviso \u00e9 v\u00e1lido at\u00e9 s\u00e1bado (12), \u00e0s 12h. Segundo o Inmet, pode chover o acumulado entre 30 e 60 mil\u00edmetros no per\u00edodo de uma hora,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/inmet_2024-10-11_18-34-50_jpg_2024-10-11_18-34-50.webp.webp?fit=1200%2C710&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/inmet_2024-10-11_18-34-50_jpg_2024-10-11_18-34-50.webp.webp?fit=1200%2C710&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/inmet_2024-10-11_18-34-50_jpg_2024-10-11_18-34-50.webp.webp?fit=1200%2C710&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/inmet_2024-10-11_18-34-50_jpg_2024-10-11_18-34-50.webp.webp?fit=1200%2C710&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/inmet_2024-10-11_18-34-50_jpg_2024-10-11_18-34-50.webp.webp?fit=1200%2C710&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":70651,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/11\/ribeirao-preto-registra-chuva-e-ventos-fortes-apos-alerta-de-tempestade\/","url_meta":{"origin":70606,"position":2},"title":"Ribeir\u00e3o Preto registra chuva e ventos fortes ap\u00f3s alerta de tempestade","author":"ismaelcolosi.com.br","date":"11 de Outubro de 2024","format":false,"excerpt":"[ad_1] Chuvas e rajadas de vento foram registrados, na tarde desta sexta-feira (11), em diversos bairros de Ribeir\u00e3o Preto. Alerta de tempestade emitido pelo Inmet (Instituto Nacional de Meteorologia) segue at\u00e9 o s\u00e1bado (12). Pode chover o acumulado entre 30 e 60 mil\u00edmetros no per\u00edodo de uma hora, com ventos\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_19-54-58_png_2024-10-11_19-54-58.webp.webp?fit=1200%2C666&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_19-54-58_png_2024-10-11_19-54-58.webp.webp?fit=1200%2C666&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_19-54-58_png_2024-10-11_19-54-58.webp.webp?fit=1200%2C666&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_19-54-58_png_2024-10-11_19-54-58.webp.webp?fit=1200%2C666&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_19-54-58_png_2024-10-11_19-54-58.webp.webp?fit=1200%2C666&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":71552,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/16\/sensacao-de-tempestade-de-areia-diz-vitima-de-explosao-em-industria-quimica-em-sertaozinho\/","url_meta":{"origin":70606,"position":3},"title":"&#8216;Sensa\u00e7\u00e3o de tempestade de areia&#8217;, diz v\u00edtima de explos\u00e3o em ind\u00fastria qu\u00edmica em Sert\u00e3ozinho","author":"ismaelcolosi.com.br","date":"16 de Outubro de 2024","format":false,"excerpt":"[ad_1] Nesta quarta-feira (16), uma das tr\u00eas v\u00edtimas do\u00a0acidente em uma f\u00e1brica de produtos qu\u00edmicos em Sert\u00e3ozinho, na regi\u00e3o de Ribeir\u00e3o Preto, relatou o que viveu na \u00faltima sexta-feira (11). Em v\u00eddeo gravado para a EPTV, Rog\u00e9rio Soares conta que estava descarregando o caminh\u00e3o quando ouviu um barulho e um\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-16_23-33-30_png_2024-10-16_23-33-30.webp.webp?fit=1200%2C603&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-16_23-33-30_png_2024-10-16_23-33-30.webp.webp?fit=1200%2C603&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-16_23-33-30_png_2024-10-16_23-33-30.webp.webp?fit=1200%2C603&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-16_23-33-30_png_2024-10-16_23-33-30.webp.webp?fit=1200%2C603&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-16_23-33-30_png_2024-10-16_23-33-30.webp.webp?fit=1200%2C603&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":70591,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/11\/caminhao-com-produtos-quimicos-explode-em-sertaozinho-veja-video\/","url_meta":{"origin":70606,"position":4},"title":"Caminh\u00e3o com produtos qu\u00edmicos explode em Sert\u00e3ozinho; Veja v\u00eddeo","author":"ismaelcolosi.com.br","date":"11 de Outubro de 2024","format":false,"excerpt":"[ad_1] Um caminh\u00e3o carregado com produtos qu\u00edmicos explodiu, no in\u00edcio da tarde desta sexta-feira (11), em Sert\u00e3ozinho, na regi\u00e3o de Ribeir\u00e3o Preto. A Pol\u00edcia Militar est\u00e1 isolando a \u00e1rea e informou que o material queimado \u00e9 altamente t\u00f3xico. Moradores precisaram evacuar o local. Ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es de feridos. Reportagem\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_16-36-14_png_2024-10-11_16-36-14.webp.webp?fit=1200%2C629&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_16-36-14_png_2024-10-11_16-36-14.webp.webp?fit=1200%2C629&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_16-36-14_png_2024-10-11_16-36-14.webp.webp?fit=1200%2C629&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_16-36-14_png_2024-10-11_16-36-14.webp.webp?fit=1200%2C629&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Sem-titulo_2024-10-11_16-36-14_png_2024-10-11_16-36-14.webp.webp?fit=1200%2C629&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":70758,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/12\/o-que-se-sabe-sobre-explosao-que-provocou-incendio-em-industria-quimica\/","url_meta":{"origin":70606,"position":5},"title":"O que se sabe sobre explos\u00e3o que provocou inc\u00eandio em ind\u00fastria qu\u00edmica","author":"ismaelcolosi.com.br","date":"12 de Outubro de 2024","format":false,"excerpt":"[ad_1] Os respons\u00e1veis pela ind\u00fastria que sofreu com inc\u00eandio em Sert\u00e3ozinho, na regi\u00e3o de Ribeir\u00e3o Preto, na tarde de sexta-feira (11), afirmou nesta s\u00e1bado (12) que as explos\u00f5es come\u00e7aram em um caminh\u00e3o, o que desencadeou uma onda de choque e explos\u00f5es. A Innove Qu\u00edmica Ind\u00fastria afirma que o inc\u00eandio come\u00e7ou\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/fogo-industria-sertaozinho_2024-10-12_19-00-06_jpg_2024-10-12_19-00-07.webp.webp?fit=1200%2C739&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/fogo-industria-sertaozinho_2024-10-12_19-00-06_jpg_2024-10-12_19-00-07.webp.webp?fit=1200%2C739&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/fogo-industria-sertaozinho_2024-10-12_19-00-06_jpg_2024-10-12_19-00-07.webp.webp?fit=1200%2C739&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/fogo-industria-sertaozinho_2024-10-12_19-00-06_jpg_2024-10-12_19-00-07.webp.webp?fit=1200%2C739&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/fogo-industria-sertaozinho_2024-10-12_19-00-06_jpg_2024-10-12_19-00-07.webp.webp?fit=1200%2C739&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-imO","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=70606"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70606\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/70607"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=70606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=70606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=70606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}