{"id":70417,"date":"2024-10-10T18:47:00","date_gmt":"2024-10-10T21:47:00","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/10\/acusado-de-matar-vizinho-em-ribeirao-passara-por-avaliacao-psiquiatrica\/"},"modified":"2024-10-10T18:47:00","modified_gmt":"2024-10-10T21:47:00","slug":"acusado-de-matar-vizinho-em-ribeirao-passara-por-avaliacao-psiquiatrica","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/10\/acusado-de-matar-vizinho-em-ribeirao-passara-por-avaliacao-psiquiatrica\/","title":{"rendered":"Acusado de matar vizinho em Ribeir\u00e3o passar\u00e1 por avalia\u00e7\u00e3o psiqui\u00e1trica"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p><strong>A Justi\u00e7a suspendeu o processo criminal de S\u00e9rgio Salom\u00e3o Bernardo<\/strong>, acusado de matar o vizinho em junho desde ano, no Centro de Ribeir\u00e3o Preto. Os dois moravam em um condom\u00ednio no <strong>Jardim Paulista, zona Leste da cidade. <\/strong><\/p>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">A suspens\u00e3o aconteceu ap\u00f3s um pedido da defesa do suspeito para realizar uma avalia\u00e7\u00e3o psicol\u00f3gica.<\/mark> A ju\u00edza respons\u00e1vel pelo caso <strong>aguarda o laudo para saber se ele \u00e9 imput\u00e1vel ou n\u00e3o.<\/strong> <\/p>\n<p><strong>Caso o resultado seja positivo para alguma doen\u00e7a mental<\/strong>, <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">S\u00e9rgio n\u00e3o pode ser levado ao tribunal do juri e receber uma pena pelo crime de homic\u00eddio doloso.<\/mark> Nesse caso, <strong>\u00e9 emitido um documento pedindo a interna\u00e7\u00e3o do r\u00e9u em um hospital psiqui\u00e1trico. <\/strong><\/p>\n<p><strong>Se o laudo apontar que o acusado n\u00e3o tem doen\u00e7a mental<\/strong>, <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">ele poder\u00e1 responder pelo crime sem nenhum tipo de benef\u00edcio. <\/mark><\/p>\n<p><strong>Uma terceira possibilidade, \u00e9 que o resultado mostre que S\u00e9rgio Salom\u00e3o \u00e9 semi-imput\u00e1vel, ou seja, ele pode ser julgado, mas a pena seria reduzida em caso de condena\u00e7\u00e3o.<\/strong><\/p>\n<h4 class=\"wp-block-heading\"><strong>RELEMBRE O CASO<\/strong><\/h4>\n<p><strong>S\u00e9rgio Salom\u00e3o \u00e9 acusado de espancar e matar o vizinho Julio Cesar da Silva, de 60 anos.<\/strong> O crime foi na regi\u00e3o central de Ribeir\u00e3o, em junho deste ano. <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">S\u00e9rgio j\u00e1 tinha desentimento com a v\u00edtima e com outros vizinhos. <\/mark><\/p>\n<p>Na \u00e9poca, <strong>diversos boletins de ocorr\u00eancia foram feitos contra o suspeito<\/strong> e <strong>uma a\u00e7\u00e3o de expuls\u00e3o do condom\u00ednio j\u00e1 tinha sido protocolada na Justi\u00e7a. <\/strong> <\/p>\n<p>SAIBA MAIS<br \/>Veja at\u00e9 quando vai o alerta para chuva forte no interior de SP<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do <strong>acidade on <\/strong>no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a> e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do <strong>acidade on<\/strong> no WhatsApp. Para entrar no grupo, basta <a href=\"https:\/\/chat.whatsapp.com\/Dtv9mxhy6V5BJBotM2OQ5k\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Diddy vai ter julgamento adiado para 2025?<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/acusado-de-matar-vizinho-em-ribeirao-passara-por-avaliacao-psiquiatrica\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A Justi\u00e7a suspendeu o processo criminal de S\u00e9rgio Salom\u00e3o Bernardo, acusado de matar o vizinho em junho desde ano, no Centro de Ribeir\u00e3o Preto. Os dois moravam em um condom\u00ednio no Jardim Paulista, zona Leste da cidade. A suspens\u00e3o aconteceu ap\u00f3s um pedido da defesa do suspeito para realizar uma avalia\u00e7\u00e3o psicol\u00f3gica. A ju\u00edza &#8230; <a title=\"Acusado de matar vizinho em Ribeir\u00e3o passar\u00e1 por avalia\u00e7\u00e3o psiqui\u00e1trica\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/10\/acusado-de-matar-vizinho-em-ribeirao-passara-por-avaliacao-psiquiatrica\/\" aria-label=\"Read more about Acusado de matar vizinho em Ribeir\u00e3o passar\u00e1 por avalia\u00e7\u00e3o psiqui\u00e1trica\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":54803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-70417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/suspeito-agredir-idoso_2024-06-27_23-46-06_png_2024-06-27_23-46-06.webp.webp?fit=984%2C554&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/suspeito-agredir-idoso_2024-06-27_23-46-06_png_2024-06-27_23-46-06.webp.webp?fit=984%2C554&ssl=1",984,554,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/suspeito-agredir-idoso_2024-06-27_23-46-06_png_2024-06-27_23-46-06.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/suspeito-agredir-idoso_2024-06-27_23-46-06_png_2024-06-27_23-46-06.webp.webp?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/suspeito-agredir-idoso_2024-06-27_23-46-06_png_2024-06-27_23-46-06.webp.webp?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/suspeito-agredir-idoso_2024-06-27_23-46-06_png_2024-06-27_23-46-06.webp.webp?fit=984%2C554&ssl=1",984,554,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/suspeito-agredir-idoso_2024-06-27_23-46-06_png_2024-06-27_23-46-06.webp.webp?fit=984%2C554&ssl=1",984,554,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/suspeito-agredir-idoso_2024-06-27_23-46-06_png_2024-06-27_23-46-06.webp.webp?fit=984%2C554&ssl=1",984,554,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A Justi\u00e7a suspendeu o processo criminal de S\u00e9rgio Salom\u00e3o Bernardo, acusado de matar o vizinho em junho desde ano, no Centro de Ribeir\u00e3o Preto. Os dois moravam em um condom\u00ednio no Jardim Paulista, zona Leste da cidade. A suspens\u00e3o aconteceu ap\u00f3s um pedido da defesa do suspeito para realizar uma avalia\u00e7\u00e3o psicol\u00f3gica. A ju\u00edza&hellip;","jetpack-related-posts":[{"id":57393,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/20\/homem-acusado-de-matar-vizinho-vira-reu-em-ribeirao-preto\/","url_meta":{"origin":70417,"position":0},"title":"Homem acusado de matar vizinho vira r\u00e9u em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"20 de July de 2024","format":false,"excerpt":"[ad_1] A 1\u00aa Vara do J\u00fari e das Execu\u00e7\u00f5es Criminais de Ribeir\u00e3o Preto recebeu a den\u00fancia contra o homem acusado de espancar o vizinho, que morreu em raz\u00e3o dos ferimentos. Com a decis\u00e3o, S\u00e9rgio Salom\u00e3o Bernardo vira r\u00e9u na acusa\u00e7\u00e3o encaminhada pelo MP-SP (Minist\u00e9rio P\u00fablico de S\u00e3o Paulo). O r\u00e9u\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/suspeito-agredir-idoso_2024-06-27_23-46-06_png_2024-06-27_23-46-06.webp.webp?fit=984%2C554&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/suspeito-agredir-idoso_2024-06-27_23-46-06_png_2024-06-27_23-46-06.webp.webp?fit=984%2C554&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/suspeito-agredir-idoso_2024-06-27_23-46-06_png_2024-06-27_23-46-06.webp.webp?fit=984%2C554&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/suspeito-agredir-idoso_2024-06-27_23-46-06_png_2024-06-27_23-46-06.webp.webp?fit=984%2C554&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":28500,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/16\/aposentado-e-condenado-a-8-anos-de-prisao-por-matar-vizinho-a-tiros-em-ribeirao-preto\/","url_meta":{"origin":70417,"position":1},"title":"Aposentado \u00e9 condenado a 8 anos de pris\u00e3o por matar vizinho a tiros em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"16 de January de 2024","format":false,"excerpt":"[ad_1] O aposentado Marcelo Lopes de Faria, de 66 anos, acusado de matar a tiros o vizinho, Hugo Rayol, de 82 anos, em Ribeir\u00e3o Preto, no ano de 2022, foi condenado a 8 anos e 10 meses de reclus\u00e3o em regime semiaberto. O acusado foi levado a J\u00fari Popular nesta\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-13.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":57394,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/20\/carro-cai-em-buraco-na-zona-leste-de-ribeirao-preto\/","url_meta":{"origin":70417,"position":2},"title":"Carro cai em buraco na zona Leste de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"20 de July de 2024","format":false,"excerpt":"[ad_1] Um carro caiu em um buraco aberto pela Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) no Jardim Paulista, em Ribeir\u00e3o Preto, na tarde deste s\u00e1bado (20). O caso aconteceu na rua Itapura. De acordo com o motorista, ele n\u00e3o viu a sinaliza\u00e7\u00e3o que havia em volta do\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/buraco-2_2024-07-20_19-27-51_jpeg_2024-07-20_19-27-51.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/buraco-2_2024-07-20_19-27-51_jpeg_2024-07-20_19-27-51.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/buraco-2_2024-07-20_19-27-51_jpeg_2024-07-20_19-27-51.webp.webp?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/buraco-2_2024-07-20_19-27-51_jpeg_2024-07-20_19-27-51.webp.webp?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/buraco-2_2024-07-20_19-27-51_jpeg_2024-07-20_19-27-51.webp.webp?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":28935,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/17\/o-que-se-sabe-sobre-o-acusado-de-matar-engenheiro-em-ribeirao-preto\/","url_meta":{"origin":70417,"position":3},"title":"O que se sabe sobre o acusado de matar engenheiro em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"17 de January de 2024","format":false,"excerpt":"[ad_1] O homem que foi preso em Nova Igua\u00e7u, no Rio de Janeiro, acusado de matar o engenheiro Paulo Roberto Carvalho Braga Pena Filho, deve ser transferido para Ribeir\u00e3o Preto at\u00e9 a pr\u00f3xima sexta-feira (19). Ele ainda n\u00e3o prestou depoimento sobre o caso. Gabriel Souza Brito foi detido pela Pol\u00edcia\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705467672_GABRIEL-SOUZA-BRITO.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705467672_GABRIEL-SOUZA-BRITO.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705467672_GABRIEL-SOUZA-BRITO.jpeg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705467672_GABRIEL-SOUZA-BRITO.jpeg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705467672_GABRIEL-SOUZA-BRITO.jpeg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":55289,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/01\/policia-civil-conclui-inquerito-do-caso-de-idoso-espancado-pelo-vizinho-no-centro-de-ribeirao\/","url_meta":{"origin":70417,"position":4},"title":"Pol\u00edcia Civil conclui inqu\u00e9rito do caso de idoso espancado pelo vizinho no Centro de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"1 de July de 2024","format":false,"excerpt":"[ad_1] A Pol\u00edcia Civil concluiu o inqu\u00e9rito do caso do idoso que morreu ap\u00f3s ser espancado pelo vizinho, no dia 25 de junho, no Centro de Ribeir\u00e3o Preto. J\u00falio C\u00e9sar da Silva, de 60 anos, e S\u00e9rgio Salom\u00e3o, de 48 anos, eram moradores de um condom\u00ednio no Jardim Paulista, zona\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/suspeito-agredir-idoso_2024-06-27_23-46-06_png_2024-06-27_23-46-06.webp.webp?fit=984%2C554&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/suspeito-agredir-idoso_2024-06-27_23-46-06_png_2024-06-27_23-46-06.webp.webp?fit=984%2C554&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/suspeito-agredir-idoso_2024-06-27_23-46-06_png_2024-06-27_23-46-06.webp.webp?fit=984%2C554&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/suspeito-agredir-idoso_2024-06-27_23-46-06_png_2024-06-27_23-46-06.webp.webp?fit=984%2C554&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":58431,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/30\/laudo-aponta-que-suspeito-estava-ciente-ao-matar-e-enterrar-mulher-na-regiao-de-ribeirao\/","url_meta":{"origin":70417,"position":5},"title":"Laudo aponta que suspeito estava ciente ao matar e enterrar mulher na regi\u00e3o de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"30 de July de 2024","format":false,"excerpt":"[ad_1] Um laudo da Justi\u00e7a apontou que Leonardo Silva, de 19 anos, suspeito de matar e enterrar o corpo de Nilza Costa Pingoud, de 62 anos, no quintal da casa onde morava em Barretos, na regi\u00e3o de Ribeir\u00e3o Preto, estava em \u201cplena capacidade de entender e se autodeterminar\u201d quando cometeu\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Design-sem-nome-1-1.png?fit=1200%2C811&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Design-sem-nome-1-1.png?fit=1200%2C811&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Design-sem-nome-1-1.png?fit=1200%2C811&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Design-sem-nome-1-1.png?fit=1200%2C811&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Design-sem-nome-1-1.png?fit=1200%2C811&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-ijL","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=70417"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70417\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/54803"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=70417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=70417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=70417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}