{"id":69791,"date":"2024-10-08T07:13:01","date_gmt":"2024-10-08T10:13:01","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/08\/antes-de-frente-fria-temperatura-pode-passar-de-40c-em-ribeirao-preto\/"},"modified":"2024-10-08T07:13:01","modified_gmt":"2024-10-08T10:13:01","slug":"antes-de-frente-fria-temperatura-pode-passar-de-40c-em-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/08\/antes-de-frente-fria-temperatura-pode-passar-de-40c-em-ribeirao-preto\/","title":{"rendered":"Antes de frente fria, temperatura pode passar de 40\u00b0C em Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p><strong>Ribeir\u00e3o Preto tem previs\u00e3o de calor extremo, com temperaturas acima de\u00a040\u00b0C nesta ter\u00e7a-feira (8) e quarta-feira (9).<\/strong><\/p>\n<p>Segundo a Climatempo, por\u00e9m, uma frente fria avan\u00e7a e refor\u00e7a as instabilidades no interior de S\u00e3o Paulo, com al\u00edvio na temperatura ainda nesta semana.<\/p>\n<p>As pancadas de chuva\u00a0localizadas est\u00e3o previstas a partir desta quarta, na regi\u00e3o de Ribeir\u00e3o Preto. No per\u00edodo da tarde, a chuva pode estar acompanhada de rajadas de vento, descargas el\u00e9tricas e granizo pontual.<\/p>\n<blockquote class=\"wp-block-quote\">\n<p>Com o avan\u00e7o das frentes frias e a reorganiza\u00e7\u00e3o da baixa press\u00e3o, as chuvas finalmente chegar\u00e3o ao Sudeste, alterando o cen\u00e1rio seco que domina a regi\u00e3o. Para o final de semana, o tempo deve continuar inst\u00e1vel em boa parte da regi\u00e3o, com chuvas mais intensas localmente<\/p>\n<p><cite>Guilherme Borges, meteorologista da Climatempo<\/cite><\/p><\/blockquote>\n<p>SAIBA MAIS<\/p>\n<p>Rede de supermercados anuncia chegada a Ribeir\u00e3o Preto<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on<\/strong>\u00a0no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Fg4ok3aAVyB59DP63pRapr\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Campanha de doa\u00e7\u00e3o de sangue de Diablo IV recebe mais de 700 doadores<\/p>\n<p><!-- CONTENT END 3 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/antes-de-frente-fria-temperatura-pode-passar-de-40c-em-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Ribeir\u00e3o Preto tem previs\u00e3o de calor extremo, com temperaturas acima de\u00a040\u00b0C nesta ter\u00e7a-feira (8) e quarta-feira (9). Segundo a Climatempo, por\u00e9m, uma frente fria avan\u00e7a e refor\u00e7a as instabilidades no interior de S\u00e3o Paulo, com al\u00edvio na temperatura ainda nesta semana. As pancadas de chuva\u00a0localizadas est\u00e3o previstas a partir desta quarta, na regi\u00e3o de &#8230; <a title=\"Antes de frente fria, temperatura pode passar de 40\u00b0C em Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/08\/antes-de-frente-fria-temperatura-pode-passar-de-40c-em-ribeirao-preto\/\" aria-label=\"Leia mais sobre Antes de frente fria, temperatura pode passar de 40\u00b0C em Ribeir\u00e3o Preto\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":69792,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-69791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/calor-onda.jpeg?fit=1600%2C900&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/calor-onda.jpeg?fit=1600%2C900&ssl=1",1600,900,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/calor-onda.jpeg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/calor-onda.jpeg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/calor-onda.jpeg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/calor-onda.jpeg?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/calor-onda.jpeg?fit=1536%2C864&ssl=1",1536,864,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/calor-onda.jpeg?fit=1600%2C900&ssl=1",1600,900,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Ribeir\u00e3o Preto tem previs\u00e3o de calor extremo, com temperaturas acima de\u00a040\u00b0C nesta ter\u00e7a-feira (8) e quarta-feira (9). Segundo a Climatempo, por\u00e9m, uma frente fria avan\u00e7a e refor\u00e7a as instabilidades no interior de S\u00e3o Paulo, com al\u00edvio na temperatura ainda nesta semana. As pancadas de chuva\u00a0localizadas est\u00e3o previstas a partir desta quarta, na regi\u00e3o de&hellip;","jetpack-related-posts":[{"id":46284,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/10\/frente-fria-chega-ao-interior-de-sp-nesta-quinta-feira-veja-a-previsao\/","url_meta":{"origin":69791,"position":0},"title":"Frente fria chega ao interior de SP nesta quinta-feira; Veja a previs\u00e3o","author":"ismaelcolosi.com.br","date":"10 de Abril de 2024","format":false,"excerpt":"[ad_1] Uma frente fria formada na Argentina deve causar chuva e temperaturas mais amenas no Sul, antes de chegar ao Sudeste do pa\u00eds, incluindo o estado de S\u00e3o Paulo e o litoral paulista, nesta semana. A alta press\u00e3o que vem na retaguarda desse sistema deve trazer um pouco de ar\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/whatsapp_image_2022-08-08_at_07_42_08.jpe","width":350,"height":200,"srcset":"https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/whatsapp_image_2022-08-08_at_07_42_08.jpe 1x, https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/whatsapp_image_2022-08-08_at_07_42_08.jpe 1.5x, https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/whatsapp_image_2022-08-08_at_07_42_08.jpe 2x, https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/whatsapp_image_2022-08-08_at_07_42_08.jpe 3x"},"classes":[]},{"id":50974,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/22\/vai-esfriar-veja-como-ficam-as-temperaturas-no-interior-de-sp-nos-proximos-dias\/","url_meta":{"origin":69791,"position":1},"title":"Vai esfriar? Veja como ficam as temperaturas no interior de SP nos pr\u00f3ximos dias","author":"ismaelcolosi.com.br","date":"22 de Maio de 2024","format":false,"excerpt":"[ad_1] A meteorologia indica uma mudan\u00e7a no tempo a partir da pr\u00f3xima sexta-feira (24), com a chegada de\u00a0uma nova e forte frente fria. Este sistema proporciona o aumento nas condi\u00e7\u00f5es de chuva e traz um ar polar mais abrangente. Segundo a Climatempo, o avan\u00e7o da frente fria deve ajudar na\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/clima_tempo_1024x576_25052021185248.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/clima_tempo_1024x576_25052021185248.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/clima_tempo_1024x576_25052021185248.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/clima_tempo_1024x576_25052021185248.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":68450,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/30\/primeira-frente-fria-de-outubro-ja-tem-data-para-chegar-ao-interior-de-sp\/","url_meta":{"origin":69791,"position":2},"title":"Primeira frente fria de outubro j\u00e1 tem data para chegar ao interior de SP","author":"ismaelcolosi.com.br","date":"30 de Setembro de 2024","format":false,"excerpt":"[ad_1] A primeira frente fria de outubro j\u00e1 tem data para chegar ao interior de S\u00e3o Paulo. Segundo o Meteored, a frente fria chega na madrugada da pr\u00f3xima quinta-feira (3) na costa de S\u00e3o Paulo, provocando chuva fraca nas regi\u00f5es Sul e Leste do estado. \u201cA semana termina, sem mudan\u00e7as\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727699544_chuva.jpeg?fit=1200%2C903&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727699544_chuva.jpeg?fit=1200%2C903&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727699544_chuva.jpeg?fit=1200%2C903&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727699544_chuva.jpeg?fit=1200%2C903&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727699544_chuva.jpeg?fit=1200%2C903&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":67711,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/25\/muito-calor-veja-as-temperaturas-no-interior-de-sp-antes-da-frente-fria\/","url_meta":{"origin":69791,"position":3},"title":"Muito calor: Veja as temperaturas no interior de SP antes da frente fria","author":"ismaelcolosi.com.br","date":"25 de Setembro de 2024","format":false,"excerpt":"[ad_1] A onda de calor que atinge o interior de S\u00e3o Paulo pode ser intensificada nos pr\u00f3ximos dias por causa da aproxima\u00e7\u00e3o de uma frente fria. Segundo a Meteored, em Ribeir\u00e3o Preto a m\u00e1xima est\u00e1 prevista em 38\u00b0C nesta quarta-feira (25) e pode atingir 40\u00b0C nesta quinta-feira (26) e sexta-feira\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-02-28-at-08.48.57.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-02-28-at-08.48.57.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-02-28-at-08.48.57.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-02-28-at-08.48.57.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-02-28-at-08.48.57.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":58946,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/05\/veja-quando-a-nova-frente-fria-chega-ao-interior-de-sp-ha-previsao-de-chuva\/","url_meta":{"origin":69791,"position":4},"title":"Veja quando a nova frente fria chega ao interior de SP; h\u00e1 previs\u00e3o de chuva","author":"ismaelcolosi.com.br","date":"5 de Agosto de 2024","format":false,"excerpt":"[ad_1] A primeira frente fria do m\u00eas de agosto deve chegar ao interior de S\u00e3o Paulo na pr\u00f3xima sexta-feira (9), de acordo com a Climatempo. As temperaturas podem cair at\u00e9 2,5\u00b0C, em rela\u00e7\u00e3o \u00e0 m\u00e9dia, na maior parte do estado \u2013 em, algumas regi\u00f5es a queda ser\u00e1 de 5\u00b0C. Os\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-05-at-15.03.28.webp.webp?fit=1200%2C553&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-05-at-15.03.28.webp.webp?fit=1200%2C553&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-05-at-15.03.28.webp.webp?fit=1200%2C553&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-05-at-15.03.28.webp.webp?fit=1200%2C553&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-05-at-15.03.28.webp.webp?fit=1200%2C553&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":59061,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/05\/frente-fria-no-interior-de-sp-confira-quando-deve-chover-em-ribeirao-preto\/","url_meta":{"origin":69791,"position":5},"title":"Frente fria no interior de SP: Confira quando deve chover em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"5 de Agosto de 2024","format":false,"excerpt":"[ad_1] Uma nova frente fria deve chegar ao Brasil nesta quarta-feira (7) e provocar uma virada no tempo em muitos estados do Centro-Sul do pa\u00eds, de acordo com a Climatempo. Esse ar frio come\u00e7a a entrar no pa\u00eds pela regi\u00e3o Sul e deve avan\u00e7ar ao longo da sexta-feira (09) sobre\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/chuva_forte_1024x576_06122019161537.jpg?fit=1024%2C575&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/chuva_forte_1024x576_06122019161537.jpg?fit=1024%2C575&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/chuva_forte_1024x576_06122019161537.jpg?fit=1024%2C575&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/chuva_forte_1024x576_06122019161537.jpg?fit=1024%2C575&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-i9F","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/69791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=69791"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/69791\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/69792"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=69791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=69791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=69791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}