{"id":69616,"date":"2024-10-07T07:45:47","date_gmt":"2024-10-07T10:45:47","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/07\/frente-fria-chega-nesta-semana-e-interior-de-sp-tem-previsao-de-chuva-forte\/"},"modified":"2024-10-07T07:45:47","modified_gmt":"2024-10-07T10:45:47","slug":"frente-fria-chega-nesta-semana-e-interior-de-sp-tem-previsao-de-chuva-forte","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/07\/frente-fria-chega-nesta-semana-e-interior-de-sp-tem-previsao-de-chuva-forte\/","title":{"rendered":"Frente fria chega nesta semana e interior de SP tem previs\u00e3o de chuva forte"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p><strong>A chegada de uma frente fria pode trazer chuva ao interior de S\u00e3o Paulo nesta semana.<\/strong><\/p>\n<p>Segundo a Climatempo, a tend\u00eancia \u00e9 que a condi\u00e7\u00e3o de chuva aumente entre quarta-feira (9) e sexta-feira (11) na regi\u00e3o Sudeste.<\/p>\n<p>H\u00e1 risco de chuva forte nas regi\u00f5es de Ribeir\u00e3o Preto, S\u00e3o Carlos e Campinas.<\/p>\n<p>A Climatempo explica que a atmosfera quente deixa a regi\u00e3o em risco para temporais localizados, com pancadas fortes, granizo, trovoadas e rajadas de vento.<\/p>\n<p>SAIBA MAIS<\/p>\n<p>Ricardo Silva e Marco Aur\u00e9lio v\u00e3o disputar o 2\u00ba turno em Ribeir\u00e3o Preto<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on<\/strong>\u00a0no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Fg4ok3aAVyB59DP63pRapr\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Quem est\u00e1 no 2\u00ba turno na elei\u00e7\u00e3o de S\u00e3o Paulo?<\/p>\n<p><!-- CONTENT END 3 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/frente-fria-chega-nesta-semana-e-interior-de-sp-tem-previsao-de-chuva-forte\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A chegada de uma frente fria pode trazer chuva ao interior de S\u00e3o Paulo nesta semana. Segundo a Climatempo, a tend\u00eancia \u00e9 que a condi\u00e7\u00e3o de chuva aumente entre quarta-feira (9) e sexta-feira (11) na regi\u00e3o Sudeste. H\u00e1 risco de chuva forte nas regi\u00f5es de Ribeir\u00e3o Preto, S\u00e3o Carlos e Campinas. A Climatempo explica &#8230; <a title=\"Frente fria chega nesta semana e interior de SP tem previs\u00e3o de chuva forte\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/07\/frente-fria-chega-nesta-semana-e-interior-de-sp-tem-previsao-de-chuva-forte\/\" aria-label=\"Leia mais sobre Frente fria chega nesta semana e interior de SP tem previs\u00e3o de chuva forte\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":58238,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-69616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/RIBEIRAO-PRETO_2024-07-29_16-25-16_jpg_2024-07-29_16-25-17.webp.webp?fit=2000%2C1131&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/RIBEIRAO-PRETO_2024-07-29_16-25-16_jpg_2024-07-29_16-25-17.webp.webp?fit=2000%2C1131&ssl=1",2000,1131,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/RIBEIRAO-PRETO_2024-07-29_16-25-16_jpg_2024-07-29_16-25-17.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/RIBEIRAO-PRETO_2024-07-29_16-25-16_jpg_2024-07-29_16-25-17.webp.webp?fit=300%2C170&ssl=1",300,170,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/RIBEIRAO-PRETO_2024-07-29_16-25-16_jpg_2024-07-29_16-25-17.webp.webp?fit=768%2C434&ssl=1",768,434,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/RIBEIRAO-PRETO_2024-07-29_16-25-16_jpg_2024-07-29_16-25-17.webp.webp?fit=1024%2C579&ssl=1",1024,579,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/RIBEIRAO-PRETO_2024-07-29_16-25-16_jpg_2024-07-29_16-25-17.webp.webp?fit=1536%2C869&ssl=1",1536,869,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/RIBEIRAO-PRETO_2024-07-29_16-25-16_jpg_2024-07-29_16-25-17.webp.webp?fit=2000%2C1131&ssl=1",2000,1131,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A chegada de uma frente fria pode trazer chuva ao interior de S\u00e3o Paulo nesta semana. Segundo a Climatempo, a tend\u00eancia \u00e9 que a condi\u00e7\u00e3o de chuva aumente entre quarta-feira (9) e sexta-feira (11) na regi\u00e3o Sudeste. H\u00e1 risco de chuva forte nas regi\u00f5es de Ribeir\u00e3o Preto, S\u00e3o Carlos e Campinas. A Climatempo explica&hellip;","jetpack-related-posts":[{"id":27423,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/12\/frente-fria-aumenta-risco-de-chuva-forte-no-interior-de-sp-veja-a-previsao\/","url_meta":{"origin":69616,"position":0},"title":"Frente fria aumenta risco de chuva forte no interior de SP; Veja a previs\u00e3o","author":"ismaelcolosi.com.br","date":"12 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A passagem de uma frente fria entre esta sexta-feira (12) e no s\u00e1bado (13) aumenta o risco de chuva forte no interior de S\u00e3o Paulo, segundo a Climatempo. Al\u00e9m disso, o predom\u00ednio de ar quente e \u00famido sobre o Brasil forma nuvens carregadas. \u201cEstas nuvens provocaram temporais em muitos\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705058466_chuva-forte.jpg?fit=1200%2C765&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705058466_chuva-forte.jpg?fit=1200%2C765&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705058466_chuva-forte.jpg?fit=1200%2C765&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705058466_chuva-forte.jpg?fit=1200%2C765&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705058466_chuva-forte.jpg?fit=1200%2C765&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":44104,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/25\/nova-frente-fria-chega-ao-interior-de-sp-veja-como-fica-o-clima-nos-proximos-dias\/","url_meta":{"origin":69616,"position":1},"title":"Nova frente fria chega ao interior de SP; Veja como fica o clima nos pr\u00f3ximos dias","author":"ismaelcolosi.com.br","date":"25 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] A \u00faltima semana de mar\u00e7o ser\u00e1 marcada pelas maiores condi\u00e7\u00f5es para pancadas de chuva em todo o Estado de S\u00e3o Paulo, de acordo com a plataforma Climatempo. Segundo a meteorologia, outra frente fria estar\u00e1 passando em alto mar na altura do litoral de S\u00e3o Paulo, o que refor\u00e7a as\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/20220619_103429681_chuva_nuvem_1200x675_21102021123142.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/20220619_103429681_chuva_nuvem_1200x675_21102021123142.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/20220619_103429681_chuva_nuvem_1200x675_21102021123142.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/20220619_103429681_chuva_nuvem_1200x675_21102021123142.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/20220619_103429681_chuva_nuvem_1200x675_21102021123142.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":55914,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/08\/chegada-de-frente-fria-muda-o-tempo-no-interior-de-sp-no-feriado-veja-onde\/","url_meta":{"origin":69616,"position":2},"title":"Chegada de frente fria muda o tempo no interior de SP no feriado; Veja onde","author":"ismaelcolosi.com.br","date":"8 de Julho de 2024","format":false,"excerpt":"[ad_1] A chegada de uma nova frente fria vai trazer mais umidade para o interior de S\u00e3o Paulo a nesta segunda-feira (8) e no feriado, segundo a Climatempo. Os meteorologistas apontam que o tempo passa a ficar mais \u00famido e nublado e o sul do estado fica em alerta para\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-13-at-09.40.24.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-13-at-09.40.24.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-13-at-09.40.24.webp.webp?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-13-at-09.40.24.webp.webp?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-13-at-09.40.24.webp.webp?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":54465,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/25\/frente-fria-de-forte-intensidade-vai-derrubar-as-temperaturas-no-interior-de-sp\/","url_meta":{"origin":69616,"position":3},"title":"Frente fria de forte intensidade vai derrubar as temperaturas no interior de SP","author":"ismaelcolosi.com.br","date":"25 de Junho de 2024","format":false,"excerpt":"[ad_1] Uma frente fria de forte intensidade se aproxima na sexta-feira (28) e ter\u00e1 potencial para derrubar as temperaturas em todas as regi\u00f5es do estado S\u00e3o Paulo. Segundo a Climatempo, em Ribeir\u00e3o Preto pode ocorrer queda brusca na temperatura a partir da pr\u00f3xima segunda-feira (1\u00ba) com m\u00ednima prevista de apenas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/frio_luva_1200x675_16042022092951.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/frio_luva_1200x675_16042022092951.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/frio_luva_1200x675_16042022092951.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/frio_luva_1200x675_16042022092951.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/frio_luva_1200x675_16042022092951.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":51356,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/27\/nova-frente-fria-se-forma-nesta-semana-veja-previsao-e-as-temperaturas-no-interior-de-sp\/","url_meta":{"origin":69616,"position":4},"title":"Nova frente fria se forma nesta semana; Veja previs\u00e3o e as temperaturas no interior de SP","author":"ismaelcolosi.com.br","date":"27 de Maio de 2024","format":false,"excerpt":"[ad_1] Uma frente fria mudou o tempo no fim de semana, com a chegada da chuva e queda da temperatura no estado de S\u00e3o Paulo. Segundo a Climatempo, a semana deve come\u00e7ar com mais umidade e risco de chuva forte no Oeste, Centro-Leste e Sul do estado paulista. As temperaturas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2023-12-23-at-18.39.14.jpeg?fit=1200%2C844&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2023-12-23-at-18.39.14.jpeg?fit=1200%2C844&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2023-12-23-at-18.39.14.jpeg?fit=1200%2C844&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2023-12-23-at-18.39.14.jpeg?fit=1200%2C844&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2023-12-23-at-18.39.14.jpeg?fit=1200%2C844&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":49719,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/13\/frente-fria-pode-trazer-chuva-ao-interior-de-sp-nesta-semana-confira-a-previsao\/","url_meta":{"origin":69616,"position":5},"title":"Frente fria pode trazer chuva ao interior de SP nesta semana; Confira a previs\u00e3o","author":"ismaelcolosi.com.br","date":"13 de Maio de 2024","format":false,"excerpt":"[ad_1] O deslocamento de uma frente fria provoca o enfraquecimento do bloqueio atmosf\u00e9rico \u2013 que mant\u00e9m as temperaturas elevadas h\u00e1 tr\u00eas semanas \u2013 e pode trazer chuva ao interior de S\u00e3o Paulo nesta semana. Segundo a Climatempo, nesta segunda-feira (13), a condi\u00e7\u00e3o \u00e9 de calor pr\u00e9-frontal, mas ainda sem probabilidade\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/RIBEIRAO-PRETO.jpg?fit=1200%2C708&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/RIBEIRAO-PRETO.jpg?fit=1200%2C708&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/RIBEIRAO-PRETO.jpg?fit=1200%2C708&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/RIBEIRAO-PRETO.jpg?fit=1200%2C708&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/RIBEIRAO-PRETO.jpg?fit=1200%2C708&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-i6Q","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/69616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=69616"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/69616\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/58238"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=69616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=69616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=69616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}