{"id":69601,"date":"2024-10-06T22:22:19","date_gmt":"2024-10-07T01:22:19","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/06\/eleicoes-2024-lucas-seren-e-reeleito-prefeito-de-bebedouro\/"},"modified":"2024-10-06T22:22:19","modified_gmt":"2024-10-07T01:22:19","slug":"eleicoes-2024-lucas-seren-e-reeleito-prefeito-de-bebedouro","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/06\/eleicoes-2024-lucas-seren-e-reeleito-prefeito-de-bebedouro\/","title":{"rendered":"Elei\u00e7\u00f5es 2024: Lucas Seren \u00e9 reeleito prefeito de Bebedouro"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>O candidato <strong>Lucas Seren<\/strong> <strong>(PL)<\/strong> foi eleito prefeito de <strong>Bebedouro<\/strong>, cidade na regi\u00e3o de <strong>Ribeir\u00e3o Preto<\/strong>, na noite deste <strong>domingo (6)<\/strong>.<\/p>\n<p>Conforme os dados do <strong>Tribunal Superior Eleitoral (TSE)<\/strong>, com <strong>100% dos votos apurados<\/strong>, <strong>Lucas Seren<\/strong> foi reeleito prefeito de <strong>Bebedouro<\/strong>, com <strong>57,70%<\/strong> dos votos.<\/p>\n<p><strong>Dr. Fernando Piffer<\/strong> <strong>(PSD)<\/strong> teve <strong>30,53%<\/strong> dos votos e <strong>Chanel<\/strong> <strong>(Republicanos)<\/strong> teve <strong>8,17%<\/strong> dos votos.<\/p>\n<p>A apura\u00e7\u00e3o voc\u00ea acompanha no<strong>\u00a0acidade on<\/strong>\u00a0em tempo real, a partir das 17h. Os n\u00fameros ser\u00e3o atualizados pelo\u00a0<strong>TSE (Tribunal Superior Eleitoral)\u00a0<\/strong>logo em seguida ao t\u00e9rmino da vota\u00e7\u00e3o.\u00a0<a href=\"https:\/\/apuracao.acidadeon.com\/ribeiraopreto\/\" target=\"_blank\" rel=\"noreferrer noopener\">Clique aqui para acompanhar.<\/a><\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/politica\/eleicoes\/eleicoes-2024-lucas-seren-e-reeleito-prefeito-de-bebedouro\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O candidato Lucas Seren (PL) foi eleito prefeito de Bebedouro, cidade na regi\u00e3o de Ribeir\u00e3o Preto, na noite deste domingo (6). Conforme os dados do Tribunal Superior Eleitoral (TSE), com 100% dos votos apurados, Lucas Seren foi reeleito prefeito de Bebedouro, com 57,70% dos votos. Dr. Fernando Piffer (PSD) teve 30,53% dos votos e &#8230; <a title=\"Elei\u00e7\u00f5es 2024: Lucas Seren \u00e9 reeleito prefeito de Bebedouro\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/06\/eleicoes-2024-lucas-seren-e-reeleito-prefeito-de-bebedouro\/\" aria-label=\"Leia mais sobre Elei\u00e7\u00f5es 2024: Lucas Seren \u00e9 reeleito prefeito de Bebedouro\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":69602,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-69601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/lucas-seren_2024-10-06_22-24-01_jpg_2024-10-06_22-24-01.webp.webp?fit=975%2C484&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/lucas-seren_2024-10-06_22-24-01_jpg_2024-10-06_22-24-01.webp.webp?fit=975%2C484&ssl=1",975,484,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/lucas-seren_2024-10-06_22-24-01_jpg_2024-10-06_22-24-01.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/lucas-seren_2024-10-06_22-24-01_jpg_2024-10-06_22-24-01.webp.webp?fit=300%2C149&ssl=1",300,149,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/lucas-seren_2024-10-06_22-24-01_jpg_2024-10-06_22-24-01.webp.webp?fit=768%2C381&ssl=1",768,381,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/lucas-seren_2024-10-06_22-24-01_jpg_2024-10-06_22-24-01.webp.webp?fit=975%2C484&ssl=1",975,484,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/lucas-seren_2024-10-06_22-24-01_jpg_2024-10-06_22-24-01.webp.webp?fit=975%2C484&ssl=1",975,484,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/lucas-seren_2024-10-06_22-24-01_jpg_2024-10-06_22-24-01.webp.webp?fit=975%2C484&ssl=1",975,484,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O candidato Lucas Seren (PL) foi eleito prefeito de Bebedouro, cidade na regi\u00e3o de Ribeir\u00e3o Preto, na noite deste domingo (6). Conforme os dados do Tribunal Superior Eleitoral (TSE), com 100% dos votos apurados, Lucas Seren foi reeleito prefeito de Bebedouro, com 57,70% dos votos. Dr. Fernando Piffer (PSD) teve 30,53% dos votos e&hellip;","jetpack-related-posts":[{"id":69591,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/06\/eleicoes-2024-leo-capitelli-e-reeleito-prefeito-de-serrana\/","url_meta":{"origin":69601,"position":0},"title":"Elei\u00e7\u00f5es 2024: L\u00e9o Capitelli \u00e9 reeleito prefeito de Serrana","author":"ismaelcolosi.com.br","date":"6 de Outubro de 2024","format":false,"excerpt":"[ad_1] Com 100% das urnas apuradas, o candidato L\u00e9o Capitelli (MDB) foi reeleito como prefeito de Serrana, com 77,89% e 19.001 votos neste domingo (6). Conforme os dados do\u00a0Tribunal Superior Eleitoral (TSE), a candidata Andr\u00e9ia Prates (PSB) recebeu 5.393 votos, representando 22,11%. As elei\u00e7\u00f5es de Serrana tiveram 3,23% de votos\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/455694350_877780544370854_4119940491297921876_n_2024-10-06_23-24-46_jpg_2024-10-06_23-24-46.webp.webp?fit=1080%2C1080&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/455694350_877780544370854_4119940491297921876_n_2024-10-06_23-24-46_jpg_2024-10-06_23-24-46.webp.webp?fit=1080%2C1080&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/455694350_877780544370854_4119940491297921876_n_2024-10-06_23-24-46_jpg_2024-10-06_23-24-46.webp.webp?fit=1080%2C1080&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/455694350_877780544370854_4119940491297921876_n_2024-10-06_23-24-46_jpg_2024-10-06_23-24-46.webp.webp?fit=1080%2C1080&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/455694350_877780544370854_4119940491297921876_n_2024-10-06_23-24-46_jpg_2024-10-06_23-24-46.webp.webp?fit=1080%2C1080&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":69585,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/06\/eleicoes-2024-itamar-bueno-e-eleito-prefeito-de-cravinhos\/","url_meta":{"origin":69601,"position":1},"title":"Elei\u00e7\u00f5es 2024: Itamar Bueno \u00e9 eleito prefeito de Cravinhos","author":"ismaelcolosi.com.br","date":"6 de Outubro de 2024","format":false,"excerpt":"[ad_1] O candidato Itamar Bueno (MDB) foi eleito prefeito de Cravinhos, cidade na regi\u00e3o de Ribeir\u00e3o Preto, na noite deste domingo (6). Conforme os dados do Tribunal Superior Eleitoral (TSE), com 100% dos votos apurados, Itamar Bueno foi reeleito prefeito de Cravinhos, com 66,36% e 12.159 votos. Curumim (Solidariedade) teve\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/454476234_1117424409804059_55167205197634569_n_2024-10-06_23-18-16_jpg_2024-10-06_23-18-16.webp.webp?fit=1181%2C777&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/454476234_1117424409804059_55167205197634569_n_2024-10-06_23-18-16_jpg_2024-10-06_23-18-16.webp.webp?fit=1181%2C777&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/454476234_1117424409804059_55167205197634569_n_2024-10-06_23-18-16_jpg_2024-10-06_23-18-16.webp.webp?fit=1181%2C777&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/454476234_1117424409804059_55167205197634569_n_2024-10-06_23-18-16_jpg_2024-10-06_23-18-16.webp.webp?fit=1181%2C777&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/454476234_1117424409804059_55167205197634569_n_2024-10-06_23-18-16_jpg_2024-10-06_23-18-16.webp.webp?fit=1181%2C777&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":69574,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/06\/eleicoes-2024-professor-emerson-e-eleito-prefeito-de-jaboticabal\/","url_meta":{"origin":69601,"position":2},"title":"Elei\u00e7\u00f5es 2024: Professor Emerson \u00e9 eleito prefeito de Jaboticabal","author":"ismaelcolosi.com.br","date":"6 de Outubro de 2024","format":false,"excerpt":"[ad_1] Com 85,99% das urnas apuradas, o candidato Professor Emerson, do MDB, foi reeleito como prefeito de Jaboticabal com 55,76% dos votos. A candidata Adriana Hori, do PSD teve 31,80% dos votos; Nelsinho Gimenez, do PL teve 7,33% dos votos e o Professor Jo\u00e3o Roberto, do Rede teve 2,93%. A\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/15996632525f58ec944a495_1599663252_3x2_md_2024-10-06_22-02-26_jpg_2024-10-06_22-02-26.webp.webp?fit=768%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/15996632525f58ec944a495_1599663252_3x2_md_2024-10-06_22-02-26_jpg_2024-10-06_22-02-26.webp.webp?fit=768%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/15996632525f58ec944a495_1599663252_3x2_md_2024-10-06_22-02-26_jpg_2024-10-06_22-02-26.webp.webp?fit=768%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/15996632525f58ec944a495_1599663252_3x2_md_2024-10-06_22-02-26_jpg_2024-10-06_22-02-26.webp.webp?fit=768%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":71660,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/17\/professor-emerson-quer-governo-mais-comprometido-no-2o-mandato-em-jaboticabal\/","url_meta":{"origin":69601,"position":3},"title":"Professor Emerson quer governo \u2018mais comprometido\u2019 no 2\u00ba mandato em Jaboticabal","author":"ismaelcolosi.com.br","date":"17 de Outubro de 2024","format":false,"excerpt":"[ad_1] O prefeito reeleito de Jaboticabal, Professor Emerson (MDB), disse nesta quinta-feira (17), em entrevista ao acidade on, querer um governo \u201cmais comprometido\u201d neste seu segundo mandato, especialmente com a sa\u00fade e a gera\u00e7\u00e3o de empregos. Assista ao v\u00eddeo abaixo. \u201cUm governo mais comprometido, que envolve mais as a\u00e7\u00f5es com\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/PROFESSOR-EMERSON_2024-10-17_15-40-36_jpg_2024-10-17_15-40-36.webp.webp?fit=1200%2C816&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/PROFESSOR-EMERSON_2024-10-17_15-40-36_jpg_2024-10-17_15-40-36.webp.webp?fit=1200%2C816&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/PROFESSOR-EMERSON_2024-10-17_15-40-36_jpg_2024-10-17_15-40-36.webp.webp?fit=1200%2C816&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/PROFESSOR-EMERSON_2024-10-17_15-40-36_jpg_2024-10-17_15-40-36.webp.webp?fit=1200%2C816&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/PROFESSOR-EMERSON_2024-10-17_15-40-36_jpg_2024-10-17_15-40-36.webp.webp?fit=1200%2C816&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":70993,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/14\/reeleito-lucas-seren-quer-melhorar-saude-zeladoria-e-contas-em-bebedouro\/","url_meta":{"origin":69601,"position":4},"title":"Reeleito, Lucas Seren quer melhorar sa\u00fade, zeladoria e contas em Bebedouro","author":"ismaelcolosi.com.br","date":"14 de Outubro de 2024","format":false,"excerpt":"[ad_1] O Grupo EP usa cookies e outras tecnologias semelhantes para melhorar a sua experi\u00eancia, analisar o tr\u00e1fego do site e personalizar o conte\u00fado. Conhe\u00e7a a nossa pol\u00edtica de privacidade e, ao continuar navegando, voc\u00ea concorda com estas condi\u00e7\u00f5es. [ad_2] Source link","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-14-at-12.25.30_2024-10-14_15-26-59_jpeg_2024-10-14_15-27-00.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-14-at-12.25.30_2024-10-14_15-26-59_jpeg_2024-10-14_15-27-00.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-14-at-12.25.30_2024-10-14_15-26-59_jpeg_2024-10-14_15-27-00.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-14-at-12.25.30_2024-10-14_15-26-59_jpeg_2024-10-14_15-27-00.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-14-at-12.25.30_2024-10-14_15-26-59_jpeg_2024-10-14_15-27-00.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":73571,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/27\/alexandre-ferreira-e-reeleito-prefeito-de-franca\/","url_meta":{"origin":69601,"position":5},"title":"Alexandre Ferreira \u00e9 reeleito prefeito de Franca","author":"ismaelcolosi.com.br","date":"27 de Outubro de 2024","format":false,"excerpt":"[ad_1] O candidato Alexandre Ferreira (MDB) foi reeleito prefeito de Franca, cidade na regi\u00e3o de Ribeir\u00e3o Preto, no come\u00e7o da noite deste domingo (27). Conforme os dados do Tribunal Superior Eleitoral (TSE), ao final da apura\u00e7\u00e3o, \u00e0s xx, o Chefe do Poder Executivo municipal recebeu 82.856 votos (58,64%). J\u00e1 Jo\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-ferreira_2024-09-09_14-40-04_jpg_2024-09-09_14-40-04.webp.webp?fit=1079%2C845&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-ferreira_2024-09-09_14-40-04_jpg_2024-09-09_14-40-04.webp.webp?fit=1079%2C845&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-ferreira_2024-09-09_14-40-04_jpg_2024-09-09_14-40-04.webp.webp?fit=1079%2C845&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-ferreira_2024-09-09_14-40-04_jpg_2024-09-09_14-40-04.webp.webp?fit=1079%2C845&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-ferreira_2024-09-09_14-40-04_jpg_2024-09-09_14-40-04.webp.webp?fit=1079%2C845&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-i6B","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/69601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=69601"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/69601\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/69602"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=69601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=69601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=69601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}