{"id":69496,"date":"2024-10-06T08:19:08","date_gmt":"2024-10-06T11:19:08","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/06\/eleicoes-2024-477-mil-eleitores-vao-as-urnas-em-ribeirao-preto-neste-domingo\/"},"modified":"2024-10-06T08:19:08","modified_gmt":"2024-10-06T11:19:08","slug":"eleicoes-2024-477-mil-eleitores-vao-as-urnas-em-ribeirao-preto-neste-domingo","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/06\/eleicoes-2024-477-mil-eleitores-vao-as-urnas-em-ribeirao-preto-neste-domingo\/","title":{"rendered":"Elei\u00e7\u00f5es 2024: 477 mil eleitores v\u00e3o \u00e0s urnas em Ribeir\u00e3o Preto neste domingo"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>O 1\u00ba turno das\u00a0elei\u00e7\u00f5es municipais de 2024\u00a0acontece neste domingo (6), das 8h \u00e0s 17h. E,\u00a0<mark style=\"background-color:#fcb900\" class=\"has-inline-color\"><strong>Ribeir\u00e3o Preto<\/strong>\u00a0conta 115 locais de vota\u00e7\u00e3o e mais de 477 mil eleitores registrados<\/mark>\u00a0para escolher o pr\u00f3ximo prefeito e os 22 vereadores a partir de 1\u00ba de janeiro de 2025.<\/p>\n<p>Veja no mapa interativo os endere\u00e7os de cada um dos locais de vota\u00e7\u00e3o do munic\u00edpio.<\/p>\n<p><iframe src=\"https:\/\/www.google.com\/maps\/d\/embed?mid=1a_7Unzdyxl3Ht7dV6qfaUP_2WO-Hkzc&amp;ehbc=2E312F\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<h4 class=\"wp-block-heading\"><strong>Transporte p\u00fablico gratuito <\/strong><\/h4>\n<p>O transporte p\u00fablico de Ribeir\u00e3o Preto <strong>ser\u00e1 gratuito neste domingo (6)<\/strong>, data do primeiro turno das elei\u00e7\u00f5es municipais de 2024.<\/p>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">A medida determina que a frota seja suficiente para transportar todos os passageiros. <\/mark><\/p>\n<h4 class=\"wp-block-heading\"><strong>O que o eleitor pode e n\u00e3o pode fazer?<\/strong><\/h4>\n<p>\u00c9 <strong>permitida <\/strong>aos eleitores a manifesta\u00e7\u00e3o individual e silenciosa por partido, candidata ou candidato, exclusivamente pelo uso de bandeiras, broches, adesivos e camisetas. <\/p>\n<p>At\u00e9 o fim da vota\u00e7\u00e3o, <strong>n\u00e3o pode <\/strong>existir aglomera\u00e7\u00e3o de pessoas com camisas e outros adere\u00e7os padronizados nem manifesta\u00e7\u00e3o coletiva ou aliciamento de eleitores. <strong>A pr\u00e1tica pode caracterizar boca de urna, crime punido com deten\u00e7\u00e3o e multa.<\/strong><\/p>\n<h4 class=\"wp-block-heading\"><strong>Vai ter \u2018Lei Seca\u2019 em Ribeir\u00e3o Preto?<\/strong><\/h4>\n<p>O<strong>\u00a0<a href=\"https:\/\/www.tre-sp.jus.br\/#\/\" target=\"_blank\" rel=\"noreferrer noopener\">TRE-SP (Tribunal Regional Eleitoral de S\u00e3o Paulo)<\/a><\/strong>\u00a0informou que\u00a0<mark style=\"background-color:#fcb900\" class=\"has-inline-color\"><strong>n\u00e3o<\/strong>\u00a0h\u00e1 determina\u00e7\u00e3o de Lei Seca para o Estado de S\u00e3o Paulo<\/mark> nas\u00a0elei\u00e7\u00f5es de 2024.\u00a0<\/p>\n<p>A proibi\u00e7\u00e3o da venda de bebidas alco\u00f3licas durante as elei\u00e7\u00f5es \u00e9 decidida localmente pelas autoridades de seguran\u00e7a p\u00fablica e eleitorais. <strong>A ideia \u00e9 reduzir os riscos de desordem que prejudiquem o processo eleitoral.<\/strong><\/p>\n<h4 class=\"wp-block-heading\"><strong>Apura\u00e7\u00e3o em tempo real<\/strong><\/h4>\n<p>O<strong> acidade on<\/strong> vai divulgar os n\u00fameros da apura\u00e7\u00e3o das elei\u00e7\u00f5es 2024 <strong>em tempo real a partir das 17h deste domingo (6).<\/strong><\/p>\n<p><a href=\"https:\/\/apuracao.acidadeon.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Clique aqui<\/a>\u00a0para acompanhar a apura\u00e7\u00e3o. \u00c9 s\u00f3 entrar e escolher o\u00a0<strong>munic\u00edpio<\/strong>. Os n\u00fameros ser\u00e3o atualizados pelo\u00a0<strong>TSE (Tribunal Superior Eleitoral)\u00a0<\/strong>logo em seguida ao t\u00e9rmino da vota\u00e7\u00e3o.\u00a0<\/p>\n<p>SAIBA MAIS<\/p>\n<p>Quaest: Veja os n\u00fameros da pesquisa eleitoral para prefeito em Ribeir\u00e3o Preto<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on<\/strong>\u00a0no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Fg4ok3aAVyB59DP63pRapr\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>LEIA TAMB\u00c9M<\/p>\n<p>At\u00e9 que horas pode votar nas elei\u00e7\u00f5es municipais?<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/politica\/eleicoes\/eleicoes-2024-477-mil-eleitores-vao-as-urnas-em-ribeirao-preto-neste-domingo\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O 1\u00ba turno das\u00a0elei\u00e7\u00f5es municipais de 2024\u00a0acontece neste domingo (6), das 8h \u00e0s 17h. E,\u00a0Ribeir\u00e3o Preto\u00a0conta 115 locais de vota\u00e7\u00e3o e mais de 477 mil eleitores registrados\u00a0para escolher o pr\u00f3ximo prefeito e os 22 vereadores a partir de 1\u00ba de janeiro de 2025. Veja no mapa interativo os endere\u00e7os de cada um dos locais &#8230; <a title=\"Elei\u00e7\u00f5es 2024: 477 mil eleitores v\u00e3o \u00e0s urnas em Ribeir\u00e3o Preto neste domingo\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/06\/eleicoes-2024-477-mil-eleitores-vao-as-urnas-em-ribeirao-preto-neste-domingo\/\" aria-label=\"Leia mais sobre Elei\u00e7\u00f5es 2024: 477 mil eleitores v\u00e3o \u00e0s urnas em Ribeir\u00e3o Preto neste domingo\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":65518,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-69496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/trevao-ribeirao-preto_2024-09-12_17-08-13_jpeg_2024-09-12_17-08-13.webp.webp?fit=1600%2C869&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/trevao-ribeirao-preto_2024-09-12_17-08-13_jpeg_2024-09-12_17-08-13.webp.webp?fit=1600%2C869&ssl=1",1600,869,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/trevao-ribeirao-preto_2024-09-12_17-08-13_jpeg_2024-09-12_17-08-13.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/trevao-ribeirao-preto_2024-09-12_17-08-13_jpeg_2024-09-12_17-08-13.webp.webp?fit=300%2C163&ssl=1",300,163,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/trevao-ribeirao-preto_2024-09-12_17-08-13_jpeg_2024-09-12_17-08-13.webp.webp?fit=768%2C417&ssl=1",768,417,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/trevao-ribeirao-preto_2024-09-12_17-08-13_jpeg_2024-09-12_17-08-13.webp.webp?fit=1024%2C556&ssl=1",1024,556,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/trevao-ribeirao-preto_2024-09-12_17-08-13_jpeg_2024-09-12_17-08-13.webp.webp?fit=1536%2C834&ssl=1",1536,834,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/trevao-ribeirao-preto_2024-09-12_17-08-13_jpeg_2024-09-12_17-08-13.webp.webp?fit=1600%2C869&ssl=1",1600,869,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O 1\u00ba turno das\u00a0elei\u00e7\u00f5es municipais de 2024\u00a0acontece neste domingo (6), das 8h \u00e0s 17h. E,\u00a0Ribeir\u00e3o Preto\u00a0conta 115 locais de vota\u00e7\u00e3o e mais de 477 mil eleitores registrados\u00a0para escolher o pr\u00f3ximo prefeito e os 22 vereadores a partir de 1\u00ba de janeiro de 2025. Veja no mapa interativo os endere\u00e7os de cada um dos locais&hellip;","jetpack-related-posts":[{"id":73463,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/26\/veja-os-numeros-de-urna-dos-candidatos-que-disputam-o-2o-turno-em-ribeirao-preto\/","url_meta":{"origin":69496,"position":0},"title":"Veja os n\u00fameros de urna dos candidatos que disputam o 2\u00ba turno em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"26 de Outubro de 2024","format":false,"excerpt":"[ad_1] Mais de 477 mil eleitores de Ribeir\u00e3o Preto v\u00e3o \u00e0s urnas neste domingo (27) quando \u00e9 realizado o 2\u00ba turno das elei\u00e7\u00f5es 2024. Os candidatos Ricardo Silva (PSD) e Marco Aur\u00e9lio (NOVO) disputam quem vai ser o pr\u00f3ximo prefeito de Ribeir\u00e3o Preto. Veja o n\u00famero de urna de cada\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio_2024-10-12_21-54-55_jpeg_2024-10-12_21-54-55.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio_2024-10-12_21-54-55_jpeg_2024-10-12_21-54-55.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio_2024-10-12_21-54-55_jpeg_2024-10-12_21-54-55.webp.webp?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio_2024-10-12_21-54-55_jpeg_2024-10-12_21-54-55.webp.webp?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ricardo-silva-marco-aurelio_2024-10-12_21-54-55_jpeg_2024-10-12_21-54-55.webp.webp?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":69422,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/05\/saiba-como-consultar-o-local-de-votacao-em-ribeirao-preto-nas-eleicoes-2024\/","url_meta":{"origin":69496,"position":1},"title":"Saiba como consultar o local de vota\u00e7\u00e3o em Ribeir\u00e3o Preto nas elei\u00e7\u00f5es 2024","author":"ismaelcolosi.com.br","date":"5 de Outubro de 2024","format":false,"excerpt":"[ad_1] O 1\u00ba turno das elei\u00e7\u00f5es municipais de 2024 acontece neste domingo (6), das 8h \u00e0s 17h. E, Ribeir\u00e3o Preto conta 115 locais de vota\u00e7\u00e3o e mais de 477 mil eleitores registrados para escolher o pr\u00f3ximo prefeito e os 22 vereadores a partir de 1\u00ba de janeiro de 2025. A\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/urna-eletronica.jpg?fit=1170%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/urna-eletronica.jpg?fit=1170%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/urna-eletronica.jpg?fit=1170%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/urna-eletronica.jpg?fit=1170%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/urna-eletronica.jpg?fit=1170%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":69441,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/05\/ribeirao-preto-tem-onibus-gratuito-neste-domingo-de-eleicoes-confira-horario\/","url_meta":{"origin":69496,"position":2},"title":"Ribeir\u00e3o Preto tem \u00f4nibus gratuito neste domingo de elei\u00e7\u00f5es; Confira hor\u00e1rio","author":"ismaelcolosi.com.br","date":"5 de Outubro de 2024","format":false,"excerpt":"[ad_1] O transporte p\u00fablico de Ribeir\u00e3o Preto ser\u00e1 gratuito neste domingo (6), data do primeiro turno das elei\u00e7\u00f5es municipais de 2024. O decreto assinado pelo prefeito Duarte Nogueira (PSDB) estabelece o passe livre nos \u00f4nibus entre 6h e 20h. A medida determina que a frota seja suficiente para transportar todos\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-48.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-48.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-48.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-48.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-48.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":22926,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/31\/2024-e-ano-de-eleicoes-municipais-veja-as-principais-datas-da-disputa\/","url_meta":{"origin":69496,"position":3},"title":"2024 \u00e9 ano de elei\u00e7\u00f5es municipais; Veja as principais datas da disputa","author":"ismaelcolosi.com.br","date":"31 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Em 2024, os mais de 470 mil eleitores de Ribeir\u00e3o Preto v\u00e3o eleger o novo prefeito, o vice e 22 vereadores. Por isso, o acidade on Ribeir\u00e3o Preto separou as principais datas do calend\u00e1rio eleitoral do novo ano para voc\u00ea decidir como ser\u00e1 o futuro da cidade. As elei\u00e7\u00f5es\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/urna-eletronica.jpg?fit=1170%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/urna-eletronica.jpg?fit=1170%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/urna-eletronica.jpg?fit=1170%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/urna-eletronica.jpg?fit=1170%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/urna-eletronica.jpg?fit=1170%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":68514,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/30\/veja-mapa-interativo-com-todos-os-locais-de-votacao-em-ribeirao-preto\/","url_meta":{"origin":69496,"position":4},"title":"Veja mapa interativo com todos os locais de vota\u00e7\u00e3o em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"30 de Setembro de 2024","format":false,"excerpt":"[ad_1] O 1\u00ba turno das Elei\u00e7\u00f5es Municipais de 2024 acontece neste domingo (6), das 8h \u00e0s 17h, em diversas institui\u00e7\u00f5es de Ribeir\u00e3o Preto. Com isso, o portal acidade on preparou um mapa com todos os locais de vota\u00e7\u00e3o na cidade. Os locais foram agrupados conforme rela\u00e7\u00e3o enviada a reportagem pelas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-82_2024-09-30_17-21-38_png_2024-09-30_17-21-38.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-82_2024-09-30_17-21-38_png_2024-09-30_17-21-38.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-82_2024-09-30_17-21-38_png_2024-09-30_17-21-38.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-82_2024-09-30_17-21-38_png_2024-09-30_17-21-38.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-82_2024-09-30_17-21-38_png_2024-09-30_17-21-38.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":72652,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/22\/quem-nao-votou-no-1o-turno-pode-votar-no-2o-turno-das-eleicoes\/","url_meta":{"origin":69496,"position":5},"title":"Quem n\u00e3o votou no 1\u00ba turno pode votar no 2\u00ba turno das elei\u00e7\u00f5es?","author":"ismaelcolosi.com.br","date":"22 de Outubro de 2024","format":false,"excerpt":"[ad_1] Quem n\u00e3o votou no 1\u00ba turno das Elei\u00e7\u00f5es Municipais de 2024, pode participar do 2\u00ba turno do pleito. Os eleitores de 15 capitais e 36 munic\u00edpios, incluindo Ribeir\u00e3o Preto, voltam \u00e0s urnas neste domingo (27), para eleger um dos candidatos que disputam o cargo de prefeito. Conforme o TSE\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/pin0304_2024-10-22_20-04-05_jpg_2024-10-22_20-04-06-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/pin0304_2024-10-22_20-04-05_jpg_2024-10-22_20-04-06-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/pin0304_2024-10-22_20-04-05_jpg_2024-10-22_20-04-06-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/pin0304_2024-10-22_20-04-05_jpg_2024-10-22_20-04-06-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/pin0304_2024-10-22_20-04-05_jpg_2024-10-22_20-04-06-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-i4U","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/69496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=69496"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/69496\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/65518"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=69496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=69496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=69496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}