{"id":68240,"date":"2024-09-27T23:51:02","date_gmt":"2024-09-28T02:51:02","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/27\/confira-as-novas-vagas-de-emprego-para-trabalhar-de-casa-trabalho-home-office-com-salarios-de-1-500-ate-3-mil-clique-e-confira-agora-84\/"},"modified":"2024-09-27T23:51:02","modified_gmt":"2024-09-28T02:51:02","slug":"confira-as-novas-vagas-de-emprego-para-trabalhar-de-casa-trabalho-home-office-com-salarios-de-1-500-ate-3-mil-clique-e-confira-agora-84","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/27\/confira-as-novas-vagas-de-emprego-para-trabalhar-de-casa-trabalho-home-office-com-salarios-de-1-500-ate-3-mil-clique-e-confira-agora-84\/","title":{"rendered":"Confira as novas vagas de emprego para trabalhar de casa. Trabalho home office, com sal\u00e1rios de 1.500 at\u00e9 3 mil, clique e confira agora"},"content":{"rendered":"<p><main id=\"main\" class=\"site-main\"><\/p>\n<div class=\"featured-widget-container\">\n<div class=\"container\">\n<div class=\"row clearfix highlight-section\">\n<div class=\"col-md-8 gutter-right\">\n<div class=\"highlight-left\">\n<div class=\"owl-carousel highlight-left-carousel\">\n<div class=\"item\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/instituto-infnet-abriu-vaga-home-office-para-auxiliar-de-suporte-academico-com-salario-de-r-1-41200-mil\/\" target=\"_blank\" rel=\"noopener\"><\/p>\n<div class=\"highlight-fimg\" style=\"background-image: url( https:\/\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/09\/Auxiliar-de-Suporte-900x600.webp );\">\n<div class=\"mask\"><\/div>\n<\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/home-office\/\" rel=\"category tag noopener\" target=\"_blank\">Home Office<\/a><\/span><\/p>\n<div class=\"highlight-info\">\n<h3 class=\"news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/instituto-infnet-abriu-vaga-home-office-para-auxiliar-de-suporte-academico-com-salario-de-r-1-41200-mil\/\" target=\"_blank\" rel=\"noopener\">Instituto Infnet abriu vaga HOME OFFICE para Auxiliar de Suporte Acad\u00eamico com sal\u00e1rio de R$\u00a01.412,00 mil<\/a><br \/>\n<\/h3>\n<div class=\"entry-meta\">\n<\/div>\n<\/div>\n<\/div>\n<div class=\"item\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/atencao-buscando-emprego-home-office-a-riachuelo-esta-com-vagas-abertas-para-assistente-contabil\/\" target=\"_blank\" rel=\"noopener\"><\/p>\n<div class=\"highlight-fimg\" style=\"background-image: url( https:\/\/www.capitalvagas.com.br\/wp-content\/uploads\/2023\/05\/Riachuelo-tem-mais-de-300-vagas-home-office-disponiveis-900x600.jpg );\">\n<div class=\"mask\"><\/div>\n<\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/home-office\/\" rel=\"category tag noopener\" target=\"_blank\">Home Office<\/a><\/span><\/p>\n<div class=\"highlight-info\">\n<h3 class=\"news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/atencao-buscando-emprego-home-office-a-riachuelo-esta-com-vagas-abertas-para-assistente-contabil\/\" target=\"_blank\" rel=\"noopener\">Aten\u00e7\u00e3o! Buscando emprego Home Office? A Riachuelo est\u00e1 com vagas abertas para Assistente Cont\u00e1bil<\/a><br \/>\n<\/h3>\n<div class=\"entry-meta\">\n<\/div>\n<\/div>\n<\/div>\n<div class=\"item\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/a-brivia-esta-com-vagas-home-office-em-aberto-para-secretarias-executivas\/\" target=\"_blank\" rel=\"noopener\"><\/p>\n<div class=\"highlight-fimg\" style=\"background-image: url( https:\/\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/09\/brivia-900x600.webp );\">\n<div class=\"mask\"><\/div>\n<\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/home-office\/\" rel=\"category tag noopener\" target=\"_blank\">Home Office<\/a><\/span><\/p>\n<div class=\"highlight-info\">\n<h3 class=\"news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/a-brivia-esta-com-vagas-home-office-em-aberto-para-secretarias-executivas\/\" target=\"_blank\" rel=\"noopener\">A Brivia est\u00e1 com vagas HOME OFFICE em aberto para Secret\u00e1rias Executivas<\/a><br \/>\n<\/h3>\n<div class=\"entry-meta\">\n<\/div>\n<\/div>\n<\/div>\n<div class=\"item\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/vaga-home-office-para-atendimento-ao-cliente-com-salario-de-ate-r-3-00000-r-65000-de-va-auxilio-home-office-de-r-23000\/\" target=\"_blank\" rel=\"noopener\"><\/p>\n<div class=\"highlight-fimg\" style=\"background-image: url( https:\/\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/09\/EFFECTI-900x600.webp );\">\n<div class=\"mask\"><\/div>\n<\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/home-office\/\" rel=\"category tag noopener\" target=\"_blank\">Home Office<\/a><\/span><\/p>\n<div class=\"highlight-info\">\n<h3 class=\"news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/vaga-home-office-para-atendimento-ao-cliente-com-salario-de-ate-r-3-00000-r-65000-de-va-auxilio-home-office-de-r-23000\/\" target=\"_blank\" rel=\"noopener\">Vaga Home Office para Atendimento ao Cliente com sal\u00e1rio de at\u00e9 R$ 3.000,00 + R$ 650,00 de VA + Aux\u00edlio Home Office de R$ 230,00<\/a><br \/>\n<\/h3>\n<div class=\"entry-meta\">\n<\/div>\n<\/div>\n<\/div>\n<div class=\"item\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/10-vagas-home-office-com-salario-de-r-1-60000-para-atendente-de-telemarketing-empresa-fornece-equipamentos\/\" target=\"_blank\" rel=\"noopener\"><\/p>\n<div class=\"highlight-fimg\" style=\"background-image: url( https:\/\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/09\/Telemarketing-900x600.webp );\">\n<div class=\"mask\"><\/div>\n<\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/home-office\/\" rel=\"category tag noopener\" target=\"_blank\">Home Office<\/a><\/span><\/p>\n<div class=\"highlight-info\">\n<h3 class=\"news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/10-vagas-home-office-com-salario-de-r-1-60000-para-atendente-de-telemarketing-empresa-fornece-equipamentos\/\" target=\"_blank\" rel=\"noopener\">10 Vagas Home Office com Sal\u00e1rio de R$ 1.600,00 para Atendente de Telemarketing! Empresa fornece equipamentos<\/a><br \/>\n<\/h3>\n<div class=\"entry-meta\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"col-md-4 gutter-left\">\n<div class=\"highlight-right highlight-right-top\" style=\"background-image: url( https:\/\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/APRENDIZ-RECORD-900x600.webp );\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/programa-aprendiz-record-2o-semestre-de-2024-inscricoes-abertas-para-nivel-medio-de-06-horas-por-dia\/\" target=\"_blank\" rel=\"noopener\"><\/p>\n<div class=\"mask\"><\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/jovem-aprendiz\/\" rel=\"category tag noopener\" target=\"_blank\">Jovem Aprendiz<\/a><\/span><\/p>\n<div class=\"highlight-info\">\n<h4 class=\"news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/programa-aprendiz-record-2o-semestre-de-2024-inscricoes-abertas-para-nivel-medio-de-06-horas-por-dia\/\" target=\"_blank\" rel=\"noopener\"><br \/>\nPrograma Aprendiz Record 2\u00ba Semestre de 2024: Inscri\u00e7\u00f5es abertas para N\u00edvel M\u00e9dio de 06 horas por dia <\/a><br \/>\n<\/h4>\n<div class=\"entry-meta\">\n<\/div>\n<\/div>\n<\/div>\n<div class=\"highlight-right highlight-right-bottom\" style=\"background-image: url( https:\/\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/09\/Auxiliar-de-Suporte-900x600.webp );\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/instituto-infnet-abriu-vaga-home-office-para-auxiliar-de-suporte-academico-com-salario-de-r-1-41200-mil\/\" target=\"_blank\" rel=\"noopener\"><\/p>\n<div class=\"mask\"><\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/home-office\/\" rel=\"category tag noopener\" target=\"_blank\">Home Office<\/a><\/span><\/p>\n<div class=\"highlight-info\">\n<h4 class=\"news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/instituto-infnet-abriu-vaga-home-office-para-auxiliar-de-suporte-academico-com-salario-de-r-1-41200-mil\/\" target=\"_blank\" rel=\"noopener\">Instituto Infnet abriu vaga HOME OFFICE para Auxiliar de Suporte Acad\u00eamico com sal\u00e1rio de R$\u00a01.412,00 mil<\/a><br \/>\n<\/h4>\n<div class=\"entry-meta\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-md-8 sticky-section\">\n<div class=\"row\">\n<div class=\"col-md-12\">\n<div class=\"archive-section-content\" id=\"post-38451\">\n<div class=\"row clearfix archive-news-content\">\n<div class=\"col-sm-6 gutter-right\">\n<div class=\"news-image\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/ganhe-ate-r-250000-por-mes-ysense-brasil-abre-novas-vagas-para-pesquisadores-online-com-pagamentos-em-dolares-ou-euros-veja-como-funciona\/\" target=\"_blank\" rel=\"noopener\"><br \/>\n<img data-recalc-dims=\"1\" width=\"761\" height=\"492\" src=\"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=761%2C492&#038;ssl=1\" class=\"img-responsive wp-post-image\" alt=\"Ganhe at\u00e9 R$ 2500,00 por m\u00eas! ySense Brasil abre novas vagas para Pesquisadores Online com pagamentos em D\u00f3lares ou Euros; Veja como funciona\" decoding=\"async\"> <\/p>\n<div class=\"mask\"><\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/blog\/\" rel=\"category tag noopener\" target=\"_blank\">Blog<\/a><\/span>\n<\/div>\n<\/div>\n<div class=\"col-sm-6 gutter-left\">\n<div class=\"news-detail\">\n<h4 class=\"news-title big-news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/ganhe-ate-r-250000-por-mes-ysense-brasil-abre-novas-vagas-para-pesquisadores-online-com-pagamentos-em-dolares-ou-euros-veja-como-funciona\/\" target=\"_blank\" rel=\"noopener\">Ganhe at\u00e9 R$ 2500,00 por m\u00eas! ySense Brasil abre novas vagas para Pesquisadores Online com pagamentos em D\u00f3lares ou Euros; Veja como funciona<\/a><br \/>\n<\/h4>\n<div class=\"entry-meta\">\n<\/div>\n<div class=\"news-content\">\n<p>Voc\u00ea est\u00e1 cansado de aplicativos que prometem pagar para realizar tarefas, mas que no final das contas acabam sendo apenas golpes elaborados? Ent\u00e3o, \u00e9 hora de conhecer plataformas reconhecidas no<\/p>\n<p><a href=\"https:\/\/www.capitalvagas.com.br\/ganhe-ate-r-250000-por-mes-ysense-brasil-abre-novas-vagas-para-pesquisadores-online-com-pagamentos-em-dolares-ou-euros-veja-como-funciona\/\" class=\"btn-more\" target=\"_blank\" rel=\"noopener\"><br \/>\nLeia mais <\/a>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"code-block code-block-3\" style=\"margin: 8px 0; clear: both;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4943055693750262\" crossorigin=\"anonymous\" type=\"6231116a22eecd06a8ca4b6f-text\/javascript\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-dn+7f+35-mv+vw\" data-ad-client=\"ca-pub-4943055693750262\" data-ad-slot=\"6748774866\"><\/ins><br \/>\n<script type=\"6231116a22eecd06a8ca4b6f-text\/javascript\">\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/div>\n<div class=\"archive-section-content\" id=\"post-38641\">\n<div class=\"row clearfix archive-news-content\">\n<div class=\"col-sm-6 gutter-right\">\n<div class=\"news-image\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/instituto-infnet-abriu-vaga-home-office-para-auxiliar-de-suporte-academico-com-salario-de-r-1-41200-mil\/\" target=\"_blank\" rel=\"noopener\"><br \/>\n<img data-recalc-dims=\"1\" width=\"761\" height=\"492\" src=\"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/09\/Auxiliar-de-Suporte-761x492.webp?resize=761%2C492&#038;ssl=1\" class=\"img-responsive wp-post-image\" alt=\"Instituto Infnet abriu vaga HOME OFFICE para Auxiliar de Suporte Acad\u00eamico com sal\u00e1rio de R$\u00a01.412,00 mil\" decoding=\"async\"> <\/p>\n<div class=\"mask\"><\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/home-office\/\" rel=\"category tag noopener\" target=\"_blank\">Home Office<\/a><\/span>\n<\/div>\n<\/div>\n<div class=\"col-sm-6 gutter-left\">\n<div class=\"news-detail\">\n<h4 class=\"news-title big-news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/instituto-infnet-abriu-vaga-home-office-para-auxiliar-de-suporte-academico-com-salario-de-r-1-41200-mil\/\" target=\"_blank\" rel=\"noopener\">Instituto Infnet abriu vaga HOME OFFICE para Auxiliar de Suporte Acad\u00eamico com sal\u00e1rio de R$\u00a01.412,00 mil<\/a><br \/>\n<\/h4>\n<div class=\"entry-meta\">\n<\/div>\n<div class=\"news-content\">\n<p>O Instituto Infnet foi fundado em 1994 e \u00e9 uma institui\u00e7\u00e3o de ensino superior, sendo composto pela Faculdade Infnet e pela ECDD \u2013 Escola de Comunica\u00e7\u00e3o e Design Digital. \u00c9<\/p>\n<p><a href=\"https:\/\/www.capitalvagas.com.br\/instituto-infnet-abriu-vaga-home-office-para-auxiliar-de-suporte-academico-com-salario-de-r-1-41200-mil\/\" class=\"btn-more\" target=\"_blank\" rel=\"noopener\"><br \/>\nLeia mais <\/a>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"code-block code-block-3\" style=\"margin: 8px 0; clear: both;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4943055693750262\" crossorigin=\"anonymous\" type=\"6231116a22eecd06a8ca4b6f-text\/javascript\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-dn+7f+35-mv+vw\" data-ad-client=\"ca-pub-4943055693750262\" data-ad-slot=\"6748774866\"><\/ins><br \/>\n<script type=\"6231116a22eecd06a8ca4b6f-text\/javascript\">\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/div>\n<div class=\"archive-section-content\" id=\"post-38639\">\n<div class=\"row clearfix archive-news-content\">\n<div class=\"col-sm-6 gutter-right\">\n<div class=\"news-image\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/atencao-buscando-emprego-home-office-a-riachuelo-esta-com-vagas-abertas-para-assistente-contabil\/\" target=\"_blank\" rel=\"noopener\">\n<picture><source srcset=\"https:\/\/www.capitalvagas.com.br\/wp-content\/webp-express\/webp-images\/doc-root\/wp-content\/uploads\/2023\/05\/Riachuelo-tem-mais-de-300-vagas-home-office-disponiveis-761x492.jpg.webp\" type=\"image\/webp\"><img data-recalc-dims=\"1\" width=\"761\" height=\"492\" src=\"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2023\/05\/Riachuelo-tem-mais-de-300-vagas-home-office-disponiveis-761x492.jpg?resize=761%2C492&#038;ssl=1\" class=\"img-responsive wp-post-image webpexpress-processed\" alt=\"Aten\u00e7\u00e3o! Buscando emprego Home Office? A Riachuelo est\u00e1 com vagas abertas para Assistente Cont\u00e1bil\" decoding=\"async\"><\/source><\/picture>\n<div class=\"mask\"><\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/home-office\/\" rel=\"category tag noopener\" target=\"_blank\">Home Office<\/a><\/span>\n<\/div>\n<\/div>\n<div class=\"col-sm-6 gutter-left\">\n<div class=\"news-detail\">\n<h4 class=\"news-title big-news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/atencao-buscando-emprego-home-office-a-riachuelo-esta-com-vagas-abertas-para-assistente-contabil\/\" target=\"_blank\" rel=\"noopener\">Aten\u00e7\u00e3o! Buscando emprego Home Office? A Riachuelo est\u00e1 com vagas abertas para Assistente Cont\u00e1bil<\/a><br \/>\n<\/h4>\n<div class=\"entry-meta\">\n<\/div>\n<div class=\"news-content\">\n<p>A Riachuelo est\u00e1 com oportunidades abertas para quem busca um emprego no modelo home office. Uma das maiores redes de moda e varejo do Brasil, a empresa est\u00e1 \u00e0 procura<\/p>\n<p><a href=\"https:\/\/www.capitalvagas.com.br\/atencao-buscando-emprego-home-office-a-riachuelo-esta-com-vagas-abertas-para-assistente-contabil\/\" class=\"btn-more\" target=\"_blank\" rel=\"noopener\"><br \/>\nLeia mais <\/a>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"code-block code-block-3\" style=\"margin: 8px 0; clear: both;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4943055693750262\" crossorigin=\"anonymous\" type=\"6231116a22eecd06a8ca4b6f-text\/javascript\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-dn+7f+35-mv+vw\" data-ad-client=\"ca-pub-4943055693750262\" data-ad-slot=\"6748774866\"><\/ins><br \/>\n<script type=\"6231116a22eecd06a8ca4b6f-text\/javascript\">\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/div>\n<div class=\"archive-section-content\" id=\"post-38634\">\n<div class=\"row clearfix archive-news-content\">\n<div class=\"col-sm-6 gutter-right\">\n<div class=\"news-image\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/a-brivia-esta-com-vagas-home-office-em-aberto-para-secretarias-executivas\/\" target=\"_blank\" rel=\"noopener\"><br \/>\n<img data-recalc-dims=\"1\" width=\"761\" height=\"492\" src=\"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/09\/brivia-761x492.webp?resize=761%2C492&#038;ssl=1\" class=\"img-responsive wp-post-image\" alt=\"A Brivia est\u00e1 com vagas HOME OFFICE em aberto para Secret\u00e1rias Executivas\" decoding=\"async\" loading=\"lazy\"> <\/p>\n<div class=\"mask\"><\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/home-office\/\" rel=\"category tag noopener\" target=\"_blank\">Home Office<\/a><\/span>\n<\/div>\n<\/div>\n<div class=\"col-sm-6 gutter-left\">\n<div class=\"news-detail\">\n<h4 class=\"news-title big-news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/a-brivia-esta-com-vagas-home-office-em-aberto-para-secretarias-executivas\/\" target=\"_blank\" rel=\"noopener\">A Brivia est\u00e1 com vagas HOME OFFICE em aberto para Secret\u00e1rias Executivas<\/a><br \/>\n<\/h4>\n<div class=\"entry-meta\">\n<\/div>\n<div class=\"news-content\">\n<p>Somos inquietos, somos desbravadores e estamos em constante transforma\u00e7\u00e3o. Por isso, estamos na busca constante de crescimentos do nosso time com profissionais inovadores, que desafiam os limites e estejam preparados<\/p>\n<p><a href=\"https:\/\/www.capitalvagas.com.br\/a-brivia-esta-com-vagas-home-office-em-aberto-para-secretarias-executivas\/\" class=\"btn-more\" target=\"_blank\" rel=\"noopener\"><br \/>\nLeia mais <\/a>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"code-block code-block-3\" style=\"margin: 8px 0; clear: both;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4943055693750262\" crossorigin=\"anonymous\" type=\"6231116a22eecd06a8ca4b6f-text\/javascript\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-dn+7f+35-mv+vw\" data-ad-client=\"ca-pub-4943055693750262\" data-ad-slot=\"6748774866\"><\/ins><br \/>\n<script type=\"6231116a22eecd06a8ca4b6f-text\/javascript\">\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/div>\n<div class=\"archive-section-content\" id=\"post-38631\">\n<div class=\"row clearfix archive-news-content\">\n<div class=\"col-sm-6 gutter-right\">\n<div class=\"news-image\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/vaga-home-office-para-atendimento-ao-cliente-com-salario-de-ate-r-3-00000-r-65000-de-va-auxilio-home-office-de-r-23000\/\" target=\"_blank\" rel=\"noopener\"><br \/>\n<img data-recalc-dims=\"1\" width=\"761\" height=\"492\" src=\"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/09\/EFFECTI-761x492.webp?resize=761%2C492&#038;ssl=1\" class=\"img-responsive wp-post-image\" alt=\"Vaga Home Office para Atendimento ao Cliente com sal\u00e1rio de at\u00e9 R$ 3.000,00 + R$ 650,00 de VA + Aux\u00edlio Home Office de R$ 230,00\" decoding=\"async\" loading=\"lazy\"> <\/p>\n<div class=\"mask\"><\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/home-office\/\" rel=\"category tag noopener\" target=\"_blank\">Home Office<\/a><\/span>\n<\/div>\n<\/div>\n<div class=\"col-sm-6 gutter-left\">\n<div class=\"news-detail\">\n<h4 class=\"news-title big-news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/vaga-home-office-para-atendimento-ao-cliente-com-salario-de-ate-r-3-00000-r-65000-de-va-auxilio-home-office-de-r-23000\/\" target=\"_blank\" rel=\"noopener\">Vaga Home Office para Atendimento ao Cliente com sal\u00e1rio de at\u00e9 R$ 3.000,00 + R$ 650,00 de VA + Aux\u00edlio Home Office de R$ 230,00<\/a><br \/>\n<\/h4>\n<div class=\"entry-meta\">\n<\/div>\n<div class=\"news-content\">\n<p>Voc\u00ea se considera um inovador, gosta de desafios e criar solu\u00e7\u00f5es que realmente fazem a diferen\u00e7a? Valoriza a colabora\u00e7\u00e3o e a diversidade de ideias, sempre buscando o melhor para os<\/p>\n<p><a href=\"https:\/\/www.capitalvagas.com.br\/vaga-home-office-para-atendimento-ao-cliente-com-salario-de-ate-r-3-00000-r-65000-de-va-auxilio-home-office-de-r-23000\/\" class=\"btn-more\" target=\"_blank\" rel=\"noopener\"><br \/>\nLeia mais <\/a>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"code-block code-block-3\" style=\"margin: 8px 0; clear: both;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4943055693750262\" crossorigin=\"anonymous\" type=\"6231116a22eecd06a8ca4b6f-text\/javascript\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-dn+7f+35-mv+vw\" data-ad-client=\"ca-pub-4943055693750262\" data-ad-slot=\"6748774866\"><\/ins><br \/>\n<script type=\"6231116a22eecd06a8ca4b6f-text\/javascript\">\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/div>\n<div class=\"archive-section-content\" id=\"post-38627\">\n<div class=\"row clearfix archive-news-content\">\n<div class=\"col-sm-6 gutter-right\">\n<div class=\"news-image\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/10-vagas-home-office-com-salario-de-r-1-60000-para-atendente-de-telemarketing-empresa-fornece-equipamentos\/\" target=\"_blank\" rel=\"noopener\"><br \/>\n<img data-recalc-dims=\"1\" width=\"761\" height=\"492\" src=\"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/09\/Telemarketing-761x492.webp?resize=761%2C492&#038;ssl=1\" class=\"img-responsive wp-post-image\" alt=\"10 Vagas Home Office com Sal\u00e1rio de R$ 1.600,00 para Atendente de Telemarketing! Empresa fornece equipamentos\" decoding=\"async\" loading=\"lazy\"> <\/p>\n<div class=\"mask\"><\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/home-office\/\" rel=\"category tag noopener\" target=\"_blank\">Home Office<\/a><\/span>\n<\/div>\n<\/div>\n<div class=\"col-sm-6 gutter-left\">\n<div class=\"news-detail\">\n<h4 class=\"news-title big-news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/10-vagas-home-office-com-salario-de-r-1-60000-para-atendente-de-telemarketing-empresa-fornece-equipamentos\/\" target=\"_blank\" rel=\"noopener\">10 Vagas Home Office com Sal\u00e1rio de R$ 1.600,00 para Atendente de Telemarketing! Empresa fornece equipamentos<\/a><br \/>\n<\/h4>\n<div class=\"entry-meta\">\n<\/div>\n<div class=\"news-content\">\n<p>Com o crescimento do trabalho remoto, muitas empresas t\u00eam buscado profissionais capacitados para atender as demandas do mercado \u00e0 dist\u00e2ncia. E, se voc\u00ea est\u00e1 em busca de uma oportunidade para<\/p>\n<p><a href=\"https:\/\/www.capitalvagas.com.br\/10-vagas-home-office-com-salario-de-r-1-60000-para-atendente-de-telemarketing-empresa-fornece-equipamentos\/\" class=\"btn-more\" target=\"_blank\" rel=\"noopener\"><br \/>\nLeia mais <\/a>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"code-block code-block-3\" style=\"margin: 8px 0; clear: both;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4943055693750262\" crossorigin=\"anonymous\" type=\"6231116a22eecd06a8ca4b6f-text\/javascript\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-dn+7f+35-mv+vw\" data-ad-client=\"ca-pub-4943055693750262\" data-ad-slot=\"6748774866\"><\/ins><br \/>\n<script type=\"6231116a22eecd06a8ca4b6f-text\/javascript\">\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/div>\n<div class=\"archive-section-content\" id=\"post-38624\">\n<div class=\"row clearfix archive-news-content\">\n<div class=\"col-sm-6 gutter-right\">\n<div class=\"news-image\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/unimed-abriu-vaga-home-office-com-remuneracao-de-r-4-27150-e-alimentacao-de-r-80000-para-consultor-de-fidelizacao\/\" target=\"_blank\" rel=\"noopener\"><br \/>\n<img data-recalc-dims=\"1\" width=\"761\" height=\"492\" src=\"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/09\/AnyConv.com__UNIMED-V-761x492.webp?resize=761%2C492&#038;ssl=1\" class=\"img-responsive wp-post-image\" alt=\"Unimed abriu vaga Home Office com Remunera\u00e7\u00e3o de R$ 4.271,50 e Alimenta\u00e7\u00e3o de R$ 800,00 para Consultor de Fideliza\u00e7\u00e3o\" decoding=\"async\" loading=\"lazy\"> <\/p>\n<div class=\"mask\"><\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/home-office\/\" rel=\"category tag noopener\" target=\"_blank\">Home Office<\/a><\/span>\n<\/div>\n<\/div>\n<div class=\"col-sm-6 gutter-left\">\n<div class=\"news-detail\">\n<h4 class=\"news-title big-news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/unimed-abriu-vaga-home-office-com-remuneracao-de-r-4-27150-e-alimentacao-de-r-80000-para-consultor-de-fidelizacao\/\" target=\"_blank\" rel=\"noopener\">Unimed abriu vaga Home Office com Remunera\u00e7\u00e3o de R$ 4.271,50 e Alimenta\u00e7\u00e3o de R$ 800,00 para Consultor de Fideliza\u00e7\u00e3o<\/a><br \/>\n<\/h4>\n<div class=\"entry-meta\">\n<\/div>\n<div class=\"news-content\">\n<p>A Unimed Grande Florian\u00f3polis, a maior cooperativa de sa\u00fade de Santa Catarina, est\u00e1 com novas oportunidades de trabalho remoto para Consultor de Fideliza\u00e7\u00e3o. H\u00e1 mais de 50 anos, nos dedicamos<\/p>\n<p><a href=\"https:\/\/www.capitalvagas.com.br\/unimed-abriu-vaga-home-office-com-remuneracao-de-r-4-27150-e-alimentacao-de-r-80000-para-consultor-de-fidelizacao\/\" class=\"btn-more\" target=\"_blank\" rel=\"noopener\"><br \/>\nLeia mais <\/a>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"code-block code-block-3\" style=\"margin: 8px 0; clear: both;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4943055693750262\" crossorigin=\"anonymous\" type=\"6231116a22eecd06a8ca4b6f-text\/javascript\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-dn+7f+35-mv+vw\" data-ad-client=\"ca-pub-4943055693750262\" data-ad-slot=\"6748774866\"><\/ins><br \/>\n<script type=\"6231116a22eecd06a8ca4b6f-text\/javascript\">\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/div>\n<div class=\"archive-section-content\" id=\"post-38620\">\n<div class=\"row clearfix archive-news-content\">\n<div class=\"col-sm-6 gutter-right\">\n<div class=\"news-image\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/sem-experiencia-10-vagas-100-home-office-com-salario-de-r-2-50000-para-atendimento-ao-cliente-me\/\" target=\"_blank\" rel=\"noopener\"><br \/>\n<img data-recalc-dims=\"1\" width=\"761\" height=\"492\" src=\"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/09\/HOME-OFFICE-761x492.webp?resize=761%2C492&#038;ssl=1\" class=\"img-responsive wp-post-image\" alt=\"Sem experi\u00eancia! 10 Vagas 100% Home Office com sal\u00e1rio de R$ 2.500,00 para Atendimento ao Cliente (ME)\" decoding=\"async\" loading=\"lazy\"> <\/p>\n<div class=\"mask\"><\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/home-office\/\" rel=\"category tag noopener\" target=\"_blank\">Home Office<\/a><\/span>\n<\/div>\n<\/div>\n<div class=\"col-sm-6 gutter-left\">\n<div class=\"news-detail\">\n<h4 class=\"news-title big-news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/sem-experiencia-10-vagas-100-home-office-com-salario-de-r-2-50000-para-atendimento-ao-cliente-me\/\" target=\"_blank\" rel=\"noopener\">Sem experi\u00eancia! 10 Vagas 100% Home Office com sal\u00e1rio de R$ 2.500,00 para Atendimento ao Cliente (ME)<\/a><br \/>\n<\/h4>\n<div class=\"entry-meta\">\n<\/div>\n<div class=\"news-content\">\n<p>Voc\u00ea est\u00e1 em busca de uma oportunidade para trabalhar de casa, com flexibilidade de hor\u00e1rios, excelente remunera\u00e7\u00e3o e possibilidade de crescimento? Ent\u00e3o essa vaga \u00e9 para voc\u00ea! Estamos recrutando 10<\/p>\n<p><a href=\"https:\/\/www.capitalvagas.com.br\/sem-experiencia-10-vagas-100-home-office-com-salario-de-r-2-50000-para-atendimento-ao-cliente-me\/\" class=\"btn-more\" target=\"_blank\" rel=\"noopener\"><br \/>\nLeia mais <\/a>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"code-block code-block-3\" style=\"margin: 8px 0; clear: both;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4943055693750262\" crossorigin=\"anonymous\" type=\"6231116a22eecd06a8ca4b6f-text\/javascript\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-dn+7f+35-mv+vw\" data-ad-client=\"ca-pub-4943055693750262\" data-ad-slot=\"6748774866\"><\/ins><br \/>\n<script type=\"6231116a22eecd06a8ca4b6f-text\/javascript\">\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/div>\n<div class=\"archive-section-content\" id=\"post-38618\">\n<div class=\"row clearfix archive-news-content\">\n<div class=\"col-sm-6 gutter-right\">\n<div class=\"news-image\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/operadora-vivo-abre-vagas-home-office-para-atendentes-online\/\" target=\"_blank\" rel=\"noopener\">\n<picture><source srcset=\"https:\/\/www.capitalvagas.com.br\/wp-content\/webp-express\/webp-images\/doc-root\/wp-content\/uploads\/2023\/06\/VIVO-HOME-OFFICE-761x492.png.webp\" type=\"image\/webp\"><img data-recalc-dims=\"1\" width=\"761\" height=\"492\" src=\"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2023\/06\/VIVO-HOME-OFFICE-761x492.png?resize=761%2C492&#038;ssl=1\" class=\"img-responsive wp-post-image webpexpress-processed\" alt=\"Operadora Vivo abre vagas Home Office para Atendentes Online!\" decoding=\"async\" loading=\"lazy\"><\/source><\/picture>\n<div class=\"mask\"><\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/home-office\/\" rel=\"category tag noopener\" target=\"_blank\">Home Office<\/a><\/span>\n<\/div>\n<\/div>\n<div class=\"col-sm-6 gutter-left\">\n<div class=\"news-detail\">\n<h4 class=\"news-title big-news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/operadora-vivo-abre-vagas-home-office-para-atendentes-online\/\" target=\"_blank\" rel=\"noopener\">Operadora Vivo abre vagas Home Office para Atendentes Online!<\/a><br \/>\n<\/h4>\n<div class=\"entry-meta\">\n<\/div>\n<div class=\"news-content\">\n<p>A Vivo est\u00e1 em busca de profissionais apaixonados por desafios e com um esp\u00edrito de dono para fazer parte da transforma\u00e7\u00e3o digital que aproxima milh\u00f5es de clientes. Com mais de<\/p>\n<p><a href=\"https:\/\/www.capitalvagas.com.br\/operadora-vivo-abre-vagas-home-office-para-atendentes-online\/\" class=\"btn-more\" target=\"_blank\" rel=\"noopener\"><br \/>\nLeia mais <\/a>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"code-block code-block-3\" style=\"margin: 8px 0; clear: both;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4943055693750262\" crossorigin=\"anonymous\" type=\"6231116a22eecd06a8ca4b6f-text\/javascript\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-dn+7f+35-mv+vw\" data-ad-client=\"ca-pub-4943055693750262\" data-ad-slot=\"6748774866\"><\/ins><br \/>\n<script type=\"6231116a22eecd06a8ca4b6f-text\/javascript\">\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/div>\n<div class=\"archive-section-content\" id=\"post-38616\">\n<div class=\"row clearfix archive-news-content\">\n<div class=\"col-sm-6 gutter-right\">\n<div class=\"news-image\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/2com-consulting-abre-vagas-home-office-oferecendo-notebook-e-celular-corporativo-para-analista-de-noc-nivel-2\/\" target=\"_blank\" rel=\"noopener\"><br \/>\n<img data-recalc-dims=\"1\" width=\"761\" height=\"492\" src=\"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2023\/09\/2com-761x492.webp?resize=761%2C492&#038;ssl=1\" class=\"img-responsive wp-post-image\" alt=\"2Com Consulting abre vagas Home Office oferecendo Notebook e celular corporativo para Analista de NOC N\u00edvel 2\" decoding=\"async\" loading=\"lazy\"> <\/p>\n<div class=\"mask\"><\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/home-office\/\" rel=\"category tag noopener\" target=\"_blank\">Home Office<\/a><\/span>\n<\/div>\n<\/div>\n<div class=\"col-sm-6 gutter-left\">\n<div class=\"news-detail\">\n<h4 class=\"news-title big-news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/2com-consulting-abre-vagas-home-office-oferecendo-notebook-e-celular-corporativo-para-analista-de-noc-nivel-2\/\" target=\"_blank\" rel=\"noopener\">2Com Consulting abre vagas Home Office oferecendo Notebook e celular corporativo para Analista de NOC N\u00edvel 2<\/a><br \/>\n<\/h4>\n<div class=\"entry-meta\">\n<\/div>\n<div class=\"news-content\">\n<p>Se voc\u00ea est\u00e1 buscando uma oportunidade de trabalho remoto, a 2com Consulting oferece uma excelente vaga para Analista de NOC N\u00edvel 2, uma posi\u00e7\u00e3o 100% home office que valoriza o<\/p>\n<p><a href=\"https:\/\/www.capitalvagas.com.br\/2com-consulting-abre-vagas-home-office-oferecendo-notebook-e-celular-corporativo-para-analista-de-noc-nivel-2\/\" class=\"btn-more\" target=\"_blank\" rel=\"noopener\"><br \/>\nLeia mais <\/a>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"code-block code-block-3\" style=\"margin: 8px 0; clear: both;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4943055693750262\" crossorigin=\"anonymous\" type=\"6231116a22eecd06a8ca4b6f-text\/javascript\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-dn+7f+35-mv+vw\" data-ad-client=\"ca-pub-4943055693750262\" data-ad-slot=\"6748774866\"><\/ins><br \/>\n<script type=\"6231116a22eecd06a8ca4b6f-text\/javascript\">\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/div>\n<div class=\"archive-section-content\" id=\"post-38612\">\n<div class=\"row clearfix archive-news-content\">\n<div class=\"col-sm-6 gutter-right\">\n<div class=\"news-image\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/sem-experiencia-la-moda-anuncia-vaga-home-office-para-assistente-de-sac\/\" target=\"_blank\" rel=\"noopener\"><br \/>\n<img data-recalc-dims=\"1\" width=\"761\" height=\"492\" src=\"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/09\/LA-MODA-761x492.webp?resize=761%2C492&#038;ssl=1\" class=\"img-responsive wp-post-image\" alt=\"Sem experi\u00eancia! La Moda anuncia vaga Home Office para Assistente de SAC!\" decoding=\"async\" loading=\"lazy\"> <\/p>\n<div class=\"mask\"><\/div>\n<p><\/a><br \/>\n<span class=\"cat-links\"><a href=\"https:\/\/www.capitalvagas.com.br\/home-office\/\" rel=\"category tag noopener\" target=\"_blank\">Home Office<\/a><\/span>\n<\/div>\n<\/div>\n<div class=\"col-sm-6 gutter-left\">\n<div class=\"news-detail\">\n<h4 class=\"news-title big-news-title\">\n<a href=\"https:\/\/www.capitalvagas.com.br\/sem-experiencia-la-moda-anuncia-vaga-home-office-para-assistente-de-sac\/\" target=\"_blank\" rel=\"noopener\">Sem experi\u00eancia! La Moda anuncia vaga Home Office para Assistente de SAC!<\/a><br \/>\n<\/h4>\n<div class=\"entry-meta\">\n<\/div>\n<div class=\"news-content\">\n<p>A La Moda est\u00e1 em busca de profissionais para a vaga de Assistente de SAC, com modelo de trabalho home office. Se voc\u00ea deseja fazer parte de uma empresa inovadora,<\/p>\n<p><a href=\"https:\/\/www.capitalvagas.com.br\/sem-experiencia-la-moda-anuncia-vaga-home-office-para-assistente-de-sac\/\" class=\"btn-more\" target=\"_blank\" rel=\"noopener\"><br \/>\nLeia mais <\/a>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"col-sm-12\">\n<nav class=\"navigation pagination\" aria-label=\"Posts\">\n<h2 class=\"screen-reader-text\">Navega\u00e7\u00e3o por posts<\/h2>\n<div class=\"nav-links\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span><br \/>\n<a class=\"page-numbers\" href=\"https:\/\/www.capitalvagas.com.br\/page\/2\/\" target=\"_blank\" rel=\"noopener\">2<\/a><br \/>\n<a class=\"page-numbers\" href=\"https:\/\/www.capitalvagas.com.br\/page\/3\/\" target=\"_blank\" rel=\"noopener\">3<\/a><br \/>\n<span class=\"page-numbers dots\">\u2026<\/span><br \/>\n<a class=\"page-numbers\" href=\"https:\/\/www.capitalvagas.com.br\/page\/50\/\" target=\"_blank\" rel=\"noopener\">50<\/a><br \/>\n<a class=\"next page-numbers\" href=\"https:\/\/www.capitalvagas.com.br\/page\/2\/\" target=\"_blank\" rel=\"noopener\">\u00bb<\/a><\/div>\n<\/nav><\/div>\n<\/div>\n<\/div>\n<div class=\"col-md-4 royale-news-sidebar sticky-section\">\n<div class=\"row clearfix sidebar\">\n<div id=\"search-2\" class=\"col-md-12 widget widget_search\">\n<form method=\"get\" class=\"search-form\" action=\"https:\/\/www.capitalvagas.com.br\/\">\n<div class=\"input-group stylish-input-group\"><label class=\"screen-reader-text\" for=\"s\">Pesquisar por:<\/label><input type=\"text\" value name=\"s\" class=\"form-control\"><span class=\"input-group-addon\"><button type=\"submit\" id=\"searchsubmit\" value=\"Pesquisar\"><i class=\"fa fa-search\"><\/i><\/button><\/span><\/div>\n<\/form>\n<\/div>\n<div id=\"media_image-9\" class=\"col-md-12 widget widget_media_image\">\n<div class=\"widget-info clearfix\">\n<h3 class=\"widget-title\">MELHORAR CURSO PARA HOME OFFICE<\/h3>\n<\/div>\n<p><a href=\"https:\/\/horadoscursos.portalje.org\/\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" width=\"576\" height=\"1024\" src=\"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Portal-JE-Cursos-576x1024.webp?resize=576%2C1024&#038;ssl=1\" class=\"image wp-image-38510  attachment-large size-large\" alt style=\"max-width: 100%; height: auto;\" title=\"MELHORAR CURSO PARA HOME OFFICE\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Portal-JE-Cursos-576x1024.webp 576w, https:\/\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Portal-JE-Cursos-169x300.webp 169w, https:\/\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Portal-JE-Cursos-768x1365.webp 768w, https:\/\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Portal-JE-Cursos-720x1280.webp 720w, https:\/\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Portal-JE-Cursos-864x1536.webp 864w, https:\/\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Portal-JE-Cursos-150x267.webp 150w, https:\/\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Portal-JE-Cursos.webp 1080w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\"><\/a><\/div>\n<div id=\"custom_html-5\" class=\"widget_text col-md-12 widget widget_custom_html\">\n<div class=\"textwidget custom-html-widget\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4943055693750262\" crossorigin=\"anonymous\" type=\"6231116a22eecd06a8ca4b6f-text\/javascript\"><\/script><\/p>\n<p><ins class=\"adsbygoogle\" style=\"display:block\" data-ad-client=\"ca-pub-4943055693750262\" data-ad-slot=\"2932818786\" data-ad-format=\"auto\" data-full-width-responsive=\"true\"><\/ins><br \/>\n<script type=\"6231116a22eecd06a8ca4b6f-text\/javascript\">\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><\/main><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>Home Office Instituto Infnet abriu vaga HOME OFFICE para Auxiliar de Suporte Acad\u00eamico com sal\u00e1rio de R$\u00a01.412,00 mil Home Office Aten\u00e7\u00e3o! Buscando emprego Home Office? A Riachuelo est\u00e1 com vagas abertas para Assistente Cont\u00e1bil Home Office A Brivia est\u00e1 com vagas HOME OFFICE em aberto para Secret\u00e1rias Executivas Home Office Vaga Home Office para Atendimento &#8230; <a title=\"Confira as novas vagas de emprego para trabalhar de casa. Trabalho home office, com sal\u00e1rios de 1.500 at\u00e9 3 mil, clique e confira agora\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/27\/confira-as-novas-vagas-de-emprego-para-trabalhar-de-casa-trabalho-home-office-com-salarios-de-1-500-ate-3-mil-clique-e-confira-agora-84\/\" aria-label=\"Leia mais sobre Confira as novas vagas de emprego para trabalhar de casa. Trabalho home office, com sal\u00e1rios de 1.500 at\u00e9 3 mil, clique e confira agora\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-68240","post","type-post","status-publish","format-standard","hentry","category-vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto"],"jetpack_featured_media_url":"","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"Home Office Instituto Infnet abriu vaga HOME OFFICE para Auxiliar de Suporte Acad\u00eamico com sal\u00e1rio de R$\u00a01.412,00 mil Home Office Aten\u00e7\u00e3o! Buscando emprego Home Office? A Riachuelo est\u00e1 com vagas abertas para Assistente Cont\u00e1bil Home Office A Brivia est\u00e1 com vagas HOME OFFICE em aberto para Secret\u00e1rias Executivas Home Office Vaga Home Office para Atendimento&hellip;","jetpack-related-posts":[{"id":57926,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/25\/confira-as-novas-vagas-de-emprego-para-trabalhar-de-casa-trabalho-home-office-com-salarios-de-1-500-ate-3-mil-clique-e-confira-agora-20\/","url_meta":{"origin":68240,"position":0},"title":"Confira as novas vagas de emprego para trabalhar de casa. Trabalho home office, com sal\u00e1rios de 1.500 at\u00e9 3 mil, clique e confira agora","author":"ismaelcolosi.com.br","date":"25 de Julho de 2024","format":false,"excerpt":"Home Office Sem experi\u00eancia! Atendente para Suporte ao Cliente HOME OFFICE com Sal\u00e1rio de R$ 1.898,00 MIL Home Office Banco Sicoob abre vagas Home Office com sal\u00e1rio de R$ 2.101 por m\u00eas para Assistente de Produtos de Cr\u00e9dito Home Office Auxiliar Administrativo 100% Home Office na Portus Digital com sal\u00e1rio\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"Sem experi\u00eancia! Atendente para Suporte ao Cliente HOME OFFICE com Sal\u00e1rio de R$ 1.898,00 MIL","src":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/07\/home-office-1-761x492.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/07\/home-office-1-761x492.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/07\/home-office-1-761x492.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/07\/home-office-1-761x492.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":57190,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/18\/confira-as-novas-vagas-de-emprego-para-trabalhar-de-casa-trabalho-home-office-com-salarios-de-1-500-ate-3-mil-clique-e-confira-agora-18\/","url_meta":{"origin":68240,"position":1},"title":"Confira as novas vagas de emprego para trabalhar de casa. Trabalho home office, com sal\u00e1rios de 1.500 at\u00e9 3 mil, clique e confira agora","author":"ismaelcolosi.com.br","date":"18 de Julho de 2024","format":false,"excerpt":"Home Office Trabalhe de Casa! Grupo Elo abre vagas HOME OFFICE para responder chat e e-mail Online Diretamente de Casa! Home Office Grupo botic\u00e1rio anuncia vaga HOME OFFICE com sal\u00e1rio 2 MIL para Assistente Administrativo Home Office Oferecendo at\u00e9 Equipamento para HOME OFFICE a Gran Cursos contrata Analista de Qualidade\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"Trabalhe de Casa! Grupo Elo abre vagas HOME OFFICE para responder chat e e-mail Online Diretamente de Casa!","src":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/07\/home-office-761x492.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/07\/home-office-761x492.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/07\/home-office-761x492.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/07\/home-office-761x492.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":59186,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/06\/confira-as-novas-vagas-de-emprego-para-trabalhar-de-casa-trabalho-home-office-com-salarios-de-1-500-ate-3-mil-clique-e-confira-agora-32\/","url_meta":{"origin":68240,"position":2},"title":"Confira as novas vagas de emprego para trabalhar de casa. Trabalho home office, com sal\u00e1rios de 1.500 at\u00e9 3 mil, clique e confira agora","author":"ismaelcolosi.com.br","date":"6 de Agosto de 2024","format":false,"excerpt":"Home Office Home Office: Atlas abre vagas 100% REMOTAS para Assistente de Atendimento com Sal\u00e1rio de R$ 1.838,69 Home Office ChatGuru abre vagas HOME OFFICE para Assistente de Backoffice com Sal\u00e1rio de R$ 2.200,00 Home Office Sem experi\u00eancia! ENVEST abre vagas para Atendimento ao Cliente Freelancer com sal\u00e1rios de R$\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"Home Office: Atlas abre vagas 100% REMOTAS para Assistente de Atendimento com Sal\u00e1rio de R$ 1.838,69","src":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/ATLAS-761x492.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/ATLAS-761x492.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/ATLAS-761x492.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/ATLAS-761x492.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":57667,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/23\/confira-as-novas-vagas-de-emprego-para-trabalhar-de-casa-trabalho-home-office-com-salarios-de-1-500-ate-3-mil-clique-e-confira-agora-19\/","url_meta":{"origin":68240,"position":3},"title":"Confira as novas vagas de emprego para trabalhar de casa. Trabalho home office, com sal\u00e1rios de 1.500 at\u00e9 3 mil, clique e confira agora","author":"ismaelcolosi.com.br","date":"23 de Julho de 2024","format":false,"excerpt":"Home Office Banco Sicoob abre vagas Home Office com sal\u00e1rio de R$ 2.101 por m\u00eas para Assistente de Produtos de Cr\u00e9dito Home Office Auxiliar Administrativo 100% Home Office na Portus Digital com sal\u00e1rio de R$ 1.700 mil Home Office Teleperformance anuncia 50 Vagas 100% Home Office para Atendente de E-commerce\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"Banco Sicoob abre vagas Home Office com sal\u00e1rio de R$ 2.101 por m\u00eas para Assistente de Produtos de Cr\u00e9dito","src":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/07\/SICOOB-HOME-OFFICE-1-761x492.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/07\/SICOOB-HOME-OFFICE-1-761x492.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/07\/SICOOB-HOME-OFFICE-1-761x492.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/07\/SICOOB-HOME-OFFICE-1-761x492.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":59058,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/05\/confira-as-novas-vagas-de-emprego-para-trabalhar-de-casa-trabalho-home-office-com-salarios-de-1-500-ate-3-mil-clique-e-confira-agora-31\/","url_meta":{"origin":68240,"position":4},"title":"Confira as novas vagas de emprego para trabalhar de casa. Trabalho home office, com sal\u00e1rios de 1.500 at\u00e9 3 mil, clique e confira agora","author":"ismaelcolosi.com.br","date":"5 de Agosto de 2024","format":false,"excerpt":"Home Office Sem experi\u00eancia! ENVEST abre vagas para Atendimento ao Cliente Freelancer com sal\u00e1rios de R$ 2.000 a R$ 3.000 mil Home Office Trabalhe de Casa! C&A abriu vagas HOME OFFICE para Especialista de Risco e Modelagem Home Office Emprego Remoto! BHS abre vagas HOME OFFICE para Assistente Administrativo Tempor\u00e1rio\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"Sem experi\u00eancia! ENVEST abre vagas para Atendimento ao Cliente Freelancer com sal\u00e1rios de R$ 2.000 a R$ 3.000 mil","src":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/ENVEST-761x492.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/ENVEST-761x492.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/ENVEST-761x492.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/ENVEST-761x492.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":72699,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/23\/confira-as-novas-vagas-de-emprego-para-trabalhar-de-casa-trabalho-home-office-com-salarios-de-1-500-ate-3-mil-clique-e-confira-agora-109\/","url_meta":{"origin":68240,"position":5},"title":"Confira as novas vagas de emprego para trabalhar de casa. Trabalho home office, com sal\u00e1rios de 1.500 at\u00e9 3 mil, clique e confira agora","author":"ismaelcolosi.com.br","date":"23 de Outubro de 2024","format":false,"excerpt":"Home Office Sem experi\u00eancia! Sem Parar abre vagas HOME OFFICE com sal\u00e1rio de R$ 2 mil PARA Assistente de Vendas das 10h \u00e0s 18h30 Home Office Gran Cursos acaba de anuncia vagas Home Office para Assistente Administrativo e oferece at\u00e9 Equipamentos Home Office DOC9 abriu vaga Imediata para Home Office\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"Ganhe at\u00e9 R$ 2500,00 por m\u00eas! ySense Brasil abre novas vagas para Pesquisadores Online com pagamentos em D\u00f3lares ou Euros; Veja como funciona","src":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.capitalvagas.com.br\/wp-content\/uploads\/2024\/08\/Ysense-761x492.webp?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-hKE","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/68240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=68240"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/68240\/revisions"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=68240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=68240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=68240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}