{"id":68108,"date":"2024-09-27T10:14:25","date_gmt":"2024-09-27T13:14:25","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/27\/veja-os-bairros-em-alerta-para-falta-dagua-nesta-sexta-em-ribeirao-preto-2\/"},"modified":"2024-09-27T10:14:25","modified_gmt":"2024-09-27T13:14:25","slug":"veja-os-bairros-em-alerta-para-falta-dagua-nesta-sexta-em-ribeirao-preto-2","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/27\/veja-os-bairros-em-alerta-para-falta-dagua-nesta-sexta-em-ribeirao-preto-2\/","title":{"rendered":"Veja os bairros em alerta para falta d\u2019\u00e1gua nesta sexta em Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p><strong>A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou que realiza <strong>nesta sexta-feira (27)<\/strong> a troca emergencial da bomba no Po\u00e7o Cadacaan, o que pode causar faltar d\u2019\u00e1gua em bairros das regi\u00f5es Leste e Norte da cidade.<\/strong><\/p>\n<h4 class=\"wp-block-heading\"><strong>Veja os bairros em alerta:<\/strong><\/h4>\n<ul>\n<li>Parte dos Campos El\u00edseos<\/li>\n<\/ul>\n<p>Ainda conforme a Saerp, a previs\u00e3o de t\u00e9rmino do servi\u00e7o \u00e9 hoje, \u00e0s 22h.<\/p>\n<p>Ap\u00f3s a conclus\u00e3o, a Saerp diz que o sistema dever\u00e1 ser religado e o abastecimento voltar\u00e1 de forma gradativa.<\/p>\n<h4 class=\"wp-block-heading\"><strong>O que fazer?\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/h4>\n<p>Caso o seu bairro apresente falhas no abastecimento, entre em contato com a\u00a0<strong>Saerp<\/strong>\u00a0pelo telefone 0800 115 0115 ou procure por um posto de atendimento (<a href=\"https:\/\/www.ribeiraopreto.sp.gov.br\/portal\/saerp\/postos-de-atendimento\" target=\"_blank\" rel=\"noreferrer noopener\">clique aqui<\/a>).<\/p>\n<p>SAIBA MAIS<\/p>\n<p>Interior de SP segue com alerta de perigo para tempestade; Veja regi\u00f5es<\/p>\n<p><strong>FIQUE ON<\/strong><\/p>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on<\/strong>\u00a0no WhatsApp. Para entrar no grupo, basta\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Dtv9mxhy6V5BJBotM2OQ5k\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Quantas ondas de calor teve no Brasil esse ano?<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/veja-os-bairros-em-alerta-para-falta-dagua-nesta-sexta-em-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou que realiza nesta sexta-feira (27) a troca emergencial da bomba no Po\u00e7o Cadacaan, o que pode causar faltar d\u2019\u00e1gua em bairros das regi\u00f5es Leste e Norte da cidade. Veja os bairros em alerta: Parte dos Campos El\u00edseos Ainda conforme a Saerp, a previs\u00e3o &#8230; <a title=\"Veja os bairros em alerta para falta d\u2019\u00e1gua nesta sexta em Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/27\/veja-os-bairros-em-alerta-para-falta-dagua-nesta-sexta-em-ribeirao-preto-2\/\" aria-label=\"Leia mais sobre Veja os bairros em alerta para falta d\u2019\u00e1gua nesta sexta em Ribeir\u00e3o Preto\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":68109,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-68108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727442866_torneira_falta_1024x576_08122020103237.jpg?fit=1024%2C576&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727442866_torneira_falta_1024x576_08122020103237.jpg?fit=1024%2C576&ssl=1",1024,576,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727442866_torneira_falta_1024x576_08122020103237.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727442866_torneira_falta_1024x576_08122020103237.jpg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727442866_torneira_falta_1024x576_08122020103237.jpg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727442866_torneira_falta_1024x576_08122020103237.jpg?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727442866_torneira_falta_1024x576_08122020103237.jpg?fit=1024%2C576&ssl=1",1024,576,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727442866_torneira_falta_1024x576_08122020103237.jpg?fit=1024%2C576&ssl=1",1024,576,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou que realiza nesta sexta-feira (27) a troca emergencial da bomba no Po\u00e7o Cadacaan, o que pode causar faltar d\u2019\u00e1gua em bairros das regi\u00f5es Leste e Norte da cidade. Veja os bairros em alerta: Parte dos Campos El\u00edseos Ainda conforme a Saerp, a previs\u00e3o&hellip;","jetpack-related-posts":[{"id":68097,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/27\/veja-os-bairros-em-alerta-para-falta-dagua-nesta-sexta-em-ribeirao-preto\/","url_meta":{"origin":68108,"position":0},"title":"Veja os bairros em alerta para falta d\u2019\u00e1gua nesta sexta em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"27 de Setembro de 2024","format":false,"excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou que realiza nesta sexta-feira (27) a troca emergencial da bomba no Po\u00e7o Cadacaan, o que pode causar faltar d\u2019\u00e1gua em bairros das regi\u00f5es Leste e Norte da cidade. Veja os bairros em alerta: Parte dos Campos El\u00edseos Ainda\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727440078_torneira_falta_1024x576_08122020103237.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727440078_torneira_falta_1024x576_08122020103237.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727440078_torneira_falta_1024x576_08122020103237.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1727440078_torneira_falta_1024x576_08122020103237.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":62972,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/30\/saerp-alerta-para-falta-dagua-em-ribeirao-preto-veja-os-bairros-afetados\/","url_meta":{"origin":68108,"position":1},"title":"Saerp alerta para falta d\u2019\u00e1gua em Ribeir\u00e3o Preto; Veja os bairros afetados","author":"ismaelcolosi.com.br","date":"30 de Agosto de 2024","format":false,"excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou que tr\u00eas bairros da zona Oeste de Ribeir\u00e3o Preto podem ficar sem \u00e1gua nesta sexta-feira (30) por conta de um reparo emergencial na rede. O servi\u00e7o est\u00e1 sendo realizado na rua Geni Maria Alves. Por conta disso, o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1725021306_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1725021306_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1725021306_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1725021306_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1725021306_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":70518,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/11\/saerp-alerta-para-falta-dagua-em-oito-bairros-de-ribeirao-preto-veja-onde\/","url_meta":{"origin":68108,"position":2},"title":"Saerp alerta para falta d&#8217;\u00e1gua em oito bairros de Ribeir\u00e3o Preto; Veja onde","author":"ismaelcolosi.com.br","date":"11 de Outubro de 2024","format":false,"excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou nesta sexta-feira (11) que oito bairros de Ribeir\u00e3o Preto podem apresentar falta d\u2019\u00e1gua. De acordo com a secretaria, o Po\u00e7o Ribeirania IV est\u00e1 paralisado devido a uma queda de energia, o que pode gerar falhas no abastecimento dos\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15_2024-07-10_14-38-39_jpg_2024-07-10_14-38-39.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15_2024-07-10_14-38-39_jpg_2024-07-10_14-38-39.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15_2024-07-10_14-38-39_jpg_2024-07-10_14-38-39.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15_2024-07-10_14-38-39_jpg_2024-07-10_14-38-39.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15_2024-07-10_14-38-39_jpg_2024-07-10_14-38-39.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":66975,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/20\/ribeirao-preto-tem-alerta-para-falta-dagua-veja-os-locais-afetados\/","url_meta":{"origin":68108,"position":3},"title":"Ribeir\u00e3o Preto tem alerta para falta d&#8217;\u00e1gua; Veja os locais afetados","author":"ismaelcolosi.com.br","date":"20 de Setembro de 2024","format":false,"excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou nesta sexta-feira (20) que bairros na regi\u00e3o de Bonfim Paulista e no Centro de Ribeir\u00e3o Preto est\u00e3o em alerta para falta d\u2019\u00e1gua. Segundo a secretaria, est\u00e1 sendo feito dois reparos emergenciais de rede na cidade, sendo uma em\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-06-17_15-27-00.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-06-17_15-27-00.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-06-17_15-27-00.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-06-17_15-27-00.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-06-17_15-27-00.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":62823,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/29\/saerp-alerta-para-falta-dagua-em-bairros-da-zona-norte-de-ribeirao-veja-quais\/","url_meta":{"origin":68108,"position":4},"title":"Saerp alerta para falta d&#8217;\u00e1gua em bairros da zona Norte de Ribeir\u00e3o; Veja quais","author":"ismaelcolosi.com.br","date":"29 de Agosto de 2024","format":false,"excerpt":"[ad_1] A Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto (Saerp) emitiu um novo alerta para falta d\u2019\u00e1gua em bairros na zona Norte do munic\u00edpio, nesta quinta-feira (29). Conforme o comunicado, equipes est\u00e3o realizando uma interliga\u00e7\u00e3o de rede no Po\u00e7o Vila Tecnol\u00f3gica, com o intuito da a\u00e7\u00e3o \u00e9 melhorar o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-24_2024-07-16_12-53-45_jpg_2024-07-16_12-53-45.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-24_2024-07-16_12-53-45_jpg_2024-07-16_12-53-45.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-24_2024-07-16_12-53-45_jpg_2024-07-16_12-53-45.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-24_2024-07-16_12-53-45_jpg_2024-07-16_12-53-45.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-24_2024-07-16_12-53-45_jpg_2024-07-16_12-53-45.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":71617,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/17\/saerp-alerta-para-falta-dagua-em-bairros-de-ribeirao-preto-veja-onde\/","url_meta":{"origin":68108,"position":5},"title":"Saerp alerta para falta d\u2019\u00e1gua em bairros de Ribeir\u00e3o Preto; Veja onde","author":"ismaelcolosi.com.br","date":"17 de Outubro de 2024","format":false,"excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou nesta quinta-feira (17) que cinco bairros de Ribeir\u00e3o Preto podem apresentar falta d\u2019\u00e1gua. De acordo com a secretaria, uma equipe realiza uma substitui\u00e7\u00e3o de bomba do po\u00e7o Clubinho, que tem o objetivo de aumentar a produ\u00e7\u00e3o de \u00e1gua\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1729170142_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1729170142_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1729170142_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1729170142_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/1729170142_Vejaosbairrosquepodemterfaltadguapor3diasnazonaLestedeRibeiroPreto_Tamanho_2_image-1-1.png?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-hIw","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/68108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=68108"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/68108\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/68109"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=68108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=68108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=68108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}