{"id":68041,"date":"2024-09-26T18:21:27","date_gmt":"2024-09-26T21:21:27","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/26\/tarifa-zero-e-dobrar-numero-de-guardas-veja-as-promessas-de-jorge-roque-para-ribeirao-preto\/"},"modified":"2024-09-26T18:21:27","modified_gmt":"2024-09-26T21:21:27","slug":"tarifa-zero-e-dobrar-numero-de-guardas-veja-as-promessas-de-jorge-roque-para-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/26\/tarifa-zero-e-dobrar-numero-de-guardas-veja-as-promessas-de-jorge-roque-para-ribeirao-preto\/","title":{"rendered":"Tarifa zero e dobrar n\u00famero de Guardas: Veja as promessas de Jorge Roque para Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<p><iframe title=\"Entrevista com o candidato \u00e0 Prefeitura de Ribeir\u00e3o Preto Jorge Roque (PT)\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/9Z1HQB6tdpo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/div>\n<\/figure>\n<p>O <strong>acidade on Ribeir\u00e3o<\/strong> realiza nesta semana uma s\u00e9rie de entrevistas com os candidatos \u00e0 <strong>Prefeitura de Ribeir\u00e3o Preto<\/strong> nas <strong>elei\u00e7\u00f5es 2024<\/strong>. Nesta quinta-feira (26) o entrevistado foi o advogado <strong>Jorge Roque (PT)<\/strong> \u2013 veja o player acima.<\/p>\n<p>Jorge Roque \u00e9 candidato pela coliga\u00e7\u00e3o Amor Por Ribeir\u00e3o, formada pela Federa\u00e7\u00e3o Brasil da Esperan\u00e7a (PT, PC do B\/PV), Federa\u00e7\u00e3o PSOL\/Rede, e pelo PMB. A candidata a vice na chapa \u00e9 Artemizia Torres, do PSOL.<\/p>\n<p>A ordem dos entrevistados foi definida de acordo com o resultado pesquisa estimulada <strong>EPTV\/Quaest (SP-07293\/2024)<\/strong> divulgada no dia de 18 setembro. Foram convidados os quatro primeiros colocados, que ser\u00e3o sabatinados ao vivo por 12 minutos. O candidato do DC, Matheus Coelho, que entrou na disputa ap\u00f3s a pesquisa eleitoral, ter\u00e1 veiculada entrevista de 2 minutos.<\/p>\n<p><strong>No transporte p\u00fablico, o senhor quer implantar a tarifa zero de forma gradual. Quem seria beneficiado no in\u00edcio e de onde viriam os recursos?<\/strong><\/p>\n<ul>\n<li> Quem seria beneficiado, seria a cidade inteira. Porque, se a popula\u00e7\u00e3o n\u00e3o tiver que gastar com transporte, ela vai gastar com com\u00e9rcio, ela vai poder gastar com o lazer, com cultura. N\u00f3s vamos ter menos carros circulando na cidade, porque isso vai direcionar pessoas para o transporte p\u00fablico. A gente sabe que j\u00e1 tem 116 cidades no Brasil que implementaram a tarifa zero. E, isso, d\u00e1 um enorme incremento no n\u00famero de passageiros. Ent\u00e3o, a cidade como um todo que \u00e9 beneficiada, principalmente se n\u00f3s substituirmos a frota movida a diesel por ve\u00edculos movidos \u00e0 energia limpa, que \u00e9 a nossa proposta, tamb\u00e9m. No nosso caso, n\u00f3s n\u00e3o estamos nem falando de ve\u00edculos el\u00e9tricos somente, mas do hidrog\u00eanio verde. De \u00f4nibus movidos a hidrog\u00eanio verde, que \u00e9 uma energia ainda mais limpa. Portanto, ela beneficia a cidade como um todo. De onde vai sair o recurso? Tem diversos modelos. Eu gosto muito de um que e o empregador, ao inv\u00e9s de pagar diretamente ao funcion\u00e1rio o vale transporte, se cria um fundo municipal. L\u00e1 tem esse dep\u00f3sito de recursos e esse fundo que viabiliza a tarifa zero. \u00c9 um modelo que eu gosto. \u00c9 um dos modelos que foram implementados no Pa\u00eds e voc\u00ea n\u00e3o onera mais ainda o cofre municipal.<\/li>\n<\/ul>\n<p><strong>Em um eventual governo do senhor a tarifa zero j\u00e1 seria liberada para todas as pessoas?<\/strong><\/p>\n<ul>\n<li>N\u00f3s faremos de forma gradual. Come\u00e7aremos com um dia, aberto para toda a popula\u00e7\u00e3o, e depois n\u00f3s ir\u00edamos implementando. Teria que fazer estudos de viabilidade.<\/li>\n<\/ul>\n<p><strong>Na parte da mobilidade, a sua proposta \u00e9 desestimular o uso do carro em Ribeir\u00e3o e priorizar o transporte p\u00fablico. Quais medidas seriam adotadas, haveria um rod\u00edzio por placas como \u00e9 na Capital?<\/strong><\/p>\n<ul>\n<li>N\u00e3o, n\u00e3o. N\u00e3o temos previs\u00e3o de rod\u00edzio aqui. Isso n\u00e3o cabe ainda em Ribeir\u00e3o. Ribeir\u00e3o tem uma frota de mais de 500 mil ve\u00edculos. O tarifa zero \u00e9 uma das medidas. Se as pessoas n\u00e3o precisarem mais pagar o \u00f4nibus, elas v\u00e3o usar mais o transporte p\u00fablico. Outra coisa \u00e9 voc\u00ea interligar melhor e, isso est\u00e1 no nosso programa de governo, a rede de transporte em Ribeir\u00e3o. Quando n\u00f3s governamos, tinha a van do Leve e Traz, que ligava \u00e0s regi\u00f5es, para as pessoas n\u00e3o terem que ir para o Centro, para pegar outro \u00f4nibus para ir a outros destinos, o que deixa o tempo de viagem muito longo. N\u00f3s temos que encurtar isso. E a outra medida \u00e9 que n\u00f3s vamos ter uma frota maior de \u00f4nibus, para diminuir o tempo de espera. N\u00f3s vamos estimular, tamb\u00e9m, as ciclovias na cidade. Muita gente quer andar de bicicleta. \u00c9 mais agrad\u00e1vel e faz bem, tamb\u00e9m, para a pessoa e para o meio ambiente.<\/li>\n<\/ul>\n<p><strong>O senhor quer criar a Secretaria Municipal de Habita\u00e7\u00e3o. Como seria o funcionamento desta pasta?<\/strong><\/p>\n<ul>\n<li>Ribeir\u00e3o tem, aproximadamente, 50 mil pessoas vivendo em favelas. Uma cidade rica como a nossa conviver com isso \u00e9 uma coisa que n\u00e3o \u00e9 admiss\u00edvel. Quando n\u00f3s governamos, n\u00f3s conseguimos entregar 15 mil unidades habitacionais. Naquela \u00e9poca, o or\u00e7amento da prefeitura era bem menor, estou falando em termos relativos, e tamb\u00e9m n\u00e3o tinha apoio do Governo Federal. Hoje n\u00f3s temos o Minha Casa, Minha Vida, al\u00e9m dos recursos da prefeitura. Ent\u00e3o, n\u00f3s vamos, de novo, entregar 15 mil unidades habitacionais. Com isso, a gente resolve o problema das favelas. Resolve o problema da moradia. A secretaria \u00e9 para gerenciar e coordenar esse processo e que vai ser feito tamb\u00e9m por meio da Cohab. Todas as secretarias t\u00eam que trabalhar de forma integrada. E, n\u00f3s temos que ter tamb\u00e9m planejamento. Por isso, que no nosso programa de governo est\u00e1 a cria\u00e7\u00e3o de um instituto voltado para o planejamento, parecido com o que tem em Curitiba desde os anos 1960. Isso, n\u00f3s ouvimos muito o setor, vou citar um nome aqui, o Silvio Contart nos convenceu a necessidade de ter esse instituto, al\u00e9m da experi\u00eancia de Curitiba. Eu estive em um debate com o Gustavo Fruet, ex-prefeito de Curitiba, e ele me mostrou todos os efeitos que esse instituto de planejamento vem tendo na hist\u00f3ria de Curitiba dos anos 1960. \u00c9 muito importante.<\/li>\n<\/ul>\n<p><strong>O seu plano \u00e9 dobrar o atual efetivo da GCM para 400 guardas. Quanto tempo isso levaria e qual seria o principal foco de atua\u00e7\u00e3o?<\/strong><\/p>\n<ul>\n<li>Hoje o custo da Guarda \u00e9 R$ 50 milh\u00f5es por ano. Ent\u00e3o, se a gente dobrar, em tese, n\u00f3s vamos dobrar o valor do investimento da Guarda Municipal. N\u00f3s vamos fazer isso ao longo dos quatro anos. O foco principal vai fazer a Guarda retomar a fun\u00e7\u00e3o origin\u00e1ria dela, que \u00e9 comunit\u00e1ria, que \u00e9 estar nos postos de sa\u00fade, estar nas escolas garantindo a seguran\u00e7a, tanto dos estudantes, quanto dos profissionais da educa\u00e7\u00e3o, e, nos postos tamb\u00e9m, aos pacientes e dos profissionais da sa\u00fade. Ent\u00e3o, vai ter uma voca\u00e7\u00e3o comunit\u00e1ria, inclusive, com a volta das bases nos bairros, que \u00e9 uma pol\u00edtica que deu muito certo e eu n\u00e3o sei por que pararam com ela. Dava certo e desmontaram essas bases da Guarda Municipal nos bairros. N\u00f3s vamos voltar essa pol\u00edtica.<\/li>\n<\/ul>\n<p><strong>Na sa\u00fade, o seu plano aposta na telemedicina, que oferece consultas pelo celular. O senhor acredita que essa medida \u00e9 eficaz?<\/strong><\/p>\n<ul>\n<li>Na verdade, o nosso principal programa na \u00e1rea da sa\u00fade \u00e9 triplicar as equipes de sa\u00fade da fam\u00edlia. Esse \u00e9 o nosso principal programa e, por isso, vai ter um atendimento preventivo e, s\u00f3 com isso, n\u00f3s vamos desafogar muito as UPAs e as UBSs. A quest\u00e3o da telemedicina \u00e9 um assess\u00f3rio. Ela s\u00f3 complementa e, para alguns casos, ela \u00e9 boa, para outros n\u00e3o. Ela \u00e9 um assess\u00f3rio, que tem funcionado bem em alguns munic\u00edpios e, tamb\u00e9m, na iniciativa privada. Ent\u00e3o, por que n\u00e3o? \u00c9 uma coisa de baixo custo e que d\u00e1 atendimento 24 horas, mas n\u00e3o serve para tudo. O nosso principal programa na \u00e1rea da sa\u00fade volto a dizer, \u00e9 triplicar as equipes de sa\u00fade da fam\u00edlia e \u00e9, tamb\u00e9m, garantir que a verba p\u00fablica v\u00e1 s\u00f3 para sa\u00fade p\u00fablica.<\/li>\n<\/ul>\n<p><strong>Ainda na \u00e1rea da sa\u00fade, o senhor quer contratar mais profissionais para as UPAs. Quando a popula\u00e7\u00e3o dever\u00e1 sentir o reflexo no servi\u00e7o oferecido?<\/strong><\/p>\n<ul>\n<li>Olha, \u00e9 de cara. Voc\u00ea abre concurso p\u00fablico. Hoje est\u00e1 faltando ortopedista, ginecologista, a quest\u00e3o da sa\u00fade mental, ent\u00e3o, nem se fala, porque est\u00e1 muito ruim aqui na cidade. Ent\u00e3o, \u00e9 de cara. Voc\u00ea contrata o m\u00e9dico, o enfermeiro, o t\u00e9cnico, ele j\u00e1 vai come\u00e7ar a prestar servi\u00e7o de qualidade para a popula\u00e7\u00e3o, porque vai ser por meio de concurso. Os terceirizados, infelizmente, t\u00eam contratos muito precarizados, recebem mal, ent\u00e3o n\u00f3s queremos abrir concursos p\u00fablicos para garantir uma sa\u00fade de qualidade em Ribeir\u00e3o Preto. N\u00f3s vamos conseguir resolver os problemas das UPAs com essas equipes de sa\u00fade da fam\u00edlia, porque vai ter aten\u00e7\u00e3o prim\u00e1ria, preventiva, e a pessoa n\u00e3o previa ir em uma UPA por conta de diabetes e por conta de hipertens\u00e3o, que \u00e9 o que mais sobrecarrega as UPAs.<\/li>\n<\/ul>\n<p><strong>O senhor quer retomar estudos para a constru\u00e7\u00e3o do aeroporto internacional na regi\u00e3o metropolitana de Ribeir\u00e3o? Qual seria a contrapartida da prefeitura?<\/strong><\/p>\n<ul>\n<li>Mas esse aeroporto n\u00e3o seria feito l\u00e1 no Leite Lopes. L\u00e1 n\u00e3o tem condi\u00e7\u00f5es de fazer. Isso s\u00f3 foi uma promessa, como foi uma promessa esse novo HC, que n\u00e3o tem projeto ainda para ele. Tinha um projeto, que quando n\u00f3s governamos j\u00e1 existia, tinha at\u00e9 um local definido para isso, que \u00e9 nas imedia\u00e7\u00f5es de Ribeir\u00e3o Preto. Isso \u00e9 muito importante, porque Ribeir\u00e3o \u00e9 um centro de com\u00e9rcio. Ent\u00e3o, se a gente tiver aqui esse centro de transporte de cargas, voc\u00ea melhora muito, amplia muito o com\u00e9rcio da cidade. \u00c9 um centro de com\u00e9rcio, e o com\u00e9rcio em Ribeir\u00e3o tem diminu\u00eddo. Por qu\u00ea? As cidades ao redor t\u00eam tido os seus pr\u00f3prios centros e, tamb\u00e9m, o com\u00e9rcio pela internet cresceu muito nos \u00faltimos anos. \u00c9, por isso, tamb\u00e9m, que n\u00f3s temos que cuidar para trazer uma ind\u00fastria, um polo aqui, que vai conduzir o desenvolvimento da cidade. Por isso, n\u00f3s estamos propondo o polo do hidrog\u00eanio verde, que garante um desenvolvimento de longo prazo, n\u00e3o s\u00f3 para Ribeir\u00e3o, mas para a nossa regi\u00e3o metropolitana.<\/li>\n<\/ul>\n<p><strong>Qual seria a contrapartida da prefeitura para o aeroporto internacional?<\/strong><\/p>\n<ul>\n<li>A prefeitura tem que dar as condi\u00e7\u00f5es, mas o que que a prefeitura pode oferecer? O terreno. A\u00ed, voc\u00ea tem a lei que regulamenta. N\u00f3s vamos fazer por licita\u00e7\u00e3o, porque, evidentemente, Ribeir\u00e3o n\u00e3o \u00e9 uma regi\u00e3o que vai ter dificuldade em ter interessados. Porque aqui tem muito fluxo de carga de com\u00e9rcio e de passageiros, portanto, n\u00f3s vamos fazer um processo normal de licita\u00e7\u00e3o. S\u00f3 vamos indicar a \u00e1rea que vai ser e dar a infraestrutura para que tenha transporte, enfim, mobilidade at\u00e9 l\u00e1.<\/li>\n<\/ul>\n<p><strong>O seu plano prev\u00ea implantar um trem tur\u00edstico em Ribeir\u00e3o Preto. De onde viriam os recursos, qual o trajeto e como funcionaria?<\/strong><\/p>\n<ul>\n<li>Primeiro, tenho muito orgulho de ter o apoio do Aguinaldo [Rodrigues da Silva], ex-presidente da Acirp e presidente do sindicato do turismo daqui da cidade. N\u00f3s discutimos muito a quest\u00e3o do turismo aqui em Ribeir\u00e3o Preto. Se n\u00f3s tivermos um circuito, por exemplo, da cerveja estruturado aqui, isso n\u00e3o \u00e9 uma fonte de gastos. \u00c9 uma fonte de lucro para a cidade. Porque vai atrair novos visitantes, que v\u00e3o ocupar a nossa cadeia hoteleira que \u00e9 boa, e que v\u00e3o consumir no nosso com\u00e9rcio e tudo isso vai gerar renda. Isso, na verdade, voc\u00ea n\u00e3o gera custos, voc\u00ea gera renda para prefeitura. Turismo \u00e9 uma atividade rent\u00e1vel se for bem explorada. Nossos museus est\u00e3o fechados, precisam reabrir. As nossas atividades culturais reduziram muito. Quando a gente governou tinha uma outra dimens\u00e3o. Inclusive, a Feira do Livro que foi criada por n\u00f3s, estava entre as quatro maiores do Pa\u00eds. [Sobre] o circuito, voc\u00ea tem muitas cervejarias em Ribeir\u00e3o Preto. Muitas. Ent\u00e3o, ele vai acompanhar as cervejarias de Ribeir\u00e3o Preto. Voc\u00ea tem a Colorado, a Invicta, n\u00e3o vou falar todos os nomes, se n\u00e3o vou esquecer, mas vai passar pelas principais cervejarias artesanais da cidade, o que vai estimular que seja divulgado.<\/li>\n<\/ul>\n<p>SAIBA MAIS<br \/>Concurso p\u00fablico com sal\u00e1rios de R$ 30 mil tem inscri\u00e7\u00f5es prorrogadas<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do<strong> acidade on<\/strong> no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Instagram <\/a>e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do <strong>acidade on<\/strong> no WhatsApp. <a href=\"https:\/\/chat.whatsapp.com\/Dtv9mxhy6V5BJBotM2OQ5k\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Globo Rep\u00f3rter celebra os 45 anos da EPTV<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/politica\/eleicoes\/tarifa-zero-e-dobrar-numero-de-guardas-veja-as-promessas-de-jorge-roque-para-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O acidade on Ribeir\u00e3o realiza nesta semana uma s\u00e9rie de entrevistas com os candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto nas elei\u00e7\u00f5es 2024. Nesta quinta-feira (26) o entrevistado foi o advogado Jorge Roque (PT) \u2013 veja o player acima. Jorge Roque \u00e9 candidato pela coliga\u00e7\u00e3o Amor Por Ribeir\u00e3o, formada pela Federa\u00e7\u00e3o Brasil da Esperan\u00e7a (PT, &#8230; <a title=\"Tarifa zero e dobrar n\u00famero de Guardas: Veja as promessas de Jorge Roque para Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/26\/tarifa-zero-e-dobrar-numero-de-guardas-veja-as-promessas-de-jorge-roque-para-ribeirao-preto\/\" aria-label=\"Read more about Tarifa zero e dobrar n\u00famero de Guardas: Veja as promessas de Jorge Roque para Ribeir\u00e3o Preto\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":68042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-68041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/jorge-roque_2024-09-26_20-26-10_jpg_2024-09-26_20-26-11.webp.webp?fit=1246%2C826&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/jorge-roque_2024-09-26_20-26-10_jpg_2024-09-26_20-26-11.webp.webp?fit=1246%2C826&ssl=1",1246,826,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/jorge-roque_2024-09-26_20-26-10_jpg_2024-09-26_20-26-11.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/jorge-roque_2024-09-26_20-26-10_jpg_2024-09-26_20-26-11.webp.webp?fit=300%2C199&ssl=1",300,199,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/jorge-roque_2024-09-26_20-26-10_jpg_2024-09-26_20-26-11.webp.webp?fit=768%2C509&ssl=1",768,509,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/jorge-roque_2024-09-26_20-26-10_jpg_2024-09-26_20-26-11.webp.webp?fit=1024%2C679&ssl=1",1024,679,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/jorge-roque_2024-09-26_20-26-10_jpg_2024-09-26_20-26-11.webp.webp?fit=1246%2C826&ssl=1",1246,826,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/jorge-roque_2024-09-26_20-26-10_jpg_2024-09-26_20-26-11.webp.webp?fit=1246%2C826&ssl=1",1246,826,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O acidade on Ribeir\u00e3o realiza nesta semana uma s\u00e9rie de entrevistas com os candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto nas elei\u00e7\u00f5es 2024. Nesta quinta-feira (26) o entrevistado foi o advogado Jorge Roque (PT) \u2013 veja o player acima. Jorge Roque \u00e9 candidato pela coliga\u00e7\u00e3o Amor Por Ribeir\u00e3o, formada pela Federa\u00e7\u00e3o Brasil da Esperan\u00e7a (PT,&hellip;","jetpack-related-posts":[{"id":67948,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/26\/jorge-roque-participa-nesta-quinta-da-serie-de-entrevistas-com-candidatos-a-prefeitura-de-ribeirao-preto\/","url_meta":{"origin":68041,"position":0},"title":"Jorge Roque participa nesta quinta da s\u00e9rie de entrevistas com candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"26 de September de 2024","format":false,"excerpt":"[ad_1] O acidade on Ribeir\u00e3o realiza nesta semana uma s\u00e9rie de entrevistas com os candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto nas elei\u00e7\u00f5es 2024. Nesta quinta-feira (26) \u00e9 a vez da sabatina do advogado Jorge Roque (PT) \u2013 veja o player acima. A entrevista ter\u00e1 12 minutos e vai ao ar,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Jorge-Roque-1_2024-09-19_21-19-48_jpg_2024-09-19_21-19-50-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Jorge-Roque-1_2024-09-19_21-19-48_jpg_2024-09-19_21-19-50-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Jorge-Roque-1_2024-09-19_21-19-48_jpg_2024-09-19_21-19-50-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Jorge-Roque-1_2024-09-19_21-19-48_jpg_2024-09-19_21-19-50-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Jorge-Roque-1_2024-09-19_21-19-48_jpg_2024-09-19_21-19-50-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":58097,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/27\/pt-confirma-jorge-roque-como-candidato-a-prefeitura-de-ribeirao-preto\/","url_meta":{"origin":68041,"position":1},"title":"PT confirma Jorge Roque como candidato \u00e0 Prefeitura de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"27 de July de 2024","format":false,"excerpt":"[ad_1] O PT (Partido dos Trabalhadores) confirmou o presidente do partido em Ribeir\u00e3o Preto, Jorge Roque, como candidato a prefeito. O an\u00fancio que incluiu, tamb\u00e9m, o nome da vice-prefeita, Artemizia Torres (PSOL), ocorreu na manh\u00e3 deste s\u00e1bado (27), na sede do PT, que fica no bairro Jardim Sumar\u00e9. \u201cDessa vez,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1_2024-07-27_14-30-52_jpg_2024-07-27_14-30-52.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1_2024-07-27_14-30-52_jpg_2024-07-27_14-30-52.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1_2024-07-27_14-30-52_jpg_2024-07-27_14-30-52.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1_2024-07-27_14-30-52_jpg_2024-07-27_14-30-52.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1_2024-07-27_14-30-52_jpg_2024-07-27_14-30-52.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":66877,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/19\/saiba-quem-e-jorge-roque-candidato-a-prefeito-de-ribeirao-preto\/","url_meta":{"origin":68041,"position":2},"title":"Saiba quem \u00e9 Jorge Roque, candidato a prefeito de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"19 de September de 2024","format":false,"excerpt":"[ad_1] A pesquisa Quaest\/EPTV, divulgada na \u00faltima quarta-feira (19), apontou que o advogado Jorge Roque (PT), aparece em segundo na inten\u00e7\u00e3o de votos dos eleitores na disputa pela Prefeitura de Ribeir\u00e3o Preto, com 7%. A Quaest consultou 852 eleitores presencialmente entre os dias 15 e 17 de setembro. A margem\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Jorge-Roque-1_2024-09-19_21-19-48_jpg_2024-09-19_21-19-50-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Jorge-Roque-1_2024-09-19_21-19-48_jpg_2024-09-19_21-19-50-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Jorge-Roque-1_2024-09-19_21-19-48_jpg_2024-09-19_21-19-50-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Jorge-Roque-1_2024-09-19_21-19-48_jpg_2024-09-19_21-19-50-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Jorge-Roque-1_2024-09-19_21-19-48_jpg_2024-09-19_21-19-50-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":57819,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/24\/veja-quem-apoia-quem-na-corrida-pela-prefeitura-de-ribeirao-preto\/","url_meta":{"origin":68041,"position":3},"title":"Veja quem apoia quem na corrida pela Prefeitura de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"24 de July de 2024","format":false,"excerpt":"[ad_1] A ex-reitora da USP (Universidade de S\u00e3o Paulo) Suely Vilela anunciou nesta quarta-feira (24) que deixou a corrida pela Prefeitura de Ribeir\u00e3o Preto nas elei\u00e7\u00f5es de 2024. Agora, a disputa pelo Executivo Municipal a partir de 2025 conta com seis pretendentes. Em nota, Suely, que foi ao segundo turno\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/candidatos-ribeirao-preto_2024-07-24_20-15-44_jpeg_2024-07-24_20-15-44.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/candidatos-ribeirao-preto_2024-07-24_20-15-44_jpeg_2024-07-24_20-15-44.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/candidatos-ribeirao-preto_2024-07-24_20-15-44_jpeg_2024-07-24_20-15-44.webp.webp?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/candidatos-ribeirao-preto_2024-07-24_20-15-44_jpeg_2024-07-24_20-15-44.webp.webp?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/candidatos-ribeirao-preto_2024-07-24_20-15-44_jpeg_2024-07-24_20-15-44.webp.webp?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":57043,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/17\/nogueira-anuncia-apoio-a-pre-candidatura-de-andre-trindade-na-disputa-pela-prefeitura-de-ribeirao\/","url_meta":{"origin":68041,"position":4},"title":"Nogueira anuncia apoio \u00e0 pr\u00e9-candidatura de Andr\u00e9 Trindade na disputa pela prefeitura de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"17 de July de 2024","format":false,"excerpt":"[ad_1] Ribeir\u00e3o Preto tem mais uma mudan\u00e7a na disputa pela prefeitura. Nesta quarta-feira (17), o PSDB, partido do prefeito Duarte Nogueira, anunciou apoio \u00e0 pr\u00e9-candidatura do ex-vereador Andr\u00e9 Trindade (Uni\u00e3o). Com isso, o ex-secret\u00e1rio Alessandro Hirata, deixa a pr\u00e9-candidatura e deve concorrer a vice na chapa. Outros nomes que j\u00e1\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__andre-trindade-tv-camara_2024-07-17_15-18-19.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__andre-trindade-tv-camara_2024-07-17_15-18-19.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__andre-trindade-tv-camara_2024-07-17_15-18-19.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__andre-trindade-tv-camara_2024-07-17_15-18-19.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__andre-trindade-tv-camara_2024-07-17_15-18-19.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":66688,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/18\/quaest-veja-os-numeros-da-pesquisa-de-intencao-de-voto-a-prefeitura-de-ribeirao-preto\/","url_meta":{"origin":68041,"position":5},"title":"Quaest: Veja os n\u00fameros da pesquisa de inten\u00e7\u00e3o de voto \u00e0 Prefeitura de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"18 de September de 2024","format":false,"excerpt":"[ad_1] A pesquisa Quaest divulgada nesta quarta-feira (18) mostra Ricardo Silva (PSD) liderando a disputa pela Prefeitura de Ribeir\u00e3o Preto com 54% dos votos. Na sequ\u00eancia, empatados tecnicamente, est\u00e3o Jorge Roque (PT), com 7%, Andr\u00e9 Trindade (Uni\u00e3o), com 5%, e Marco Aur\u00e9lio (Novo), com 5% dos votos. Essa foi \u00e0\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-55_2024-09-18_21-24-19_png_2024-09-18_21-24-19.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-55_2024-09-18_21-24-19_png_2024-09-18_21-24-19.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-55_2024-09-18_21-24-19_png_2024-09-18_21-24-19.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-55_2024-09-18_21-24-19_png_2024-09-18_21-24-19.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-55_2024-09-18_21-24-19_png_2024-09-18_21-24-19.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-hHr","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/68041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=68041"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/68041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/68042"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=68041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=68041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=68041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}