{"id":67963,"date":"2024-09-26T12:19:10","date_gmt":"2024-09-26T15:19:10","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/26\/estudantes-de-escola-publica-de-ribeirao-participam-de-intercambio-no-exterior\/"},"modified":"2024-09-26T12:19:10","modified_gmt":"2024-09-26T15:19:10","slug":"estudantes-de-escola-publica-de-ribeirao-participam-de-intercambio-no-exterior","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/26\/estudantes-de-escola-publica-de-ribeirao-participam-de-intercambio-no-exterior\/","title":{"rendered":"Estudantes de escola p\u00fablica de Ribeir\u00e3o participam de interc\u00e2mbio no exterior"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>O programa in\u00e9dito de interc\u00e2mbio do <strong>Governo do Estado de S\u00e3o Paulo<\/strong>, levar\u00e1 estudantes da rede estadual para <strong>Austr\u00e1lia<\/strong>, <strong>Canad\u00e1<\/strong>, <strong>Nova Zel\u00e2ndia <\/strong>e <strong>Reino Unido <\/strong>na primeira turma do <a href=\"https:\/\/www.prontospromundo.educacao.sp.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Prontos pro Mundo<\/a>. <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">Na regi\u00e3o de Ribeir\u00e3o Preto, s\u00e3o 16 estudantes selecionados.<\/mark><\/p>\n<p>O interc\u00e2mbio <strong>ter\u00e1 dura\u00e7\u00e3o de tr\u00eas meses<\/strong>, <strong>ser\u00e1 100% gratuito<\/strong>, com todos os custos e organiza\u00e7\u00e3o providenciados pela <strong>Secretaria de Educa\u00e7\u00e3o de S\u00e3o Paulo<\/strong>.\u00a0<mark style=\"background-color:#fcb900\" class=\"has-inline-color\">Esta \u00e9 a primeira vez que alunos da rede estadual paulista s\u00e3o beneficiados com interc\u00e2mbio internacional.<\/mark><\/p>\n<p>Os estudantes selecionados <strong>ser\u00e3o matriculados em escolas do ensino m\u00e9dio<\/strong> e <strong>ficar\u00e3o hospedados em casa de uma fam\u00edlia local.\u00a0\u00a0<\/strong><\/p>\n<p><strong>Pais, m\u00e3es ou respons\u00e1veis legais precisam entregar \u00e0s escolas os documentos necess\u00e1rios para o andamento do processo do interc\u00e2mbio at\u00e9 esta quinta-feira (26).<\/strong> <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">Tamb\u00e9m termina hoje<\/mark>, o prazo para que fam\u00edlias de estudantes que optarem por <strong>n\u00e3o viajar <\/strong>formalizem a decis\u00e3o \u00e0 escola. Assim, <strong>a vaga ser\u00e1 disponibilizada a outro estudante classificado.<\/strong><\/p>\n<p>Para os estudantes interessados, <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">uma nova sele\u00e7\u00e3o ser\u00e1 feita ainda este ano para outras 500 vagas do programa<\/mark>, com <strong>embarque previsto para o segundo semestre de 2025. <\/strong>A sele\u00e7\u00e3o \u00e9 feita por etapas de provas e as outras regras estabelecidas por edital.<\/p>\n<p>SAIBA MAIS<br \/>Saerp alerta para falta d\u2019\u00e1gua em Ribeir\u00e3o Preto; Veja locais afetados<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do <strong>acidade on <\/strong>no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a> e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do<strong> acidade on<\/strong> no WhatsApp. Para entrar no grupo, basta <a href=\"https:\/\/chat.whatsapp.com\/Dtv9mxhy6V5BJBotM2OQ5k\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Onde P. Diddy est\u00e1 preso?\u00a0<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/estudantes-de-escola-publica-de-ribeirao-participam-de-intercambio-no-exterior\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O programa in\u00e9dito de interc\u00e2mbio do Governo do Estado de S\u00e3o Paulo, levar\u00e1 estudantes da rede estadual para Austr\u00e1lia, Canad\u00e1, Nova Zel\u00e2ndia e Reino Unido na primeira turma do Prontos pro Mundo. Na regi\u00e3o de Ribeir\u00e3o Preto, s\u00e3o 16 estudantes selecionados. O interc\u00e2mbio ter\u00e1 dura\u00e7\u00e3o de tr\u00eas meses, ser\u00e1 100% gratuito, com todos os &#8230; <a title=\"Estudantes de escola p\u00fablica de Ribeir\u00e3o participam de interc\u00e2mbio no exterior\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/26\/estudantes-de-escola-publica-de-ribeirao-participam-de-intercambio-no-exterior\/\" aria-label=\"Leia mais sobre Estudantes de escola p\u00fablica de Ribeir\u00e3o participam de interc\u00e2mbio no exterior\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":67964,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-67963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46_2024-09-26_14-52-20_png_2024-09-26_14-52-20.webp.webp?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46_2024-09-26_14-52-20_png_2024-09-26_14-52-20.webp.webp?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46_2024-09-26_14-52-20_png_2024-09-26_14-52-20.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46_2024-09-26_14-52-20_png_2024-09-26_14-52-20.webp.webp?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46_2024-09-26_14-52-20_png_2024-09-26_14-52-20.webp.webp?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46_2024-09-26_14-52-20_png_2024-09-26_14-52-20.webp.webp?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46_2024-09-26_14-52-20_png_2024-09-26_14-52-20.webp.webp?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46_2024-09-26_14-52-20_png_2024-09-26_14-52-20.webp.webp?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O programa in\u00e9dito de interc\u00e2mbio do Governo do Estado de S\u00e3o Paulo, levar\u00e1 estudantes da rede estadual para Austr\u00e1lia, Canad\u00e1, Nova Zel\u00e2ndia e Reino Unido na primeira turma do Prontos pro Mundo. Na regi\u00e3o de Ribeir\u00e3o Preto, s\u00e3o 16 estudantes selecionados. O interc\u00e2mbio ter\u00e1 dura\u00e7\u00e3o de tr\u00eas meses, ser\u00e1 100% gratuito, com todos os&hellip;","jetpack-related-posts":[{"id":11134,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/05\/governo-de-sp-lanca-bolsas-para-intercambio-nos-eua\/","url_meta":{"origin":67963,"position":0},"title":"Governo de SP lan\u00e7a bolsas para interc\u00e2mbio nos EUA","author":"ismaelcolosi.com.br","date":"5 de Dezembro de 2023","format":false,"excerpt":"[ad_1] O governo de S\u00e3o Paulo lan\u00e7ou programa para conceder mil bolsas de interc\u00e2mbio gratuitas para estudantes do ensino m\u00e9dio. S\u00e3o bolsas para col\u00e9gios em cinco pa\u00edses: Estados Unidos, Canad\u00e1, Nova Zel\u00e2ndia, Austr\u00e1lia e Inglaterra. A experi\u00eancia ter\u00e1 dura\u00e7\u00e3o de um semestre. Cr\u00e9ditos: Stadtratte\/iStockGoverno de SP lan\u00e7a programa de interc\u00e2mbio\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aprender-ingles.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aprender-ingles.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aprender-ingles.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aprender-ingles.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aprender-ingles.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":76385,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/12\/regiao-leva-379-mil-alunos-ao-saresp\/","url_meta":{"origin":67963,"position":1},"title":"Regi\u00e3o leva 37,9 mil alunos ao Saresp\u00a0","author":"ismaelcolosi.com.br","date":"12 de Novembro de 2024","format":false,"excerpt":"[ad_1] Edi\u00e7\u00e3o deste ano traz novidades na bonifica\u00e7\u00e3o para escolas que alcan\u00e7arem as metas; para 9\u00ba ano, alunos com bons resultados ser\u00e3o pr\u00e9-selecionados para programa de interc\u00e2mbio 12 de novembro de 202412 de novembro de 202412 Compartilhar0 A Secretaria da Educa\u00e7\u00e3o do Estado de S\u00e3o Paulo (Seduc-SP) aplicar\u00e1, a partir\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Saresp-Mastrangelo-Reino-A2IMG-scaled.jpg?fit=750%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Saresp-Mastrangelo-Reino-A2IMG-scaled.jpg?fit=750%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Saresp-Mastrangelo-Reino-A2IMG-scaled.jpg?fit=750%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/Saresp-Mastrangelo-Reino-A2IMG-scaled.jpg?fit=750%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":788,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/09\/projeto-leva-alunos-da-rede-publica-de-ribeirao-e-regiao-para-intercambio-em-portugal\/","url_meta":{"origin":67963,"position":2},"title":"Projeto leva alunos da rede p\u00fablica de Ribeir\u00e3o e regi\u00e3o para interc\u00e2mbio em Portugal","author":"ismaelcolosi.com.br","date":"9 de Novembro de 2023","format":false,"excerpt":"[ad_1] Um grupo de alunos do oitavo ano de escolas p\u00fablicas de Ribeir\u00e3o Preto e Serrana ir\u00e3o viajar, neste s\u00e1bado (11), para Lisboa, em Portugal, para visitar pontos hist\u00f3ricos da cidade e participar de discuss\u00f5es sobre coloniza\u00e7\u00e3o com estudantes e professores portugueses. A viagem faz parte da premia\u00e7\u00e3o da s\u00e9tima\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-08-at-17.16.02.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-08-at-17.16.02.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-08-at-17.16.02.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-08-at-17.16.02.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-08-at-17.16.02.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":39702,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/27\/alunos-da-regiao-de-ribeirao-preto-passam-por-seletiva-para-intercambio\/","url_meta":{"origin":67963,"position":3},"title":"Alunos da regi\u00e3o de Ribeir\u00e3o Preto passam por seletiva para interc\u00e2mbio","author":"ismaelcolosi.com.br","date":"27 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] O programa \u201cProntos pro Mundo\u201d do Governo do Estado de S\u00e3o Paulo selecionou 1.497 alunos da regi\u00e3o de Ribeir\u00e3o Preto para participarem de aulas intensivas de ingl\u00eas como prepara\u00e7\u00e3o para disputarem uma vaga para fazer interc\u00e2mbio em 2025. Dos 72 mil estudantes selecionados em todo estado, apenas 1.000 ser\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-17-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-17-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-17-1.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-17-1.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-17-1.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":11716,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/06\/ong-oferece-cursos-gratuitos-de-ingles-e-bolsas-de-intercambio\/","url_meta":{"origin":67963,"position":4},"title":"ONG oferece cursos gratuitos de ingl\u00eas e bolsas de interc\u00e2mbio","author":"ismaelcolosi.com.br","date":"6 de Dezembro de 2023","format":false,"excerpt":"[ad_1] A ONG Soul Bil\u00edngue est\u00e1 inscri\u00e7\u00f5es abertas no programa de cursos gratuitos de ingl\u00eas e bolsas de interc\u00e2mbio para as turmas do primeiro semestre de 2024. S\u00e3o oferecidas 330 vagas para jovens moradores do Norte, Nordeste e Sudeste do Brasil, com idade de 18 a 26 anos, renda per\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/londres.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/londres.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/londres.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/londres.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/londres.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":71752,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/17\/ribeirao-preto-recebe-feira-de-intercambio-com-entrada-gratuita\/","url_meta":{"origin":67963,"position":5},"title":"Ribeir\u00e3o Preto recebe feira de interc\u00e2mbio com entrada gratuita","author":"ismaelcolosi.com.br","date":"17 de Outubro de 2024","format":false,"excerpt":"[ad_1] A 1\u00aa Expo Interc\u00e2mbio Ribeir\u00e3o Preto chega a cidade no pr\u00f3ximo s\u00e1bado (19). O evento voltado para a educa\u00e7\u00e3o internacional acontecer\u00e1 no hotel Wyndham Garden, das 14h \u00e0s 18h e ter\u00e1 entrada gratuita. Na programa\u00e7\u00e3o, palestras e rodas de conversa com intercambistas que dividir\u00e3o com o p\u00fablico suas experi\u00eancias,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-10-17_20-37-07_png_2024-10-17_20-37-07.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-10-17_20-37-07_png_2024-10-17_20-37-07.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-10-17_20-37-07_png_2024-10-17_20-37-07.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-10-17_20-37-07_png_2024-10-17_20-37-07.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-10-17_20-37-07_png_2024-10-17_20-37-07.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-hGb","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=67963"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/67964"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=67963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=67963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=67963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}