{"id":67930,"date":"2024-09-26T10:07:45","date_gmt":"2024-09-26T13:07:45","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/26\/transformers-e-pacto-de-redencao-chegam-aos-cinemas-nesta-quinta-veja-estreias\/"},"modified":"2024-09-26T10:07:45","modified_gmt":"2024-09-26T13:07:45","slug":"transformers-e-pacto-de-redencao-chegam-aos-cinemas-nesta-quinta-veja-estreias","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/26\/transformers-e-pacto-de-redencao-chegam-aos-cinemas-nesta-quinta-veja-estreias\/","title":{"rendered":"\u2018Transformers\u2019 e \u2018Pacto de Reden\u00e7\u00e3o\u2019 chegam aos cinemas nesta quinta; Veja estreias"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>Nesta <strong>quinta-feira (26)<\/strong>, os destaques nas estreias dos <strong>cinemas <\/strong>de <strong>Ribeir\u00e3o Preto<\/strong> s\u00e3o os filmes \u2018<strong>Transformers<\/strong>\u2019 e \u2018<strong>Pacto de Reden\u00e7\u00e3o<\/strong>\u2019. Os cin\u00e9filos ainda recebem outros dois lan\u00e7amentos. Para quem gosta, op\u00e7\u00f5es de filme s\u00e3o o que n\u00e3o falta nesta semana. <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">Confira abaixo.<\/mark><\/p>\n<p>Ribeir\u00e3o Preto conta com quatro cinemas, o <strong>UCI<\/strong> localizado no Ribeir\u00e3o Shopping, o <strong>Cinep\u00f3lis<\/strong> nos shoppings Santa \u00darsula e Iguatemi e o <strong>Cinemark<\/strong>, no Novo Shopping.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Transformers: O In\u00edcio<\/strong><\/h4>\n<p>Os cinemas de <strong>Ribeir\u00e3o Preto<\/strong> recebem nesta <strong>quinta-feira (26)<\/strong> a sequ\u00eancia de uma das franquias de maior sucesso entre os amantes de <strong>Transformers<\/strong>. O longa conta a origem da rivalidade entre <strong>Optimus Prime <\/strong>e<strong> Megatron<\/strong>. O filme \u00e9 ambientado no planeta de <strong>Cybertron<\/strong> e n\u00e3o ter\u00e1 intera\u00e7\u00e3o com seres humanos no <strong>planeta Terra<\/strong>. A<strong> classifica\u00e7\u00e3o indicativa<\/strong> do filme \u00e9 <strong>livre<\/strong>. Veja o trailer:<\/p>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<p><iframe title=\"Transformers: O In\u00edcio | Trailer 2 Oficial | DUB | Paramount Pictures Brasil\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/ZMwravIqS1U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/div>\n<\/figure>\n<h4 class=\"wp-block-heading\"><strong>Pacto de Reden\u00e7\u00e3o<\/strong><\/h4>\n<p>O drama dirigido e interpretado por <strong>Michael Keaton<\/strong> acompanha um assassino de aluguel diagnosticado com uma forma r\u00e1pida de dem\u00eancia, uma condi\u00e7\u00e3o rara. Antes de perder completamente o controle de sua mente, seu filho adulto, <strong>Milles<\/strong> (<strong>James Marsden<\/strong>), com quem n\u00e3o tinha contato h\u00e1 <strong>cinco anos,<\/strong> pede ajuda para encobrir um crime que ele cometeu, e o pai que se redimir procura ajuda de <strong>Xavier<\/strong> (<strong>Al Pacino<\/strong>) e juntos v\u00e3o tentar de tudo para alcan\u00e7ar o sucesso. A <strong>classifica\u00e7\u00e3o indicativa<\/strong> \u00e9 de <strong>14 anos<\/strong>. Confira o trailer:<\/p>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<p>\n<iframe title=\"PACTO DE REDEN\u00c7\u00c3O | Trailer Legendado\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/DVF6j31QgyE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/p>\n<\/figure>\n<h4 class=\"wp-block-heading\"><strong>A Forja<\/strong>: <strong>O Poder da Transforma\u00e7\u00e3o<\/strong><\/h4>\n<p>A hist\u00f3ria se passa um ano ap\u00f3s <strong>Isaiah Wright (Aspen Kennedy)<\/strong>, um jovem de <strong>19 anos<\/strong> viciado em basquete e videogames, terminar o ensino m\u00e9dio, onde se encontra perdido e sem dire\u00e7\u00e3o. At\u00e9 que recebe um ultimato: encontrar um rumo ou sair de casa.<\/p>\n<p>Ap\u00f3s o apoio e as ora\u00e7\u00f5es de sua m\u00e3e solteira, <strong>Cynthia (Priscilla C. Shirer)<\/strong>, e da devota <strong>Dona Clara (Karen Abercrombie)<\/strong>, ele recebe a oportunidade de trabalhar, ele \u00e9 guiado por um mentor surpreendente que o desafia a refletir sobre seu futuro. No decorrer da hist\u00f3ria, <strong>Isaiah<\/strong> come\u00e7a a entender que <strong>Deus<\/strong> pode ter um prop\u00f3sito maior para sua vida. A <strong>classifica\u00e7\u00e3o indicativa<\/strong> \u00e9 <strong>livre<\/strong>. Veja o trailer:<\/p>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<p><iframe title=\"A Forja - O Poder da Transforma\u00e7\u00e3o | Trailer Dublado\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/ohQ1IZmce5w?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/div>\n<\/figure>\n<h4 class=\"wp-block-heading\"><strong>Look Back<\/strong><\/h4>\n<p>Esta anima\u00e7\u00e3o de anime se baseia no <em>mang\u00e1<\/em> de<strong> Tatsuki Fujimoto<\/strong>. A trama acompanha uma estudante do ensino fundamental, tem seus <em>mang\u00e1s<\/em> de com\u00e9dia publicados no jornal peri\u00f3dico da escola. Por\u00e9m, sua confian\u00e7a em seu talento fica abalada quando as tirinhas de outra aluna reclusa e que n\u00e3o consegue frequentar as aulas presencialmente, tamb\u00e9m ganham espa\u00e7o.<\/p>\n<p>O amor pela arte de desenhar <em>mang\u00e1s<\/em> e dedica\u00e7\u00e3o de ambas acabam as unindo, fazendo com que elas se esforcem para alcan\u00e7ar seus sonhos. A<strong> classifica\u00e7\u00e3o indicativa<\/strong> \u00e9 de<strong> 12 anos<\/strong>. Assista ao trailer:<\/p>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<p><iframe title=\"LOOK BACK (Trailer oficial 2) Legendado\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/S6sXWd4RfgA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/div>\n<\/figure>\n<p>SAIBA MAIS<br \/>Veja quando a frente fria traz chuva e al\u00edvio no calor para o interior de SP<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do <strong>acidade on <\/strong>no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a> e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do acidade on no WhatsApp. Para entrar no grupo, basta <a href=\"https:\/\/chat.whatsapp.com\/Dtv9mxhy6V5BJBotM2OQ5k\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Raquel Brito est\u00e1 gr\u00e1vida?<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/lazer-e-cultura\/transformers-e-pacto-de-redencao-chegam-aos-cinemas-nesta-quinta-veja-estreias\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Nesta quinta-feira (26), os destaques nas estreias dos cinemas de Ribeir\u00e3o Preto s\u00e3o os filmes \u2018Transformers\u2019 e \u2018Pacto de Reden\u00e7\u00e3o\u2019. Os cin\u00e9filos ainda recebem outros dois lan\u00e7amentos. Para quem gosta, op\u00e7\u00f5es de filme s\u00e3o o que n\u00e3o falta nesta semana. Confira abaixo. Ribeir\u00e3o Preto conta com quatro cinemas, o UCI localizado no Ribeir\u00e3o Shopping, &#8230; <a title=\"\u2018Transformers\u2019 e \u2018Pacto de Reden\u00e7\u00e3o\u2019 chegam aos cinemas nesta quinta; Veja estreias\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/26\/transformers-e-pacto-de-redencao-chegam-aos-cinemas-nesta-quinta-veja-estreias\/\" aria-label=\"Leia mais sobre \u2018Transformers\u2019 e \u2018Pacto de Reden\u00e7\u00e3o\u2019 chegam aos cinemas nesta quinta; Veja estreias\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":67931,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-67930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/20240724-ovicio-transformers-inicio-elenco-1024x576-1_2024-09-26_11-45-18.webp.webp?fit=1024%2C576&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/20240724-ovicio-transformers-inicio-elenco-1024x576-1_2024-09-26_11-45-18.webp.webp?fit=1024%2C576&ssl=1",1024,576,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/20240724-ovicio-transformers-inicio-elenco-1024x576-1_2024-09-26_11-45-18.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/20240724-ovicio-transformers-inicio-elenco-1024x576-1_2024-09-26_11-45-18.webp.webp?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/20240724-ovicio-transformers-inicio-elenco-1024x576-1_2024-09-26_11-45-18.webp.webp?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/20240724-ovicio-transformers-inicio-elenco-1024x576-1_2024-09-26_11-45-18.webp.webp?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/20240724-ovicio-transformers-inicio-elenco-1024x576-1_2024-09-26_11-45-18.webp.webp?fit=1024%2C576&ssl=1",1024,576,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/20240724-ovicio-transformers-inicio-elenco-1024x576-1_2024-09-26_11-45-18.webp.webp?fit=1024%2C576&ssl=1",1024,576,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Nesta quinta-feira (26), os destaques nas estreias dos cinemas de Ribeir\u00e3o Preto s\u00e3o os filmes \u2018Transformers\u2019 e \u2018Pacto de Reden\u00e7\u00e3o\u2019. Os cin\u00e9filos ainda recebem outros dois lan\u00e7amentos. Para quem gosta, op\u00e7\u00f5es de filme s\u00e3o o que n\u00e3o falta nesta semana. Confira abaixo. Ribeir\u00e3o Preto conta com quatro cinemas, o UCI localizado no Ribeir\u00e3o Shopping,&hellip;","jetpack-related-posts":[{"id":50020,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/14\/paramount-divulga-trailer-oficial-da-nova-temporada-de-transformers-a-centelha-da-terra\/","url_meta":{"origin":67930,"position":0},"title":"Paramount+ divulga trailer oficial da nova temporada de Transformers: A Centelha da Terra","author":"ismaelcolosi.com.br","date":"14 de Maio de 2024","format":false,"excerpt":"[ad_1] Casa \/ Televis\u00e3o \/ Paramount+ divulga trailer oficial da nova temporada de Transformers: A Centelha da TerraParamount+ divulga trailer oficial da nova temporada de Transformers: A Centelha da TerraSegunda Temporada Da S\u00e9rie De Anima\u00e7\u00e3o Estrear\u00e1 Dia 06 De Julho Exclusivamente No Paramount+ Produzida Pela Nickelodeon E Hasbro Entertainment, A\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/5b06e90b762468f309d1f7675ad366371168846025b8a2a481487aba1b1109df.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/5b06e90b762468f309d1f7675ad366371168846025b8a2a481487aba1b1109df.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/5b06e90b762468f309d1f7675ad366371168846025b8a2a481487aba1b1109df.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/5b06e90b762468f309d1f7675ad366371168846025b8a2a481487aba1b1109df.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/5b06e90b762468f309d1f7675ad366371168846025b8a2a481487aba1b1109df.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":58612,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/01\/cinema-o-exorcismo-e-tuesday-sao-as-estreias-nesta-quinta-em-ribeirao\/","url_meta":{"origin":67930,"position":1},"title":"Cinema: \u2018O Exorcismo\u2019 e \u2018Tuesday\u2019 s\u00e3o as estreias nesta quinta em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"1 de Agosto de 2024","format":false,"excerpt":"[ad_1] Na primeira quinta-feira de agosto, os cinemas de Ribeir\u00e3o Preto trazem duas estreias imperd\u00edveis. Entre os lan\u00e7amentos, est\u00e3o: \u201cO Exorcismo\u201d e \u201cTuesday \u2013 O \u00daltimo Abra\u00e7o\u201c, duas produ\u00e7\u00f5es que v\u00e3o desde o terror sobrenatural at\u00e9 o drama comovente. Ribeir\u00e3o Preto conta com quatro cinemas: o UCI, localizado no Ribeir\u00e3oShopping,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/tuesday_2024-08-01_12-11-31_jpg_2024-08-01_12-11-32.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/tuesday_2024-08-01_12-11-31_jpg_2024-08-01_12-11-32.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/tuesday_2024-08-01_12-11-31_jpg_2024-08-01_12-11-32.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/tuesday_2024-08-01_12-11-31_jpg_2024-08-01_12-11-32.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/tuesday_2024-08-01_12-11-31_jpg_2024-08-01_12-11-32.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":54694,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/27\/to-de-graca-e-um-lugar-silencioso-entram-em-cartaz-nos-cinemas-nesta-quinta-feira-confira\/","url_meta":{"origin":67930,"position":2},"title":"\u2018T\u00f4 De Gra\u00e7a\u2019 e \u2018Um Lugar Silencioso\u2019 entram em cartaz nos cinemas nesta quinta-feira; Confira","author":"ismaelcolosi.com.br","date":"27 de Junho de 2024","format":false,"excerpt":"[ad_1] Nesta quinta-feira (27), os cinemas de Ribeir\u00e3o Preto recebem filmes nacionais e internacionais. Entre os longas que entram em cartaz, os destaques s\u00e3o: \u201cT\u00f4 De Gra\u00e7a \u2013 O Filme\u201d e \u201cUm Lugar Silencioso: Dia Um\u201d. Ribeir\u00e3o Preto conta com quatro cinemas, o UCI localizado no Ribeir\u00e3o Shopping, o Cinep\u00f3lis\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Capturar_2024-06-27_12-20-49_jpg_2024-06-27_12-20-49.webp.webp?fit=768%2C417&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Capturar_2024-06-27_12-20-49_jpg_2024-06-27_12-20-49.webp.webp?fit=768%2C417&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Capturar_2024-06-27_12-20-49_jpg_2024-06-27_12-20-49.webp.webp?fit=768%2C417&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Capturar_2024-06-27_12-20-49_jpg_2024-06-27_12-20-49.webp.webp?fit=768%2C417&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":61549,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/22\/filmes-de-suspense-e-aventura-tomam-conta-dos-cinemas-nesta-quinta-feira-veja-estreias\/","url_meta":{"origin":67930,"position":3},"title":"Filmes de suspense e aventura tomam conta dos cinemas nesta quinta-feira; Veja estreias","author":"ismaelcolosi.com.br","date":"22 de Agosto de 2024","format":false,"excerpt":"[ad_1] Quinta-feira \u00e9 dia de ficar por dentro das estreias dos cinemas de Ribeir\u00e3o Preto. Esta semana, a programa\u00e7\u00e3o \u00e9 marcada por seis filmes de suspense e aventura. Os grandes destaques s\u00e3o: \u201cO Corvo\u201c, \u201cPisque Duas Vezes\u201d e \u201cTipos de Gentileza\u201d. Ribeir\u00e3o Preto conta com quatro cinemas, o UCI localizado\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/pisque-duas-vezes_2024-08-22_13-12-15_jpg_2024-08-22_13-12-15.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/pisque-duas-vezes_2024-08-22_13-12-15_jpg_2024-08-22_13-12-15.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/pisque-duas-vezes_2024-08-22_13-12-15_jpg_2024-08-22_13-12-15.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/pisque-duas-vezes_2024-08-22_13-12-15_jpg_2024-08-22_13-12-15.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/pisque-duas-vezes_2024-08-22_13-12-15_jpg_2024-08-22_13-12-15.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":49259,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/09\/planeta-dos-macacos-o-reinado-estreia-nos-cinemas-de-ribeirao-preto\/","url_meta":{"origin":67930,"position":4},"title":"\u2018Planeta dos Macacos: O Reinado\u2019 estreia nos cinemas de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"9 de Maio de 2024","format":false,"excerpt":"[ad_1] O filme \u201cPlaneta dos Macacos: O Reinado\u201d estreia nesta quinta-feira (8) nos cinemas de Ribeir\u00e3o Preto. A trama que traz continua\u00e7\u00e3o da trilogia feita entre 2011 e 2017, tamb\u00e9m marca uma tentativa de reiniciar a saga. A hist\u00f3ria se passa anos ap\u00f3s a morte do chimpanz\u00e9 C\u00e9sar. Os macacos\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/planeta-dos-macacos-o-reinado_x9v9_2024-05-09_12-40-54_jpg_2024-05-09_12-40-54.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/planeta-dos-macacos-o-reinado_x9v9_2024-05-09_12-40-54_jpg_2024-05-09_12-40-54.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/planeta-dos-macacos-o-reinado_x9v9_2024-05-09_12-40-54_jpg_2024-05-09_12-40-54.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/planeta-dos-macacos-o-reinado_x9v9_2024-05-09_12-40-54_jpg_2024-05-09_12-40-54.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/planeta-dos-macacos-o-reinado_x9v9_2024-05-09_12-40-54_jpg_2024-05-09_12-40-54.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":48358,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/02\/veja-os-lancamentos-nos-cinemas-de-ribeirao-preto-nesta-quinta-feira\/","url_meta":{"origin":67930,"position":5},"title":"Veja os lan\u00e7amentos nos cinemas de Ribeir\u00e3o Preto nesta quinta-feira","author":"ismaelcolosi.com.br","date":"2 de Maio de 2024","format":false,"excerpt":"[ad_1] Os cinemas de Ribeir\u00e3o Preto contam com lan\u00e7amentos nesta quinta-feira (2). Al\u00e9m das op\u00e7\u00f5es como, \u201cO Dubl\u00ea\u201d, \u201cA Teia\u201d e \u201cF\u00e9rias Trocadas\u201d que estreiam hoje. Confira a programa\u00e7\u00e3o completa: Ribeir\u00e3o Preto conta com quatro cinemas nos shoppings: o UCI localizado no Ribeir\u00e3o Shopping, o Cinep\u00f3lis nos shoppings Santa \u00darsula\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/o-duble-1024x576-1_2024-05-02_12-09-03_jpeg_2024-05-02_12-09-03.webp.webp?fit=904%2C508&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/o-duble-1024x576-1_2024-05-02_12-09-03_jpeg_2024-05-02_12-09-03.webp.webp?fit=904%2C508&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/o-duble-1024x576-1_2024-05-02_12-09-03_jpeg_2024-05-02_12-09-03.webp.webp?fit=904%2C508&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/o-duble-1024x576-1_2024-05-02_12-09-03_jpeg_2024-05-02_12-09-03.webp.webp?fit=904%2C508&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-hFE","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=67930"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/67931"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=67930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=67930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=67930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}