{"id":67905,"date":"2024-09-26T07:42:42","date_gmt":"2024-09-26T10:42:42","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/26\/embraer-oferece-200-vagas-de-estagio-com-salario-de-ate-r-1-800-e-opcao-de-home-office\/"},"modified":"2024-09-26T07:42:42","modified_gmt":"2024-09-26T10:42:42","slug":"embraer-oferece-200-vagas-de-estagio-com-salario-de-ate-r-1-800-e-opcao-de-home-office","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/26\/embraer-oferece-200-vagas-de-estagio-com-salario-de-ate-r-1-800-e-opcao-de-home-office\/","title":{"rendered":"Embraer oferece 200 vagas de est\u00e1gio com sal\u00e1rio de at\u00e9 R$ 1.800 e op\u00e7\u00e3o de home office"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"\">\n<div class=\"content-infos\">\n<div class=\"texts\">\n<p class=\"author tooltip-comp\"> Da reda\u00e7\u00e3o<span class=\"icon-i\">i<\/span><span class=\"tooltiptext\"> <span class=\"author\"><span>Da reda\u00e7\u00e3o<\/span> <\/span><span class=\"desc\"\/> <\/span><\/p>\n<p>26\/09\/2024 &#8211; 7:30<\/p>\n<\/div>\n<div id=\"share-modal\" class=\"share-modal\"> <button class=\"box-close btn-share\"> <img decoding=\"async\" src=\"https:\/\/istoedinheiro.com.br\/wp-content\/themes\/dinheiro-wp-theme\/assets\/img\/svg\/closeIcon.svg?x46096\" alt=\"Close icon\" class=\"close-btn lazy\"\/> <\/button><\/div>\n<\/p><\/div>\n<p>O programa de est\u00e1gio da Embraer encerra as inscri\u00e7\u00f5es no \u00faltimo dia de setembro, a segunda-feira, 30. S\u00e3o 200 vagas em diversas \u00e1reas, com sal\u00e1rios que v\u00e3o de R$ 360 para 24 horas semanais at\u00e9 R$ 1.800 para 120 horas. Al\u00e9m da remunera\u00e7\u00e3o, os pessoas receber\u00e3o vale-transporte, vale-refei\u00e7\u00e3o, plano m\u00e9dico e assist\u00eancia odontol\u00f3gica.<\/p>\n<p>As vagas est\u00e3o dispon\u00edveis para pessoas de todas as idades e lugares do Brasil, com op\u00e7\u00f5es de regime presencial, h\u00edbrido ou totalmente remoto. Os requerimentos de forma\u00e7\u00e3o abrangem tanto o t\u00e9cnico como universit\u00e1rio, em diferentes \u00e1reas como administrativo, engenharia e tecnologia da informa\u00e7\u00e3o.<\/p>\n<p>Para se inscrever, os candidatos devem acessar a p\u00e1gina do programa na plataforma de recursos humanos Guppy. Veja <a href=\"https:\/\/programasembraer.gupy.io\/\" target=\"_blank\" rel=\"noopener\">neste link<\/a>.<\/p>\n<p>O processo de sele\u00e7\u00e3o abrange din\u00e2micas online na segunda quinzena de outubro. Os aprovados ser\u00e3o divulgados no dia 6 de dezembro.<\/p>\n<p>A Embraer \u00e9 uma empresa fabricante de aeronaves para a avia\u00e7\u00e3o comercial e executiva, defesa e seguran\u00e7a e clientes agr\u00edcolas.<\/p>\n<div id=\"share-modal\" class=\"share-modal\"> <button class=\"box-close btn-share\"> <img decoding=\"async\" src=\"https:\/\/istoedinheiro.com.br\/wp-content\/themes\/dinheiro-wp-theme\/assets\/img\/svg\/closeIcon.svg?x46096\" alt=\"Close icon\" class=\"close-btn lazy\"\/> <\/button><\/div>\n<\/p><\/div>\n<p><script>!function(f,b,e,v,n,t,s){if(f.fbq)return;n=f.fbq=function(){n.callMethod?n.callMethod.apply(n,arguments):n.queue.push(arguments)};if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0';n.queue=[];t=b.createElement(e);t.async=!0;t.src=v;s=b.getElementsByTagName(e)[0];s.parentNode.insertBefore(t,s)}(window,document,'script','<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/istoedinheiro.com.br\/programa-de-estagio-da-embraer-oferece-200-vagas-com-remuneracao-de-ate-r-1-800\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Da reda\u00e7\u00e3oi Da reda\u00e7\u00e3o 26\/09\/2024 &#8211; 7:30 O programa de est\u00e1gio da Embraer encerra as inscri\u00e7\u00f5es no \u00faltimo dia de setembro, a segunda-feira, 30. S\u00e3o 200 vagas em diversas \u00e1reas, com sal\u00e1rios que v\u00e3o de R$ 360 para 24 horas semanais at\u00e9 R$ 1.800 para 120 horas. Al\u00e9m da remunera\u00e7\u00e3o, os pessoas receber\u00e3o vale-transporte, &#8230; <a title=\"Embraer oferece 200 vagas de est\u00e1gio com sal\u00e1rio de at\u00e9 R$ 1.800 e op\u00e7\u00e3o de home office\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/26\/embraer-oferece-200-vagas-de-estagio-com-salario-de-ate-r-1-800-e-opcao-de-home-office\/\" aria-label=\"Leia mais sobre Embraer oferece 200 vagas de est\u00e1gio com sal\u00e1rio de at\u00e9 R$ 1.800 e op\u00e7\u00e3o de home office\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":67906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3598],"tags":[],"class_list":["post-67905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empregos-classificados-vagas-trabalho"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/tagreuters.com2024binary_LYNXMPEK7B0JL-VIEWIMAGE.jpg?fit=450%2C300&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/tagreuters.com2024binary_LYNXMPEK7B0JL-VIEWIMAGE.jpg?fit=450%2C300&ssl=1",450,300,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/tagreuters.com2024binary_LYNXMPEK7B0JL-VIEWIMAGE.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/tagreuters.com2024binary_LYNXMPEK7B0JL-VIEWIMAGE.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/tagreuters.com2024binary_LYNXMPEK7B0JL-VIEWIMAGE.jpg?fit=450%2C300&ssl=1",450,300,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/tagreuters.com2024binary_LYNXMPEK7B0JL-VIEWIMAGE.jpg?fit=450%2C300&ssl=1",450,300,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/tagreuters.com2024binary_LYNXMPEK7B0JL-VIEWIMAGE.jpg?fit=450%2C300&ssl=1",450,300,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/tagreuters.com2024binary_LYNXMPEK7B0JL-VIEWIMAGE.jpg?fit=450%2C300&ssl=1",450,300,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Da reda\u00e7\u00e3oi Da reda\u00e7\u00e3o 26\/09\/2024 &#8211; 7:30 O programa de est\u00e1gio da Embraer encerra as inscri\u00e7\u00f5es no \u00faltimo dia de setembro, a segunda-feira, 30. S\u00e3o 200 vagas em diversas \u00e1reas, com sal\u00e1rios que v\u00e3o de R$ 360 para 24 horas semanais at\u00e9 R$ 1.800 para 120 horas. Al\u00e9m da remunera\u00e7\u00e3o, os pessoas receber\u00e3o vale-transporte,&hellip;","jetpack-related-posts":[{"id":85534,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/05\/21\/embraer-oferece-200-vagas-de-estagio-com-bolsas-de-ate-r-2-400-veja-como-se-candidatar\/","url_meta":{"origin":67905,"position":0},"title":"Embraer oferece 200 vagas de est\u00e1gio com bolsas de at\u00e9 R$ 2.400; veja como se candidatar","author":"ismaelcolosi.com.br","date":"21 de Maio de 2025","format":false,"excerpt":"[ad_1] A Embraer anunciou a abertura das inscri\u00e7\u00f5es para uma nova edi\u00e7\u00e3o de seu programa de est\u00e1gio. S\u00e3o 200 vagas dispon\u00edveis para estudantes do ensino superior cursando Tecnologia, Administra\u00e7\u00e3o ou Engenharia e alunos do ensino t\u00e9cnico. Os aprovados v\u00e3o receber mensalmente bolsas de at\u00e9 R$ 2.400, al\u00e9m dos benef\u00edcios ofertados\u2026","rel":"","context":"In &quot;Empregos - Classificados&quot;","block_context":{"text":"Empregos - Classificados","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":85769,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/05\/28\/inscricoes-para-200-vagas-de-estagio-da-embraer-com-bolsa-de-r-2-400-se-encerram-nesse-domingo\/","url_meta":{"origin":67905,"position":1},"title":"Inscri\u00e7\u00f5es para 200 vagas de est\u00e1gio da Embraer com bolsa de R$ 2.400 se encerram nesse domingo","author":"ismaelcolosi.com.br","date":"28 de Maio de 2025","format":false,"excerpt":"[ad_1] O prazo para as inscri\u00e7\u00f5es para o programa de est\u00e1gio da Embraer se encerra nesse domingo, 25. S\u00e3o mais de 200 vagas dispon\u00edveis para estudantes do ensino superior cursando Tecnologia, Administra\u00e7\u00e3o ou Engenharia e alunos do ensino t\u00e9cnico. Os aprovados v\u00e3o receber mensalmente bolsas de at\u00e9 R$ 2.400, al\u00e9m\u2026","rel":"","context":"In &quot;Empregos - Classificados&quot;","block_context":{"text":"Empregos - Classificados","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":85533,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/05\/21\/sabesp-abre-120-vagas-de-estagio-com-bolsa-de-r-2-200-veja-como-se-candidatar\/","url_meta":{"origin":67905,"position":2},"title":"Sabesp abre 120 vagas de est\u00e1gio com bolsa de R$ 2.200; veja como se candidatar","author":"ismaelcolosi.com.br","date":"21 de Maio de 2025","format":false,"excerpt":"[ad_1] A Sabesp anunciou a abertura de seu Programa de Est\u00e1gio Sabesp 2025 na ter\u00e7a-feira, 13.\u00a0 Ao todo s\u00e3o 120 vagas para estudantes de diversas \u00e1reas do conhecimento, com oportunidades em 22 cidades do estado de S\u00e3o Paulo. As inscri\u00e7\u00f5es v\u00e3o at\u00e9 2 de junho e devem ser feitas atrav\u00e9s\u2026","rel":"","context":"In &quot;Empregos - Classificados&quot;","block_context":{"text":"Empregos - Classificados","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":85222,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/05\/06\/chance-imperdivel-vaga-de-operador-de-cad-com-salario-de-ate-r-2-mil-beneficios-poucas-vagas-envie-seu-curriculo-agora-ou-fique-de-fora\/","url_meta":{"origin":67905,"position":3},"title":"CHANCE IMPERD\u00cdVEL! Vaga de OPERADOR DE CAD com sal\u00e1rio de at\u00e9 R$ 2 mil + BENEF\u00cdCIOS! ENVIE seu curr\u00edculo AGORA poucas vagas!","author":"Arthur Tijolo","date":"6 de Maio de 2025","format":false,"excerpt":"Um Operador de CAD em uma uniformeria trabalha com softwares de desenho assistido por computador para criar, modificar e organizar moldes e padr\u00f5es de uniformes. Suas principais fun\u00e7\u00f5es incluem: \ud83d\udccc Responsabilidades Desenvolver e ajustar moldes de uniformes no software CAD. Criar encaixes para otimizar o uso de tecidos e reduzir\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/474445751_1956389254885080_5015843430235700133_n.jpg?fit=1080%2C1068&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/474445751_1956389254885080_5015843430235700133_n.jpg?fit=1080%2C1068&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/474445751_1956389254885080_5015843430235700133_n.jpg?fit=1080%2C1068&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/474445751_1956389254885080_5015843430235700133_n.jpg?fit=1080%2C1068&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/474445751_1956389254885080_5015843430235700133_n.jpg?fit=1080%2C1068&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":90208,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2026\/05\/07\/vaga-imperdivel-ganhe-280-por-4h-nao-fique-de-fora\/","url_meta":{"origin":67905,"position":4},"title":"Vaga Imperd\u00edvel: Ganhe R$ 280,00 por 4h! N\u00e3o Fique de Fora!","author":"Arthur Tijolo","date":"7 de Maio de 2026","format":false,"excerpt":"\ud83d\udccc Detalhes da Vaga \u00c1rea: Radiologia, Fisioterapia e Terapia Ocupacional Fun\u00e7\u00e3o: Tutor\/Professor Carga hor\u00e1ria: 4 horas Dia e hor\u00e1rio: Sextas-feiras, das 18h30 \u00e0s 22h30 Formato das aulas: Din\u00e2mico, participativo, com oficinas e atividades pr\u00e1ticas sempre que poss\u00edvel \ud83c\udfaf Responsabilidades Acessar previamente o conte\u00fado disponibilizado pela institui\u00e7\u00e3o Assistir \u00e0s aulas de\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2026\/03\/474584636_1956390221551650_4662155764068416880_n-1.jpg?fit=1080%2C992&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2026\/03\/474584636_1956390221551650_4662155764068416880_n-1.jpg?fit=1080%2C992&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2026\/03\/474584636_1956390221551650_4662155764068416880_n-1.jpg?fit=1080%2C992&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2026\/03\/474584636_1956390221551650_4662155764068416880_n-1.jpg?fit=1080%2C992&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2026\/03\/474584636_1956390221551650_4662155764068416880_n-1.jpg?fit=1080%2C992&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":47232,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/25\/embraer-abriu-200-vagas-sem-experiencia-para-todo-pais\/","url_meta":{"origin":67905,"position":5},"title":"Embraer abriu 200 vagas sem experi\u00eancia para todo pa\u00eds","author":"ismaelcolosi.com.br","date":"25 de Abril de 2024","format":false,"excerpt":"[ad_1] Embraer anunciou 200 vagas sem experi\u00eancia e possibilidade de trabalho em casa A Embraer, l\u00edder no setor aeroespacial, est\u00e1 com inscri\u00e7\u00f5es abertas para mais de 200 vagas sem experi\u00eancia e h\u00edbridas, ou seja, com possibilidade parcial de trabalho em casa. H\u00e1 oportunidades tanto para quem tem faculdade como para\u2026","rel":"","context":"In &quot;Empregos - Classificados&quot;","block_context":{"text":"Empregos - Classificados","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Untitled-design-5.png?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Untitled-design-5.png?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Untitled-design-5.png?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Untitled-design-5.png?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Untitled-design-5.png?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-hFf","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=67905"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67905\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/67906"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=67905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=67905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=67905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}