{"id":6755,"date":"2023-11-26T20:27:27","date_gmt":"2023-11-26T23:27:27","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/26\/garota-de-12-anos-cai-da-janela-de-apartamento-de-5o-andar\/"},"modified":"2023-11-26T20:27:27","modified_gmt":"2023-11-26T23:27:27","slug":"garota-de-12-anos-cai-da-janela-de-apartamento-de-5o-andar","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/26\/garota-de-12-anos-cai-da-janela-de-apartamento-de-5o-andar\/","title":{"rendered":"Garota de 12 anos cai da janela de apartamento de 5\u00ba andar"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div itemprop=\"text\">\n<p>Um triste episodio marcou a vida de uma fam\u00edlia devido a um tr\u00e1gico acidente que aconteceu na \u00faltima sexta-feira (24).<\/p>\n<p>De acordo com as primeiras informa\u00e7\u00f5es repassadas pelas autoridades que respons\u00e1veis por atender a ocorr\u00eancia, uma pr\u00e9-adolescente de 12 anos caiu da janela do quinto andar de um edif\u00edcio.<\/p>\n<p>O caso aconteceu na cidade de Tubar\u00e3o, que fica localizada na regi\u00e3o sul do estado de Santa Catarina. Os socorristas do Corpo de Bombeiros de Santa Catarina (CBMSC), se deslocaram at\u00e9 o local do acidente para realizar o resgate da v\u00edtima por volta das 19h.<\/p>\n<p>Ainda de acordo com os socorristas do Corpo de Bombeiros, a v\u00edtima foi encontrada estirada ao solo, ela apresentava hemorragia no rosto, fratura do f\u00eamur e com uma suspeita de hemorragia interna.<\/p>\n<p>Depois que os socorristas fizeram os primeiros atendimentos e conseguiram estabilizar a garotinha, os bombeiros afirmaram que a v\u00edtima foi encaminhada para uma unidade de sa\u00fade mais pr\u00f3xima, onde deu entrada em estado bastante grave.<\/p>\n<p>As informa\u00e7\u00f5es dos socorristas do Corpo de Bombeiros foram repassadas neste domingo (26), entretanto, n\u00e3o h\u00e1 informa\u00e7\u00f5es atuais sobre o estado de sa\u00fade da garotinha.<\/p>\n<p>Os nomes dos envolvidos no caso n\u00e3o foram revelados, o que dificulta a busca por not\u00edcias sobre o estado de sa\u00fade de v\u00edtima.<\/p>\n<p><b>Bombeiros foram acionados para atender v\u00edtima de acidente de tr\u00e2nsito em Blumenau<\/b><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/fnmais.com\/wp-content\/uploads\/2023\/11\/postiimg-6563cf94594821619.jpeg?w=1200&#038;ssl=1\" alt=\"Acidente aconteceu na noite de sbado 25 no bairro Vila Nova mulher ficou presa dentro aps capotar o veculo\"\/><\/p>\n<p>Uma mulher de 41 anos teve que ser resgatada pela equipe do Corpo de Bombeiros Militar ap\u00f3s um incidente ocorrido na noite de s\u00e1bado (25) em Blumenau, no Vale do Itaja\u00ed.<\/p>\n<p>Depois de ser retirada do ve\u00edculo, a mulher passou por avalia\u00e7\u00e3o de um profissional m\u00e9dico e foi encaminhada. O condutor do ve\u00edculo atingido n\u00e3o estava presente no local no momento do incidente.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/fnmais.com\/sc-garota-12-anos-cai-janela-apartamento-5o-andar\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Um triste episodio marcou a vida de uma fam\u00edlia devido a um tr\u00e1gico acidente que aconteceu na \u00faltima sexta-feira (24). De acordo com as primeiras informa\u00e7\u00f5es repassadas pelas autoridades que respons\u00e1veis por atender a ocorr\u00eancia, uma pr\u00e9-adolescente de 12 anos caiu da janela do quinto andar de um edif\u00edcio. O caso aconteceu na cidade &#8230; <a title=\"Garota de 12 anos cai da janela de apartamento de 5\u00ba andar\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/26\/garota-de-12-anos-cai-da-janela-de-apartamento-de-5o-andar\/\" aria-label=\"Leia mais sobre Garota de 12 anos cai da janela de apartamento de 5\u00ba andar\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":6756,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6563cf961e2b45989.jpg?fit=1200%2C628&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6563cf961e2b45989.jpg?fit=1200%2C628&ssl=1",1200,628,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6563cf961e2b45989.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6563cf961e2b45989.jpg?fit=300%2C157&ssl=1",300,157,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6563cf961e2b45989.jpg?fit=768%2C402&ssl=1",768,402,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6563cf961e2b45989.jpg?fit=1024%2C536&ssl=1",1024,536,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6563cf961e2b45989.jpg?fit=1200%2C628&ssl=1",1200,628,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6563cf961e2b45989.jpg?fit=1200%2C628&ssl=1",1200,628,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Um triste episodio marcou a vida de uma fam\u00edlia devido a um tr\u00e1gico acidente que aconteceu na \u00faltima sexta-feira (24). De acordo com as primeiras informa\u00e7\u00f5es repassadas pelas autoridades que respons\u00e1veis por atender a ocorr\u00eancia, uma pr\u00e9-adolescente de 12 anos caiu da janela do quinto andar de um edif\u00edcio. O caso aconteceu na cidade&hellip;","jetpack-related-posts":[{"id":20977,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/26\/quem-era-o-motorista-da-carreta-que-perdeu-a-vida-na-temida-curva-da-morte-da-sc-161\/","url_meta":{"origin":6755,"position":0},"title":"Quem era o motorista da carreta que perdeu a vida na temida &#8216;curva da morte&#8217; da SC-161","author":"ismaelcolosi.com.br","date":"26 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Na manh\u00e3 desta ter\u00e7a-feira (26), um grave acidente ceifou a vida do motorista de uma carreta. O Ve\u00edculo de carga tombou, na altura do munic\u00edpio de Romel\u00e2ndia, localizado na regi\u00e3o Oeste do estado de Santa Catarina.De acordo com os socorristas do Corpo de Bombeiros do estado de Santa Catarina,\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658b677396ef58045.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658b677396ef58045.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658b677396ef58045.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658b677396ef58045.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658b677396ef58045.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4236,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/21\/sc-acidente-em-cidade-catarinense-deixa-vitima-fatal-e-feridos\/","url_meta":{"origin":6755,"position":1},"title":"SC: Acidente em cidade catarinense deixa v\u00edtima fatal e feridos","author":"ismaelcolosi.com.br","date":"21 de Novembro de 2023","format":false,"excerpt":"[ad_1] Nesta segunda-feira (20), um grave acidente deixou uma v\u00edtima fatal e feridos em uma cidade localizada no interior do estado de Santa Catarina.Uma mulher perdeu avida em uma colis\u00e3o que aconteceu na cidade de Ilhota, que fica no Vale do Itaja\u00ed.De acordo com os socorristas do Corpo de Bombeiros\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655c5dd7a030a9296.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655c5dd7a030a9296.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655c5dd7a030a9296.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655c5dd7a030a9296.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655c5dd7a030a9296.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15926,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/14\/bebe-de-apenas-4-meses-cai-do-3o-andar-de-predio-e-explicacao-causa-espanto\/","url_meta":{"origin":6755,"position":2},"title":"Beb\u00ea de apenas 4 meses cai do 3\u00ba andar de pr\u00e9dio e explica\u00e7\u00e3o causa espanto","author":"ismaelcolosi.com.br","date":"14 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Uma situa\u00e7\u00e3o dram\u00e1tica abalou o bairro Aero Rancho, em Campo Grande, na noite desta ter\u00e7a, dia 12 de dezembro, quando uma beb\u00ea de apenas 4 meses caiu do terceiro andar do condom\u00ednio residencial CH8.O incidente, que deixou a pequena em estado grave com hemorragia intracraniana, levantou preocupa\u00e7\u00f5es sobre as\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657b52d17a0c53298.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657b52d17a0c53298.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657b52d17a0c53298.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657b52d17a0c53298.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657b52d17a0c53298.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":28326,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/15\/quem-e-o-piloto-de-asa-delta-que-perdeu-a-vida-apos-queda-em-area-de-mata\/","url_meta":{"origin":6755,"position":3},"title":"Quem \u00e9 o piloto de asa delta que perdeu a vida ap\u00f3s queda em \u00e1rea de mata","author":"ismaelcolosi.com.br","date":"15 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Neste \u00faltimo domingo (14), o que era para ser um momento de pura divers\u00e3o, terminou de maneira tr\u00e1gica. Um indiv\u00edduo perdeu a vida ap\u00f3s sofrer uma queda de asa-delta.O acidente aconteceu no munic\u00edpio de Pomerode, situado no Vale do Itaja\u00ed, localizado no interior do estado de Santa Catarina. Giovanni\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a5760a8c9758560.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a5760a8c9758560.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a5760a8c9758560.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a5760a8c9758560.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a5760a8c9758560.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":16958,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/17\/sc-quem-e-o-jovem-que-perdeu-a-vida-encarcerado-em-acidente-entre-carro-e-onibus\/","url_meta":{"origin":6755,"position":4},"title":"SC: Quem \u00e9 o jovem que perdeu a vida encarcerado em acidente entre carro e \u00f4nibus","author":"ismaelcolosi.com.br","date":"17 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Um grave acidente que ocorreu na rodovia SC-480 terminou em uma grande trag\u00e9dia. Na manh\u00e3 deste s\u00e1bado (16), um acidente ocorreu nas proximidades do Col\u00e9gio Agr\u00edcola La Salle.Na altura da cidade de Xanxer\u00ea, que est\u00e1 localizada no interior do estado de Santa Catarina, a comunidade local ficou estarrecida com\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657e5dbaa2f488060.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657e5dbaa2f488060.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657e5dbaa2f488060.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657e5dbaa2f488060.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657e5dbaa2f488060.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":12823,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/08\/acidente-entre-caminhao-e-carreta-na-br-282-deixa-vitimas-fatais-e-detalhes-sobre-a-colisao-sao-expostos\/","url_meta":{"origin":6755,"position":5},"title":"Acidente entre caminh\u00e3o e carreta na BR-282 deixa v\u00edtimas fatais e detalhes sobre a colis\u00e3o s\u00e3o expostos","author":"ismaelcolosi.com.br","date":"8 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Na manh\u00e3 desta sexta-feira (8), um grave acidente provocou uma enorme trag\u00e9dia deixando v\u00edtimas fatais. As primeiras informa\u00e7\u00f5es repassadas pelas autoridades respons\u00e1veis por atender a ocorr\u00eancia.Segundo as informa\u00e7\u00f5es, a colis\u00e3o frontal entre um caminh\u00e3o e uma carreta aconteceu por volta das 7h30, na rodovia BR-282, na altura do munic\u00edpio\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6573712feb1b31817.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6573712feb1b31817.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6573712feb1b31817.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6573712feb1b31817.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6573712feb1b31817.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-1KX","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6755"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6755\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/6756"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}