{"id":6735,"date":"2023-11-26T18:31:52","date_gmt":"2023-11-26T21:31:52","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/26\/por-que-o-cha-verde-e-considerado-um-dos-mais-saudaveis-do-mundo\/"},"modified":"2023-11-26T18:31:52","modified_gmt":"2023-11-26T21:31:52","slug":"por-que-o-cha-verde-e-considerado-um-dos-mais-saudaveis-do-mundo","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/26\/por-que-o-cha-verde-e-considerado-um-dos-mais-saudaveis-do-mundo\/","title":{"rendered":"Por que o ch\u00e1 verde \u00e9 considerado um dos mais saud\u00e1veis do mundo?"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<div id=\"attachment_2313585\" class=\"wp-caption alignnone\">\n<div class=\"d-flex justify-content-center\" data-attachment-id=\"2313585\">\n<div class=\"position-relative d-inline-block\"><img data-recalc-dims=\"1\" data-portal-copyright=\"Getty Images\/iStockphoto\" decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-2313585 size-full\" src=\"https:\/\/i0.wp.com\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-479453608.jpg?resize=1200%2C800&#038;ssl=1\" alt=\"Semelhante a outros alimentos \u200b\u200bque cont\u00eam antioxidantes, ch\u00e1 verde ajuda na preven\u00e7\u00e3o de in\u00fameras doen\u00e7as \u2013 iStock\/Getty Images\" width=\"1200\" height=\"800\" srcset=\"https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-479453608.jpg 1254w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-479453608-450x300.jpg 450w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/11\/istock-479453608-768x512.jpg 768w\" sizes=\"(max-width: 1254px) 100vw, 1254px\"\/><\/p>\n<p>Cr\u00e9ditos: Getty Images\/iStockphoto<\/p>\n<\/div>\n<\/div>\n<p><span class=\"post-imagem__legenda\">Semelhante a outros alimentos \u200b\u200bque cont\u00eam antioxidantes, ch\u00e1 verde ajuda na preven\u00e7\u00e3o de in\u00fameras doen\u00e7as \u2013 iStock\/Getty Images<\/span><\/p>\n<\/div>\n<p>Feito das folhas da planta <strong><a href=\"https:\/\/www.gov.br\/saude\/pt-br\/assuntos\/saude-brasil\/eu-quero-ter-peso-saudavel\/noticias\/2018\/cha-verde-emagrece-tire-suas-duvidas-sobre-a-bebida\" target=\"_blank\" rel=\"noopener\">Camelllia sinensis<\/a><\/strong>, o ch\u00e1 verde cont\u00e9m ingredientes que ajudam manter o corpo jovem e o protegem contra in\u00fameras doen\u00e7as, mesmo as mais graves, como c\u00e2ncer e <strong><a href=\"https:\/\/catracalivre.com.br\/saude-bem-estar\/saude-dos-pes-ajuda-a-prever-doencas-cardiovasculares\/\" target=\"_blank\" rel=\"noopener\">doen\u00e7as cardiovasculares.<\/a><\/strong><\/p>\n<h2>Benef\u00edcios do ch\u00e1 verde<\/h2>\n<p>A bebida tem uma forte a\u00e7\u00e3o antioxidante, que ajuda o corpo a neutralizar os radicais livres, e est\u00e3o envolvidos no desenvolvimento de doen\u00e7as cardiovasculares e c\u00e2ncer e causam o envelhecimento da pele<\/p>\n<p>Nos \u00faltimos anos, a produ\u00e7\u00e3o cient\u00edfica tem destacado o poder do ch\u00e1 verde para o controle da press\u00e3o sangu\u00ednea e n\u00edveis de colesterol, que ajuda a reduzir o risco de doen\u00e7as cardiovasculares.<\/p>\n<p>A exemplo de um estudo chin\u00eas, em que os participantes tomaram uma c\u00e1psula de extrato da bebida todos os dias durante tr\u00eas meses, enquanto o grupo de controle recebeu apenas um placebo. Os resultados mostraram que os n\u00edveis de colesterol no grupo do ch\u00e1 verde melhoraram, enquanto os do grupo do placebo n\u00e3o.<\/p>\n<p>Apesar dos resultados promissores, especialistas refor\u00e7am que n\u00e3o se deve esperar um efeito milagroso da erva. Isso porque os antioxidantes n\u00e3o s\u00e3o suficientes para prevenir totalmente as doen\u00e7as cardiovasculares.<\/p>\n<p>Al\u00e9m disso, um estilo de vida saud\u00e1vel com uma dieta balanceada, exerc\u00edcios f\u00edsicos e baixo consumo de \u00e1lcool, bem como o controle do estresse, \u00e9 muito mais importante.<\/p>\n<h2>Efeitos colaterais<\/h2>\n<p>Embora seja bem tolerado e considerado inofensivo \u00e0 sa\u00fade, quando consumido excessivamente o ch\u00e1 verde pode causar dist\u00farbios do sono e arritmia card\u00edaca devido \u00e0 cafe\u00edna. Estudos tamb\u00e9m\u00a0apontam que cerca de cinco a seis litros por dia, pode causar outros efeitos colaterais, como n\u00e1useas e dores abdominais e, no pior dos casos, at\u00e9 danos ao f\u00edgado. Ningu\u00e9m costuma beber tanto ch\u00e1.<\/p>\n<\/div>\n<p><script>\n\t\t! function(f, b, e, v, n, t, s) {\n\t\t\tif (f.fbq) return;\n\t\t\tn = f.fbq = function() {\n\t\t\t\tn.callMethod ?\n\t\t\t\t\tn.callMethod.apply(n, arguments) : n.queue.push(arguments)\n\t\t\t};\n\t\t\tif (!f._fbq) f._fbq = n;\n\t\t\tn.push = n;\n\t\t\tn.loaded = !0;\n\t\t\tn.version = '2.0';\n\t\t\tn.queue = [];\n\t\t\tt = b.createElement(e);\n\t\t\tt.async = !0;\n\t\t\tt.src = v;\n\t\t\ts = b.getElementsByTagName(e)[0];\n\t\t\ts.parentNode.insertBefore(t, s)\n\t\t}(window, document, 'script',\n\t\t\t'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n\t\tfbq('init', '338315473262380');\n\t\tfbq('track', 'PageView');\n\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/catracalivre.com.br\/saude-bem-estar\/por-que-o-cha-verde-e-considerado-um-dos-mais-saudaveis-do-mundo\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Cr\u00e9ditos: Getty Images\/iStockphoto Semelhante a outros alimentos \u200b\u200bque cont\u00eam antioxidantes, ch\u00e1 verde ajuda na preven\u00e7\u00e3o de in\u00fameras doen\u00e7as \u2013 iStock\/Getty Images Feito das folhas da planta Camelllia sinensis, o ch\u00e1 verde cont\u00e9m ingredientes que ajudam manter o corpo jovem e o protegem contra in\u00fameras doen\u00e7as, mesmo as mais graves, como c\u00e2ncer e doen\u00e7as cardiovasculares. &#8230; <a title=\"Por que o ch\u00e1 verde \u00e9 considerado um dos mais saud\u00e1veis do mundo?\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/26\/por-que-o-cha-verde-e-considerado-um-dos-mais-saudaveis-do-mundo\/\" aria-label=\"Leia mais sobre Por que o ch\u00e1 verde \u00e9 considerado um dos mais saud\u00e1veis do mundo?\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":6736,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-6735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-479453608.jpg?fit=1200%2C638&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-479453608.jpg?fit=1200%2C638&ssl=1",1200,638,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-479453608.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-479453608.jpg?fit=300%2C160&ssl=1",300,160,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-479453608.jpg?fit=768%2C408&ssl=1",768,408,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-479453608.jpg?fit=1024%2C544&ssl=1",1024,544,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-479453608.jpg?fit=1200%2C638&ssl=1",1200,638,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-479453608.jpg?fit=1200%2C638&ssl=1",1200,638,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Cr\u00e9ditos: Getty Images\/iStockphoto Semelhante a outros alimentos \u200b\u200bque cont\u00eam antioxidantes, ch\u00e1 verde ajuda na preven\u00e7\u00e3o de in\u00fameras doen\u00e7as \u2013 iStock\/Getty Images Feito das folhas da planta Camelllia sinensis, o ch\u00e1 verde cont\u00e9m ingredientes que ajudam manter o corpo jovem e o protegem contra in\u00fameras doen\u00e7as, mesmo as mais graves, como c\u00e2ncer e doen\u00e7as cardiovasculares.&hellip;","jetpack-related-posts":[{"id":18399,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/20\/estudo-entrega-qual-cha-tomar-para-eliminar-gordura-do-figado\/","url_meta":{"origin":6735,"position":0},"title":"Estudo entrega qual ch\u00e1 tomar para eliminar gordura do f\u00edgado","author":"ismaelcolosi.com.br","date":"20 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Cr\u00e9ditos: Depositphotos\/KirillMCh\u00e1 que ajuda a eliminar gordura do f\u00edgado Quantas vezes voc\u00ea j\u00e1 ouviu falar sobre os benef\u00edcios do ch\u00e1 verde para a sa\u00fade? Pois bem, uma recente pesquisa da Universidade Estadual da Pensilv\u00e2nia lan\u00e7ou luz sobre mais um desses benef\u00edcios: a melhoria na sa\u00fade do f\u00edgado. O estudo\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-113262454-xl-scaled.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-113262454-xl-scaled.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-113262454-xl-scaled.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-113262454-xl-scaled.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-113262454-xl-scaled.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":13091,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/09\/cha-pode-ser-a-chave-no-combate-ao-alzheimer-diz-estudo\/","url_meta":{"origin":6735,"position":1},"title":"Ch\u00e1 pode ser a chave no combate ao Alzheimer, diz estudo","author":"ismaelcolosi.com.br","date":"9 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Cr\u00e9ditos: Getty Images\/iStockphotoCatequinas do ch\u00e1 verde e o resveratrol diminu\u00edram a forma\u00e7\u00e3o de placas nas c\u00e9lulas neurais, reduzindo a possibilidade Alzheimer \u2013 iStock\/Getty Images Considerada um dos maiores desafios da medicina nos dias atuais, o Alzheimer \u00e9 uma doen\u00e7a neurodegenerativa cr\u00f4nica e progressiva, que se se manifesta principalmente em\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1218126236.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1218126236.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1218126236.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1218126236.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1218126236.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8695,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/30\/as-melhores-bebidas-para-sugar-acucar-no-sangue\/","url_meta":{"origin":6735,"position":2},"title":"As melhores bebidas para sugar a\u00e7\u00facar no sangue","author":"ismaelcolosi.com.br","date":"30 de Novembro de 2023","format":false,"excerpt":"[ad_1] O controle do a\u00e7\u00facar no sangue ou da glicose\u00a0\u00a0\u00e9 fundamental para pessoas com diagn\u00f3stico de diabetes ou resist\u00eancia \u00e0 insulina. Isso depende quase inteiramente da dieta, por isso, \u00e9 importante saber quais alimentos e bebidas possuem um efeito positivo. No entanto, \u00e9 sempre importante consultar um profissional de sa\u00fade\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1673610589.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1673610589.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1673610589.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1673610589.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1673610589.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15526,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/13\/4-tipos-de-chas-poderosos-que-desincham-o-corpo\/","url_meta":{"origin":6735,"position":3},"title":"4 tipos de ch\u00e1s poderosos que desincham o corpo","author":"ismaelcolosi.com.br","date":"13 de Dezembro de 2023","format":false,"excerpt":"[ad_1] No universo da busca por h\u00e1bitos saud\u00e1veis e solu\u00e7\u00f5es naturais para problemas de sa\u00fade, um aliado surpreendente emerge: o ch\u00e1, que n\u00e3o s\u00f3 satisfaz paladares, mas tamb\u00e9m pode ser uma pe\u00e7a fundamental na redu\u00e7\u00e3o do incha\u00e7o corporal. Recentemente, uma pesquisa revelou que certos tipos de ch\u00e1 t\u00eam propriedades que\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1441044138.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1441044138.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1441044138.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1441044138.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1441044138.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6315,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/25\/bebidas-que-voce-deve-consumir-todas-as-manhas-para-evitar-o-colesterol-alto\/","url_meta":{"origin":6735,"position":4},"title":"Bebidas que voc\u00ea deve consumir todas as manh\u00e3s para evitar o colesterol alto","author":"ismaelcolosi.com.br","date":"25 de Novembro de 2023","format":false,"excerpt":"[ad_1] Cr\u00e9ditos: isa-7777\/istockBebidas como o ch\u00e1 verde cont\u00e9m catequinas, compostos associados \u00e0 redu\u00e7\u00e3o do colesterol \u2013 iStock\/Getty Images O colesterol \u00e9 uma subst\u00e2ncia cerosa semelhante \u00e0 gordura encontrada no sangue, usado pelo organismo para produzir novas c\u00e9lulas e horm\u00f4nios. Existem dois tipos principais de colesterol: lipoprote\u00edna de alta densidade (HDL)\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-471942753.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-471942753.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-471942753.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-471942753.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-471942753.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4000,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/20\/bebida-deixa-os-dentes-mais-amarelos-que-cafe-e-vinho-alertam-especialistas\/","url_meta":{"origin":6735,"position":5},"title":"Bebida deixa os dentes mais amarelos que caf\u00e9 e vinho, alertam especialistas","author":"ismaelcolosi.com.br","date":"20 de Novembro de 2023","format":false,"excerpt":"[ad_1] Cr\u00e9ditos: Getty Images\/iStockphotoBebida possui alta concentra\u00e7\u00e3o de taninos, que s\u00e3o um grupo de compostos amargos e adstringentes, deixando os dentes mais amarelos \u2013 iStock\/Getty Images Dois dos principais vil\u00f5es da est\u00e9tica dent\u00e1ria, o vinho e caf\u00e9 s\u00e3o frequentemente apontados como os grandes respons\u00e1veis por amarelar os dentes a longo\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1339375313.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1339375313.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1339375313.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1339375313.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1339375313.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-1KD","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6735"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/6736"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}