{"id":6271,"date":"2023-11-25T12:00:25","date_gmt":"2023-11-25T15:00:25","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/25\/mega-sena-deve-pagar-neste-sabado-premio-de-r-26-milhoes\/"},"modified":"2023-11-25T12:00:25","modified_gmt":"2023-11-25T15:00:25","slug":"mega-sena-deve-pagar-neste-sabado-premio-de-r-26-milhoes","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/25\/mega-sena-deve-pagar-neste-sabado-premio-de-r-26-milhoes\/","title":{"rendered":"Mega-Sena deve pagar neste s\u00e1bado pr\u00eamio de R$ 26 milh\u00f5es"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"post-365246\">\n<header class=\"entry-header penci-entry-header penci-title-center\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2023-11-25T12:00:25-03:00\">25 de novembro de 2023 | 12:00<\/time><time class=\"updated\" datetime=\"2023-11-25T08:57:54-03:00\">25 de novembro de 2023 | 8:57<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"365246\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Mega-Sena%20deve%20pagar%20neste%20s\u00e1bado%20pr\u00eamio%20de%20R$%2026%20milh\u00f5es%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/mega-sena-deve-pagar-neste-sabado-premio-de-r-26-milhoes\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/header>\n<div class=\"penci-entry-content entry-content\">\n<p>O concurso 2.660 da Mega-Sena, que ser\u00e1 realizado neste s\u00e1bado (25) \u00e0 noite em S\u00e3o Paulo, pagar\u00e1 o pr\u00eamio de R$ 26 milh\u00f5es a quem acertar as seis dezenas. O sorteio ser\u00e1 \u00e0s 20h no Espa\u00e7o da Sorte, na Avenida Paulista.<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.png?w=1200&#038;ssl=1\"\/><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.gif?w=1200&#038;ssl=1\"\/><\/p>\n<p>Ningu\u00e9m acertou as seis dezenas no \u00faltimo concurso (2.659) \u2013\u00a011 \u2013 36 \u2013 46 \u2013 53 \u2013 55 \u2013 60 \u2013 e o pr\u00eamio acumulou.<\/p>\n<p>As apostas para o concurso de hoje podem ser feitas at\u00e9 as 19h (hor\u00e1rio de Bras\u00edlia) nas casas lot\u00e9ricas credenciadas pela Caixa, em todo o pa\u00eds ou pela internet.<\/p>\n<p>O jogo simples, com seis dezenas marcadas, custa R$ 5.<\/p>\n<\/div>\n<footer class=\"penci-entry-footer\"\/><\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/mega-sena-deve-pagar-neste-sabado-premio-de-r-26-milhoes\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 25 de novembro de 2023 | 12:0025 de novembro de 2023 | 8:57 0 O concurso 2.660 da Mega-Sena, que ser\u00e1 realizado neste s\u00e1bado (25) \u00e0 noite em S\u00e3o Paulo, pagar\u00e1 o pr\u00eamio de R$ 26 milh\u00f5es a quem acertar as seis dezenas. O sorteio ser\u00e1 \u00e0s 20h no Espa\u00e7o da Sorte, na Avenida&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":6272,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[239,260,262,263,261,507,264],"class_list":["post-6271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-deve","tag-megasena","tag-milhoes","tag-neste","tag-pagar","tag-premio","tag-sabado"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/1700925436_mega-sena-1-scaled.jpg?fit=1000%2C598&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/1700925436_mega-sena-1-scaled.jpg?fit=1000%2C598&ssl=1",1000,598,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/1700925436_mega-sena-1-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/1700925436_mega-sena-1-scaled.jpg?fit=300%2C179&ssl=1",300,179,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/1700925436_mega-sena-1-scaled.jpg?fit=768%2C459&ssl=1",768,459,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/1700925436_mega-sena-1-scaled.jpg?fit=1000%2C598&ssl=1",1000,598,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/1700925436_mega-sena-1-scaled.jpg?fit=1000%2C598&ssl=1",1000,598,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/1700925436_mega-sena-1-scaled.jpg?fit=1000%2C598&ssl=1",1000,598,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/1700925436_mega-sena-1-scaled.jpg?resize=930%2C598&ssl=1",930,598,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 25 de novembro de 2023 | 12:0025 de novembro de 2023 | 8:57 0 O concurso 2.660 da Mega-Sena, que ser\u00e1 realizado neste s\u00e1bado (25) \u00e0 noite em S\u00e3o Paulo, pagar\u00e1 o pr\u00eamio de R$ 26 milh\u00f5es a quem acertar as seis dezenas. O sorteio ser\u00e1 \u00e0s 20h no Espa\u00e7o da Sorte, na Avenida&hellip;&nbsp;","jetpack-related-posts":[{"id":1284,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/11\/mega-sena-pode-pagar-r-30-milhoes-neste-sabado\/","url_meta":{"origin":6271,"position":0},"title":"Mega-Sena pode pagar R$ 30 milh\u00f5es neste s\u00e1bado","author":"ismaelcolosi.com.br","date":"11 de Novembro de 2023","format":false,"excerpt":"[ad_1] 11 de novembro de 2023 | 13:0011 de novembro de 2023 | 12:19 0O concurso 2.655 da Mega-Sena pode pagar\u00a0R$ 30 milh\u00f5es neste s\u00e1bado (11) para quem acertar as seis dezenas sorteadas. O sorteio ser\u00e1 realizado \u00e0s 20h. As apostas podem ser feitas at\u00e9 as 19h nas casas lot\u00e9ricas.No\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mega-sena-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mega-sena-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mega-sena-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mega-sena-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1380,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/12\/mega-sena-acumula-e-proximo-concurso-deve-pagar-r-37-milhoes\/","url_meta":{"origin":6271,"position":1},"title":"Mega-Sena acumula e pr\u00f3ximo concurso deve pagar R$ 37 milh\u00f5es","author":"ismaelcolosi.com.br","date":"12 de Novembro de 2023","format":false,"excerpt":"[ad_1] 12 de novembro de 2023 | 12:0012 de novembro de 2023 | 11:41 0Ningu\u00e9m acertou as seis dezenas do concurso 2.655 da Mega-Sena, sorteadas nesse s\u00e1bado (11) \u00e0 noite em S\u00e3o Paulo. Os n\u00fameros s\u00e3o\u00a010 \u2013 23 \u2013 30 \u2013 31 \u2013 49 \u2013 56. A previs\u00e3o para o\u00a0pr\u00f3ximo\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mega_sena_mcajr_abr_2904223680-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mega_sena_mcajr_abr_2904223680-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mega_sena_mcajr_abr_2904223680-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mega_sena_mcajr_abr_2904223680-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6659,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/26\/mega-sena-acumula-e-proximo-premio-e-estimado-em-r-32-milhoes\/","url_meta":{"origin":6271,"position":2},"title":"Mega-Sena acumula e pr\u00f3ximo pr\u00eamio \u00e9 estimado em R$ 32 milh\u00f5es","author":"ismaelcolosi.com.br","date":"26 de Novembro de 2023","format":false,"excerpt":"[ad_1] 26 de novembro de 2023 | 13:3026 de novembro de 2023 | 13:05 0Ningu\u00e9m acertou as seis dezenas do Concurso 2.660 da Mega-Sena, sorteadas na noite de s\u00e1bado (25), em S\u00e3o Paulo.Os n\u00fameros sorteados foram 06, 12, 13, 20, 38 e 60. A quina teve 57 acertadores e cada\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/megasena-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/megasena-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/megasena-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/megasena-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":7558,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/28\/mega-sena-sorteia-nesta-terca-feira-r-32-milhoes\/","url_meta":{"origin":6271,"position":3},"title":"Mega-Sena sorteia nesta ter\u00e7a R$ 32 milh\u00f5es","author":"ismaelcolosi.com.br","date":"28 de Novembro de 2023","format":false,"excerpt":"[ad_1] 28 de novembro de 2023 | 12:0028 de novembro de 2023 | 8:20 0As seis dezenas do concurso 2.661 da Mega-Sena ser\u00e3o sorteadas, a partir das 20h (hor\u00e1rio de Bras\u00edlia), no Espa\u00e7o da Sorte, em S\u00e3o Paulo, com transmiss\u00e3o ao vivo pelo canal da Caixa no YouTube e no\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mega_sena-1112203505_0-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mega_sena-1112203505_0-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mega_sena-1112203505_0-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mega_sena-1112203505_0-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":8555,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/30\/mega-sena-sorteia-premio-estimado-em-r-37-milhoes\/","url_meta":{"origin":6271,"position":4},"title":"Mega-Sena sorteia pr\u00eamio estimado em R$ 37 milh\u00f5es","author":"ismaelcolosi.com.br","date":"30 de Novembro de 2023","format":false,"excerpt":"[ad_1] 30 de novembro de 2023 | 12:0030 de novembro de 2023 | 9:36 0As seis dezenas do concurso 2.662 da Mega-Sena ser\u00e3o sorteadas nesta quinta-feira (30), a partir das 20h (hor\u00e1rio de Bras\u00edlia), no Espa\u00e7o da Sorte, localizado na Avenida Paulista, n\u00ba 750, na cidade de S\u00e3o Paulo, com\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mega_sena-1112203504_0-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mega_sena-1112203504_0-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mega_sena-1112203504_0-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mega_sena-1112203504_0-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":71097,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/14\/raspadinhas-sao-relancadas-pela-caixa-com-premios-de-ate-r-2-milhoes\/","url_meta":{"origin":6271,"position":5},"title":"\u2018Raspadinhas\u2019 s\u00e3o relan\u00e7adas pela Caixa com pr\u00eamios de at\u00e9 R$ 2 milh\u00f5es","author":"ismaelcolosi.com.br","date":"14 de Outubro de 2024","format":false,"excerpt":"[ad_1] A Caixa Econ\u00f4mica Federal anunciou nesta segunda-feira (14) que vai relan\u00e7ar a \u201craspadinha\u201d. As vendas nas unidades lot\u00e9ricas come\u00e7am no dia 2 de novembro e as apostas custaram entre R$ 2,50 e R$ 20. O retorno da loteria, batizada de Instant\u00e2nea, conta com premia\u00e7\u00f5es entre R$ 2,50 at\u00e9 R$\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/raspadinha_2024-10-15_00-10-47_jpg_2024-10-15_00-10-47-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/raspadinha_2024-10-15_00-10-47_jpg_2024-10-15_00-10-47-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/raspadinha_2024-10-15_00-10-47_jpg_2024-10-15_00-10-47-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/raspadinha_2024-10-15_00-10-47_jpg_2024-10-15_00-10-47-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/raspadinha_2024-10-15_00-10-47_jpg_2024-10-15_00-10-47-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-1D9","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6271"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6271\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/6272"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}