{"id":62707,"date":"2024-08-28T20:15:32","date_gmt":"2024-08-28T23:15:32","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/28\/o-que-se-sabe-sobre-uso-da-agua-do-rio-pardo-para-abastecimento-de-ribeirao-2\/"},"modified":"2024-08-28T20:15:32","modified_gmt":"2024-08-28T23:15:32","slug":"o-que-se-sabe-sobre-uso-da-agua-do-rio-pardo-para-abastecimento-de-ribeirao-2","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/28\/o-que-se-sabe-sobre-uso-da-agua-do-rio-pardo-para-abastecimento-de-ribeirao-2\/","title":{"rendered":"O que se sabe sobre uso da \u00e1gua do rio Pardo para abastecimento de Ribeir\u00e3o"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>A <strong>Prefeitura de Ribeir\u00e3o Preto<\/strong> publicou no <strong>Di\u00e1rio Oficial do Munic\u00edpio<\/strong> desta quarta-feira (28), a licita\u00e7\u00e3o que aponta o cons\u00f3rcio vencedor do <strong>estudo para utiliza\u00e7\u00e3o das \u00e1guas do rio Pardo no abastecimento do munic\u00edpio.<\/strong><\/p>\n<p>A Administra\u00e7\u00e3o Municipal assinou com a <strong>Caixa Econ\u00f4mica Federal<\/strong> um <strong>contrato de financiamento <\/strong>de <strong>R$ 3 milh\u00f5es<\/strong> para realiza\u00e7\u00e3o desse estudo em <strong>julho de 2023<\/strong>.<\/p>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">Conforme o munic\u00edpio, <strong>o projeto prev\u00ea a capta\u00e7\u00e3o<\/strong>, <strong>tratamento <\/strong>e <strong>distribui\u00e7\u00e3o da \u00e1gua do rio Pardo <\/strong>para complementa\u00e7\u00e3o do sistema, que atualmente, utiliza a \u00e1gua captada no <strong>Aqu\u00edfero Guarani<\/strong>.<\/mark><\/p>\n<p><strong>A previs\u00e3o de conclus\u00e3o de todo o projeto e utiliza\u00e7\u00e3o efetiva da \u00e1gua do Rio Pardo \u00e9 para 2030<\/strong>. A <strong>Secretaria de \u00c1guas e Esgoto de Ribeir\u00e3o Preto (Saerp)<\/strong> j\u00e1 tem liberada a outorga para utiliza\u00e7\u00e3o de 3 metros c\u00fabicos por segundo das \u00e1guas do rio Pardo.<\/p>\n<p>O cons\u00f3rcio classificado \u00e9 composto pelas empresas <strong>Geasa Engenharia LTDA<\/strong>, <strong>Nippon Koei Lac Do Brasil LTDA<\/strong> e <strong>Techne Engenheiros Consultores LTDA<\/strong>.<\/p>\n<p>Segundo o edital, a proposta realizada foi de<strong> R$ 2.599.756,55<\/strong>. Agora, ser\u00e1 aberto o prazo para interposi\u00e7\u00e3o dos recursos.<\/p>\n<h4 class=\"wp-block-heading\"><strong>O estudo<\/strong><\/h4>\n<p>O <strong>projeto de capta\u00e7\u00e3o de \u00e1gua do rio Pardo <\/strong>est\u00e1 divido em tr\u00eas etapas: a primeira fase de estudos deve ser conclu\u00edda nove meses ap\u00f3s a contrata\u00e7\u00e3o da empresa respons\u00e1vel.<\/p>\n<p>Na sequ\u00eancia, ser\u00e1 realizada a estrutura\u00e7\u00e3o financeira e, por fim, a constru\u00e7\u00e3o do novo sistema que ser\u00e1 interligado ao atual para distribui\u00e7\u00e3o da \u00e1gua de maneira uniforme a todas as regi\u00f5es de <strong>Ribeir\u00e3o Preto<\/strong>.<\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<p>SAIBA MAIS<\/p>\n<p>Inc\u00eandio atinge canavial e mata da regi\u00e3o de Ribeir\u00e3o; veja v\u00eddeo<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on<\/strong>\u00a0no<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on<\/strong>\u00a0no WhatsApp.<a href=\"https:\/\/chat.whatsapp.com\/Dtv9mxhy6V5BJBotM2OQ5k\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Como teca foi possu\u00edda?<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/politica\/o-que-se-sabe-sobre-uso-da-agua-do-rio-pardo-para-abastecimento-de-ribeirao\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A Prefeitura de Ribeir\u00e3o Preto publicou no Di\u00e1rio Oficial do Munic\u00edpio desta quarta-feira (28), a licita\u00e7\u00e3o que aponta o cons\u00f3rcio vencedor do estudo para utiliza\u00e7\u00e3o das \u00e1guas do rio Pardo no abastecimento do munic\u00edpio. A Administra\u00e7\u00e3o Municipal assinou com a Caixa Econ\u00f4mica Federal um contrato de financiamento de R$ 3 milh\u00f5es para realiza\u00e7\u00e3o desse &#8230; <a title=\"O que se sabe sobre uso da \u00e1gua do rio Pardo para abastecimento de Ribeir\u00e3o\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/28\/o-que-se-sabe-sobre-uso-da-agua-do-rio-pardo-para-abastecimento-de-ribeirao-2\/\" aria-label=\"Read more about O que se sabe sobre uso da \u00e1gua do rio Pardo para abastecimento de Ribeir\u00e3o\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":62708,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-62707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1724886932_RIO-PARDO.jpg?fit=2000%2C1142&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1724886932_RIO-PARDO.jpg?fit=2000%2C1142&ssl=1",2000,1142,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1724886932_RIO-PARDO.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1724886932_RIO-PARDO.jpg?fit=300%2C171&ssl=1",300,171,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1724886932_RIO-PARDO.jpg?fit=768%2C439&ssl=1",768,439,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1724886932_RIO-PARDO.jpg?fit=1024%2C585&ssl=1",1024,585,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1724886932_RIO-PARDO.jpg?fit=1536%2C877&ssl=1",1536,877,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/1724886932_RIO-PARDO.jpg?fit=2000%2C1142&ssl=1",2000,1142,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A Prefeitura de Ribeir\u00e3o Preto publicou no Di\u00e1rio Oficial do Munic\u00edpio desta quarta-feira (28), a licita\u00e7\u00e3o que aponta o cons\u00f3rcio vencedor do estudo para utiliza\u00e7\u00e3o das \u00e1guas do rio Pardo no abastecimento do munic\u00edpio. A Administra\u00e7\u00e3o Municipal assinou com a Caixa Econ\u00f4mica Federal um contrato de financiamento de R$ 3 milh\u00f5es para realiza\u00e7\u00e3o desse&hellip;","jetpack-related-posts":[{"id":62702,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/28\/o-que-se-sabe-sobre-uso-da-agua-do-rio-pardo-para-abastecimento-de-ribeirao\/","url_meta":{"origin":62707,"position":0},"title":"O que se sabe sobre uso da \u00e1gua do rio Pardo para abastecimento de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"28 de August de 2024","format":false,"excerpt":"[ad_1] A Prefeitura de Ribeir\u00e3o Preto publicou no Di\u00e1rio Oficial do Munic\u00edpio desta quarta-feira (28), a licita\u00e7\u00e3o que aponta o cons\u00f3rcio vencedor do estudo para utiliza\u00e7\u00e3o das \u00e1guas do rio Pardo no abastecimento do munic\u00edpio. A Administra\u00e7\u00e3o Municipal assinou com a Caixa Econ\u00f4mica Federal um contrato de financiamento de R$\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/RIO-PARDO.jpg?fit=1200%2C685&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/RIO-PARDO.jpg?fit=1200%2C685&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/RIO-PARDO.jpg?fit=1200%2C685&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/RIO-PARDO.jpg?fit=1200%2C685&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/RIO-PARDO.jpg?fit=1200%2C685&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":66803,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/19\/projeto-sobre-a-utilizacao-da-agua-do-rio-pardo-em-ribeirao-preto-custara-r-25-milhoes\/","url_meta":{"origin":62707,"position":1},"title":"Projeto sobre a utiliza\u00e7\u00e3o da \u00e1gua do rio Pardo em Ribeir\u00e3o Preto custar\u00e1 R$ 2,5 milh\u00f5es","author":"ismaelcolosi.com.br","date":"19 de September de 2024","format":false,"excerpt":"[ad_1] A Prefeitura de Ribeir\u00e3o Preto homologou o cons\u00f3rcio vencedor da licita\u00e7\u00e3o para realiza\u00e7\u00e3o do projeto b\u00e1sico e dos estudos preliminares, econ\u00f4mico\/financeiro e ambientais para utiliza\u00e7\u00e3o da \u00e1gua do rio Pardo pela Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto). A homologa\u00e7\u00e3o da licita\u00e7\u00e3o foi publicada no Di\u00e1rio Oficial\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/RIO-PARDO.jpg?fit=1200%2C685&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/RIO-PARDO.jpg?fit=1200%2C685&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/RIO-PARDO.jpg?fit=1200%2C685&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/RIO-PARDO.jpg?fit=1200%2C685&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/RIO-PARDO.jpg?fit=1200%2C685&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":70989,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/14\/estudo-revela-que-chuvas-nao-conseguem-repor-toda-a-agua-consumida-do-aquifero-guarani\/","url_meta":{"origin":62707,"position":2},"title":"Estudo revela que chuvas n\u00e3o conseguem repor toda a \u00e1gua consumida do Aqu\u00edfero Guarani","author":"ismaelcolosi.com.br","date":"14 de October de 2024","format":false,"excerpt":"[ad_1] Por reda\u00e7\u00e3o acidade on e Guilherme Jeronymo, da Ag\u00eancia Brasil Um estudo realizado por pesquisadores da Unesp (Universidade Estadual Paulista) mostrou que as chuvas n\u00e3o conseguem repor toda a \u00e1gua do Aqu\u00edfero Guarani necess\u00e1ria para garantir a manuten\u00e7\u00e3o do reservat\u00f3rio, que se estende por \u00e1reas do Sul e Sudeste\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/a-lagoa-tranquila-do-por-do-sol-reflete-a-arvore-amarela-do-outono-gerada-pela-ia.jpg?fit=1200%2C686&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/a-lagoa-tranquila-do-por-do-sol-reflete-a-arvore-amarela-do-outono-gerada-pela-ia.jpg?fit=1200%2C686&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/a-lagoa-tranquila-do-por-do-sol-reflete-a-arvore-amarela-do-outono-gerada-pela-ia.jpg?fit=1200%2C686&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/a-lagoa-tranquila-do-por-do-sol-reflete-a-arvore-amarela-do-outono-gerada-pela-ia.jpg?fit=1200%2C686&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/a-lagoa-tranquila-do-por-do-sol-reflete-a-arvore-amarela-do-outono-gerada-pela-ia.jpg?fit=1200%2C686&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":39596,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/27\/licitacao-para-captacao-de-agua-do-rio-pardo-nao-atrai-interessados\/","url_meta":{"origin":62707,"position":3},"title":"Licita\u00e7\u00e3o para capta\u00e7\u00e3o de \u00e1gua do rio Pardo n\u00e3o atrai interessados","author":"ismaelcolosi.com.br","date":"27 de February de 2024","format":false,"excerpt":"[ad_1] A Secretaria de \u00c1gua e Esgoto (Saerp), por meio da prefeitura de Ribeir\u00e3o Preto, reabriu na sexta-feira, 24 de fevereiro, a licita\u00e7\u00e3o (tomada de pre\u00e7os) visando a contrata\u00e7\u00e3o de empresa ou cons\u00f3rcio para elabora\u00e7\u00e3o de estudos preliminares, projeto b\u00e1sico e estudos econ\u00f4micos e ambientais para capta\u00e7\u00e3o de \u00e1gua do\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Pardo-Alfredo-Risk-Arquivo-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Pardo-Alfredo-Risk-Arquivo-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Pardo-Alfredo-Risk-Arquivo-scaled.jpg?fit=1000%2C563&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Pardo-Alfredo-Risk-Arquivo-scaled.jpg?fit=1000%2C563&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":45247,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/03\/consorcios-disputam-estudo-para-captacao-de-agua-do-rio-pardo\/","url_meta":{"origin":62707,"position":4},"title":"Cons\u00f3rcios disputam estudo para capta\u00e7\u00e3o de \u00e1gua do rio Pardo\u00a0","author":"ismaelcolosi.com.br","date":"3 de April de 2024","format":false,"excerpt":"[ad_1] 3 de abril de 2024 | 10:002 de abril de 2024 | 20:17 0 Dois cons\u00f3rcios disputam a licita\u00e7\u00e3o (tomada de pre\u00e7os) aberta pela prefeitura de Ribeir\u00e3o Preto visando a contrata\u00e7\u00e3o de empresa ou grupo para elabora\u00e7\u00e3o de estudos preliminares, econ\u00f4micos e ambientais e de projeto b\u00e1sico para capta\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/PardoRP-Alfredo-Risk.jpg?fit=800%2C450&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/PardoRP-Alfredo-Risk.jpg?fit=800%2C450&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/PardoRP-Alfredo-Risk.jpg?fit=800%2C450&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/PardoRP-Alfredo-Risk.jpg?fit=800%2C450&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":34508,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/02\/camara-de-ribeirao-aprova-lei-que-pode-salvar-o-clube-regatas-entenda\/","url_meta":{"origin":62707,"position":5},"title":"C\u00e2mara de Ribeir\u00e3o aprova lei que pode salvar o Clube Regatas; Entenda","author":"ismaelcolosi.com.br","date":"2 de February de 2024","format":false,"excerpt":"[ad_1] A C\u00e2mara de Ribeir\u00e3o Preto aprovou, em primeira discuss\u00e3o, o projeto de lei complementar 80\/2023, que pode salvar o Clube Regatas. A vota\u00e7\u00e3o aconteceu na sess\u00e3o da \u00faltima quinta-feira (1\u00ba de fevereiro). A proposta recebeu 21 votos favor\u00e1veis e um contr\u00e1rio \u2013 apenas Lu\u00eds Fran\u00e7a (PSB) votou contra. O\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/rio-pardo-regatas.jpg?fit=984%2C553&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/rio-pardo-regatas.jpg?fit=984%2C553&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/rio-pardo-regatas.jpg?fit=984%2C553&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/rio-pardo-regatas.jpg?fit=984%2C553&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-gjp","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=62707"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62707\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/62708"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=62707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=62707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=62707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}