{"id":62315,"date":"2024-08-26T20:22:59","date_gmt":"2024-08-26T23:22:59","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/26\/o-que-se-sabe-sobre-presos-por-incendios-na-regiao-de-ribeirao-preto\/"},"modified":"2024-08-26T20:22:59","modified_gmt":"2024-08-26T23:22:59","slug":"o-que-se-sabe-sobre-presos-por-incendios-na-regiao-de-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/26\/o-que-se-sabe-sobre-presos-por-incendios-na-regiao-de-ribeirao-preto\/","title":{"rendered":"O que se sabe sobre presos por inc\u00eandios na regi\u00e3o de Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>At\u00e9 a noite desta segunda-feira (26), ao menos quatro pessoas foram presas suspeitas de terem iniciados inc\u00eandios em \u00e1reas de vegeta\u00e7\u00e3o no <strong>interior de S\u00e3o Paulo<\/strong>, sendo dois deles em <strong>Batatais<\/strong>, na regi\u00e3o de<strong> Ribeir\u00e3o Preto<\/strong>.<\/p>\n<p>Um deles \u00e9 Alessandro Arantes, de 42 anos, preso no domingo (25). Segundo a pol\u00edcia<mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">, ele tem passagens pela Justi\u00e7a por roubo e homic\u00eddio<\/mark> \u2013 a defesa dele n\u00e3o foi encontrada para comentar o caso. Ele teve a pris\u00e3o preventiva decretada.<\/p>\n<p>Outro suspeito foi detido na cidade nesta segunda-feira. O homem, que n\u00e3o teve o nome divulgado ateava fogo em terreno no Jardim Valenciano. <\/p>\n<p>Moradores do bairro chamaram a Pol\u00edcia Militar, que conseguiram capturar o acusador pr\u00f3ximo do local, que confessou o crime. O suspeito estava com um isqueiro e f\u00f3sforos.<\/p>\n<p>\u201cA grande quest\u00e3o \u00e9 saber se eram coisas pontuais ou organizadas\u201d, disse o diretor do <strong>Deinter-3 (Departamento de Pol\u00edcia Judici\u00e1ria de S\u00e3o Paulo Interior)<\/strong>, Jorge Amaro Cury Neto, respons\u00e1vel pelas investiga\u00e7\u00f5es na regi\u00e3o de Ribeir\u00e3o Preto, \u00e0 <strong>EPTV<\/strong>.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Multas<\/strong><\/h4>\n<p>Al\u00e9m das pris\u00f5es, <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">a <strong>Pol\u00edcia Militar Ambiental<\/strong> aplicou mais de R$ 15 mil em multas em dois homens, em Porto Ferreira<\/mark>. Ap\u00f3s den\u00fancia, os agentes foram ao local em que o inc\u00eandio foi provocado e encontraram diversas infra\u00e7\u00f5es ambientais, como lenhas em chamas para limpeza da vegeta\u00e7\u00e3o.<\/p>\n<p>Um dos infratores era propriet\u00e1rio de um s\u00edtio. Contra eles, foram registrados seis autos de infra\u00e7\u00e3o ambiental.<\/p>\n<p>Em nota, a Pol\u00edcia Civil informou que est\u00e1 mobilizada para investigar todas as ocorr\u00eancias de inc\u00eandio criminoso no estado, especialmente as que ocorrem nas regi\u00f5es afetadas pelas queimadas.<\/p>\n<p>\u201cAs equipes de investiga\u00e7\u00e3o est\u00e3o atentas \u00e0s imagens que circulam nas redes sociais e aos registros de boletins de ocorr\u00eancia para realizar dilig\u00eancias e identificar os autores\u201d, informa o comunicado.<\/p>\n<p>SAIBA MAIS<br \/>\u2018Saerpinho\u2019: Catedral reclama de falta d\u2019\u00e1gua no Centro de Ribeir\u00e3o Preto<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do <strong>acidade on<\/strong> no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Instagram<\/a> e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do<strong> acidade on<\/strong> no WhatsApp. <a href=\"https:\/\/chat.whatsapp.com\/Dtv9mxhy6V5BJBotM2OQ5k\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Governo de SP anuncia ajuda a produtores afetados pelos inc\u00eandios florestais<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/o-que-se-sabe-sobre-presos-por-incendios-na-regiao-de-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] At\u00e9 a noite desta segunda-feira (26), ao menos quatro pessoas foram presas suspeitas de terem iniciados inc\u00eandios em \u00e1reas de vegeta\u00e7\u00e3o no interior de S\u00e3o Paulo, sendo dois deles em Batatais, na regi\u00e3o de Ribeir\u00e3o Preto. Um deles \u00e9 Alessandro Arantes, de 42 anos, preso no domingo (25). Segundo a pol\u00edcia, ele tem passagens &#8230; <a title=\"O que se sabe sobre presos por inc\u00eandios na regi\u00e3o de Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/26\/o-que-se-sabe-sobre-presos-por-incendios-na-regiao-de-ribeirao-preto\/\" aria-label=\"Read more about O que se sabe sobre presos por inc\u00eandios na regi\u00e3o de Ribeir\u00e3o Preto\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":62316,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-62315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alessandro_2024-08-26_23-13-14_jpg_2024-08-26_23-13-14.webp.webp?fit=942%2C663&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alessandro_2024-08-26_23-13-14_jpg_2024-08-26_23-13-14.webp.webp?fit=942%2C663&ssl=1",942,663,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alessandro_2024-08-26_23-13-14_jpg_2024-08-26_23-13-14.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alessandro_2024-08-26_23-13-14_jpg_2024-08-26_23-13-14.webp.webp?fit=300%2C211&ssl=1",300,211,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alessandro_2024-08-26_23-13-14_jpg_2024-08-26_23-13-14.webp.webp?fit=768%2C541&ssl=1",768,541,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alessandro_2024-08-26_23-13-14_jpg_2024-08-26_23-13-14.webp.webp?fit=942%2C663&ssl=1",942,663,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alessandro_2024-08-26_23-13-14_jpg_2024-08-26_23-13-14.webp.webp?fit=942%2C663&ssl=1",942,663,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/alessandro_2024-08-26_23-13-14_jpg_2024-08-26_23-13-14.webp.webp?fit=942%2C663&ssl=1",942,663,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] At\u00e9 a noite desta segunda-feira (26), ao menos quatro pessoas foram presas suspeitas de terem iniciados inc\u00eandios em \u00e1reas de vegeta\u00e7\u00e3o no interior de S\u00e3o Paulo, sendo dois deles em Batatais, na regi\u00e3o de Ribeir\u00e3o Preto. Um deles \u00e9 Alessandro Arantes, de 42 anos, preso no domingo (25). Segundo a pol\u00edcia, ele tem passagens&hellip;","jetpack-related-posts":[{"id":66751,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/19\/passa-a-bolsa-ai-cozinheira-e-assaltada-na-zona-sul-de-ribeirao-preto\/","url_meta":{"origin":62315,"position":0},"title":"&#8216;Passa a bolsa a\u00ed&#8217;: Cozinheira \u00e9 assaltada na zona Sul de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"19 de September de 2024","format":false,"excerpt":"[ad_1] Uma cozinheira de 31 anos teve a bolsa roubada no Alto da Boa Vista, na zona Sul de Ribeir\u00e3o Preto, logo ap\u00f3s sair do trabalho. O crime ocorreu no fim da noite do \u00faltimo dia 5 de setembro, mas o boletim de ocorr\u00eancia (BO) somente foi registrado nesta quarta-feira\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1726748700_pm_qru_1024x576_25052021184558.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1726748700_pm_qru_1024x576_25052021184558.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1726748700_pm_qru_1024x576_25052021184558.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1726748700_pm_qru_1024x576_25052021184558.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":52019,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/03\/policia-detem-suspeito-de-balear-jovem-apos-confusao-em-estacionamento-de-ribeirao-preto\/","url_meta":{"origin":62315,"position":1},"title":"Pol\u00edcia det\u00e9m suspeito de balear jovem ap\u00f3s confus\u00e3o em estacionamento de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"3 de June de 2024","format":false,"excerpt":"[ad_1] A Pol\u00edcia Civil deteve nesta segunda-feira (3) um suspeito de balear na cabe\u00e7a o jovem\u00a0Ruan C\u00e9sar Godoi, de 22 anos, depois de uma confus\u00e3o em um estacionamento de ve\u00edculos, ocorrida na madrugada deste domingo (2), na avenida Jer\u00f4nimo Gon\u00e7alves, regi\u00e3o central de Ribeir\u00e3o Preto.\u00a0 O suspeito presta esclarecimentos na\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/cpj_policia_1024x576_21012021082231.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/cpj_policia_1024x576_21012021082231.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/cpj_policia_1024x576_21012021082231.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/cpj_policia_1024x576_21012021082231.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":62816,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/29\/mais-dois-suspeitos-sao-presos-por-incendios-na-regiao-de-ribeirao\/","url_meta":{"origin":62315,"position":2},"title":"Mais dois suspeitos s\u00e3o presos por inc\u00eandios na regi\u00e3o de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"29 de August de 2024","format":false,"excerpt":"[ad_1] Dois homens foram presos pela Pol\u00edcia Militar suspeitos de atear fogo em uma \u00e1rea de vegeta\u00e7\u00e3o na regi\u00e3o de Ribeir\u00e3o. A pris\u00e3o aconteceu \u00e0s margens da Rodovia F\u00e1bio Talarico, em\u00a0Franca, na noite desta quarta-feira (29). Com isso, chega a nove o n\u00famero de pris\u00f5es de pessoas suspeitas de participar\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/INCENDIO_2024-08-23_18-57-32_jpg_2024-08-23_18-57-32.webp.webp?fit=1200%2C784&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/INCENDIO_2024-08-23_18-57-32_jpg_2024-08-23_18-57-32.webp.webp?fit=1200%2C784&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/INCENDIO_2024-08-23_18-57-32_jpg_2024-08-23_18-57-32.webp.webp?fit=1200%2C784&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/INCENDIO_2024-08-23_18-57-32_jpg_2024-08-23_18-57-32.webp.webp?fit=1200%2C784&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/INCENDIO_2024-08-23_18-57-32_jpg_2024-08-23_18-57-32.webp.webp?fit=1200%2C784&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":62353,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/27\/desce-desce-diz-ladrao-durante-roubo-de-carro-no-transito-em-ribeirao-preto\/","url_meta":{"origin":62315,"position":3},"title":"&#8216;Desce, desce&#8217;, diz ladr\u00e3o durante roubo de carro no tr\u00e2nsito em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"27 de August de 2024","format":false,"excerpt":"[ad_1] Um carro foi roubado na noite desta segunda-feira (26), em pleno tr\u00e2nsito da avenida Henri Nestl\u00e9, zona Leste de Ribeir\u00e3o Preto. O motorista, uma promotora de vendas de 62 anos, disse \u00e0 pol\u00edcia no boletim de ocorr\u00eancia (BO) que voltava para casa e travegava no sentido Centro-bairro, quando foi\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/20220620_114539075_policia_qru_1024x576_25052021184749_jpg_715985292.jpg?fit=1200%2C606&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/20220620_114539075_policia_qru_1024x576_25052021184749_jpg_715985292.jpg?fit=1200%2C606&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/20220620_114539075_policia_qru_1024x576_25052021184749_jpg_715985292.jpg?fit=1200%2C606&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/20220620_114539075_policia_qru_1024x576_25052021184749_jpg_715985292.jpg?fit=1200%2C606&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/20220620_114539075_policia_qru_1024x576_25052021184749_jpg_715985292.jpg?fit=1200%2C606&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":37010,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/13\/suspeito-de-envolvimento-na-morte-de-policial-aposentado-e-preso-na-regiao-de-ribeirao\/","url_meta":{"origin":62315,"position":4},"title":"Suspeito de envolvimento na morte de policial aposentado \u00e9 preso na regi\u00e3o de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"13 de February de 2024","format":false,"excerpt":"[ad_1] A Pol\u00edcia Militar prendeu um suspeito de envolvimento na morte do policial reformado Darie Alves Tremura, de 63 anos. A v\u00edtima foi morta durante uma tentativa de assalto na rua Tibiri\u00e7\u00e1, Centro de Ribeir\u00e3o Preto. De acordo com o boletim de ocorr\u00eancia (BO), o suspeito foi preso na rodovia\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707854789_WhatsApp-Image-2024-02-12-at-16.27.00.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707854789_WhatsApp-Image-2024-02-12-at-16.27.00.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707854789_WhatsApp-Image-2024-02-12-at-16.27.00.jpeg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707854789_WhatsApp-Image-2024-02-12-at-16.27.00.jpeg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707854789_WhatsApp-Image-2024-02-12-at-16.27.00.jpeg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":28474,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/15\/foto-ajuda-policia-a-prender-suspeito-de-matar-engenheiro-em-ribeirao-preto\/","url_meta":{"origin":62315,"position":5},"title":"Foto ajuda pol\u00edcia a prender suspeito de matar engenheiro em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"15 de January de 2024","format":false,"excerpt":"[ad_1] Uma foto tirada pelo engenheiro Paulo Roberto Carvalho Braga Pena Filho, e enviada a um amigo, foi o que ajudou a Pol\u00edcia Civil a encontrar o suspeito de matar o homem, no final de 2023. A imagem foi divulgada nesta segunda-feira (15), ap\u00f3s a pris\u00e3o do acusado, Gabriel Souza\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-12.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-12.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-12.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-12.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-12.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-gd5","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=62315"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62315\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/62316"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=62315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=62315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=62315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}