{"id":62073,"date":"2024-08-25T11:11:48","date_gmt":"2024-08-25T14:11:48","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/25\/saerp-afirma-que-reservatorios-de-agua-apresentam-niveis-baixos-em-ribeirao-preto\/"},"modified":"2024-08-25T11:11:48","modified_gmt":"2024-08-25T14:11:48","slug":"saerp-afirma-que-reservatorios-de-agua-apresentam-niveis-baixos-em-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/25\/saerp-afirma-que-reservatorios-de-agua-apresentam-niveis-baixos-em-ribeirao-preto\/","title":{"rendered":"Saerp afirma que reservat\u00f3rios de \u00e1gua apresentam n\u00edveis baixos em Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>A<strong><a href=\"https:\/\/www.ribeiraopreto.sp.gov.br\/portal\/saerp\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto)<\/a><\/strong> informou que todos os sistemas de abastecimento de \u00e1gua de <strong>Ribeir\u00e3o Preto <\/strong>est\u00e3o funcionando na manh\u00e3 deste domingo (25), contudo est\u00e3o <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">apresentando n\u00edveis \u201cmuito baixos\u201d, o que pode afetar o abastecimento nas partes mais altas da cidade.<\/mark><\/p>\n<p>Nesta manh\u00e3, a reportagem do <strong>acidade on Ribeir\u00e3o <\/strong>recebeu diversas reclama\u00e7\u00f5es de moradores do Ipiranga, por conta da falta d\u2019\u00e1gua.<\/p>\n<p>Segundo o comunicado, emitido por volta das 10h, as equipes da secretaria est\u00e3o percorrendo as 120 \u00e1reas operacionais para verificar a situa\u00e7\u00e3o de funcionamento de cada uma delas.<\/p>\n<p>\u201cA Saerp destaca que todas as equipes est\u00e3o se empenhando a fim de manter o abastecimento para a popula\u00e7\u00e3o, al\u00e9m do fornecimento de caminh\u00f5es pipa com prioridade para hospitais, UPA\u2019s, escolas e creches\u201d, informa comunicado.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Po\u00e7os desligados<\/strong><\/h4>\n<p>Os po\u00e7os Parque Ribeir\u00e3o e Educand\u00e1rio est\u00e3o desligados, afetando as regi\u00f5es dos bairros Parque Ribeir\u00e3o e Jardim Independ\u00eancia.<\/p>\n<p>No Parque Ribeir\u00e3o, ser\u00e1 necess\u00e1ria a substitui\u00e7\u00e3o da bomba, com previs\u00e3o de t\u00e9rmino \u00e0s 23h, sendo que o abastecimento dever\u00e1 voltar gradativamente ao longo da segunda-feira.<\/p>\n<p>O po\u00e7o Educand\u00e1rio foi aberto chamado junto a CPFL para verificar poss\u00edvel queima de fus\u00edvel.<\/p>\n<p>O sistema de abastecimento Sumar\u00e9 continua com reserva\u00e7\u00e3o m\u00ednima, afetando os bairros Alto da Boa Vista, Jardim S\u00e3o Luiz, Jardim Iraj\u00e1, Jardim Calif\u00f3rnia, entre outros na regi\u00e3o.<\/p>\n<p>SAIBA MAIS<br \/>Domingo come\u00e7a com fuma\u00e7a e chuva em Ribeir\u00e3o Preto; V\u00eddeo<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do<strong> acidade on <\/strong>no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\/reels\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Instagram<\/a> e no Facebook.<\/p>\n<p>Receba not\u00edcias do<strong> acidade on <\/strong>no WhatsApp. <a href=\"https:\/\/chat.whatsapp.com\/Dtv9mxhy6V5BJBotM2OQ5k\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Onde tem previs\u00e3o de neve no Brasil?\u00a0<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/saerp-afirma-que-reservatorios-de-agua-apresentam-niveis-baixos-em-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou que todos os sistemas de abastecimento de \u00e1gua de Ribeir\u00e3o Preto est\u00e3o funcionando na manh\u00e3 deste domingo (25), contudo est\u00e3o apresentando n\u00edveis \u201cmuito baixos\u201d, o que pode afetar o abastecimento nas partes mais altas da cidade. Nesta manh\u00e3, a reportagem do acidade on &#8230; <a title=\"Saerp afirma que reservat\u00f3rios de \u00e1gua apresentam n\u00edveis baixos em Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/25\/saerp-afirma-que-reservatorios-de-agua-apresentam-niveis-baixos-em-ribeirao-preto\/\" aria-label=\"Read more about Saerp afirma que reservat\u00f3rios de \u00e1gua apresentam n\u00edveis baixos em Ribeir\u00e3o Preto\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":62074,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-62073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/falta-agua.jpg?fit=1068%2C801&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/falta-agua.jpg?fit=1068%2C801&ssl=1",1068,801,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/falta-agua.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/falta-agua.jpg?fit=300%2C225&ssl=1",300,225,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/falta-agua.jpg?fit=768%2C576&ssl=1",768,576,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/falta-agua.jpg?fit=1024%2C768&ssl=1",1024,768,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/falta-agua.jpg?fit=1068%2C801&ssl=1",1068,801,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/falta-agua.jpg?fit=1068%2C801&ssl=1",1068,801,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou que todos os sistemas de abastecimento de \u00e1gua de Ribeir\u00e3o Preto est\u00e3o funcionando na manh\u00e3 deste domingo (25), contudo est\u00e3o apresentando n\u00edveis \u201cmuito baixos\u201d, o que pode afetar o abastecimento nas partes mais altas da cidade. Nesta manh\u00e3, a reportagem do acidade on&hellip;","jetpack-related-posts":[{"id":62101,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/25\/esta-sem-agua-em-ribeirao-preto-saiba-como-acionar-a-saerp\/","url_meta":{"origin":62073,"position":0},"title":"Est\u00e1 sem \u00e1gua em Ribeir\u00e3o Preto? Saiba como acionar a Saerp","author":"ismaelcolosi.com.br","date":"25 de August de 2024","format":false,"excerpt":"[ad_1] Em raz\u00e3o dos inc\u00eandios que atingem Ribeir\u00e3o Preto nos \u00faltimos dias, houve oscila\u00e7\u00f5es de energia el\u00e9trica que afetaram o funcionamento de alguns po\u00e7os de capta\u00e7\u00e3o d\u2019\u00e1gua na cidade. Por conta disso, a Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informa que a popula\u00e7\u00e3o pode acionar a pasta\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/bebedouro-saerp.jpg?fit=1056%2C574&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/bebedouro-saerp.jpg?fit=1056%2C574&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/bebedouro-saerp.jpg?fit=1056%2C574&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/bebedouro-saerp.jpg?fit=1056%2C574&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/bebedouro-saerp.jpg?fit=1056%2C574&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":64862,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/09\/bairros-de-ribeirao-preto-podem-ficar-sem-agua-ate-amanha-veja-os-locais\/","url_meta":{"origin":62073,"position":1},"title":"Bairros de Ribeir\u00e3o Preto podem ficar sem \u00e1gua at\u00e9 amanh\u00e3; Veja os locais","author":"ismaelcolosi.com.br","date":"9 de September de 2024","format":false,"excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou que quatro bairros da zona Sul de Ribeir\u00e3o Preto podem ficar sem \u00e1gua at\u00e9 a manh\u00e3 de ter\u00e7a-feira (10). Segundo a secretaria, equipes est\u00e3o realizando a troca emergencial da bomba do po\u00e7o CDHU. Por conta disso, pode ocasionar\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/bebedouro-saerp.jpg?fit=1056%2C574&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/bebedouro-saerp.jpg?fit=1056%2C574&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/bebedouro-saerp.jpg?fit=1056%2C574&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/bebedouro-saerp.jpg?fit=1056%2C574&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/bebedouro-saerp.jpg?fit=1056%2C574&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":46527,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/12\/servicos-se-estendem-e-pode-faltar-agua-em-bairros-de-ribeirao-preto-veja-locais-afetados\/","url_meta":{"origin":62073,"position":2},"title":"Servi\u00e7os se estendem e pode faltar \u00e1gua em bairros de Ribeir\u00e3o Preto; Veja locais afetados","author":"ismaelcolosi.com.br","date":"12 de April de 2024","format":false,"excerpt":"[ad_1] A Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o (Saerp) informou que os servi\u00e7os de manuten\u00e7\u00e3o no po\u00e7o Flamboyans, iniciado nesta quinta-feira (11), foram estendidos devido a complexidades do trabalho. O \u00f3rg\u00e3o informou que equipes est\u00e3o trabalhando em manobras e monitoramento do sistema, contudo, podem ocorrer intermit\u00eancias nos bairros: Ainda\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/falta-de-agua-3.jpg?fit=1200%2C673&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/falta-de-agua-3.jpg?fit=1200%2C673&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/falta-de-agua-3.jpg?fit=1200%2C673&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/falta-de-agua-3.jpg?fit=1200%2C673&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/falta-de-agua-3.jpg?fit=1200%2C673&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":59887,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/13\/saerp-alerta-para-falta-dagua-em-ribeirao-preto-veja-os-locais\/","url_meta":{"origin":62073,"position":3},"title":"Saerp alerta para falta d\u2019\u00e1gua em Ribeir\u00e3o Preto; Veja os locais","author":"ismaelcolosi.com.br","date":"13 de August de 2024","format":false,"excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) alerta para falta d\u2019\u00e1gua em condom\u00ednios no distrito de Bonfim Paulista, em Ribeir\u00e3o Preto. Segundo a secretaria, equipes est\u00e3o realizando a manuten\u00e7\u00e3o preventiva nos reservat\u00f3rios Alphaville I, II e III. Por conta disso, pode gerar a falha no abastecimento\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/torneira-agua_2024-07-22_12-45-42_jpg_2024-07-22_12-45-42.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/torneira-agua_2024-07-22_12-45-42_jpg_2024-07-22_12-45-42.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/torneira-agua_2024-07-22_12-45-42_jpg_2024-07-22_12-45-42.webp.webp?fit=1170%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/torneira-agua_2024-07-22_12-45-42_jpg_2024-07-22_12-45-42.webp.webp?fit=1170%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/torneira-agua_2024-07-22_12-45-42_jpg_2024-07-22_12-45-42.webp.webp?fit=1170%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":58214,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/29\/saerp-alerta-para-falta-dagua-em-ribeirao-preto-veja-locais-afetados\/","url_meta":{"origin":62073,"position":4},"title":"Saerp alerta para falta d\u2019\u00e1gua em Ribeir\u00e3o Preto; Veja locais afetados","author":"ismaelcolosi.com.br","date":"29 de July de 2024","format":false,"excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) publicou um aviso para falta d\u2019\u00e1gua no Centro de Ribeir\u00e3o Preto nesta segunda-feira (29). As falhas no abastecimento podem ser provocadas por conta do rompimento da rede de \u00e1gua. O rompimento teria ocorrido durante as obras de Mobilidade Urbana.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15_2024-07-10_14-38-39_jpg_2024-07-10_14-38-39.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15_2024-07-10_14-38-39_jpg_2024-07-10_14-38-39.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15_2024-07-10_14-38-39_jpg_2024-07-10_14-38-39.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15_2024-07-10_14-38-39_jpg_2024-07-10_14-38-39.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15_2024-07-10_14-38-39_jpg_2024-07-10_14-38-39.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":69944,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/08\/bairros-de-ribeirao-preto-podem-ficar-sem-agua-ate-amanha\/","url_meta":{"origin":62073,"position":5},"title":"Bairros de Ribeir\u00e3o Preto podem ficar sem \u00e1gua at\u00e9 amanh\u00e3","author":"ismaelcolosi.com.br","date":"8 de October de 2024","format":false,"excerpt":"[ad_1] A Saerp (Secretaria de \u00c1gua e Esgoto de Ribeir\u00e3o Preto) informou que seis bairros da zona Oeste de Ribeir\u00e3o Preto podem ficar sem \u00e1gua at\u00e9 quarta-feira (9), \u00e0s 5h. De acordo com a secretaria, equipes da pasta est\u00e3o realizando a troca emergencial da bomba no Po\u00e7o Parque Ribeir\u00e3o, o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/divulgacao_cesan-Foto-Marcello-Casal-Jr.Agencia-Brasil_2024-08-21_12-20-22_jpg_2024-08-21_12-20-22.webp.webp?fit=600%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/divulgacao_cesan-Foto-Marcello-Casal-Jr.Agencia-Brasil_2024-08-21_12-20-22_jpg_2024-08-21_12-20-22.webp.webp?fit=600%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/divulgacao_cesan-Foto-Marcello-Casal-Jr.Agencia-Brasil_2024-08-21_12-20-22_jpg_2024-08-21_12-20-22.webp.webp?fit=600%2C400&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-g9b","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=62073"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62073\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/62074"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=62073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=62073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=62073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}