{"id":61858,"date":"2024-08-23T16:35:47","date_gmt":"2024-08-23T19:35:47","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/23\/veja-a-situacao-das-rodovias-da-regiao-de-ribeirao-preto-durante-incendios\/"},"modified":"2024-08-23T16:35:47","modified_gmt":"2024-08-23T19:35:47","slug":"veja-a-situacao-das-rodovias-da-regiao-de-ribeirao-preto-durante-incendios","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/23\/veja-a-situacao-das-rodovias-da-regiao-de-ribeirao-preto-durante-incendios\/","title":{"rendered":"Veja a situa\u00e7\u00e3o das rodovias da regi\u00e3o de Ribeir\u00e3o Preto durante inc\u00eandios"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>Inc\u00eandios voltam a atingir a regi\u00e3o de <strong>Ribeir\u00e3o Preto<\/strong> nesta sexta-feira (23). Por conta disso, rodovias precisaram ser interditadas em raz\u00e3o da fuma\u00e7a, por\u00e9m nenhum acidente foi registrado at\u00e9 o momento. <\/p>\n<h4 class=\"wp-block-heading\"><strong>Confira as interdi\u00e7\u00f5es<\/strong><\/h4>\n<p><strong>SP255 \u2013 Rodovia Ant\u00f4nio Machado Sant\u2019Anna \u2013 Cravinhos<\/strong> <\/p>\n<ul>\n<li>Pista dupla e ambos os sentidos interditados<\/li>\n<\/ul>\n<p><strong>SP334 \u2013 C\u00e2ndido Portinari\u00a0 em Jardin\u00f3polis<\/strong><\/p>\n<ul>\n<li>Pista dupla e liberada \u00e0s 15:30h, com comboio da Pol\u00edcia guiando o fluxo<\/li>\n<\/ul>\n<p><strong>SP333 \u2013 Rodovia Carlos Tonanni, em Barrinha<\/strong><\/p>\n<ul>\n<li>Pista dupla e interdi\u00e7\u00e3o total sem previs\u00e3o de libera\u00e7\u00e3o<\/li>\n<\/ul>\n<p><strong>SP322 \u2013 Rodovia Armando de Salles Oliveira, entre Pitangueiras e Sert\u00e3ozinho<\/strong><\/p>\n<ul>\n<li>Pista dupla e interdi\u00e7\u00e3o total sem previs\u00e3o de libera\u00e7\u00e3o<\/li>\n<\/ul>\n<p><strong>SP291 \u2013 Rodovia Mario Doneg\u00e1, em Dumont<\/strong><\/p>\n<ul>\n<li>Pista dupla com interdi\u00e7\u00e3o no sentido norte. Tr\u00e1fego fluindo no esquema de pare e siga sentido sul <\/li>\n<\/ul>\n<p>SAIBA MAIS<br \/>Receita abre consulta ao 4\u00ba lote de restitui\u00e7\u00f5es nesta sexta; Saiba como fazer<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do <strong>acidade on <\/strong>no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a> e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do<strong> acidade on <\/strong>no WhatsApp. Para entrar no grupo, basta <a href=\"https:\/\/chat.whatsapp.com\/Dtv9mxhy6V5BJBotM2OQ5k\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/><a href=\"https:\/\/acidadeon.com\/tudoep\/tudo-noticias\/quando-tera-chuva-em-sp-frente-fria-traz-ventania-de-70-km-h\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Quando ter\u00e1 chuva em SP? Frente fria traz ventania de 70 km\/h.<\/a><\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/veja-a-situacao-das-rodovias-da-regiao-de-ribeirao-preto-durante-incendios\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Inc\u00eandios voltam a atingir a regi\u00e3o de Ribeir\u00e3o Preto nesta sexta-feira (23). Por conta disso, rodovias precisaram ser interditadas em raz\u00e3o da fuma\u00e7a, por\u00e9m nenhum acidente foi registrado at\u00e9 o momento. Confira as interdi\u00e7\u00f5es SP255 \u2013 Rodovia Ant\u00f4nio Machado Sant\u2019Anna \u2013 Cravinhos Pista dupla e ambos os sentidos interditados SP334 \u2013 C\u00e2ndido Portinari\u00a0 em &#8230; <a title=\"Veja a situa\u00e7\u00e3o das rodovias da regi\u00e3o de Ribeir\u00e3o Preto durante inc\u00eandios\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/23\/veja-a-situacao-das-rodovias-da-regiao-de-ribeirao-preto-durante-incendios\/\" aria-label=\"Read more about Veja a situa\u00e7\u00e3o das rodovias da regi\u00e3o de Ribeir\u00e3o Preto durante inc\u00eandios\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":61859,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-61858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/INCENDIO_2024-08-23_18-57-32_jpg_2024-08-23_18-57-32.webp.webp?fit=1200%2C784&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/INCENDIO_2024-08-23_18-57-32_jpg_2024-08-23_18-57-32.webp.webp?fit=1200%2C784&ssl=1",1200,784,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/INCENDIO_2024-08-23_18-57-32_jpg_2024-08-23_18-57-32.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/INCENDIO_2024-08-23_18-57-32_jpg_2024-08-23_18-57-32.webp.webp?fit=300%2C196&ssl=1",300,196,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/INCENDIO_2024-08-23_18-57-32_jpg_2024-08-23_18-57-32.webp.webp?fit=768%2C502&ssl=1",768,502,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/INCENDIO_2024-08-23_18-57-32_jpg_2024-08-23_18-57-32.webp.webp?fit=1024%2C669&ssl=1",1024,669,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/INCENDIO_2024-08-23_18-57-32_jpg_2024-08-23_18-57-32.webp.webp?fit=1200%2C784&ssl=1",1200,784,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/INCENDIO_2024-08-23_18-57-32_jpg_2024-08-23_18-57-32.webp.webp?fit=1200%2C784&ssl=1",1200,784,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Inc\u00eandios voltam a atingir a regi\u00e3o de Ribeir\u00e3o Preto nesta sexta-feira (23). Por conta disso, rodovias precisaram ser interditadas em raz\u00e3o da fuma\u00e7a, por\u00e9m nenhum acidente foi registrado at\u00e9 o momento. Confira as interdi\u00e7\u00f5es SP255 \u2013 Rodovia Ant\u00f4nio Machado Sant\u2019Anna \u2013 Cravinhos Pista dupla e ambos os sentidos interditados SP334 \u2013 C\u00e2ndido Portinari\u00a0 em&hellip;","jetpack-related-posts":[{"id":61992,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/24\/mais-uma-rodovia-da-regiao-de-ribeirao-e-interditada-veja-qual\/","url_meta":{"origin":61858,"position":0},"title":"Mais uma rodovia da regi\u00e3o de Ribeir\u00e3o \u00e9 interditada; veja qual","author":"ismaelcolosi.com.br","date":"24 de August de 2024","format":false,"excerpt":"[ad_1] Inc\u00eandio e fuma\u00e7a causaram a interdi\u00e7\u00e3o de mais uma rodovia da regi\u00e3o de Ribeir\u00e3o Preto, na tarde deste s\u00e1bado (24). A rodovia Maur\u00edlio Biagi, em Pontal, est\u00e1 interditada nos dois sentidos. Ainda n\u00e3o h\u00e1 previs\u00e3o de libera\u00e7\u00e3o da via de acordo com a concession\u00e1ria. Mais cedo, ao menos duas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/pontal_2024-08-24_17-55-00_png_2024-08-24_17-55-00.webp.webp?fit=366%2C454&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":61982,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/24\/incendios-voltam-a-fechar-rodovias-na-regiao-de-ribeirao-preto\/","url_meta":{"origin":61858,"position":1},"title":"Inc\u00eandios voltam a fechar rodovias na regi\u00e3o de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"24 de August de 2024","format":false,"excerpt":"[ad_1] Ao menos duas rodovias da regi\u00e3o de Ribeir\u00e3o Preto foram interdiadas por causa de queimadas neste s\u00e1bado (24). Assista ao v\u00eddeo abaixo. Segundo a concession\u00e1ria ViaPaulista, os dois sentidos da C\u00e2ndido Portinari (SP-334) foram bloqueados no km 341, em Brodowski. O tr\u00e2nsito, por\u00e9m, j\u00e1 est\u00e1 liberado no trecho. J\u00e1\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-24-at-13.30.57_2024-08-24_16-31-21_jpeg_2024-08-24_16-31-21.webp.webp?fit=1200%2C838&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-24-at-13.30.57_2024-08-24_16-31-21_jpeg_2024-08-24_16-31-21.webp.webp?fit=1200%2C838&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-24-at-13.30.57_2024-08-24_16-31-21_jpeg_2024-08-24_16-31-21.webp.webp?fit=1200%2C838&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-24-at-13.30.57_2024-08-24_16-31-21_jpeg_2024-08-24_16-31-21.webp.webp?fit=1200%2C838&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-24-at-13.30.57_2024-08-24_16-31-21_jpeg_2024-08-24_16-31-21.webp.webp?fit=1200%2C838&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":61812,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/23\/incendios-voltam-a-interditar-rodovias-na-regiao-de-ribeirao-preto-veja-video\/","url_meta":{"origin":61858,"position":2},"title":"Inc\u00eandios voltam a interditar rodovias na regi\u00e3o de Ribeir\u00e3o Preto; Veja v\u00eddeo","author":"ismaelcolosi.com.br","date":"23 de August de 2024","format":false,"excerpt":"[ad_1] Ao menos tr\u00eas rodovias foram interditadas nesta sexta-feira (23) por causa de inc\u00eandios na regi\u00e3o de Ribeir\u00e3o Preto. Assista ao v\u00eddeo abaixo. Segundo a concession\u00e1ria Entrevias, h\u00e1 bloqueio no km 340 da Att\u00edlio Balbo (SP-322), sentido Oeste, em Sert\u00e3ozinho. Tamb\u00e9m h\u00e1 interdi\u00e7\u00e3o na pra\u00e7a de Ped\u00e1gio de Pitangueiras, no\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/FOGO_2024-08-23_15-53-56_jpg_2024-08-23_15-53-56.webp.webp?fit=1200%2C664&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/FOGO_2024-08-23_15-53-56_jpg_2024-08-23_15-53-56.webp.webp?fit=1200%2C664&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/FOGO_2024-08-23_15-53-56_jpg_2024-08-23_15-53-56.webp.webp?fit=1200%2C664&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/FOGO_2024-08-23_15-53-56_jpg_2024-08-23_15-53-56.webp.webp?fit=1200%2C664&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/FOGO_2024-08-23_15-53-56_jpg_2024-08-23_15-53-56.webp.webp?fit=1200%2C664&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":62071,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/25\/anhanguera-e-interditada-por-conta-de-incendio-em-ribeirao-preto\/","url_meta":{"origin":61858,"position":3},"title":"Anhanguera \u00e9 interditada por conta de inc\u00eandio em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"25 de August de 2024","format":false,"excerpt":"[ad_1] A rodovia Anhanguera foi interditada nos dois sentidos, na noite deste s\u00e1bado (24), em Ribeir\u00e3o Preto, na altura do quil\u00f4metro 302. A interdi\u00e7\u00e3o foi motivada por um inc\u00eandio em vegeta\u00e7\u00e3o. N\u00e3o h\u00e1 previs\u00e3o de libera\u00e7\u00e3o. Mais cedo, outro trecho da Anhanguera, em Jardin\u00f3polis, tamb\u00e9m havia passado por bloqueio. A\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/anhanguera_2024-08-24_23-29-46_jpg_2024-08-24_23-29-46.webp.webp?fit=1132%2C734&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/anhanguera_2024-08-24_23-29-46_jpg_2024-08-24_23-29-46.webp.webp?fit=1132%2C734&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/anhanguera_2024-08-24_23-29-46_jpg_2024-08-24_23-29-46.webp.webp?fit=1132%2C734&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/anhanguera_2024-08-24_23-29-46_jpg_2024-08-24_23-29-46.webp.webp?fit=1132%2C734&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/anhanguera_2024-08-24_23-29-46_jpg_2024-08-24_23-29-46.webp.webp?fit=1132%2C734&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":54871,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/28\/acidente-provoca-interdicao-e-congestionamento-na-anhanguera-em-ribeirao\/","url_meta":{"origin":61858,"position":4},"title":"Acidente provoca interdi\u00e7\u00e3o e congestionamento na Anhanguera em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"28 de June de 2024","format":false,"excerpt":"[ad_1] Um acidente na manh\u00e3 desta sexta-feira (28) provocou a interdi\u00e7\u00e3o e congestionamento, de ao menos um quil\u00f4metro, no quil\u00f4metro 313 da rodovia Anhanguera (SP-330) em Ribeir\u00e3o Preto. A pista interditada \u00e9 no sentido norte. Segundo a Arteris Via Paulista, concession\u00e1ria que administra o trecho, o fluxo de ve\u00edculos est\u00e1\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__acesso-anhanguera-cravinhos_2024-06-22_15-28-46.webp.webp?fit=1162%2C689&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__acesso-anhanguera-cravinhos_2024-06-22_15-28-46.webp.webp?fit=1162%2C689&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__acesso-anhanguera-cravinhos_2024-06-22_15-28-46.webp.webp?fit=1162%2C689&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__acesso-anhanguera-cravinhos_2024-06-22_15-28-46.webp.webp?fit=1162%2C689&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/AnyConv.com__acesso-anhanguera-cravinhos_2024-06-22_15-28-46.webp.webp?fit=1162%2C689&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":42290,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/13\/motorista-fica-gravemente-ferido-apos-capotamento-em-rodovia-da-regiao-de-ribeirao\/","url_meta":{"origin":61858,"position":5},"title":"Motorista fica gravemente ferido ap\u00f3s capotamento em rodovia da regi\u00e3o de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"13 de March de 2024","format":false,"excerpt":"[ad_1] Um homem ficou gravemente ferido ap\u00f3s capotar o ve\u00edculo que dirigia na tarde desta quarta-feira (13), na rodovia Ronan Rocha (SP 345), em Franca. Segundo informa\u00e7\u00f5es apuradas pela EPTV, o motorista seguia sentido ao Distrito Industrial da cidade quando perdeu o controle da dire\u00e7\u00e3o, invadiu o acostamento e capotou.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-47.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-47.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-47.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-47.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-47.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-g5I","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=61858"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/61859"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=61858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=61858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=61858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}