{"id":61544,"date":"2024-08-22T11:06:11","date_gmt":"2024-08-22T14:06:11","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/22\/saiba-quem-sao-os-candidatos-a-prefeitura-de-franca\/"},"modified":"2024-08-22T11:06:11","modified_gmt":"2024-08-22T14:06:11","slug":"saiba-quem-sao-os-candidatos-a-prefeitura-de-franca","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/22\/saiba-quem-sao-os-candidatos-a-prefeitura-de-franca\/","title":{"rendered":"Saiba quem s\u00e3o os candidatos \u00e0 Prefeitura de Franca"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p><strong>Franca<\/strong>, na <strong>interior de S\u00e3o Paulo<\/strong>, \u00e9 uma das cidades como mais pretendentes na disputa pela prefeitura nas <strong>elei\u00e7\u00f5es 2024<\/strong> \u2013 novo ao todo. <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">O primeiro turno est\u00e1 marcado para o dia 6 de outubro <\/mark>e, se necess\u00e1rio, o segundo turno acontece no dia 27 de outubro.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Veja os candidatos:<\/strong><\/h4>\n<p><strong>Alexandre Ferreira \u2013 MDB<\/strong><\/p>\n<p><strong>Alexandre Tabah \u2013 Novo<\/strong><\/p>\n<p><strong>Dr. Ubiali \u2013 PSB<\/strong><\/p>\n<p><strong>Guilherme Cortez \u2013 Psol<\/strong><\/p>\n<p><strong>Jo\u00e3o Rocha \u2013 PL<\/strong><\/p>\n<p><strong>Jo\u00e3o Scarpanti \u2013 PCO<\/strong><\/p>\n<p><strong>Jonas Carvalho \u2013 Mobiliza<\/strong><\/p>\n<p><strong>Mariana Negri \u2013 PT<\/strong><\/p>\n<p><strong>Tito \u2013 PCB<\/strong><\/p>\n<p>As informa\u00e7\u00f5es sobre todos os candidatos a prefeito de Franca, como nome completo, profiss\u00e3o, grau de instru\u00e7\u00e3o, patrim\u00f4nio, podem ser conferidos no<a href=\"https:\/\/divulgacandcontas.tse.jus.br\/divulga\/#\/candidato\/SUDESTE\/SP\/2045202024\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> <strong>Divulgacand <\/strong>(clique aqui)<\/a>.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Vereadores<\/strong><\/h4>\n<p>Ao todo, Franca conta com 249 candidatos a vereador nas elei\u00e7\u00f5es de 2024. O Legislativo da cidade conta com 15 vagas. Todos os candidatos podem ser conferido <a href=\"https:\/\/divulgacandcontas.tse.jus.br\/divulga\/#\/candidato\/SUDESTE\/SP\/2045202024\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">clicando aqui<\/a>.<\/p>\n<p>SAIBA MAIS<br \/>Interior de SP segue em alerta vermelho; Veja quando tem previs\u00e3o de chuva<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do<strong> acidade on <\/strong>no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Instagram <\/a>e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do <strong>acidade on <\/strong>no WhatsApp.<a href=\"https:\/\/chat.whatsapp.com\/Dtv9mxhy6V5BJBotM2OQ5k\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>\u2018Estrela da Casa\u2019: participantes recebem dicas de Ludmilla<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/politica\/eleicoes\/saiba-quem-sao-os-candidatos-a-prefeitura-de-franca\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Franca, na interior de S\u00e3o Paulo, \u00e9 uma das cidades como mais pretendentes na disputa pela prefeitura nas elei\u00e7\u00f5es 2024 \u2013 novo ao todo. O primeiro turno est\u00e1 marcado para o dia 6 de outubro e, se necess\u00e1rio, o segundo turno acontece no dia 27 de outubro. Veja os candidatos: Alexandre Ferreira \u2013 MDB &#8230; <a title=\"Saiba quem s\u00e3o os candidatos \u00e0 Prefeitura de Franca\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/22\/saiba-quem-sao-os-candidatos-a-prefeitura-de-franca\/\" aria-label=\"Read more about Saiba quem s\u00e3o os candidatos \u00e0 Prefeitura de Franca\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":61545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-61544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/prefeitura-de-franca_2024-08-22_13-37-01_jpg_2024-08-22_13-37-01.webp.webp?fit=1200%2C793&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/prefeitura-de-franca_2024-08-22_13-37-01_jpg_2024-08-22_13-37-01.webp.webp?fit=1200%2C793&ssl=1",1200,793,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/prefeitura-de-franca_2024-08-22_13-37-01_jpg_2024-08-22_13-37-01.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/prefeitura-de-franca_2024-08-22_13-37-01_jpg_2024-08-22_13-37-01.webp.webp?fit=300%2C198&ssl=1",300,198,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/prefeitura-de-franca_2024-08-22_13-37-01_jpg_2024-08-22_13-37-01.webp.webp?fit=768%2C508&ssl=1",768,508,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/prefeitura-de-franca_2024-08-22_13-37-01_jpg_2024-08-22_13-37-01.webp.webp?fit=1024%2C677&ssl=1",1024,677,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/prefeitura-de-franca_2024-08-22_13-37-01_jpg_2024-08-22_13-37-01.webp.webp?fit=1200%2C793&ssl=1",1200,793,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/prefeitura-de-franca_2024-08-22_13-37-01_jpg_2024-08-22_13-37-01.webp.webp?fit=1200%2C793&ssl=1",1200,793,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Franca, na interior de S\u00e3o Paulo, \u00e9 uma das cidades como mais pretendentes na disputa pela prefeitura nas elei\u00e7\u00f5es 2024 \u2013 novo ao todo. O primeiro turno est\u00e1 marcado para o dia 6 de outubro e, se necess\u00e1rio, o segundo turno acontece no dia 27 de outubro. Veja os candidatos: Alexandre Ferreira \u2013 MDB&hellip;","jetpack-related-posts":[{"id":69579,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/06\/alexandre-ferreira-e-joao-rocha-vao-disputar-o-2o-turno-em-franca\/","url_meta":{"origin":61544,"position":0},"title":"Alexandre Ferreira e Jo\u00e3o Rocha v\u00e3o disputar o 2\u00ba turno em Franca","author":"ismaelcolosi.com.br","date":"6 de October de 2024","format":false,"excerpt":"[ad_1] Os candidatos Alexandre Ferreira (MDB) e Jo\u00e3o Rocha (PL) v\u00e3o decidir no 2\u00ba turno, que ser\u00e1 realizado no dia 27 de outubro, quem ser\u00e1 o pr\u00f3ximo prefeito de Franca. Conforme os dados do Tribunal Superior Eleitoral (TSE), ao final da apura\u00e7\u00e3o, \u00e0s 19h30, Alexandre recebeu 73.390 votos (47,18%) e\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-20_2024-10-06_22-39-25_jpg_2024-10-06_22-39-25.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-20_2024-10-06_22-39-25_jpg_2024-10-06_22-39-25.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-20_2024-10-06_22-39-25_jpg_2024-10-06_22-39-25.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-20_2024-10-06_22-39-25_jpg_2024-10-06_22-39-25.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-20_2024-10-06_22-39-25_jpg_2024-10-06_22-39-25.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":69340,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/04\/veja-os-numeros-dos-candidatos-a-prefeito-de-franca-nas-eleicoes-2024\/","url_meta":{"origin":61544,"position":1},"title":"Veja os n\u00fameros dos candidatos a prefeito de Franca nas elei\u00e7\u00f5es 2024","author":"ismaelcolosi.com.br","date":"4 de October de 2024","format":false,"excerpt":"[ad_1] O primeiro turno das elei\u00e7\u00f5es 2024 acontece neste domingo (6) e os locais de vota\u00e7\u00e3o estar\u00e3o abertos das 8h \u00e0s 17h. Ao longo da campanha, o acidade on realizou uma s\u00e9rie de entrevistas com os candidatos \u00e0 Prefeitura de Franca. Lista de candidatos a prefeito de Franca em 2024*:\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/candidatos-franca_2024-10-04_19-59-34_jpeg_2024-10-04_19-59-34.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/candidatos-franca_2024-10-04_19-59-34_jpeg_2024-10-04_19-59-34.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/candidatos-franca_2024-10-04_19-59-34_jpeg_2024-10-04_19-59-34.webp.webp?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/candidatos-franca_2024-10-04_19-59-34_jpeg_2024-10-04_19-59-34.webp.webp?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/candidatos-franca_2024-10-04_19-59-34_jpeg_2024-10-04_19-59-34.webp.webp?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":65895,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/14\/veja-o-que-alexandre-tabah-disse-na-entrevista-da-serie-entre-os-candidatos-a-prefeitura-de-franca\/","url_meta":{"origin":61544,"position":2},"title":"Veja o que Alexandre Tabah disse na entrevista da s\u00e9rie entre os candidatos \u00e0 Prefeitura de Franca","author":"ismaelcolosi.com.br","date":"14 de September de 2024","format":false,"excerpt":"[ad_1] O acidade on Ribeir\u00e3o realizou nesta semana uma s\u00e9rie de entrevistas com os candidatos \u00e0 Prefeitura de Franca nas elei\u00e7\u00f5es 2024. Neste s\u00e1bado (14) o entrevistado foi o empres\u00e1rio Alexandre Tabah (Novo) \u2013 veja o player acima. A sequ\u00eancia de entrevistas foi definida por ordem alfab\u00e9tica. Cinco candidatos foram\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-tabah_2024-09-14_17-41-26_jpeg_2024-09-14_17-41-26.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-tabah_2024-09-14_17-41-26_jpeg_2024-09-14_17-41-26.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-tabah_2024-09-14_17-41-26_jpeg_2024-09-14_17-41-26.webp.webp?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-tabah_2024-09-14_17-41-26_jpeg_2024-09-14_17-41-26.webp.webp?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-tabah_2024-09-14_17-41-26_jpeg_2024-09-14_17-41-26.webp.webp?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":65871,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/14\/alexandre-tabah-participa-neste-sabado-da-serie-de-entrevistas-com-candidatos-a-prefeitura-de-franca\/","url_meta":{"origin":61544,"position":3},"title":"Alexandre Tabah participa neste s\u00e1bado da s\u00e9rie de entrevistas com candidatos \u00e0 Prefeitura de Franca","author":"ismaelcolosi.com.br","date":"14 de September de 2024","format":false,"excerpt":"[ad_1] O acidade on Ribeir\u00e3o realiza nesta semana uma s\u00e9rie de entrevistas com os candidatos \u00e0 Prefeitura de Franca nas elei\u00e7\u00f5es 2024. Neste s\u00e1bado (14) \u00e9 a vez da sabatina com o empres\u00e1rio Alexandre Tabah (Novo) \u2013 veja o player acima. A entrevista vai ao ar, ao vivo, logo ap\u00f3s\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-tabah_2024-09-14_13-54-19_jpg_2024-09-14_13-54-19.webp.webp?fit=1080%2C833&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-tabah_2024-09-14_13-54-19_jpg_2024-09-14_13-54-19.webp.webp?fit=1080%2C833&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-tabah_2024-09-14_13-54-19_jpg_2024-09-14_13-54-19.webp.webp?fit=1080%2C833&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-tabah_2024-09-14_13-54-19_jpg_2024-09-14_13-54-19.webp.webp?fit=1080%2C833&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-tabah_2024-09-14_13-54-19_jpg_2024-09-14_13-54-19.webp.webp?fit=1080%2C833&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":72167,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/20\/eptv-transmite-debate-em-novo-formato-com-os-candidatos-a-prefeitura-de-franca\/","url_meta":{"origin":61544,"position":4},"title":"EPTV transmite debate em novo formato com os candidatos \u00e0 Prefeitura de Franca","author":"ismaelcolosi.com.br","date":"20 de October de 2024","format":false,"excerpt":"[ad_1] O Grupo EP realiza neste domingo (20) o debate do segundo turno das elei\u00e7\u00f5es 2024 entre os candidatos \u00e0 Prefeitura de Franca, Alexandre Ferreira (MDB) e Jo\u00e3o Rocha (PL). O embate ser\u00e1 transmitido ao vivo pela EPTV Ribeir\u00e3o Preto ap\u00f3s o programa Fant\u00e1stico, \u00e0s 23h30. Em novo formato, o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-20_2024-10-06_22-39-25_jpg_2024-10-06_22-39-25.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-20_2024-10-06_22-39-25_jpg_2024-10-06_22-39-25.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-20_2024-10-06_22-39-25_jpg_2024-10-06_22-39-25.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-20_2024-10-06_22-39-25_jpg_2024-10-06_22-39-25.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-20_2024-10-06_22-39-25_jpg_2024-10-06_22-39-25.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":64790,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/09\/alexandre-ferreira-abre-serie-de-entrevistas-com-candidatos-a-prefeitura-de-franca\/","url_meta":{"origin":61544,"position":5},"title":"Alexandre Ferreira abre s\u00e9rie de entrevistas com candidatos \u00e0 Prefeitura de Franca","author":"ismaelcolosi.com.br","date":"9 de September de 2024","format":false,"excerpt":"[ad_1] O acidade on Ribeir\u00e3o come\u00e7a nesta segunda-feira (9) uma s\u00e9rie de entrevistas com os candidatos \u00e0 Prefeitura de Franca nas elei\u00e7\u00f5es 2024. O primeiro entrevistado \u00e9 o atual prefeito de Franca, Alexandre Ferreira (MDB) \u2013 veja o player acima. A entrevista vai ao ar, ao vivo, logo ap\u00f3s a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-ferreira_2024-09-09_14-40-04_jpg_2024-09-09_14-40-04.webp.webp?fit=1079%2C845&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-ferreira_2024-09-09_14-40-04_jpg_2024-09-09_14-40-04.webp.webp?fit=1079%2C845&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-ferreira_2024-09-09_14-40-04_jpg_2024-09-09_14-40-04.webp.webp?fit=1079%2C845&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-ferreira_2024-09-09_14-40-04_jpg_2024-09-09_14-40-04.webp.webp?fit=1079%2C845&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/alexandre-ferreira_2024-09-09_14-40-04_jpg_2024-09-09_14-40-04.webp.webp?fit=1079%2C845&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-g0E","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=61544"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61544\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/61545"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=61544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=61544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=61544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}