{"id":60390,"date":"2024-08-15T16:31:12","date_gmt":"2024-08-15T19:31:12","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/15\/vagas-de-empregos-na-microset-tecnologia-para-trabalhar-em-ribeirao-preto-sp-12\/"},"modified":"2024-08-15T16:31:12","modified_gmt":"2024-08-15T19:31:12","slug":"vagas-de-empregos-na-microset-tecnologia-para-trabalhar-em-ribeirao-preto-sp-12","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/15\/vagas-de-empregos-na-microset-tecnologia-para-trabalhar-em-ribeirao-preto-sp-12\/","title":{"rendered":"Vagas de empregos na Microset Tecnologia  para trabalhar em Ribeir\u00e3o Preto-SP"},"content":{"rendered":"<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 euwBIb\"><a aria-label=\"Vaga para vacancy_type_effective como Analista Fiscal  em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vagasmicroset.gupy.io\/jobs\/7162117?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 kYdTkU\">\n<div class=\"sc-f5007364-4 eiyEcj\">Analista Fiscal <\/div>\n<div class=\"sc-f5007364-5 KCtRP\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 gIgRzt\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 euwBIb\"><a aria-label=\"Vaga para vacancy_type_effective como Assistente de Service Desk I em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vagasmicroset.gupy.io\/jobs\/7627039?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 kYdTkU\">\n<div class=\"sc-f5007364-4 eiyEcj\">Assistente de Service Desk I<\/div>\n<div class=\"sc-f5007364-5 KCtRP\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 gIgRzt\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<h1 font-family=\"'Inter', sans-serif\" color=\"#27262A\" my=\"0\" id=\"h1\" class=\"sc-iHGNWf diwYlf sc-e9dd4d1-5 kQslax\">Microset Tecnologia <\/h1>\n<li data-testid=\"job-list__listitem\" class=\"sc-f5007364-2 euwBIb\"><a aria-label=\"Vaga para vacancy_type_effective como Analista Fiscal  em Ribeir\u00e3o Preto - SP\" data-testid=\"job-list__listitem-href\" href=\"https:\/\/vagasmicroset.gupy.io\/jobs\/7162117?jobBoardSource=gupy_public_page\" target=\"_blank\" rel=\"noopener\">\n<div class=\"sc-f5007364-3 kYdTkU\">\n<div class=\"sc-f5007364-4 eiyEcj\">Analista Fiscal <\/div>\n<div class=\"sc-f5007364-5 KCtRP\">Ribeir\u00e3o Preto &#8211; SP<\/div>\n<div class=\"sc-f5007364-6 gIgRzt\">Efetivo<\/div>\n<\/div>\n<p><\/a><\/li>\n<h2 data-testid=\"section-V\u00eddeos -title\" class=\"sc-6fde0c52-0 kpbBna\">V\u00eddeos <\/h2>\n<p><iframe data-testid=\"video-iframe\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/1VOCtCboY04?hl=pt\" title=\"V\u00eddeo sobre a empresa 1\" width=\"100%\" class=\"sc-ed722fcc-2 iczbIF\"><\/iframe><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>Analista Fiscal Ribeir\u00e3o Preto &#8211; SP Efetivo Assistente de Service Desk I Ribeir\u00e3o Preto &#8211; SP Efetivo Microset Tecnologia Analista Fiscal Ribeir\u00e3o Preto &#8211; SP Efetivo V\u00eddeos \ud83d\udce2 Aviso Legal O site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra &#8230; <a title=\"Vagas de empregos na Microset Tecnologia  para trabalhar em Ribeir\u00e3o Preto-SP\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/15\/vagas-de-empregos-na-microset-tecnologia-para-trabalhar-em-ribeirao-preto-sp-12\/\" aria-label=\"Read more about Vagas de empregos na Microset Tecnologia  para trabalhar em Ribeir\u00e3o Preto-SP\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":60391,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-60390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vagas-de-empregos-em-ribeirao-preto-regiao-brasil"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1",1080,327,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/2023-03-15_13-45_bannerUrl.png?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/2023-03-15_13-45_bannerUrl.png?fit=300%2C91&ssl=1",300,91,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/2023-03-15_13-45_bannerUrl.png?fit=768%2C233&ssl=1",768,233,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/2023-03-15_13-45_bannerUrl.png?fit=1024%2C310&ssl=1",1024,310,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1",1080,327,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/2023-03-15_13-45_bannerUrl.png?fit=1080%2C327&ssl=1",1080,327,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"Analista Fiscal Ribeir\u00e3o Preto &#8211; SP Efetivo Assistente de Service Desk I Ribeir\u00e3o Preto &#8211; SP Efetivo Microset Tecnologia Analista Fiscal Ribeir\u00e3o Preto &#8211; SP Efetivo V\u00eddeos \ud83d\udce2 Aviso Legal O site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra&hellip;","jetpack-related-posts":[{"id":51279,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/25\/mais-de-10-vagas-de-emprego-de-recepcionista-em-ribeirao-preto-sp-28\/","url_meta":{"origin":60390,"position":0},"title":"Mais de 10 vagas de emprego de Recepcionista em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"25 de May de 2024","format":false,"excerpt":"Recepcionista Secretaria executiva Recepcionista de Loja - Petz Ribeir\u00e3o Preto Presidente Vargas Recepcionista Administrativa Secretaria executiva Ribeir\u00e3o Preto - SPEfetivo Recepcionista Recepcionista RECEPCIONISTA Recepcionista Recepcionista","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/1716674054_aaa-6.png?fit=500%2C265&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":51015,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/22\/vagas-de-emprego-na-area-de-logistica-em-ribeirao-preto-sp-4\/","url_meta":{"origin":60390,"position":1},"title":"Vagas de emprego na \u00e1rea de log\u00edstica em Ribeir\u00e3o Preto-SP","author":"ismaelcolosi.com.br","date":"22 de May de 2024","format":false,"excerpt":"Auxiliar de Estoque Auxiliar De Expedi\u00e7\u00e3o Auxiliar de Opera\u00e7\u00e3o e Estoque | CD Farma Ribeir\u00e3o Preto - SPRibeir\u00e3o Preto - SPEfetivo Estoquista RB Estoquista RB Assistente III (Gente e Gest\u00e3o - Toca do Urso) Operador Log\u00edstico - Com Experi\u00eancia Estoquista Assistente Get notified about new Log\u00edstica jobs in Ribeir\u00e3o Preto,\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Novas-vagas-de-emprego-na-area-de-logistica-Saiba-como-enviar-seu-curriculo.jpg?fit=1199%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Novas-vagas-de-emprego-na-area-de-logistica-Saiba-como-enviar-seu-curriculo.jpg?fit=1199%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Novas-vagas-de-emprego-na-area-de-logistica-Saiba-como-enviar-seu-curriculo.jpg?fit=1199%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Novas-vagas-de-emprego-na-area-de-logistica-Saiba-como-enviar-seu-curriculo.jpg?fit=1199%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Novas-vagas-de-emprego-na-area-de-logistica-Saiba-como-enviar-seu-curriculo.jpg?fit=1199%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":35194,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/05\/agente-escolarribeirao-preto-spefetivo\/","url_meta":{"origin":60390,"position":2},"title":"Agente EscolarRibeir\u00e3o Preto &#8211; SPEfetivo","author":"ismaelcolosi.com.br","date":"5 de February de 2024","format":false,"excerpt":"SobreVagasFazer login como candidato(a)Grupo SEBSelo de FeedbackCONHE\u00c7A NOSSA HIST\u00d3RIAO nosso time tem mais de 6 mil agentes de transforma\u00e7\u00e3o que participam ativamente da vida de mais de 310 mil estudantes em mais de 30 pa\u00edses, preparando crian\u00e7as e jovens para os desafios do futuro em qualquer lugar do mundo. Falou\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707156251_2021-12-09_14-39_logo.png?fit=1182%2C1182&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707156251_2021-12-09_14-39_logo.png?fit=1182%2C1182&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707156251_2021-12-09_14-39_logo.png?fit=1182%2C1182&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707156251_2021-12-09_14-39_logo.png?fit=1182%2C1182&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707156251_2021-12-09_14-39_logo.png?fit=1182%2C1182&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":27124,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/11\/agente-escolar-ribeirao-preto-spefetivo\/","url_meta":{"origin":60390,"position":3},"title":"Agente Escolar  Ribeir\u00e3o Preto &#8211; SPEfetivo","author":"ismaelcolosi.com.br","date":"11 de January de 2024","format":false,"excerpt":"SobreVagasFazer login como candidato(a)Grupo SEBSelo de FeedbackCONHE\u00c7A NOSSA HIST\u00d3RIAO nosso time tem mais de 6 mil agentes de transforma\u00e7\u00e3o que participam ativamente da vida de mais de 310 mil estudantes em mais de 30 pa\u00edses, preparando crian\u00e7as e jovens para os desafios do futuro em qualquer lugar do mundo. Falou\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1704994961_2021-12-09_14-39_logo.png?fit=1182%2C1182&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1704994961_2021-12-09_14-39_logo.png?fit=1182%2C1182&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1704994961_2021-12-09_14-39_logo.png?fit=1182%2C1182&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1704994961_2021-12-09_14-39_logo.png?fit=1182%2C1182&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1704994961_2021-12-09_14-39_logo.png?fit=1182%2C1182&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":35823,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/07\/vagas-em-ribeirao-preto-destaques-4\/","url_meta":{"origin":60390,"position":4},"title":"Vagas em Ribeir\u00e3o Preto: Destaques","author":"ismaelcolosi.com.br","date":"7 de February de 2024","format":false,"excerpt":"Lista de Vagas em Ribeir\u00e3o Preto Ribeir\u00e3o Preto - SP Auxiliar de Estoque Ver mais Ribeir\u00e3o Preto - SP Gerente de Loja Ver mais Ribeir\u00e3o Preto - SP Santa Casa de Ribeir\u00e3o Preto: Confira as vagas dispon\u00edveis Ver mais Ribeir\u00e3o Preto - SP Balconista Ver mais Ribeir\u00e3o Preto - SP\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707332188_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707332188_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707332188_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707332188_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707332188_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14913,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/12\/vagas-em-ribeirao-preto-destaques\/","url_meta":{"origin":60390,"position":5},"title":"Vagas em Ribeir\u00e3o Preto: Destaques","author":"ismaelcolosi.com.br","date":"12 de December de 2023","format":false,"excerpt":"Vagas em Ribeir\u00e3o Preto: Destaques No data was found Lista de Vagas em Ribeir\u00e3o Preto Ribeir\u00e3o Preto - SP Cacau Show- Consultor Comercial Ver mais Ribeir\u00e3o Preto - SP Vendedor | Vans Ribeir\u00e3o Ver mais Ribeir\u00e3o Preto - SP MR. KITSCH \u2013 Vendedor(a) Ver mais Ribeir\u00e3o Preto - SP OCULARIUM\u2026","rel":"","context":"In &quot;Vagas de Emprego em Ribeir\u00e3o Preto-SP&quot;","block_context":{"text":"Vagas de Emprego em Ribeir\u00e3o Preto-SP","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702416303_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702416303_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702416303_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702416303_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702416303_maxresdefault.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-fI2","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/60390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=60390"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/60390\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/60391"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=60390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=60390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=60390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}