{"id":60176,"date":"2024-08-14T16:47:25","date_gmt":"2024-08-14T19:47:25","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/14\/destrocos-do-aviao-que-caiu-em-vinhedo-serao-encaminhados-para-ribeirao-preto\/"},"modified":"2024-08-14T16:47:25","modified_gmt":"2024-08-14T19:47:25","slug":"destrocos-do-aviao-que-caiu-em-vinhedo-serao-encaminhados-para-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/14\/destrocos-do-aviao-que-caiu-em-vinhedo-serao-encaminhados-para-ribeirao-preto\/","title":{"rendered":"Destro\u00e7os do avi\u00e3o que caiu em Vinhedo ser\u00e3o encaminhados para Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>Os <strong>objetos pessoais das v\u00edtimas <\/strong>e <strong>parte dos destro\u00e7os<\/strong> do <strong>avi\u00e3o que caiu em Vinhedo<\/strong>, na \u00faltima sexta-feira (9), ser\u00e3o encaminhados para <strong>Ribeir\u00e3o Preto<\/strong>, cidade sede da <strong>Voepass<\/strong>, companhia a\u00e9rea respons\u00e1vel pela <strong>aeronave ATR-72<\/strong>.<\/p>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">De acordo com a empresa, ap\u00f3s o <strong>processo de limpeza espec\u00edfico, o material ficar\u00e1 armazenado na cidade at\u00e9 que todos os familiares das 62 v\u00edtimas sejam indenizados.<\/strong><\/mark><\/p>\n<p>No domingo (11), ap\u00f3s a finaliza\u00e7\u00e3o do trabalho de retirada dos corpos das v\u00edtimas, o <strong>Centro de Investiga\u00e7\u00e3o e Preven\u00e7\u00e3o de Acidentes Aeron\u00e1uticos (Cenipa)<\/strong> fez a <strong>remo\u00e7\u00e3o dos motores<\/strong>, <strong>cauda <\/strong>e <strong>caixas-preta<\/strong> da aeronave.<\/p>\n<p>Com isso, o trabalho de remo\u00e7\u00e3o dos objetos <strong>deveria ter come\u00e7ado na segunda-feira (12)<\/strong>, contudo, foi interrompido ap\u00f3s <strong>novo material gen\u00e9tico ser encontrado no local do acidente<\/strong>. <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">O processo foi retomado no final da manh\u00e3 desta quarta-feira (14).<\/mark><\/p>\n<h3 class=\"wp-block-heading\"><strong>Reuni\u00f5es di\u00e1rias com familiares<\/strong><\/h3>\n<p>O presidente e co-fundador da Voepass, comandante <strong>Jos\u00e9 Luiz Fel\u00edcio Filho<\/strong>, se manifestou pela primeira vez na noite desta ter\u00e7a-feira (13), ap\u00f3s a queda de um avi\u00e3o.<\/p>\n<p>No pronunciamento, Jos\u00e9 Luiz <strong>lamentou o ocorrido<\/strong> e informou que a empresa est\u00e1 <strong>garantindo assist\u00eancia aos familiares das v\u00edtimas <\/strong>do voo 2283.<\/p>\n<figure class=\"wp-block-pullquote\">\n<blockquote>\n<p>Eu e minha equipe estamos realizando reuni\u00f5es di\u00e1rias com os familiares e criamos tamb\u00e9m um canal de comunica\u00e7\u00e3o exclusivo pra que todos tenham acesso de forma correta e transparente e objetiva a qualquer momento<\/p>\n<\/blockquote>\n<\/figure>\n<h4 class=\"wp-block-heading\"><strong>O acidente<\/strong><\/h4>\n<p>O avi\u00e3o que caiu em <strong>Vinhedo<\/strong>, no <strong>interior de S\u00e3o Paulo<\/strong>, saiu de <strong>Cascavel-PR<\/strong>, \u00e0s 11h40 na \u00faltima sexta-feira (9), e tinha como destino o <strong>aeroporto Internacional de Guarulhos<\/strong>. <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">Segundo a empresa, estavam no avi\u00e3o 58 passageiros, al\u00e9m de quatro tripulantes.<\/mark><\/p>\n<p>Durante coletiva de imprensa, realizada no dia do acidente, a Voepass informou que o avi\u00e3o \u201cestava perfeitamente naveg\u00e1vel\u201d, contudo, disse que os avi\u00f5es modelo ATR-72, s\u00e3o mais sens\u00edvel \u00e0 situa\u00e7\u00e3o de gelo, <strong>uma das hip\u00f3teses para causa da queda.<\/strong><\/p>\n<p>O <strong>Instituto M\u00e9dico-Legal (IML)<\/strong> concluiu que as v\u00edtimas do acidente morreram de politraumatismo. A aeronave despencou mais de <strong>4 mil metros de altura em apenas um minuto at\u00e9 atingir o solo.<\/strong><\/p>\n<p>At\u00e9 o <strong>in\u00edcio da tarde desta quarta-feira<\/strong>, o <strong>IML <\/strong>identificou que <strong>56 corpos<\/strong>. Desses, 27 foram liberados aos familiares e outros cinco est\u00e3o em processo de libera\u00e7\u00e3o, aguardando a documenta\u00e7\u00e3o complementar.<\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<p>SAIBA MAIS<\/p>\n<p>Mulher \u00e9 resgatada de condi\u00e7\u00f5es an\u00e1logas \u00e0 escravid\u00e3o na regi\u00e3o de Ribeir\u00e3o Preto<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on\u00a0<\/strong>no WhatsApp. Para entrar no grupo, basta\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Dtv9mxhy6V5BJBotM2OQ5k\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>\u2018Estrela da Casa\u2019: qual participante foi bloqueada pelo Zez\u00e9 Di Camargo?<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/destrocos-do-aviao-que-caiu-em-vinhedo-serao-encaminhados-para-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Os objetos pessoais das v\u00edtimas e parte dos destro\u00e7os do avi\u00e3o que caiu em Vinhedo, na \u00faltima sexta-feira (9), ser\u00e3o encaminhados para Ribeir\u00e3o Preto, cidade sede da Voepass, companhia a\u00e9rea respons\u00e1vel pela aeronave ATR-72. De acordo com a empresa, ap\u00f3s o processo de limpeza espec\u00edfico, o material ficar\u00e1 armazenado na cidade at\u00e9 que todos &#8230; <a title=\"Destro\u00e7os do avi\u00e3o que caiu em Vinhedo ser\u00e3o encaminhados para Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/14\/destrocos-do-aviao-que-caiu-em-vinhedo-serao-encaminhados-para-ribeirao-preto\/\" aria-label=\"Read more about Destro\u00e7os do avi\u00e3o que caiu em Vinhedo ser\u00e3o encaminhados para Ribeir\u00e3o Preto\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":60177,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-60176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/aviaoqueda_2024-08-10_13-32-48_jpeg_2024-08-10_13-32-48-1068x601-1_2024-08-14_19-27-26.webp.webp?fit=1068%2C601&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/aviaoqueda_2024-08-10_13-32-48_jpeg_2024-08-10_13-32-48-1068x601-1_2024-08-14_19-27-26.webp.webp?fit=1068%2C601&ssl=1",1068,601,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/aviaoqueda_2024-08-10_13-32-48_jpeg_2024-08-10_13-32-48-1068x601-1_2024-08-14_19-27-26.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/aviaoqueda_2024-08-10_13-32-48_jpeg_2024-08-10_13-32-48-1068x601-1_2024-08-14_19-27-26.webp.webp?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/aviaoqueda_2024-08-10_13-32-48_jpeg_2024-08-10_13-32-48-1068x601-1_2024-08-14_19-27-26.webp.webp?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/aviaoqueda_2024-08-10_13-32-48_jpeg_2024-08-10_13-32-48-1068x601-1_2024-08-14_19-27-26.webp.webp?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/aviaoqueda_2024-08-10_13-32-48_jpeg_2024-08-10_13-32-48-1068x601-1_2024-08-14_19-27-26.webp.webp?fit=1068%2C601&ssl=1",1068,601,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/aviaoqueda_2024-08-10_13-32-48_jpeg_2024-08-10_13-32-48-1068x601-1_2024-08-14_19-27-26.webp.webp?fit=1068%2C601&ssl=1",1068,601,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Os objetos pessoais das v\u00edtimas e parte dos destro\u00e7os do avi\u00e3o que caiu em Vinhedo, na \u00faltima sexta-feira (9), ser\u00e3o encaminhados para Ribeir\u00e3o Preto, cidade sede da Voepass, companhia a\u00e9rea respons\u00e1vel pela aeronave ATR-72. De acordo com a empresa, ap\u00f3s o processo de limpeza espec\u00edfico, o material ficar\u00e1 armazenado na cidade at\u00e9 que todos&hellip;","jetpack-related-posts":[{"id":59611,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/09\/governo-de-sp-decreta-luto-de-tres-dias-por-causa-de-acidente-aereo-no-interior\/","url_meta":{"origin":60176,"position":0},"title":"Governo de SP decreta luto de tr\u00eas dias por causa de acidente a\u00e9reo no interior","author":"ismaelcolosi.com.br","date":"9 de August de 2024","format":false,"excerpt":"[ad_1] O governador do Estado de S\u00e3o Paulo, Tarc\u00edsio de Freitas, decretou luto de tr\u00eas dias em homenagem \u00e0s v\u00edtimas do acidente a\u00e9reo em Vinhedo, no interior de S\u00e3o Paulo, nesta sexta-feira (9). O avi\u00e3o era da Voepass, antiga Passaredo, empresa que tem sede em Ribeir\u00e3o Preto. Conforme anunciado anteriormente\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/denny_cesare_codigo_19_272915_2024-08-09_21-14-55_jpg_2024-08-09_21-14-55-1068x712-1_2024-08-09_23-42-09.webp.webp?fit=1068%2C712&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/denny_cesare_codigo_19_272915_2024-08-09_21-14-55_jpg_2024-08-09_21-14-55-1068x712-1_2024-08-09_23-42-09.webp.webp?fit=1068%2C712&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/denny_cesare_codigo_19_272915_2024-08-09_21-14-55_jpg_2024-08-09_21-14-55-1068x712-1_2024-08-09_23-42-09.webp.webp?fit=1068%2C712&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/denny_cesare_codigo_19_272915_2024-08-09_21-14-55_jpg_2024-08-09_21-14-55-1068x712-1_2024-08-09_23-42-09.webp.webp?fit=1068%2C712&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/denny_cesare_codigo_19_272915_2024-08-09_21-14-55_jpg_2024-08-09_21-14-55-1068x712-1_2024-08-09_23-42-09.webp.webp?fit=1068%2C712&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":59613,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/09\/governo-de-sp-decreta-luto-de-tres-dias-por-causa-de-acidente-aereo-no-interior-2\/","url_meta":{"origin":60176,"position":1},"title":"Governo de SP decreta luto de tr\u00eas dias por causa de acidente a\u00e9reo no interior","author":"ismaelcolosi.com.br","date":"9 de August de 2024","format":false,"excerpt":"[ad_1] O governador do Estado de S\u00e3o Paulo, Tarc\u00edsio de Freitas, decretou luto de tr\u00eas dias em homenagem \u00e0s v\u00edtimas do acidente a\u00e9reo em Vinhedo, no interior de S\u00e3o Paulo, nesta sexta-feira (9). O avi\u00e3o era da Voepass, antiga Passaredo, empresa que tem sede em Ribeir\u00e3o Preto. Conforme anunciado anteriormente\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/denny_cesare_codigo_19_272915_2024-08-09_21-14-55_jpg_2024-08-09_21-14-55-1068x712-1_2024-08-09_23-42-09.webp.webp?fit=1068%2C712&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/denny_cesare_codigo_19_272915_2024-08-09_21-14-55_jpg_2024-08-09_21-14-55-1068x712-1_2024-08-09_23-42-09.webp.webp?fit=1068%2C712&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/denny_cesare_codigo_19_272915_2024-08-09_21-14-55_jpg_2024-08-09_21-14-55-1068x712-1_2024-08-09_23-42-09.webp.webp?fit=1068%2C712&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/denny_cesare_codigo_19_272915_2024-08-09_21-14-55_jpg_2024-08-09_21-14-55-1068x712-1_2024-08-09_23-42-09.webp.webp?fit=1068%2C712&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/denny_cesare_codigo_19_272915_2024-08-09_21-14-55_jpg_2024-08-09_21-14-55-1068x712-1_2024-08-09_23-42-09.webp.webp?fit=1068%2C712&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":59934,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/13\/vitimas-da-queda-de-aviao-no-interior-de-sp-morreram-por-politraumatismo\/","url_meta":{"origin":60176,"position":2},"title":"V\u00edtimas da queda de avi\u00e3o no interior de SP morreram por politraumatismo","author":"ismaelcolosi.com.br","date":"13 de August de 2024","format":false,"excerpt":"[ad_1] O IML (Instituto M\u00e9dico-Legal) concluiu que as v\u00edtimas do acidente com o avi\u00e3o da Voepass, em Vinhedo, no interior de S\u00e3o Paulo, na sexta-feira (9), morreram de politraumatismo. O acidente deixou 62 mortos \u2013 sendo 58 passageiros e quatro tripulantes. A aeronave despencou mais de 4 mil metros de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/bombeiros_2024-08-13_16-00-44_jpeg_2024-08-13_16-00-44.webp.webp?fit=800%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/bombeiros_2024-08-13_16-00-44_jpeg_2024-08-13_16-00-44.webp.webp?fit=800%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/bombeiros_2024-08-13_16-00-44_jpeg_2024-08-13_16-00-44.webp.webp?fit=800%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/bombeiros_2024-08-13_16-00-44_jpeg_2024-08-13_16-00-44.webp.webp?fit=800%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":59582,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/09\/lula-e-tarcisio-lamentam-queda-de-aviao-no-interior-de-sp\/","url_meta":{"origin":60176,"position":3},"title":"Lula e Tarc\u00edsio lamentam queda de avi\u00e3o no interior de SP","author":"ismaelcolosi.com.br","date":"9 de August de 2024","format":false,"excerpt":"[ad_1] O presidente Luiz In\u00e1cio Lula da Silva pediu um minuto de sil\u00eancio para as v\u00edtimas da queda do avi\u00e3o com 58 passageiros e quatro tripulantes em Vinhedo, operado pela Voepass, com sede em Ribeir\u00e3o Preto, nesta sexta-feira (9). Queria que todos se colocassem de p\u00e9 para que a gente\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":59598,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/09\/lula-e-tarcisio-lamentam-queda-de-aviao-no-interior-de-sp-2\/","url_meta":{"origin":60176,"position":4},"title":"Lula e Tarc\u00edsio lamentam queda de avi\u00e3o no interior de SP","author":"ismaelcolosi.com.br","date":"9 de August de 2024","format":false,"excerpt":"[ad_1] O presidente Luiz In\u00e1cio Lula da Silva pediu um minuto de sil\u00eancio para as v\u00edtimas da queda do avi\u00e3o com 58 passageiros e quatro tripulantes em Vinhedo, operado pela Voepass, com sede em Ribeir\u00e3o Preto, nesta sexta-feira (9). Queria que todos se colocassem de p\u00e9 para que a gente\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T162854.895_2024-08-09_19-29-00_png_2024-08-09_19-29-00.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":59607,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/09\/quem-era-a-vitima-de-ribeirao-preto-que-morreu-em-acidente-de-aviao-no-interior-de-sp\/","url_meta":{"origin":60176,"position":5},"title":"Quem era a v\u00edtima de Ribeir\u00e3o Preto que morreu em acidente de avi\u00e3o no interior de SP","author":"ismaelcolosi.com.br","date":"9 de August de 2024","format":false,"excerpt":"[ad_1] A comiss\u00e1ria de bordo Rubia Silva de Lima, de Ribeir\u00e3o Preto, \u00e9 uma das v\u00edtimas da queda de um avi\u00e3o da Voepass, antiga Passaredo, que aconteceu em Vinhedo, interior de SP, nesta sexta-feira (9). Nas redes sociais, a mulher de 41 anos publicava diversas fotos de viagens que realizou.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T195802.137_2024-08-09_23-10-34_png_2024-08-09_23-10-34.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T195802.137_2024-08-09_23-10-34_png_2024-08-09_23-10-34.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T195802.137_2024-08-09_23-10-34_png_2024-08-09_23-10-34.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T195802.137_2024-08-09_23-10-34_png_2024-08-09_23-10-34.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-09T195802.137_2024-08-09_23-10-34_png_2024-08-09_23-10-34.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-fEA","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/60176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=60176"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/60176\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/60177"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=60176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=60176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=60176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}