{"id":58904,"date":"2024-08-03T17:06:48","date_gmt":"2024-08-03T20:06:48","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/03\/uniao-brasil-define-andre-trindade-como-candidato-a-prefeitura-de-ribeirao-preto\/"},"modified":"2024-08-03T17:06:48","modified_gmt":"2024-08-03T20:06:48","slug":"uniao-brasil-define-andre-trindade-como-candidato-a-prefeitura-de-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/03\/uniao-brasil-define-andre-trindade-como-candidato-a-prefeitura-de-ribeirao-preto\/","title":{"rendered":"Uni\u00e3o Brasil define Andr\u00e9 Trindade como candidato \u00e0 Prefeitura de Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_106\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p><strong>O Uni\u00e3o Brasil (UB) oficializou a candidatura de Andr\u00e9 Trindade \u00e0 Prefeitura de Ribeir\u00e3o Preto durante conven\u00e7\u00e3o realizada neste s\u00e1bado (3), na C\u00e2mara Municipal.<\/strong> O nome do <strong>ex-secret\u00e1rio municipal de Justi\u00e7a e da Casa Civil, Alessandro Hirata (PSDB)<\/strong>, tamb\u00e9m foi <strong>oficializado <\/strong>como <strong>candidato <\/strong>a <strong>vice<\/strong>.<\/p>\n<p><strong>Trindade <\/strong>\u00e9 <strong>ex-l\u00edder<\/strong> do atual <strong>governo municipal <\/strong>no <strong>Legislativo<\/strong>.<\/p>\n<blockquote class=\"wp-block-quote\">\n<p>\u201cVamos seguir na transforma\u00e7\u00e3o de tudo aquilo que as pessoas merecem e precisam para viver melhor. Vamos fazer ainda mais para \u00e1reas fundamentais como sa\u00fade, educa\u00e7\u00e3o e bem-estar social. Iremos governar com respeito para todas as pessoas\u201d<\/p>\n<p><cite>Andr\u00e9 Trindade, candidato \u00e0 Prefeitura de Ribeir\u00e3o Preto<\/cite><\/p><\/blockquote>\n<h4 class=\"wp-block-heading\"><strong>Sobre o candidato<\/strong><\/h4>\n<ul>\n<li>Andr\u00e9 Trindade tem 45 anos, \u00e9 casado e pai de um filho<\/li>\n<\/ul>\n<ul>\n<li>Nascido na Vila Tib\u00e9rio e morador do Jardim Proc\u00f3pio por 20 anos<\/li>\n<\/ul>\n<ul>\n<li>Foi vereador l\u00edder da bancada do governo de Duarte Nogueira (PSDB) na C\u00e2mara de Ribeir\u00e3o Preto<\/li>\n<\/ul>\n<ul>\n<li>Foi secret\u00e1rio de Esportes de Ribeir\u00e3o Preto<\/li>\n<\/ul>\n<p>SAIBA MAIS<\/p>\n<p>Veja o que muda para popula\u00e7\u00e3o de Ribeir\u00e3o Preto com novo projeto de ilumina\u00e7\u00e3o p\u00fablica<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on<\/strong>\u00a0no WhatsApp. Para entrar no grupo, basta\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Dtv9mxhy6V5BJBotM2OQ5k\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Avalia\u00e7\u00e3o de Lula se iguala a Bolsonaro<\/p>\n<p><!-- CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/uniao-brasil-define-andre-trindade-como-candidato-a-prefeitura-de-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O Uni\u00e3o Brasil (UB) oficializou a candidatura de Andr\u00e9 Trindade \u00e0 Prefeitura de Ribeir\u00e3o Preto durante conven\u00e7\u00e3o realizada neste s\u00e1bado (3), na C\u00e2mara Municipal. O nome do ex-secret\u00e1rio municipal de Justi\u00e7a e da Casa Civil, Alessandro Hirata (PSDB), tamb\u00e9m foi oficializado como candidato a vice. Trindade \u00e9 ex-l\u00edder do atual governo municipal no Legislativo. &#8230; <a title=\"Uni\u00e3o Brasil define Andr\u00e9 Trindade como candidato \u00e0 Prefeitura de Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/03\/uniao-brasil-define-andre-trindade-como-candidato-a-prefeitura-de-ribeirao-preto\/\" aria-label=\"Read more about Uni\u00e3o Brasil define Andr\u00e9 Trindade como candidato \u00e0 Prefeitura de Ribeir\u00e3o Preto\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":58905,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-58904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-03-at-13.58.46_2024-08-03_19-37-00_jpeg_2024-08-03_19-37-02-scaled.webp.webp?fit=2560%2C1706&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-03-at-13.58.46_2024-08-03_19-37-00_jpeg_2024-08-03_19-37-02-scaled.webp.webp?fit=2560%2C1706&ssl=1",2560,1706,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-03-at-13.58.46_2024-08-03_19-37-00_jpeg_2024-08-03_19-37-02-scaled.webp.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-03-at-13.58.46_2024-08-03_19-37-00_jpeg_2024-08-03_19-37-02-scaled.webp.webp?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-03-at-13.58.46_2024-08-03_19-37-00_jpeg_2024-08-03_19-37-02-scaled.webp.webp?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-03-at-13.58.46_2024-08-03_19-37-00_jpeg_2024-08-03_19-37-02-scaled.webp.webp?fit=1024%2C682&ssl=1",1024,682,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-03-at-13.58.46_2024-08-03_19-37-00_jpeg_2024-08-03_19-37-02-scaled.webp.webp?fit=1536%2C1024&ssl=1",1536,1024,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-03-at-13.58.46_2024-08-03_19-37-00_jpeg_2024-08-03_19-37-02-scaled.webp.webp?fit=2048%2C1365&ssl=1",2048,1365,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O Uni\u00e3o Brasil (UB) oficializou a candidatura de Andr\u00e9 Trindade \u00e0 Prefeitura de Ribeir\u00e3o Preto durante conven\u00e7\u00e3o realizada neste s\u00e1bado (3), na C\u00e2mara Municipal. O nome do ex-secret\u00e1rio municipal de Justi\u00e7a e da Casa Civil, Alessandro Hirata (PSDB), tamb\u00e9m foi oficializado como candidato a vice. Trindade \u00e9 ex-l\u00edder do atual governo municipal no Legislativo.&hellip;","jetpack-related-posts":[{"id":58932,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/04\/uniao-brasil-define-andre-trindade-como-candidato-a-prefeitura-de-ribeirao-preto-2\/","url_meta":{"origin":58904,"position":0},"title":"Uni\u00e3o Brasil define Andr\u00e9 Trindade como candidato \u00e0 Prefeitura de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"4 de August de 2024","format":false,"excerpt":"[ad_1] O Uni\u00e3o Brasil (UB) oficializou a candidatura de Andr\u00e9 Trindade \u00e0 Prefeitura de Ribeir\u00e3o Preto durante conven\u00e7\u00e3o realizada neste s\u00e1bado (3), na C\u00e2mara Municipal. O nome do ex-secret\u00e1rio municipal de Justi\u00e7a e da Casa Civil, Alessandro Hirata (PSDB), tamb\u00e9m foi oficializado como candidato a vice. Trindade \u00e9 ex-l\u00edder do\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-03-at-13.58.46_2024-08-03_19-37-00_jpeg_2024-08-03_19-37-02-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-03-at-13.58.46_2024-08-03_19-37-00_jpeg_2024-08-03_19-37-02-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-03-at-13.58.46_2024-08-03_19-37-00_jpeg_2024-08-03_19-37-02-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-03-at-13.58.46_2024-08-03_19-37-00_jpeg_2024-08-03_19-37-02-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-03-at-13.58.46_2024-08-03_19-37-00_jpeg_2024-08-03_19-37-02-scaled.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":67587,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/24\/andre-trindade-participa-nesta-terca-da-serie-de-entrevistas-com-candidatos-a-prefeitura-de-ribeirao-preto\/","url_meta":{"origin":58904,"position":1},"title":"Andr\u00e9 Trindade participa nesta ter\u00e7a da s\u00e9rie de entrevistas com candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"24 de September de 2024","format":false,"excerpt":"[ad_1] O acidade on Ribeir\u00e3o realiza nesta semana uma s\u00e9rie de entrevistas com os candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto nas elei\u00e7\u00f5es 2024. Nesta ter\u00e7a-feira (24) \u00e9 a vez da sabatina do empres\u00e1rio e ex-vereador Andr\u00e9 Trindade (Uni\u00e3o) \u2013 veja o player acima. A entrevista ter\u00e1 12 minutos e vai\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-60_2024-09-19_21-29-32_png_2024-09-19_21-29-32.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-60_2024-09-19_21-29-32_png_2024-09-19_21-29-32.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-60_2024-09-19_21-29-32_png_2024-09-19_21-29-32.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-60_2024-09-19_21-29-32_png_2024-09-19_21-29-32.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-60_2024-09-19_21-29-32_png_2024-09-19_21-29-32.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":57043,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/17\/nogueira-anuncia-apoio-a-pre-candidatura-de-andre-trindade-na-disputa-pela-prefeitura-de-ribeirao\/","url_meta":{"origin":58904,"position":2},"title":"Nogueira anuncia apoio \u00e0 pr\u00e9-candidatura de Andr\u00e9 Trindade na disputa pela prefeitura de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"17 de July de 2024","format":false,"excerpt":"[ad_1] Ribeir\u00e3o Preto tem mais uma mudan\u00e7a na disputa pela prefeitura. Nesta quarta-feira (17), o PSDB, partido do prefeito Duarte Nogueira, anunciou apoio \u00e0 pr\u00e9-candidatura do ex-vereador Andr\u00e9 Trindade (Uni\u00e3o). Com isso, o ex-secret\u00e1rio Alessandro Hirata, deixa a pr\u00e9-candidatura e deve concorrer a vice na chapa. Outros nomes que j\u00e1\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__andre-trindade-tv-camara_2024-07-17_15-18-19.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__andre-trindade-tv-camara_2024-07-17_15-18-19.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__andre-trindade-tv-camara_2024-07-17_15-18-19.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__andre-trindade-tv-camara_2024-07-17_15-18-19.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__andre-trindade-tv-camara_2024-07-17_15-18-19.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":69187,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/04\/veja-como-foi-o-debate-da-eptv-com-candidatos-a-prefeitura-de-ribeirao-preto\/","url_meta":{"origin":58904,"position":3},"title":"Veja como foi o debate da EPTV com candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"4 de October de 2024","format":false,"excerpt":"[ad_1] Quatro candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto participaram do debate promovido pela EPTV na noite desta quinta-feira (3), que se estendeu at\u00e9 o come\u00e7o da madrugada de sexta-feira (4). O debate foi mediado pelo jornalista Guilherme Nali. Os quatro candidatos \u2013 Andr\u00e9 Trindade (Uni\u00e3o), Jorge Roque (PT), Marco Aur\u00e9lio\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-93_2024-10-04_02-58-43_png_2024-10-04_02-58-43.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-93_2024-10-04_02-58-43_png_2024-10-04_02-58-43.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-93_2024-10-04_02-58-43_png_2024-10-04_02-58-43.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-93_2024-10-04_02-58-43_png_2024-10-04_02-58-43.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-93_2024-10-04_02-58-43_png_2024-10-04_02-58-43.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":57819,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/24\/veja-quem-apoia-quem-na-corrida-pela-prefeitura-de-ribeirao-preto\/","url_meta":{"origin":58904,"position":4},"title":"Veja quem apoia quem na corrida pela Prefeitura de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"24 de July de 2024","format":false,"excerpt":"[ad_1] A ex-reitora da USP (Universidade de S\u00e3o Paulo) Suely Vilela anunciou nesta quarta-feira (24) que deixou a corrida pela Prefeitura de Ribeir\u00e3o Preto nas elei\u00e7\u00f5es de 2024. Agora, a disputa pelo Executivo Municipal a partir de 2025 conta com seis pretendentes. Em nota, Suely, que foi ao segundo turno\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/candidatos-ribeirao-preto_2024-07-24_20-15-44_jpeg_2024-07-24_20-15-44.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/candidatos-ribeirao-preto_2024-07-24_20-15-44_jpeg_2024-07-24_20-15-44.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/candidatos-ribeirao-preto_2024-07-24_20-15-44_jpeg_2024-07-24_20-15-44.webp.webp?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/candidatos-ribeirao-preto_2024-07-24_20-15-44_jpeg_2024-07-24_20-15-44.webp.webp?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/candidatos-ribeirao-preto_2024-07-24_20-15-44_jpeg_2024-07-24_20-15-44.webp.webp?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":54756,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/27\/veja-quem-sao-os-pre-candidatos-a-prefeitura-de-ribeirao-preto\/","url_meta":{"origin":58904,"position":5},"title":"Veja quem s\u00e3o os pr\u00e9-candidatos \u00e0 Prefeitura de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"27 de June de 2024","format":false,"excerpt":"[ad_1] As pr\u00e9-candidaturas \u00e0 Prefeitura de Ribeir\u00e3o Preto t\u00eam dividido an\u00fancios de interesse em disputar o cargo do Executivo e desist\u00eancias. Neste cen\u00e1rio, as informa\u00e7\u00f5es mais recentes s\u00e3o da confirma\u00e7\u00e3o da disputa de Andr\u00e9 Trindade (Uni\u00e3o). O an\u00fancio da pr\u00e9-candidatura de Andr\u00e9 Trindade (Uni\u00e3o Brasil) aconteceu nesta quinta-feira (27). Qual\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Capturar_2024-06-27_16-02-08_jpg_2024-06-27_16-02-08.webp.webp?fit=865%2C491&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Capturar_2024-06-27_16-02-08_jpg_2024-06-27_16-02-08.webp.webp?fit=865%2C491&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Capturar_2024-06-27_16-02-08_jpg_2024-06-27_16-02-08.webp.webp?fit=865%2C491&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Capturar_2024-06-27_16-02-08_jpg_2024-06-27_16-02-08.webp.webp?fit=865%2C491&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-fk4","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/58904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=58904"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/58904\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/58905"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=58904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=58904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=58904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}